{"id":120043,"date":"2022-01-31T10:12:48","date_gmt":"2022-01-31T09:12:48","guid":{"rendered":"https:\/\/www.asd-int.com\/mini_blog\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/"},"modified":"2022-02-09T16:00:37","modified_gmt":"2022-02-09T15:00:37","slug":"frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer","status":"publish","type":"mini_blog","link":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/","title":{"rendered":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer"},"content":{"rendered":"\n<p>Seit dem 1. Januar 2022 ist die Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer allgemein eingef\u00fchrt worden und gilt verbindlich.\r\n\r\nDie wichtigste Auswirkung dieser \u00c4nderung ist die<strong>Verpflichtung des steuerpflichtigen Importeurs, in Frankreich eine Umsatzsteuer-Identifikationsnummer<\/strong> zu haben.\r\n\r\nUm den Unternehmen die M\u00f6glichkeit zu geben, die Vorschriften einzuhalten und zu verhindern, dass ihre Waren am franz\u00f6sischen Zoll blockiert werden, haben die Zoll- und Steuerbeh\u00f6rden eine \u00dcbergangsfrist bis zum 30. Juni 2022 festgelegt.\r\n\r\nUm von dieser \u00dcbergangszeit zu profitieren, muss das au\u00dferhalb der Europ\u00e4ischen Union ans\u00e4ssige Unternehmen Folgendes tun:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Vor dem 1. M\u00e4rz 2022 <a href=\"https:\/\/www.asd-int.com\/de\/fiskalvertretung-frankreich\/\">einen akkreditierten Steuervertreter in Frankreich benennen<\/a>;<\/li><li>Vor dem 1. M\u00e4rz 2022 einen Antrag auf Registrierung f\u00fcr die Umsatzsteuer in Frankreich stellen.<\/li><\/ul>\n\n\n\n<p>Nicht in der EU ans\u00e4ssige Unternehmen, die diese beiden Bedingungen nicht erf\u00fcllen, k\u00f6nnen die \u00dcbergangszeit nicht in Anspruch nehmen und werden f\u00fcr all ihre Importgesch\u00e4fte in Frankreich gesperrt. <br><br>F\u00fcr weitere Details setzen Sie sich bitte mit uns in Verbindung.<\/p>\n\n\n\n<p>Quelle: <a href=\"https:\/\/ec.europa.eu\/taxation_customs\/system\/files\/2021-12\/C_2021_9852_1_EN_ACT_part1_v4.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">ec.europa.eu<\/a> (PDF auf Englisch)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit dem 1. Januar 2022 ist die Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer allgemein eingef\u00fchrt worden und gilt verbindlich. Die wichtigste Auswirkung dieser \u00c4nderung ist&#8230;<\/p>\n","protected":false},"author":36,"featured_media":118862,"menu_order":0,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[97,3485],"tags":[2049,3486],"pays":[865],"class_list":["post-120043","mini_blog","type-mini_blog","status-publish","format-standard","has-post-thumbnail","hentry","category-alle","category-mwst","tag-alle-de","tag-mwst","pays-france-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group<\/title>\n<meta name=\"description\" content=\"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-09T15:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/01\/france-periode-transitoire-autoliquidation-tva-importation.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/\",\"name\":\"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/france-periode-transitoire-autoliquidation-tva-importation.jpg\",\"datePublished\":\"2022-01-31T09:12:48+00:00\",\"dateModified\":\"2022-02-09T15:00:37+00:00\",\"description\":\"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/france-periode-transitoire-autoliquidation-tva-importation.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/france-periode-transitoire-autoliquidation-tva-importation.jpg\",\"width\":1440,\"height\":960,\"caption\":\"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\",\"name\":\"ASD\",\"description\":\"Vereinfachen Sie Ihre internationalen Gesch\u00e4fte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group","description":"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/","og_locale":"de_DE","og_type":"article","og_title":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group","og_description":"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.","og_url":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/","og_site_name":"ASD","article_modified_time":"2022-02-09T15:00:37+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/01\/france-periode-transitoire-autoliquidation-tva-importation.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/","url":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/","name":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/01\/france-periode-transitoire-autoliquidation-tva-importation.jpg","datePublished":"2022-01-31T09:12:48+00:00","dateModified":"2022-02-09T15:00:37+00:00","description":"Die Zoll- und Steuerverwaltungen richten angesichts der Umkehrung der Steuerschuldnerschaft f\u00fcr die Einfuhrumsatzsteuer eine \u00dcbergangszeit ein.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/01\/france-periode-transitoire-autoliquidation-tva-importation.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/01\/france-periode-transitoire-autoliquidation-tva-importation.jpg","width":1440,"height":960,"caption":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/de\/frankreich-einfuehrung-einer-uebergangszeit-angesichts-der-umkehrung-der-steuerschuldnerschaft-bei-der-einfuhrumsatzsteuer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/de\/"},{"@type":"ListItem","position":2,"name":"Frankreich: Einf\u00fchrung einer \u00dcbergangszeit angesichts der Umkehrung der Steuerschuldnerschaft bei der Einfuhrumsatzsteuer"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/de\/#website","url":"https:\/\/www.asd-int.com\/de\/","name":"ASD","description":"Vereinfachen Sie Ihre internationalen Gesch\u00e4fte","publisher":{"@id":"https:\/\/www.asd-int.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/de\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asd-int.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog\/120043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog"}],"about":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/types\/mini_blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":0,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog\/120043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/media\/118862"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/media?parent=120043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/categories?post=120043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/tags?post=120043"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/pays?post=120043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}