{"id":197228,"date":"2025-08-05T16:41:11","date_gmt":"2025-08-05T14:41:11","guid":{"rendered":"https:\/\/www.asd-int.com\/mini_blog\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/"},"modified":"2026-04-27T10:05:00","modified_gmt":"2026-04-27T08:05:00","slug":"obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist","status":"publish","type":"mini_blog","link":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/","title":{"rendered":"Obligatorische Logistikumschlag: Verl\u00e4ngerung der \u00dcbergangsfrist"},"content":{"rendered":"\n<div class=\"wp-block-essential-blocks-notice  root-eb-notice-a5jgo\"><div class=\"eb-parent-wrapper eb-parent-eb-notice-a5jgo \"><div class=\"eb-notice-wrapper eb-notice-a5jgo\" data-id=\"eb-notice-a5jgo\" data-show-again=\"false\"><div class=\"eb-notice-title-wrapper\"><div class=\"eb-notice-title\">\u26a0\ufe0f <strong>Achtung<\/strong><\/div><\/div><span class=\"eb-notice-dismiss\" style=\"cursor:pointer\"><\/span><div><div class=\"eb-notice-text\">Diese Regelung ist <strong>seit dem 20. April 2026 verbindlich<\/strong>.<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.asd-int.com\/de\/elo-antizipieren-sie-die-neue-verpflichtung-die-ab-april-2025-den-grenzuebertritt-zwischen-dem-vereinigten-konigreich-und-der-eu-erleichtern-wird\/\">Entgegen unserer fr\u00fcheren Ank\u00fcndigung<\/a>, wird die <strong>Obligatorische Logistikumschlag (ELO)<\/strong>, die im Rahmen der intelligenten Brexit-Grenze eingef\u00fchrt wurde, <strong>nicht wie urspr\u00fcnglich geplant ab dem 1. September 2025 verpflichtend<\/strong>. Die Generaldirektion f\u00fcr Zoll und indirekte Steuern (DGDDI) hat die Verl\u00e4ngerung der \u00dcbergangsfrist bis Herbst 2025 angek\u00fcndigt. <strong>Das genaue Datum der Umstellung wird im September best\u00e4tigt<\/strong>, um den Betreibern und \u00dcberfahrtsgesellschaften ausreichend Vorbereitungszeit zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Das neue endg\u00fcltige Einf\u00fchrungsdatum wurde auf den 20. April 2026 festgelegt.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wer ist betroffen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alle Stra\u00dfenfahrzeuge<\/strong>, ob beladen oder leer, sind <strong>verpflichtet, bei der Grenz\u00fcberschreitung \u00fcber eine ELO zu verf\u00fcgen<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Ziele der ELO:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zentralisierung der Zolldokumente<\/strong>: Eine einzige Akte pro Fahrzeug, um alle erforderlichen Erkl\u00e4rungen zu b\u00fcndeln.<\/li>\n\n\n\n<li><strong>Zeitersparnis<\/strong>: Ein einziger Scan pro Fahrzeug beim Abgang oder bei der Ankunft, was den Grenz\u00fcbertritt beschleunigt.<\/li>\n\n\n\n<li><strong>Sicherung der Abl\u00e4ufe<\/strong>: Reduzierung der Risiken durch fehlende oder inkonsistente Zolldokumente<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Umsetzung:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Schrittweise Einf\u00fchrung<\/strong> ab Ende April 2025 im Rahmen einer \u00dcbergangsfrist.<\/li>\n\n\n\n<li><strong>Verpflichtung verschoben auf Herbst 2025<\/strong>, mit einem genauen Datum, das im September von den Zollbeh\u00f6rden mitgeteilt wird.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Funktionsweise der ELO<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ein <strong>einziger Umschlag pro Fahrzeug<\/strong>, der alle f\u00fcr den \u00dcbergang erforderlichen Dokumente b\u00fcndelt.<\/li>\n\n\n\n<li>Ein <strong>einziges designiertes Aussteller<\/strong>, das f\u00fcr die Verwaltung und Erstellung der ELO verantwortlich ist.<\/li>\n\n\n\n<li>Bei Sammelladungen <strong>werden alle Waren in denselben Umschlag integriert<\/strong>.<\/li>\n\n\n\n<li>Das Ganze wird durch einen <strong>eindeutigen Barcode<\/strong> identifiziert, der die Zollkontrollen erleichtert.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">ASD Group unterst\u00fctzt Sie mit seiner Plattform MyASD<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">ASD Group bietet Ihnen eine einfache und effektive L\u00f6sung zur Verwaltung Ihrer ELO <strong>dank <a href=\"https:\/\/www.asd-int.com\/de\/myasd\/\">unserer Plattform MyASD<\/a><\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Automatische Zusammenfassung der Dokumente<\/strong>, die mit jedem Fahrzeug verbunden sind.<\/li>\n\n\n\n<li><strong>Bereitstellung der ELO<\/strong> in einem sicheren Bereich.<\/li>\n\n\n\n<li><strong>Direkte \u00dcbermittlung<\/strong> an den Fahrer m\u00f6glich f\u00fcr einen reibungslosen Grenz\u00fcbertritt.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr alle Fragen oder Unterst\u00fctzung bei der Einhaltung der Vorschriften steht <a href=\"https:\/\/www.asd-int.com\/de\/kontakt\/\">unser Team Ihnen zur Verf\u00fcgung<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle: <a href=\"https:\/\/www.douane.gouv.fr\/fiche\/enveloppe-logistique-obligatoire-elo-un-passage-cle-pour-les-echanges-roro-avec-le-royaume\" target=\"_blank\" rel=\"noreferrer noopener\">Generaldirektion f\u00fcr Zoll und indirekte Steuern (DGDDI)<\/a> (auf Franz\u00f6sisch)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entgegen unserer fr\u00fcheren Ank\u00fcndigung, wird die Obligatorische Logistikumschlag (ELO), die im Rahmen der intelligenten Brexit-Grenze eingef\u00fchrt wurde, nicht wie urspr\u00fcnglich geplant ab dem 1. September&#8230;<\/p>\n","protected":false},"author":36,"featured_media":197174,"menu_order":0,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[4595],"tags":[4672,4692],"pays":[3456,4202],"class_list":["post-197228","mini_blog","type-mini_blog","status-publish","format-standard","has-post-thumbnail","hentry","category-zoll-de","tag-brexit-de","tag-zollrechtliche-verpflichtungen","pays-europaische-union","pays-royaumeuni-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group<\/title>\n<meta name=\"description\" content=\"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T08:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/08\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"961\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/\",\"name\":\"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg\",\"datePublished\":\"2025-08-05T14:41:11+00:00\",\"dateModified\":\"2026-04-27T08:05:00+00:00\",\"description\":\"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg\",\"width\":1440,\"height\":961,\"caption\":\"Enveloppe logistique obligatoire : Prolongation de la p\u00e9riode transitoire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\",\"name\":\"ASD\",\"description\":\"Vereinfachen Sie Ihre internationalen Gesch\u00e4fte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group","description":"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/","og_locale":"de_DE","og_type":"article","og_title":"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group","og_description":"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.","og_url":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/","og_site_name":"ASD","article_modified_time":"2026-04-27T08:05:00+00:00","og_image":[{"width":1440,"height":961,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/08\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/","url":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/","name":"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/08\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg","datePublished":"2025-08-05T14:41:11+00:00","dateModified":"2026-04-27T08:05:00+00:00","description":"Die franz\u00f6sischen Zollbeh\u00f6rden (DGDDI) verl\u00e4ngern die \u00dcbergangsfrist f\u00fcr die ELO. Erfahren Sie, wer betroffen ist, wie die ELO funktioniert und wie ASD Group Sie unterst\u00fctzen kann.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/08\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/08\/enveloppe-logistique-obligatoire-prolongation-de-la-periode-transitoire.jpg","width":1440,"height":961,"caption":"Enveloppe logistique obligatoire : Prolongation de la p\u00e9riode transitoire"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/de\/obligatorische-logistikumschlag-verlaengerung-der-uebergangsfrist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/de\/"},{"@type":"ListItem","position":2,"name":"ELO: Verl\u00e4ngerung der \u00dcbergangsfrist"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/de\/#website","url":"https:\/\/www.asd-int.com\/de\/","name":"ASD","description":"Vereinfachen Sie Ihre internationalen Gesch\u00e4fte","publisher":{"@id":"https:\/\/www.asd-int.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/de\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asd-int.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog\/197228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog"}],"about":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/types\/mini_blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":5,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog\/197228\/revisions"}],"predecessor-version":[{"id":211101,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/mini_blog\/197228\/revisions\/211101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/media\/197174"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/media?parent=197228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/categories?post=197228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/tags?post=197228"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/de\/wp-json\/wp\/v2\/pays?post=197228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}