{"id":824,"count":14,"description":"","link":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/","name":"Romania","slug":"roumanie-en","taxonomy":"pays","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Romania Archives | ASD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Romania Archives | ASD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1054\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/country\\\/roumanie-en\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/country\\\/roumanie-en\\\/\",\"name\":\"Romania Archives | ASD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/country\\\/roumanie-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/country\\\/roumanie-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Romania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/\",\"name\":\"ASD\",\"description\":\"Simplify your international growth\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Romania Archives | ASD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/","og_locale":"en_US","og_type":"article","og_title":"Romania Archives | ASD","og_url":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/","og_site_name":"ASD","og_image":[{"width":1054,"height":714,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/","url":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/","name":"Romania Archives | ASD","isPartOf":{"@id":"https:\/\/www.asd-int.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/en\/country\/roumanie-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/en\/"},{"@type":"ListItem","position":2,"name":"Romania"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/en\/#website","url":"https:\/\/www.asd-int.com\/en\/","name":"ASD","description":"Simplify your international growth","publisher":{"@id":"https:\/\/www.asd-int.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/en\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.asd-int.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/pays\/824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/pays"}],"about":[{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/taxonomies\/pays"}],"wp:post_type":[{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/posts?pays=824"},{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/service?pays=824"},{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/carriere_asd?pays=824"},{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/mini_blog?pays=824"},{"href":"https:\/\/www.asd-int.com\/en\/wp-json\/wp\/v2\/presse?pays=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}