{"id":174578,"date":"2024-04-18T09:05:10","date_gmt":"2024-04-18T07:05:10","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=mini_blog&#038;p=174578"},"modified":"2024-04-22T11:06:36","modified_gmt":"2024-04-22T09:06:36","slug":"francia-reforma-de-la-tarjeta-btp","status":"publish","type":"mini_blog","link":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/","title":{"rendered":"Francia: Reforma de la tarjeta BTP"},"content":{"rendered":"\n<p>Introducida por la ley n.\u00ba 2015-990 de 6 de agosto de 2015, <strong>la Tarjeta de Identificaci\u00f3n Profesional de los trabajadores del sector de la construcci\u00f3n y las obras p\u00fablicas<\/strong>, conocida como Tarjeta BTP, est\u00e1 siendo reformada por el decreto n.\u00ba 2024-112 de 15 de febrero de 2024, que entra en vigor el 1 de abril de 2024.<\/p>\n\n<p>Desde 2015, los <strong>trabajadores extranjeros desplazados a Francia<\/strong> para realizar trabajos de construcci\u00f3n u obras p\u00fablicas deben disponer de una tarjeta BTP v\u00e1lida para cada obra en la que trabajen. Por tanto, para cada desplazamiento, <strong>el empresario debe solicitar tantas tarjetas BTP como empleados y obras<\/strong>.<\/p>\n\n<p><strong>Qu\u00e9 cambia a partir del 1 de abril de 2024 :<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Periodo de validez de la tarjeta BTP:<\/strong> En aras de la simplificaci\u00f3n, a partir del 1 de abril de 2024, los empleados de un empleador establecido fuera de Francia que realicen trabajos de construcci\u00f3n u obras p\u00fablicas deber\u00e1n estar en posesi\u00f3n de una tarjeta BTP v\u00e1lida durante cinco a\u00f1os (art\u00edculo R. 8292-3 del C\u00f3digo de Trabajo franc\u00e9s). El periodo de validez se indicar\u00e1 en cada tarjeta BTP, junto con su fecha de caducidad.<\/li>\n\n\n\n<li><strong>Multiasignaci\u00f3n:<\/strong> No obstante, se desactivar\u00e1 entre cada periodo de comisi\u00f3n de servicio y entre dos asignaciones (para los trabajadores temporales contratados por empresas de trabajo temporal establecidas en Francia). Por tanto, se ha modificado el art\u00edculo R. 8292-3 2\u00b0 del C\u00f3digo del Trabajo.<\/li>\n\n\n\n<li><strong>Multiempleador:<\/strong> La tarjeta BTP ser\u00e1, por tanto, multiempleador y podr\u00e1 incluir un n\u00famero ilimitado de comisiones de servicio y lugares de trabajo, que se ir\u00e1n a\u00f1adiendo a medida que sea necesario.<\/li>\n\n\n\n<li><strong>Supresi\u00f3n de las ubicaciones de las comisiones de servicio:<\/strong> La localizaci\u00f3n de las comisiones de servicio ya no aparecer\u00e1 en las tarjetas BTP. S\u00f3lo aparecer\u00e1 en las declaraciones SIPSI.<\/li>\n\n\n\n<li><strong>Cambio en el gestor de las tarjetas BTP:<\/strong> A partir de ahora, no es la Union des Caisses la que expide las tarjetas BTP, sino la asociaci\u00f3n \u00abCIBTP France <em>(Fondo de Vacaciones por Condiciones Meteorol\u00f3gicas Adversas y Festivos de Construcci\u00f3n y Obras P\u00fablicas Francia)<\/em>\u00ab, que se encarga de la gesti\u00f3n administrativa, t\u00e9cnica y financiera de esta tarjeta (art\u00edculo R.8291-2 del C\u00f3digo del Trabajo franc\u00e9s).<\/li>\n<\/ul>\n\n<p><strong>Lo que no cambiar\u00e1 a partir del 1 de abril de 2024:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Los empresarios de fuera de Francia que desplacen a trabajadores por cuenta ajena deben solicitar siempre las tarjetas BTP a la asociaci\u00f3n \u00abCIBTP Francia\u00bb a cambio de una cuota cuyo importe determina la asociaci\u00f3n \u00abCIBTP Francia\u00bb (art\u00edculo R.8291-3 del C\u00f3digo del Trabajo franc\u00e9s).<\/li>\n\n\n\n<li>Al igual que antes, a la espera de la expedici\u00f3n de la tarjeta de identificaci\u00f3n profesional, la asociaci\u00f3n \u00abCIBTP France\u00bb enviar\u00e1 por v\u00eda electr\u00f3nica al empresario o a su representante un certificado provisional equivalente a una tarjeta de identificaci\u00f3n profesional para su expedici\u00f3n al trabajador en cuesti\u00f3n.<\/li>\n\n\n\n<li>El titular de la tarjeta de identificaci\u00f3n profesional o del certificado provisional debe presentarla sin demora a requerimiento de cualquiera de los agentes de control mencionados en el art\u00edculo L. 8271-1-2 del C\u00f3digo de Trabajo franc\u00e9s.<\/li>\n<\/ul>\n\n<p>Para m\u00e1s informaci\u00f3n, no dude en ponerse en <a href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">contacto con nuestros expertos<\/a>.<\/p>\n\n<p>Fuentes : <\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.legifrance.gouv.fr\/download\/file\/W4iHY0uxkQIwQpA2B7hi3txJZvxKXBoNLUNa3sUly-c=\/JOE_TEXTE\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00e9gifrance<\/a> (en franc\u00e9s) \/ <a href=\"https:\/\/www.cibtp.fr\/carte-btp\/nouveautes-2024\" target=\"_blank\" rel=\"noreferrer noopener\">CIBTP<\/a> (en franc\u00e9s)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Introducida por la ley n.\u00ba 2015-990 de 6 de agosto de 2015, la Tarjeta de Identificaci\u00f3n Profesional de los trabajadores del sector de la construcci\u00f3n&#8230;<\/p>\n","protected":false},"author":36,"featured_media":174573,"menu_order":0,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3737],"tags":[4569],"pays":[1177],"class_list":["post-174578","mini_blog","type-mini_blog","status-publish","format-standard","has-post-thumbnail","hentry","category-desplazamiento-de-los-trabajadores","tag-tarjeta-btp","pays-france-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Francia: Reforma de la tarjeta BTP | ASD Group<\/title>\n<meta name=\"description\" content=\"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Francia: Reforma de la tarjeta BTP | ASD Group\" \/>\n<meta property=\"og:description\" content=\"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T09:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/04\/france-reforme-de-la-carte-BTP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/\",\"name\":\"Francia: Reforma de la tarjeta BTP | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/france-reforme-de-la-carte-BTP.jpg\",\"datePublished\":\"2024-04-18T07:05:10+00:00\",\"dateModified\":\"2024-04-22T09:06:36+00:00\",\"description\":\"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/france-reforme-de-la-carte-BTP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/france-reforme-de-la-carte-BTP.jpg\",\"width\":1440,\"height\":720,\"caption\":\"France : r\u00e9forme de la carte BTP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/francia-reforma-de-la-tarjeta-btp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Francia: Reforma de la tarjeta BTP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique su desarrollo internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Francia: Reforma de la tarjeta BTP | ASD Group","description":"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/","og_locale":"es_ES","og_type":"article","og_title":"Francia: Reforma de la tarjeta BTP | ASD Group","og_description":"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.","og_url":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/","og_site_name":"ASD","article_modified_time":"2024-04-22T09:06:36+00:00","og_image":[{"width":1440,"height":720,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/04\/france-reforme-de-la-carte-BTP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/","url":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/","name":"Francia: Reforma de la tarjeta BTP | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/04\/france-reforme-de-la-carte-BTP.jpg","datePublished":"2024-04-18T07:05:10+00:00","dateModified":"2024-04-22T09:06:36+00:00","description":"En abril de 2024 entrar\u00e1 en vigor una nueva reforma de la tarjeta de identificaci\u00f3n profesional para los trabajadores del sector de la construcci\u00f3n y la ingenier\u00eda civil.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/04\/france-reforme-de-la-carte-BTP.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/04\/france-reforme-de-la-carte-BTP.jpg","width":1440,"height":720,"caption":"France : r\u00e9forme de la carte BTP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/es\/francia-reforma-de-la-tarjeta-btp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/es\/"},{"@type":"ListItem","position":2,"name":"Francia: Reforma de la tarjeta BTP"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/es\/#website","url":"https:\/\/www.asd-int.com\/es\/","name":"ASD","description":"Simplifique su desarrollo internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/es\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/mini_blog\/174578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/mini_blog"}],"about":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/types\/mini_blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":5,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/mini_blog\/174578\/revisions"}],"predecessor-version":[{"id":174650,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/mini_blog\/174578\/revisions\/174650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/media\/174573"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/media?parent=174578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/categories?post=174578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/tags?post=174578"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/pays?post=174578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}