{"id":194616,"date":"2025-06-04T15:00:57","date_gmt":"2025-06-04T13:00:57","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=service&#038;p=194616"},"modified":"2026-04-29T09:24:42","modified_gmt":"2026-04-29T07:24:42","slug":"asd-taxflow","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/","title":{"rendered":"ASD Taxflow"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"194616\" class=\"elementor elementor-194616 elementor-190698\" data-elementor-post-type=\"service\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73e42ee5 e-con-full hero-template-services e-flex e-con e-parent\" data-id=\"73e42ee5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-31bc92e3 e-con-full e-flex e-con e-child\" data-id=\"31bc92e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7126ee65 elementor-widget elementor-widget-text-editor\" data-id=\"7126ee65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"\/\">INICIO<\/a> > <a href=\"\/myasd\/\">MYASD<\/a> > <a href=\"https:\/\/www.asd-int.com\/es\/servicios-fiscal\/\">FISCAL<\/a> > ASD TAXFLOW<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d1f2372 e-con-full e-flex e-con e-child\" data-id=\"2d1f2372\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5c7b88f6 e-con-full e-flex e-con e-child\" data-id=\"5c7b88f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ae11177 elementor-widget elementor-widget-image\" data-id=\"4ae11177\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png\" title=\"asd-taxflow-logo-blanc-transparent\" alt=\"asd-taxflow-logo-blanc-transparent\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3afcd537 elementor-widget elementor-widget-heading\" data-id=\"3afcd537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Simplifica tus declaraciones de IVA y mant\u00e9n un control total sobre tu cumplimiento<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7857f151 elementor-widget elementor-widget-text-editor\" data-id=\"7857f151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CENTRALIZA, SECURIZA Y DOMINA TODAS TUS OBLIGACIONES DE DECLARACI\u00d3N DE IVA GRACIAS A UNA SOLUCI\u00d3N COMPLETA, DISE\u00d1ADA PARA EMPRESAS EXIGENTES.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64800570 e-con-full e-flex e-con e-child\" data-id=\"64800570\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a51e elementor-tablet-align-justify elementor-widget elementor-widget-button\" data-id=\"b59a51e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/servicios-fiscal\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nuestras soluciones fiscales y de IVA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-636abbe8 elementor-tablet-align-justify elementor-widget elementor-widget-button\" data-id=\"636abbe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cont\u00e1ctanos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87fa936 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"87fa936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b90f166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b90f166\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f1cc8c7\" data-id=\"4f1cc8c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bc9a4f2 elementor-widget elementor-widget-html\" data-id=\"6bc9a4f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e395c20 elementor-widget elementor-widget-html\" data-id=\"4e395c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75bef015 elementor-widget elementor-widget-heading\" data-id=\"75bef015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Simplifica y securiza tus declaraciones de IVA con ASD Taxflow<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcbf7a8 elementor-widget elementor-widget-text-editor\" data-id=\"bcbf7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">\u00bfEst\u00e1s <strong>harto de las complejidades relacionadas con las declaraciones de IVA<\/strong> en la Uni\u00f3n Europea? \u00bfNecesitas una soluci\u00f3n r\u00e1pida y centralizada? \u00a1Prueba ASD Taxflow hoy mismo!<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-42b92ec4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42b92ec4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cd2596a\" data-id=\"1cd2596a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-381c4f23 elementor-widget elementor-widget-heading\" data-id=\"381c4f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Eres<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21656653 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"21656653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-minimize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfUna empresa que realiza <b>intercambios de bienes o servicios intracomunitarios<\/b> en B2C?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-minimize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfUna empresa de servicios con <b>presencia en varios pa\u00edses<\/b>?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-minimize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfUna empresa que utiliza un <b>representante o agente fiscal<\/b>?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-minimize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfUn industrial o fabricante <b>que exporta a varios pa\u00edses de la UE<\/b>?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-minimize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfUn despacho de contabilidad o asesor\u00eda fiscal que gestiona varios clientes con <b>obligaciones de IVA europeas<\/b>?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-091f39b\" data-id=\"091f39b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99c6aa1 elementor-widget elementor-widget-heading\" data-id=\"99c6aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Deseas<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01a3b12 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"01a3b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bf<b>Seguimiento en tiempo real<\/b> del progreso de tus expedientes?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bf<b>Recibir r\u00e1pidamente tus declaraciones<\/b> en cuanto las procesen nuestros operadores?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bf<b>Beneficiarte de un acceso centralizado<\/b> a todos tus documentos declarados?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bf<b>Eliminar los intercambios de correos electr\u00f3nicos contraproducentes<\/b> limitando su volumen?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bf<b>Ahorrar tiempo<\/b> durante las inspecciones?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-351cc503 elementor-widget elementor-widget-heading\" data-id=\"351cc503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubre las ventajasde ASD TAXFLOW<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e82ac01 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e82ac01\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-09ba1b1\" data-id=\"09ba1b1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c677044 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c677044\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d479cc3 elementor-widget elementor-widget-heading\" data-id=\"d479cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ahorro de tiempo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a7314 elementor-widget elementor-widget-text-editor\" data-id=\"b6a7314\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Optimiza tu tiempo<\/strong> y simplifica el intercambio y la gesti\u00f3n de tus expedientes con solo unos clics. <b>ASD Taxflow es una plataforma de intercambio<\/b> con nuestros operadores de uso r\u00e1pido.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a911619\" data-id=\"a911619\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b182255 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b182255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3070b05 elementor-widget elementor-widget-heading\" data-id=\"3070b05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ahorro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a57f4 elementor-widget elementor-widget-text-editor\" data-id=\"25a57f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">El uso de nuestra plataforma <strong>reduce as\u00ed los costos<\/strong> relacionados con la impresi\u00f3n, el env\u00edo postal o por correo electr\u00f3nico y la gesti\u00f3n en papel.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-678f46e\" data-id=\"678f46e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5b1b1e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b5b1b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf38c3 elementor-widget elementor-widget-heading\" data-id=\"ccf38c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Centralizaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad095ba elementor-widget elementor-widget-text-editor\" data-id=\"ad095ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><b>Todos los expedientes y documentos declarativos<\/b> est\u00e1n agrupados en una interfaz \u00fanica.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fe89e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"9fe89e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-907bf89\" data-id=\"907bf89\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb7e138 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cb7e138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-headset\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acef81e elementor-widget elementor-widget-heading\" data-id=\"acef81e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Asistencia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c199854 elementor-widget elementor-widget-text-editor\" data-id=\"c199854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Optimizaci\u00f3n de todos tus intercambios<\/strong> electr\u00f3nicos con nuestros operadores y asistencia en tiempo real.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fc91ab2\" data-id=\"fc91ab2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-986acd4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"986acd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4ef65a elementor-widget elementor-widget-heading\" data-id=\"b4ef65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cumplimiento<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9379bf7 elementor-widget elementor-widget-text-editor\" data-id=\"9379bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Te aseguras de <strong>presentar tus declaraciones conformes<\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-713f42a\" data-id=\"713f42a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39f0d5b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"39f0d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-clock\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bacaa7e elementor-widget elementor-widget-heading\" data-id=\"bacaa7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anticipaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20b12e elementor-widget elementor-widget-text-editor\" data-id=\"f20b12e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Anticipa las declaraciones de IVA<\/strong> y pres\u00e9ntalas durante las inspecciones.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7e4277 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f7e4277\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9c5021e\" data-id=\"9c5021e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f6db4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c8f6db4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-leaf\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b3c8cb elementor-widget elementor-widget-heading\" data-id=\"0b3c8cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Reducci\u00f3n de la huella de carbono digital<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7a2d44 elementor-widget elementor-widget-text-editor\" data-id=\"e7a2d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Reduce tu huella de carbono<\/strong> con ASD Taxflow: un correo electr\u00f3nico de 1 MB emite 11 g de CO\u2082, hasta 50 g con varios archivos adjuntos, mientras que 1 GB almacenado durante un a\u00f1o en Francia emite 0,24 g.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd516a6\" data-id=\"dd516a6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cd63f1e\" data-id=\"cd63f1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d6ebdba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d6ebdba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c4b2f06\" data-id=\"6c4b2f06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21109c6f elementor-widget elementor-widget-html\" data-id=\"21109c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b6be3b4 elementor-widget elementor-widget-heading\" data-id=\"4b6be3b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 ASD Taxflow?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6626f8dc elementor-widget elementor-widget-text-editor\" data-id=\"6626f8dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Demuestra tu cumplimiento con las exigencias de la administraci\u00f3n<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-736d3db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"736d3db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37c5644d\" data-id=\"37c5644d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2645aa65 elementor-widget elementor-widget-image\" data-id=\"2645aa65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"516\" height=\"516\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/tva-intracommunautaire-illustration-es.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-194684\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/tva-intracommunautaire-illustration-es.png 516w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/tva-intracommunautaire-illustration-es-300x300.png 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/tva-intracommunautaire-illustration-es-150x150.png 150w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48cbdb8f\" data-id=\"48cbdb8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35128f3f elementor-widget elementor-widget-text-editor\" data-id=\"35128f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"223\" data-end=\"605\"><b>Gestionar las declaraciones de IVA en varios pa\u00edses de la Uni\u00f3n Europea es un verdadero quebradero de cabeza<\/b> para muchas empresas. Entre las normativas locales, las obligaciones de facturaci\u00f3n, los plazos a cumplir y los formatos de declaraci\u00f3n espec\u00edficos de cada Estado miembro, <b>el riesgo de error o retraso es significativo<\/b> \u2014 y puede conllevar sanciones financieras considerables.<\/p><br><p data-start=\"607\" data-end=\"1061\">Nuestra soluci\u00f3n de software ha sido dise\u00f1ada para<b> simplificar y securizar esta gesti\u00f3n<\/b>. Permite centralizar, en una interfaz \u00fanica, todas tus declaraciones peri\u00f3dicas de IVA, el seguimiento de los pagos y el historial de intercambios con nuestros operadores encargados de tus declaraciones. <br \/><br \/>Se acabaron las hojas de c\u00e1lculo dispersas, los correos electr\u00f3nicos de recordatorio y las m\u00faltiples plataformas: <b>todo est\u00e1 agrupado, estructurado y accesible en tiempo real<\/b>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fcfbde1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fcfbde1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a97d4b0\" data-id=\"4a97d4b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dc563bd elementor-widget elementor-widget-html\" data-id=\"5dc563bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3776ad97 elementor-widget elementor-widget-html\" data-id=\"3776ad97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cfa3205 elementor-widget elementor-widget-heading\" data-id=\"5cfa3205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 hace ASD Taxflow?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-319ef115 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"319ef115\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c429da3\" data-id=\"4c429da3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-76082cdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76082cdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc852f7\" data-id=\"dc852f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2374a7 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c2374a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Dashboard.png\" class=\"attachment-medium_large size-medium_large wp-image-194493\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Dashboard.png 500w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Dashboard-300x180.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33edf3aa\" data-id=\"33edf3aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57d84020 elementor-widget elementor-widget-heading\" data-id=\"57d84020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Gesti\u00f3n centralizada y digital de todas tus declaraciones de IVA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5defaa elementor-widget elementor-widget-text-editor\" data-id=\"2b5defaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puedes cargar todos los documentos relacionados con cada uno de tus expedientes de IVA (como facturas, notas de cr\u00e9dito, etc.) y recuperarlos en cualquier momento. <strong>Un ahorro de tiempo considerable durante las inspecciones.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46ff4010 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"46ff4010\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-786a2066\" data-id=\"786a2066\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-597f5188 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"597f5188\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2415aceb\" data-id=\"2415aceb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3bbe9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3bbe9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d4259fb\" data-id=\"5d4259fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f16539a elementor-widget elementor-widget-heading\" data-id=\"5f16539a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Exportaci\u00f3n de facturas facilitada para controles o auditor\u00edas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d49a33a elementor-widget elementor-widget-text-editor\" data-id=\"4d49a33a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En caso de control fiscal en un Estado miembro, la administraci\u00f3n puede requerir un <strong>acceso r\u00e1pido a las facturas correspondientes<\/strong>.<br data-start=\"1512\" data-end=\"1515\" \/>ASD Taxflow permite <strong>exportar r\u00e1pidamente las facturas<\/strong> y los justificantes asociados, formateados seg\u00fan las exigencias locales.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20beb478\" data-id=\"20beb478\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6516c7d0 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6516c7d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Invoice.png\" class=\"attachment-medium_large size-medium_large wp-image-194536\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Invoice.png 500w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Invoice-300x180.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f79324 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f79324\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4c3e6311\" data-id=\"4c3e6311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab23895 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab23895\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3edbad77\" data-id=\"3edbad77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b975a2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b975a2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d5ce2d8\" data-id=\"4d5ce2d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ade56c5 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3ade56c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"300\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Declaration.png\" class=\"attachment-medium_large size-medium_large wp-image-194507\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Declaration.png 500w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/06\/ASD-Taxflow-Declaration-300x180.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a20954b\" data-id=\"6a20954b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c44fe8e elementor-widget elementor-widget-heading\" data-id=\"2c44fe8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Vista global optimizada para el seguimiento de cada declaraci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63736275 elementor-widget elementor-widget-text-editor\" data-id=\"63736275\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>ASD Taxflow es una plataforma de intercambio de tus declaraciones de IVA. <\/strong>Todo ello con el objetivo de ofrecerte una visibilidad global que te permita centrarte en lo esencial.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11700290 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"11700290\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7c8440a4\" data-id=\"7c8440a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61b54227 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61b54227\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d5e58f6\" data-id=\"4d5e58f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42e4c70d elementor-widget elementor-widget-html\" data-id=\"42e4c70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba72cb8 elementor-widget elementor-widget-heading\" data-id=\"1ba72cb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son las funcionalidades de ASD Taxflow?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d87a7 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4d87a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gesti\u00f3n, almacenamiento y archivo de los documentos relacionados con cada declaraci\u00f3n (facturas, notas de cr\u00e9dito, etc.)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gesti\u00f3n colaborativa entre distintos operadores<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Panel de control centralizado y f\u00e1cil de usar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Historial de cada expediente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Progreso paso a paso<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Notificaciones para cada expediente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alertas de vigilancia reglamentaria<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Declaraciones detalladas (Pa\u00eds y per\u00edodo de presentaci\u00f3n, periodicidad, etc.)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22c207d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22c207d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b031f73\" data-id=\"4b031f73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-695b89b9 elementor-widget elementor-widget-html\" data-id=\"695b89b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3efaa34c elementor-widget elementor-widget-html\" data-id=\"3efaa34c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764e473b elementor-widget elementor-widget-heading\" data-id=\"764e473b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">contacta con nuestros expertos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49425263 elementor-widget elementor-widget-heading\" data-id=\"49425263\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres saber m\u00e1s sobre ASD Taxflow?<br>Cont\u00e1ctanos a trav\u00e9s del formulario a continuaci\u00f3n y te responderemos lo antes posible.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2610be elementor-widget elementor-widget-shortcode\" data-id=\"4f2610be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=6291427' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_style_asd frm_full_submit\" id=\"frm_form_49_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form-2026\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Contact 2026<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"49\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_49\" id=\"frm_hide_fields_49\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form-2026\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_49\" name=\"frm_submit_entry_49\" value=\"3aead7d492\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/service\/194616\" \/><div id=\"frm_field_696_container\" class=\"frm_form_field  frm12 frm_first formcontact-require frm_html_container form-field\">* Los campos marcados con un asterisco son obligatorios para que podamos procesar su solicitud. Algunos de nuestros servicios no est\u00e1n disponibles en todas las regiones y\/o en todos los sectores.\n<\/div>\n<div id=\"frm_field_635_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">1<\/span><span class=\"subtitle-title\">Tu empresa<\/span><\/div>\n<div id=\"frm_field_616_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_i41ef2\" class=\"frm_primary_label\">\u00bfCu\u00e1l es el nombre de tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef2\" name=\"item_meta[616]\" value=\"\"  placeholder=\"Nombre de tu empresa\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_759_container\" class=\"frm_form_field frm_section_heading form-field  section-hidden frm_hide_section\">\r\n\r\n\r\n\r\n<div id=\"frm_field_622_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order0 sort-alphabetically\">\r\n    <label for=\"field_okuhn3\" class=\"frm_primary_label\">\u00bfEn qu\u00e9 pa\u00eds est\u00e1 establecida tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[622]\" id=\"field_okuhn3\"  data-sectionid=\"759\"  data-placeholder=\"Elige el pa\u00eds donde deseas establecerte\"  placeholder=\"Elige el pa\u00eds donde deseas establecerte\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfEn qu\u00e9 pa\u00eds est\u00e1 establecida tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el pa\u00eds donde deseas establecerte<\/option><option  value=\"DE\">Alemania<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AR\">Argentina<\/option><option  value=\"AT\">Austria<\/option><option  value=\"BR\">Brasil<\/option><option  value=\"BG\">Bulgaria<\/option><option  value=\"BE\">B\u00e9lgica<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CZ\">Chequia<\/option><option  value=\"CY\">Chipre<\/option><option  value=\"HR\">Croacia<\/option><option  value=\"DK\">Dinamarca<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"ES\">Espa\u00f1a<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Estonia<\/option><option  value=\"FI\">Finlandia<\/option><option  value=\"FR\">Francia<\/option><option  value=\"GR\">Grecia<\/option><option  value=\"HU\">Hungr\u00eda<\/option><option  value=\"IE\">Irlanda<\/option><option  value=\"IS\">Islandia<\/option><option  value=\"IT\">Italia<\/option><option  value=\"LV\">Letonia<\/option><option  value=\"LI\">Liechtenstein<\/option><option  value=\"LT\">Lituania<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"MD\">Moldavia<\/option><option  value=\"MX\">M\u00e9xico<\/option><option  value=\"MC\">M\u00f3naco<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"NL\">Pa\u00edses Bajos<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"RS\">Serbia<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option><option  value=\"TR\">Turqu\u00eda<\/option><option  value=\"UA\">Ucrania<\/option><option  value=\"Other\">Otro pa\u00eds (por favor especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_617_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 order2 sort-alphabetically\">\r\n    <label for=\"field_85w6d2\" class=\"frm_primary_label\">\u00bfCu\u00e1l es el sector de actividad de tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[617]\" id=\"field_85w6d2\"  data-sectionid=\"759\"  data-placeholder=\"Elige tu sector de actividad\"  placeholder=\"Elige tu sector de actividad\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es el sector de actividad de tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige tu sector de actividad<\/option><option  value=\"Agriculture\">Agricultura\n<\/option><option  value=\"Agroalimentaire\">Agroalimentario<\/option><option  value=\"Automobile\">Autom\u00f3vil\n<\/option><option  value=\"Banque et assurances\">Banca y seguros\n<\/option><option  value=\"Commerce\">Comercio\n<\/option><option  value=\"B\u00e2timent et travaux publics (BTP)\">Construcci\u00f3n y obras p\u00fablicas\n<\/option><option  value=\"Conseil et services aux entreprises\">Consultor\u00eda y servicios para empresas<\/option><option  value=\"Culture et loisirs\">Cultura y ocio<\/option><option  value=\"Sport et \u00e9v\u00e9nements\">Deporte y eventos<\/option><option  value=\"Distribution\">Distribuci\u00f3n<\/option><option  value=\"\u00c9ducation et formation\">Educaci\u00f3n y formaci\u00f3n<\/option><option  value=\"\u00c9nergie\">Energ\u00eda<\/option><option  value=\"H\u00f4tellerie et restauration\">Hosteler\u00eda y restauraci\u00f3n<\/option><option  value=\"Industrie manufacturi\u00e8re\">Industria manufacturera<\/option><option  value=\"Informatique et num\u00e9rique\">Inform\u00e1tica y tecnolog\u00eda digital<\/option><option  value=\"Immobilier\">Inmobiliario<\/option><option  value=\"Recherche et d\u00e9veloppement\">Investigaci\u00f3n y desarrollo<\/option><option  value=\"Logistique et transport\">Log\u00edstica y transporte<\/option><option  value=\"Luxe et mode\">Lujo y moda<\/option><option  value=\"M\u00e9dias et communication\">Medios y comunicaci\u00f3n<\/option><option  value=\"M\u00e9tallurgie et sid\u00e9rurgie\">Metalurgia y siderurgia<\/option><option  value=\"Chimie et pharmacie\">Qu\u00edmica y farmacia\n<\/option><option  value=\"Sant\u00e9 et bien-\u00eatre\">Salud y bienestar<\/option><option  value=\"S\u00e9curit\u00e9 et d\u00e9fense\">Seguridad y defensa<\/option><option  value=\"Services publics et administration\">Servicios p\u00fablicos y administraci\u00f3n<\/option><option  value=\"T\u00e9l\u00e9communications\">Telecomunicaciones<\/option><option  value=\"Textile et habillement\">Textiles y ropa<\/option><option  value=\"Tourisme\">Turismo<\/option><option  value=\"Other\">Otro sector (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_639_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order1\">\r\n\t<label for=\"field_6q8fw\" id=\"field_6q8fw_label\" class=\"frm_primary_label\">Has elegido \"Otro pa\u00eds\", \u00bfpuedes especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_6q8fw\" name=\"item_meta[639]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Completa el pa\u00eds de establecimiento\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Has elegido &quot;Otro pa\u00eds&quot;, \u00bfpuedes especificar? no es v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_640_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_alignright order3\">\r\n\t<label for=\"field_8yduw\" id=\"field_8yduw_label\" class=\"frm_primary_label\">Elegiste \"Otro sector\", \u00bfpod\u00e9s especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_8yduw\" name=\"item_meta[640]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Completa el sector de actividad\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Elegiste &quot;Otro sector&quot;, \u00bfpod\u00e9s especificar? no es v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<\/div>\n<div id=\"frm_field_637_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">2<\/span><span class=\"subtitle-title\">Tus necesidades<\/span><\/div>\n<div id=\"frm_field_623_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 relative frm_first sort-alphabetically\">\r\n    <label for=\"field_l1biv3\" class=\"frm_primary_label\">\u00bfEn qu\u00e9 pa\u00eds deseas desarrollar tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[623]\" id=\"field_l1biv3\"  data-placeholder=\"Elige el pa\u00eds donde deseas expandirte (paso 1\/4)\"  placeholder=\"Elige el pa\u00eds donde deseas expandirte (paso 1\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfEn qu\u00e9 pa\u00eds deseas desarrollar tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el pa\u00eds donde deseas expandirte (paso 1\/4)<\/option><option  value=\"DE\">Alemania<\/option><option  value=\"AT\">Austria\n<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CZ\">Chequia<\/option><option  value=\"CY\">Chipre\n<\/option><option  value=\"HR\">Croacia\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"ES\">Espa\u00f1a\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"HU\">Hungr\u00eda\n<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"LV\">Letonia\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"NL\">Pa\u00edses Bajos<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_681_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nqwnw\" id=\"field_nqwnw_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Espa\u00f1a?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[681]\" id=\"field_nqwnw\"  data-placeholder=\"Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Espa\u00f1a? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_647_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_31i7k\" id=\"field_31i7k_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Alemania?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[647]\" id=\"field_31i7k\"  data-placeholder=\"Elige el \u00e1rea de servicio en Alemania (paso 2\/4)\"  placeholder=\"Elige el \u00e1rea de servicio en Alemania (paso 2\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Alemania? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Alemania (paso 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_648_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n\t<label for=\"field_2p88l\" id=\"field_2p88l_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Austria?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[648]\" id=\"field_2p88l\"  data-placeholder=\"Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Austria? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_649_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_9i5uq\" id=\"field_9i5uq_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para B\u00e9lgica?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[649]\" id=\"field_9i5uq\"  data-placeholder=\"Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para B\u00e9lgica?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_677_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3n29\" id=\"field_v3n29_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Bulgaria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[677]\" id=\"field_v3n29\"  data-placeholder=\"Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Bulgaria?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_651_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7frx6\" id=\"field_7frx6_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Canad\u00e1?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[651]\" id=\"field_7frx6\"  data-placeholder=\"Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Canad\u00e1? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_676_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xhngf\" id=\"field_xhngf_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Chipre?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[676]\" id=\"field_xhngf\"  data-placeholder=\"Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Chipre?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_675_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_iyrkx\" id=\"field_iyrkx_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Croacia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[675]\" id=\"field_iyrkx\"  data-placeholder=\"Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Croacia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_674_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hh8ys\" id=\"field_hh8ys_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Dinamarca?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[674]\" id=\"field_hh8ys\"  data-placeholder=\"Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Dinamarca?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_673_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xk6v1\" id=\"field_xk6v1_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Estonia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[673]\" id=\"field_xk6v1\"  data-placeholder=\"Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Estonia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_650_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7127q\" id=\"field_7127q_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para los Estados Unidos?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[650]\" id=\"field_7127q\"  data-placeholder=\"Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para los Estados Unidos? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n<\/option><option  value=\"Fiscal : Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_672_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hrplp\" id=\"field_hrplp_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Finlandia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[672]\" id=\"field_hrplp\"  data-placeholder=\"Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Finlandia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_671_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jw8ml\" id=\"field_jw8ml_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Francia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[671]\" id=\"field_jw8ml\"  data-placeholder=\"Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Francia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_670_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_3gqvi\" id=\"field_3gqvi_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Grecia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[670]\" id=\"field_3gqvi\"  data-placeholder=\"Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Grecia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_669_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ajvsb\" id=\"field_ajvsb_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Hungr\u00eda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[669]\" id=\"field_ajvsb\"  data-placeholder=\"Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Hungr\u00eda?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_668_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r1kza\" id=\"field_r1kza_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Irlanda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[668]\" id=\"field_r1kza\"  data-placeholder=\"Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Irlanda?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_667_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_qo5nf\" id=\"field_qo5nf_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Italia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[667]\" id=\"field_qo5nf\"  data-placeholder=\"Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Italia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_666_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z3dfa\" id=\"field_z3dfa_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Letonia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[666]\" id=\"field_z3dfa\"  data-placeholder=\"Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Letonia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_665_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mm4zs\" id=\"field_mm4zs_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Lituania?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[665]\" id=\"field_mm4zs\"  data-placeholder=\"Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Lituania?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_664_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_kel0x\" id=\"field_kel0x_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Luxemburgo?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[664]\" id=\"field_kel0x\"  data-placeholder=\"Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Luxemburgo?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_663_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dcpyc\" id=\"field_dcpyc_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Malta?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[663]\" id=\"field_dcpyc\"  data-placeholder=\"Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Malta?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_662_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zz48j\" id=\"field_zz48j_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para los Pa\u00edses Bajos?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[662]\" id=\"field_zz48j\"  data-placeholder=\"Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para los Pa\u00edses Bajos?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_661_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ji2cs\" id=\"field_ji2cs_label\" class=\"frm_primary_label\">Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[661]\" id=\"field_ji2cs\"  data-placeholder=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_659_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aepqm\" id=\"field_aepqm_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Portugal?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[659]\" id=\"field_aepqm\"  data-placeholder=\"Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Portugal? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_658_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_d1twg\" id=\"field_d1twg_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Chequia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[658]\" id=\"field_d1twg\"  data-placeholder=\"Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Chequia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_657_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3096\" id=\"field_v3096_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Ruman\u00eda?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[657]\" id=\"field_v3096\"  data-placeholder=\"Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Ruman\u00eda? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_656_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hlo6e\" id=\"field_hlo6e_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para el Reino Unido?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[656]\" id=\"field_hlo6e\"  data-placeholder=\"Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para el Reino Unido? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_655_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_azerr\" id=\"field_azerr_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Eslovaquia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[655]\" id=\"field_azerr\"  data-placeholder=\"Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Eslovaquia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_654_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vtjje\" id=\"field_vtjje_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Eslovenia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[654]\" id=\"field_vtjje\"  data-placeholder=\"Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Eslovenia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_653_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_e1wi2\" id=\"field_e1wi2_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Suecia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[653]\" id=\"field_e1wi2\"  data-placeholder=\"Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Suecia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_652_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mf65v\" id=\"field_mf65v_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Suiza?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[652]\" id=\"field_mf65v\"  data-placeholder=\"Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Suiza? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_678_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_19pbf\" id=\"field_19pbf_label\" class=\"frm_primary_label\">[Alemania] Fiscal: IVA, Impuestos, Formalidades & Obligacione\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[678]\" id=\"field_19pbf\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Fiscal: IVA, Impuestos, Formalidades &amp; Obligacione no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/ZM\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ ZM \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_679_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gz1w7\" id=\"field_gz1w7_label\" class=\"frm_primary_label\">[Alemania] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[679]\" id=\"field_gz1w7\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_798_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dego5\" id=\"field_dego5_label\" class=\"frm_primary_label\">[Alemania] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[798]\" id=\"field_dego5\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_682_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eeeq6\" id=\"field_eeeq6_label\" class=\"frm_primary_label\">[Austria] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[682]\" id=\"field_eeeq6\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_683_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r8c1d\" id=\"field_r8c1d_label\" class=\"frm_primary_label\">[Austria] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[683]\" id=\"field_r8c1d\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_799_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_95ick\" id=\"field_95ick_label\" class=\"frm_primary_label\">[Austria] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[799]\" id=\"field_95ick\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_684_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aw4s9\" id=\"field_aw4s9_label\" class=\"frm_primary_label\">[B\u00e9lgica] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[684]\" id=\"field_aw4s9\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_685_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8oi4a\" id=\"field_8oi4a_label\" class=\"frm_primary_label\">[B\u00e9lgica] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[685]\" id=\"field_8oi4a\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_686_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hnplb\" id=\"field_hnplb_label\" class=\"frm_primary_label\">[B\u00e9lgica] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[686]\" id=\"field_hnplb\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_687_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dsbn4\" id=\"field_dsbn4_label\" class=\"frm_primary_label\">[Bulgaria] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[687]\" id=\"field_dsbn4\"  data-placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\"  placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Bulgaria] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Bulgaria (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_800_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gbi4d\" id=\"field_gbi4d_label\" class=\"frm_primary_label\">[Bulgaria] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[800]\" id=\"field_gbi4d\"  data-placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\"  placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Bulgaria] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Bulgaria (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_689_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_a9qen\" id=\"field_a9qen_label\" class=\"frm_primary_label\">[Canad\u00e1] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[689]\" id=\"field_a9qen\"  data-placeholder=\"Elija el servicio en Canad\u00e1 (paso 3\/4)\"  placeholder=\"Elija el servicio en Canad\u00e1 (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Canad\u00e1] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Canad\u00e1 (paso 3\/4)<\/option><option  value=\"Gestion des taxes TPS\/TVH\/TVP\">Gesti\u00f3n de los impuestos GST\/HST\/PST<\/option><option  value=\"Gestion de la certification employeur non-r\u00e9sident\">Gesti\u00f3n de la certificaci\u00f3n de empleadores no residentes<\/option><option  value=\"Gestion de la dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents\">Gesti\u00f3n de la exenci\u00f3n de retenci\u00f3n de impuestos para empleadores no residentes<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_646_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8yjzs\" id=\"field_8yjzs_label\" class=\"frm_primary_label\">[Espa\u00f1a] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[646]\" id=\"field_8yjzs\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Gestion de la taxe sur les emballages plastiques non r\u00e9utilisables\">Gesti\u00f3n del impuesto sobre envases de pl\u00e1stico no reutilizables<\/option><option  value=\"Gestion de la taxe sur les pneus usag\u00e9s\">Gesti\u00f3n del impuesto sobre neum\u00e1ticos usados<\/option><option  value=\"Gestion de l&#039;Eco Tax DEEE (WEEE)\">Gesti\u00f3n del Eco-Impuesto DEEE (WEEE)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_641_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_whqtx\" id=\"field_whqtx_label\" class=\"frm_primary_label\">[Espa\u00f1a] Aduanas: Operaciones, Tr\u00e1mites y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[641]\" id=\"field_whqtx\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Aduanas: Operaciones, Tr\u00e1mites y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_643_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_upzx7\" id=\"field_upzx7_label\" class=\"frm_primary_label\">[Espa\u00f1a] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[643]\" id=\"field_upzx7\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_691_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5vbnj\" id=\"field_5vbnj_label\" class=\"frm_primary_label\">[Francia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[691]\" id=\"field_5vbnj\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale immobili\u00e8re\">Representaci\u00f3n fiscal inmobiliaria<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_692_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y17z7\" id=\"field_y17z7_label\" class=\"frm_primary_label\">[Francia] Aduanas: Operaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[692]\" id=\"field_y17z7\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Aduanas: Operaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations EMEBI (ERTVA\u2026)\/DES\">Gesti\u00f3n de las declaraciones EMEBI (ERTVA\u2026)\/DES<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gesti\u00f3n de las operaciones aduaneras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires et SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de RTC et RCO\">Acompa\u00f1amiento para la obtenci\u00f3n de IAV y IVO<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de la certification OEA\">Acompa\u00f1amiento para la obtenci\u00f3n de la certificaci\u00f3n OEA<\/option><option  value=\"Gestion des DDR selon le RDUE\">Gesti\u00f3n de los DDD seg\u00fan EUDR<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas<\/option><option  value=\"Gestion de la taxe carbone (CBAM\/MACF)\">Gesti\u00f3n del impuesto al carbono (CBAM)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_693_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q9gx\" id=\"field_q9gx_label\" class=\"frm_primary_label\">[Francia] Social: Regulaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[693]\" id=\"field_q9gx\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Social: Regulaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion des missions de d\u00e9tachement de salari\u00e9s \u00e9trangers en France (ASD SPW)\">Gesti\u00f3n de las misiones de destacamento de empleados extranjeros en Francia (ASD SPW)<\/option><option  value=\"Gestion de la repr\u00e9sentation fiscale dans le cadre du pr\u00e9l\u00e8vement \u00e0 la source\">Gesti\u00f3n de la representaci\u00f3n fiscal en el marco de la retenci\u00f3n en la fuente<\/option><option  value=\"Gestion de repr\u00e9sentation de firme \u00e9trang\u00e8re\">Gesti\u00f3n de la representaci\u00f3n de una empresa extranjera<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_694_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5kh5i\" id=\"field_5kh5i_label\" class=\"frm_primary_label\">[Francia] Estrategia: Desarrollo de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[694]\" id=\"field_5kh5i\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Estrategia: Desarrollo de empresas no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Gestion de la domiciliation d&#039;entreprise\">Gesti\u00f3n de la domiciliaci\u00f3n de la empresa<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_698_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jlotu\" id=\"field_jlotu_label\" class=\"frm_primary_label\">[Estados Unidos] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[698]\" id=\"field_jlotu\"  data-placeholder=\"Elige el servicio en Estados Unidos (paso 3\/4)\"  placeholder=\"Elige el servicio en Estados Unidos (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estados Unidos] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estados Unidos (paso 3\/4)<\/option><option  value=\"Gestion de la &quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Gesti\u00f3n del &quot;Sales and Use Tax&quot; en Estados Unidos<\/option><option  value=\"Gestion des formulaires W-8 et W-9 aux \u00c9tats-Unis\">Gesti\u00f3n de los formularios W-8 y W-9 en Estados Unidos<\/option><option  value=\"Gestion des formalit\u00e9s li\u00e9es au Nexus aux \u00c9tats-Unis\">Gesti\u00f3n de las formalidades relacionadas con el Nexus en Estados Unidos<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_699_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_44svk\" id=\"field_44svk_label\" class=\"frm_primary_label\">[Italia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[699]\" id=\"field_44svk\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du Visto di Conformit\u00e0\">Gesti\u00f3n del Visto di Conformit\u00e0<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_700_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ys0xm\" id=\"field_ys0xm_label\" class=\"frm_primary_label\">[Italia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[700]\" id=\"field_ys0xm\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_701_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1anf4\" id=\"field_1anf4_label\" class=\"frm_primary_label\">[Italia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[701]\" id=\"field_1anf4\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_702_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zq0ua\" id=\"field_zq0ua_label\" class=\"frm_primary_label\">[Chipre] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[702]\" id=\"field_zq0ua\"  data-placeholder=\"Elige el servicio en Chipre (paso 3\/4)\"  placeholder=\"Elige el servicio en Chipre (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chipre] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Chipre (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_801_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q3a1e\" id=\"field_q3a1e_label\" class=\"frm_primary_label\">[Chipre] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[801]\" id=\"field_q3a1e\"  data-placeholder=\"Elige el servicio en Chipre (paso 3\/4)\"  placeholder=\"Elige el servicio en Chipre (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chipre] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Chipre (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_704_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_s06v4\" id=\"field_s06v4_label\" class=\"frm_primary_label\">[Croacia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[704]\" id=\"field_s06v4\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_705_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vjfrb\" id=\"field_vjfrb_label\" class=\"frm_primary_label\">[Croacia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[705]\" id=\"field_vjfrb\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_802_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xna4z\" id=\"field_xna4z_label\" class=\"frm_primary_label\">[Croacia] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[802]\" id=\"field_xna4z\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_706_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2i1vf\" id=\"field_2i1vf_label\" class=\"frm_primary_label\">[Dinamarca] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[706]\" id=\"field_2i1vf\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List \/ EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_707_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_g3d2w\" id=\"field_g3d2w_label\" class=\"frm_primary_label\">[Dinamarca] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[707]\" id=\"field_g3d2w\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_803_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1df4u\" id=\"field_1df4u_label\" class=\"frm_primary_label\">[Dinamarca] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[803]\" id=\"field_1df4u\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_708_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_cs0h5\" id=\"field_cs0h5_label\" class=\"frm_primary_label\">[Estonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[708]\" id=\"field_cs0h5\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_709_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2ahrq\" id=\"field_2ahrq_label\" class=\"frm_primary_label\">[Estonia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[709]\" id=\"field_2ahrq\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_804_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_urojq\" id=\"field_urojq_label\" class=\"frm_primary_label\">[Estonia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[804]\" id=\"field_urojq\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_710_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jz0iw\" id=\"field_jz0iw_label\" class=\"frm_primary_label\">[Finlandia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[710]\" id=\"field_jz0iw\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_711_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z5cpa\" id=\"field_z5cpa_label\" class=\"frm_primary_label\">[Finlandia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[711]\" id=\"field_z5cpa\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_805_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oyx7h\" id=\"field_oyx7h_label\" class=\"frm_primary_label\">[Finlandia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[805]\" id=\"field_oyx7h\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_712_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6jrxn\" id=\"field_6jrxn_label\" class=\"frm_primary_label\">[Grecia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[712]\" id=\"field_6jrxn\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_713_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rgel6\" id=\"field_rgel6_label\" class=\"frm_primary_label\">[Grecia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[713]\" id=\"field_rgel6\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_806_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6ls28\" id=\"field_6ls28_label\" class=\"frm_primary_label\">[Grecia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[806]\" id=\"field_6ls28\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_714_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_w6w9o\" id=\"field_w6w9o_label\" class=\"frm_primary_label\">[Hungr\u00eda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[714]\" id=\"field_w6w9o\"  data-placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Hungr\u00eda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Hungr\u00eda (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_807_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jxc2i\" id=\"field_jxc2i_label\" class=\"frm_primary_label\">[Hungr\u00eda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[807]\" id=\"field_jxc2i\"  data-placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Hungr\u00eda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Hungr\u00eda (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_716_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lhn0a\" id=\"field_lhn0a_label\" class=\"frm_primary_label\">[Irlanda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[716]\" id=\"field_lhn0a\"  data-placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Irlanda (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_808_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hpoqk\" id=\"field_hpoqk_label\" class=\"frm_primary_label\">[Irlanda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[808]\" id=\"field_hpoqk\"  data-placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Irlanda (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_718_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eh4ic\" id=\"field_eh4ic_label\" class=\"frm_primary_label\">[Letonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[718]\" id=\"field_eh4ic\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_719_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4t4b4\" id=\"field_4t4b4_label\" class=\"frm_primary_label\">[Letonia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[719]\" id=\"field_4t4b4\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_809_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_btj00\" id=\"field_btj00_label\" class=\"frm_primary_label\">[Letonia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[809]\" id=\"field_btj00\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_720_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_62mpm\" id=\"field_62mpm_label\" class=\"frm_primary_label\">[Lituania] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[720]\" id=\"field_62mpm\"  data-placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Lituania (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_721_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_fqvcn\" id=\"field_fqvcn_label\" class=\"frm_primary_label\">[Lituania] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[721]\" id=\"field_fqvcn\"  data-placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Lituania (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_810_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_tahxc\" id=\"field_tahxc_label\" class=\"frm_primary_label\">[Lituania] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[810]\" id=\"field_tahxc\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_722_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6asdz\" id=\"field_6asdz_label\" class=\"frm_primary_label\">[Luxemburgo] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[722]\" id=\"field_6asdz\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_723_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_uv0bx\" id=\"field_uv0bx_label\" class=\"frm_primary_label\">[Luxemburgo] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[723]\" id=\"field_uv0bx\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_811_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q5m9h\" id=\"field_q5m9h_label\" class=\"frm_primary_label\">[Luxemburgo] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[811]\" id=\"field_q5m9h\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_725_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_de7m1\" id=\"field_de7m1_label\" class=\"frm_primary_label\">[Malta] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[725]\" id=\"field_de7m1\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_726_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_n2ufm\" id=\"field_n2ufm_label\" class=\"frm_primary_label\">[Malta] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[726]\" id=\"field_n2ufm\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Gestion des d\u00e9clarations europ\u00e9ennes de services (DES)\">Gesti\u00f3n de las declaraciones europeas de servicios (DES)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_813_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_l10m9\" id=\"field_l10m9_label\" class=\"frm_primary_label\">[Malta] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[813]\" id=\"field_l10m9\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_727_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2af4r\" id=\"field_2af4r_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[727]\" id=\"field_2af4r\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_728_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_za0r\" id=\"field_za0r_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[728]\" id=\"field_za0r\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_814_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_i16up\" id=\"field_i16up_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[814]\" id=\"field_i16up\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_729_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_h5qk6\" id=\"field_h5qk6_label\" class=\"frm_primary_label\">[Polonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[729]\" id=\"field_h5qk6\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_730_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_42afs\" id=\"field_42afs_label\" class=\"frm_primary_label\">[Polonia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[730]\" id=\"field_42afs\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_731_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rd7rn\" id=\"field_rd7rn_label\" class=\"frm_primary_label\">[Polonia] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[731]\" id=\"field_rd7rn\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_733_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6wlea\" id=\"field_6wlea_label\" class=\"frm_primary_label\">[Portugal] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[733]\" id=\"field_6wlea\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Facturation \u00e9lectronique et\/ou e-reporting\">Facturaci\u00f3n electr\u00f3nica y\/o e-reporting<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_734_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_u9472\" id=\"field_u9472_label\" class=\"frm_primary_label\">[Portugal] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[734]\" id=\"field_u9472\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gesti\u00f3n de las operaciones aduaneras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires,SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accises pour la vente \u00e0 distance de boissons alcooliques au Portugal\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas en Portugal<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_815_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rlp4g\" id=\"field_rlp4g_label\" class=\"frm_primary_label\">[Portugal] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[815]\" id=\"field_rlp4g\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Accompagnement certification logiciel facturation \u00e9lectronique\">Acompa\u00f1amiento en la certificaci\u00f3n del software de facturaci\u00f3n electr\u00f3nica<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_735_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5hg1m\" id=\"field_5hg1m_label\" class=\"frm_primary_label\">[Chequia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[735]\" id=\"field_5hg1m\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chequia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_736_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_t8kbm\" id=\"field_t8kbm_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[736]\" id=\"field_t8kbm\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_816_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oawcf\" id=\"field_oawcf_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[816]\" id=\"field_oawcf\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_739_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4y9dt\" id=\"field_4y9dt_label\" class=\"frm_primary_label\">[Ruman\u00eda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[739]\" id=\"field_4y9dt\"  data-placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\"  placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Ruman\u00eda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Ruman\u00eda (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_817_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_69ksn\" id=\"field_69ksn_label\" class=\"frm_primary_label\">[Ruman\u00eda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[817]\" id=\"field_69ksn\"  data-placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\"  placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Ruman\u00eda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Ruman\u00eda (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_741_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ownk6\" id=\"field_ownk6_label\" class=\"frm_primary_label\">[Reino Unido] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[741]\" id=\"field_ownk6\"  data-placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\"  placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en el Reino Unido (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_742_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ioidj\" id=\"field_ioidj_label\" class=\"frm_primary_label\">[Reino Unido] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[742]\" id=\"field_ioidj\"  data-placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\"  placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en el Reino Unido (paso 3\/4)<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res et d\u00e9douanements\">Gesti\u00f3n de operaciones aduaneras y despacho de aduanas<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires, SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_743_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v16pe\" id=\"field_v16pe_label\" class=\"frm_primary_label\">[Eslovaquia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[743]\" id=\"field_v16pe\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_744_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_idpgs\" id=\"field_idpgs_label\" class=\"frm_primary_label\">[Eslovaquia] Aduanas: Operaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[744]\" id=\"field_idpgs\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Aduanas: Operaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_818_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nueuk\" id=\"field_nueuk_label\" class=\"frm_primary_label\">[Eslovaquia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[818]\" id=\"field_nueuk\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_745_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_11566a\" id=\"field_11566a_label\" class=\"frm_primary_label\">[Eslovenia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[745]\" id=\"field_11566a\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_747_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lwwyc\" id=\"field_lwwyc_label\" class=\"frm_primary_label\">[Eslovenia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[747]\" id=\"field_lwwyc\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_819_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z7hx0\" id=\"field_z7hx0_label\" class=\"frm_primary_label\">[Eslovenia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[819]\" id=\"field_z7hx0\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_748_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_shkof\" id=\"field_shkof_label\" class=\"frm_primary_label\">[Suecia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[748]\" id=\"field_shkof\"  data-placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suecia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suecia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_820_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hgxin\" id=\"field_hgxin_label\" class=\"frm_primary_label\">[Suecia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[820]\" id=\"field_hgxin\"  data-placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suecia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suecia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_750_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y6l2p\" id=\"field_y6l2p_label\" class=\"frm_primary_label\">[Suiza] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[750]\" id=\"field_y6l2p\"  data-placeholder=\"Elige el servicio en Suiza (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suiza (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suiza] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suiza (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Remboursement TVA (13e)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_626_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_bz8k12\" class=\"frm_primary_label\">Explica brevemente tu necesidad\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[626]\" id=\"field_bz8k12\" rows=\"5\"  placeholder=\"Ej.: Nuestra empresa desea recuperar el IVA en Alemania... (paso 4\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Explica brevemente tu necesidad&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_638_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">3<\/span><span class=\"subtitle-title\">Tus datos de contacto<\/span><\/div>\n<div id=\"frm_field_619_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_ocfup142\" class=\"frm_primary_label\">Nombre\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup142\" name=\"item_meta[619]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Nombre&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_618_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n    <label for=\"field_qh4icy42\" class=\"frm_primary_label\">Apellido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy42\" name=\"item_meta[618]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Apellido&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_620_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc3\" class=\"frm_primary_label\">Direcci\u00f3n de correo electr\u00f3nico\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc3\" name=\"item_meta[620]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_621_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa4\" class=\"frm_primary_label\">Tel\u00e9fono\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa4\" name=\"item_meta[621]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"El tel\u00e9fono no es v\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_628_container\" class=\"frm_form_field form-field  frm_none_container checkbox formcontact-newsletter vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Bolet\u00edn\n\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_628-0\">\t\t\t<label  for=\"field_e2sgs2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[628][]\" id=\"field_e2sgs2-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Bolet\u00edn\n no es v\u00e1lido\"   \/> Me gustar\u00eda recibir los boletines de noticias de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_629_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox formcontact-rgpd vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_629-0\">\t\t\t<label  for=\"field_y30e3-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[629][]\" id=\"field_y30e3-0\" value=\"J&#039;accepte que mes donn\u00e9es soient utilis\u00e9es pour traiter ma demande, conform\u00e9ment \u00e0 la &lt;a href=&quot;https:\/\/www.asd-int.com\/confidentialite-et-donnees-personnelles\/&quot; target=&quot;_blank&quot; rel=&quot;noopener noreferrer&quot;&gt;politique de confidentialit\u00e9.&lt;\/a&gt;\"  data-reqmsg=\"Este campo no puede estar vac\u00edo.\n\" data-invmsg=\"RGPD no es v\u00e1lido\"   aria-required=\"true\"  \/> Acepto que mis datos sean utilizados para tramitar tu solicitud, de conformidad con la <a href=\"https:\/\/www.asd-int.com\/confidentialite-et-donnees-personnelles\/\" target=\"_blank\" rel=\"noopener noreferrer\">pol\u00edtica de privacidad.<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_630_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\" \/><\/div>\n<div id=\"frm_field_631_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t2_label\" class=\"frm_primary_label\">CAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t2\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[632]\" id=\"field_8qg9b2\" value=\"\"     \/>\n\t\t<div id=\"frm_field_627_container\" class=\"frm_form_field  formcontact-recaptcha frm_html_container form-field\">Este sitio est\u00e1 protegido por reCAPTCHA.<\/div>\n<div id=\"frm_field_633_container\" class=\"frm_form_field form-field  frm12 frm_first\">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">ENVIAR MI SOLICITUD<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_936_container\">\n\t\t\t<label for=\"field_xr8p3\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_xr8p3\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[936]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvgxGRShcMECHi48UXJ+NmvqqJthN5gOvn1wK4uhECoulZ\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>INICIO > MYASD > FISCAL > ASD TAXFLOW Simplifica tus declaraciones de IVA y mant\u00e9n un control total sobre tu cumplimiento CENTRALIZA, SECURIZA Y DOMINA&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_angie_page":false,"_eb_attr":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"pays":[],"activites":[],"type_service":[],"class_list":["post-194616","service","type-service","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group<\/title>\n<meta name=\"description\" content=\"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/es\/asd-taxflow\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/es\/asd-taxflow\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T07:24:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/\",\"name\":\"ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png\",\"datePublished\":\"2025-06-04T13:00:57+00:00\",\"dateModified\":\"2026-04-29T07:24:42+00:00\",\"description\":\"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/asd-taxflow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"asd taxflow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique su desarrollo internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group","description":"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/","og_locale":"es_ES","og_type":"article","og_title":"ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group","og_description":"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.","og_url":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/","og_site_name":"ASD","article_modified_time":"2026-04-29T07:24:42+00:00","og_image":[{"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/","url":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/","name":"ASD Taxflow: Simplifica tus declaraciones de IVA | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png","datePublished":"2025-06-04T13:00:57+00:00","dateModified":"2026-04-29T07:24:42+00:00","description":"Gestiona tus declaraciones de IVA f\u00e1cilmente con ASD Taxflow. Soluci\u00f3n centralizada para cumplir normativas y ahorrar tiempo en auditor\u00edas.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/es\/asd-taxflow\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/asd-taxflow-logo-blanc-transparent-r4vidfepg2iom85jjmt660alu0s6rc7aua97a7qypi.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/es\/asd-taxflow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/es\/"},{"@type":"ListItem","position":2,"name":"asd taxflow"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/es\/#website","url":"https:\/\/www.asd-int.com\/es\/","name":"ASD","description":"Simplifique su desarrollo internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/es\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/194616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":9,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/194616\/revisions"}],"predecessor-version":[{"id":211622,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/194616\/revisions\/211622"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/media?parent=194616"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/pays?post=194616"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/activites?post=194616"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/type_service?post=194616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}