{"id":203310,"date":"2026-01-30T09:05:38","date_gmt":"2026-01-30T08:05:38","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=service&#038;p=203310"},"modified":"2026-04-30T13:04:47","modified_gmt":"2026-04-30T11:04:47","slug":"gestion-de-formalidades-y-despachos-aduaneros","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/","title":{"rendered":"Conf\u00eda en expertos para gestionar tus tr\u00e1mites aduaneros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"203310\" class=\"elementor elementor-203310 elementor-203088\" data-elementor-post-type=\"service\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9f14e e-con-full hero-template-services e-flex e-con e-parent\" data-id=\"5b9f14e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t<div class=\"elementor-element elementor-element-9392d90 e-con-full e-flex e-con e-child\" data-id=\"9392d90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99098c8 elementor-widget elementor-widget-text-editor\" data-id=\"99098c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><a href=\"\/\">INICIO<\/a> &gt; <a href=\"\/tous-nos-services\/\">NUESTROS SERVICIOS<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/es\/servicios-aduana\/\">OPERACIONES Y OBLIGACIONES ADUANERAS<\/a> &gt; TR\u00c1MITES Y DESPACHOS ADUANEROS<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9785cc e-con-full e-flex e-con e-child\" data-id=\"e9785cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d4e97f e-con-full e-flex e-con e-child\" data-id=\"3d4e97f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80da5d2 elementor-widget elementor-widget-heading\" data-id=\"80da5d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conf\u00eda en expertos para la gesti\u00f3n de tus tr\u00e1mites aduaneros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b7fa2 elementor-widget elementor-widget-text-editor\" data-id=\"a8b7fa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>TR\u00c1MITES ADUANEROS POST-BREXIT: FACILITA EL PASO DE TUS MERCANC\u00cdAS ENTRE REINO UNIDO, FRANCIA Y LA UNI\u00d3N EUROPEA.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ac42ee e-con-full e-flex e-con e-child\" data-id=\"5ac42ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1259e3c elementor-tablet-align-justify elementor-widget elementor-widget-button\" data-id=\"1259e3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/servicios-aduana\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nuestras soluciones aduaneras<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55f40e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a55f40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de001ba e-flex e-con-boxed e-con e-parent\" data-id=\"de001ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b30a638 elementor-widget elementor-widget-menu-anchor\" data-id=\"b30a638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"aduanas\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbfd1cc menu-template-services service-douane e-transform e-transform e-transform e-transform e-flex e-con-boxed e-con e-parent\" data-id=\"fbfd1cc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:134,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70dc3e8 menu-services-liste e-flex e-con-boxed e-con e-child\" data-id=\"70dc3e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-834bac1 e-flex e-con-boxed e-con e-child\" data-id=\"834bac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b2ac2 elementor-widget elementor-widget-heading\" data-id=\"e0b2ac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#aduanas\">Aduanas<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dae3ef e-flex e-con-boxed e-con e-child\" data-id=\"2dae3ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94c1b36 elementor-widget elementor-widget-heading\" data-id=\"94c1b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#que-hacemos-por-ti\">Qu\u00e9 hacemos por ti<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83d5f87 e-flex e-con-boxed e-con e-child\" data-id=\"83d5f87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c829f5b elementor-widget elementor-widget-heading\" data-id=\"c829f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#razones-para-contar-con-nosotros\">Razones para contar con nosotros<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d77319e e-flex e-con-boxed e-con e-parent\" data-id=\"d77319e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-411bef1 e-con-full e-flex e-con e-child\" data-id=\"411bef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-91974b7 e-con-full e-flex e-con e-child\" data-id=\"91974b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4fe582 elementor-widget elementor-widget-html\" data-id=\"f4fe582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37b0995 elementor-widget elementor-widget-html\" data-id=\"37b0995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc3f86 elementor-widget elementor-widget-heading\" data-id=\"2fc3f86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASD Group Customs, tu experto en tr\u00e1mites aduaneros e import-export<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f17f470 elementor-widget elementor-widget-text-editor\" data-id=\"f17f470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conf\u00eda la gesti\u00f3n de tus <strong>tr\u00e1mites aduaneros internacionales<\/strong> a ASD Group y asegura tus operaciones de <strong>importaci\u00f3n y exportaci\u00f3n<\/strong>. Nuestros equipos expertos se encargan del <strong>despacho aduanero<\/strong>, los procedimientos aduaneros espec\u00edficos y todas las obligaciones normativas relacionadas con el transporte internacional de mercanc\u00edas.<\/p>\n<p>ASD Group centraliza tus operaciones aduaneras y log\u00edsticas garantizando una coordinaci\u00f3n \u00f3ptima entre todos los actores de la cadena: clientes, transportistas, almacenes y <strong>aduanas<\/strong>. Resultado: <strong>flujos internacionales simplificados<\/strong>, conformes y eficientes en cada etapa.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c459cf e-grid e-con-full e-con e-child\" data-id=\"5c459cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4abcda0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4abcda0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png\" class=\"attachment-full size-full wp-image-203298\" alt=\"Logo AEO - Operador Econ\u00f3mico Autorizado\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png 800w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo-300x300.png 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo-150x150.png 150w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Operador Econ\u00f3mico Autorizado<\/h3><p class=\"elementor-image-box-description\">En el marco de sus actividades de declaraciones aduaneras y conformidad internacional, <b>ASD Group es un Operador Econ\u00f3mico Autorizado. Esta certificaci\u00f3n acredita la fiabilidad y conformidad de sus servicios<\/b>, ofreciendo a los clientes operaciones aduaneras m\u00e1s r\u00e1pidas, seguras y eficientes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8771f5d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8771f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"343\" height=\"324\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/RDE-Medailloon-ASD-GROUP-DOUANE.png\" class=\"attachment-full size-full wp-image-203299\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/RDE-Medailloon-ASD-GROUP-DOUANE.png 343w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/RDE-Medailloon-ASD-GROUP-DOUANE-300x283.png 300w\" sizes=\"(max-width: 343px) 100vw, 343px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Representante Aduanero Registrado (RDE)<\/h3><p class=\"elementor-image-box-description\">ASD Group es un Representante Aduanero Registrado (RDE) que opera en varios pa\u00edses de la Uni\u00f3n Europea, <b>reconocido por la DGDDI (Direcci\u00f3n General de Aduanas y Derechos Indirectos) en Francia por su competencia, solvencia y conformidad normativa<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b6f5d3 e-con-full form-template-services elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0b6f5d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b59b4e elementor-widget elementor-widget-heading\" data-id=\"3b59b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u00a1NO ASUMAS RIESGOS!<br \/><br \/>\u00a1CONFIANOS TUS TR\u00c1MITES A NUESTROS EXPERTOS EN ADUANAS Y CONC\u00c9NTRATE EN TU NEGOCIO!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9636c e-transform elementor-widget elementor-widget-shortcode\" data-id=\"3b9636c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_49_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form-2026\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Contact 2026<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"49\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_49\" id=\"frm_hide_fields_49\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form-2026\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_49\" name=\"frm_submit_entry_49\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/service\/203310\" \/><div id=\"frm_field_696_container\" class=\"frm_form_field  frm12 frm_first formcontact-require frm_html_container form-field\"><em>* Los campos marcados con un asterisco son obligatorios para que podamos procesar su solicitud.<\/em> <em>Algunos de nuestros servicios no est\u00e1n disponibles en todas las regiones y\/o en todos los sectores.<\/em>\n<\/div>\n<div id=\"frm_field_635_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><strong>1\/ Tu empresa<\/strong><\/div>\n<div id=\"frm_field_616_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_i41ef2\" class=\"frm_primary_label\">\u00bfCu\u00e1l es el nombre de tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef2\" name=\"item_meta[616]\" value=\"\"  placeholder=\"Nombre de tu empresa\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_759_container\" class=\"frm_form_field frm_section_heading form-field  section-hidden frm_hide_section\">\r\n<h3 class=\"frm_pos_none frm_section_spacing\"><\/h3>\r\n\r\n\r\n<div id=\"frm_field_622_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order0 sort-alphabetically\">\r\n    <label for=\"field_okuhn3\" class=\"frm_primary_label\">\u00bfEn qu\u00e9 pa\u00eds est\u00e1 establecida tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[622]\" id=\"field_okuhn3\"  data-sectionid=\"759\"  data-placeholder=\"Elige el pa\u00eds donde deseas establecerte\"  placeholder=\"Elige el pa\u00eds donde deseas establecerte\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfEn qu\u00e9 pa\u00eds est\u00e1 establecida tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el pa\u00eds donde deseas establecerte<\/option><option  value=\"DE\">Alemania<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AR\">Argentina<\/option><option  value=\"AT\">Austria<\/option><option  value=\"BR\">Brasil<\/option><option  value=\"BG\">Bulgaria<\/option><option  value=\"BE\">B\u00e9lgica<\/option><option  value=\"CZ\">Chequia<\/option><option  value=\"CY\">Chipre<\/option><option  value=\"HR\">Croacia<\/option><option  value=\"DK\">Dinamarca<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"ES\">Espa\u00f1a<\/option><option  value=\"EE\">Estonia<\/option><option  value=\"FI\">Finlandia<\/option><option  value=\"FR\">Francia<\/option><option  value=\"GR\">Grecia<\/option><option  value=\"HU\">Hungr\u00eda<\/option><option  value=\"IE\">Irlanda<\/option><option  value=\"IS\">Islandia<\/option><option  value=\"IT\">Italia<\/option><option  value=\"LV\">Letonia<\/option><option  value=\"LI\">Liechtenstein<\/option><option  value=\"LT\">Lituania<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"MD\">Moldavia<\/option><option  value=\"MX\">M\u00e9xico<\/option><option  value=\"MC\">M\u00f3naco<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"NL\">Pa\u00edses Bajos<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"RS\">Serbia<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option><option  value=\"TR\">Turqu\u00eda<\/option><option  value=\"UA\">Ucrania<\/option><option  value=\"Other\">Otro pa\u00eds (por favor especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_617_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 order2 sort-alphabetically\">\r\n    <label for=\"field_85w6d2\" class=\"frm_primary_label\">\u00bfCu\u00e1l es el sector de actividad de tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[617]\" id=\"field_85w6d2\"  data-sectionid=\"759\"  data-placeholder=\"Elige tu sector de actividad\"  placeholder=\"Elige tu sector de actividad\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es el sector de actividad de tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige tu sector de actividad<\/option><option  value=\"Agriculture\">Agricultura\n<\/option><option  value=\"Agroalimentaire\">Agroalimentario<\/option><option  value=\"Automobile\">Autom\u00f3vil\n<\/option><option  value=\"Banque et assurances\">Banca y seguros\n<\/option><option  value=\"Commerce\">Comercio\n<\/option><option  value=\"B\u00e2timent et travaux publics (BTP)\">Construcci\u00f3n y obras p\u00fablicas\n<\/option><option  value=\"Conseil et services aux entreprises\">Consultor\u00eda y servicios para empresas<\/option><option  value=\"Culture et loisirs\">Cultura y ocio<\/option><option  value=\"Sport et \u00e9v\u00e9nements\">Deporte y eventos<\/option><option  value=\"Distribution\">Distribuci\u00f3n<\/option><option  value=\"\u00c9ducation et formation\">Educaci\u00f3n y formaci\u00f3n<\/option><option  value=\"\u00c9nergie\">Energ\u00eda<\/option><option  value=\"H\u00f4tellerie et restauration\">Hosteler\u00eda y restauraci\u00f3n<\/option><option  value=\"Industrie manufacturi\u00e8re\">Industria manufacturera<\/option><option  value=\"Informatique et num\u00e9rique\">Inform\u00e1tica y tecnolog\u00eda digital<\/option><option  value=\"Immobilier\">Inmobiliario<\/option><option  value=\"Recherche et d\u00e9veloppement\">Investigaci\u00f3n y desarrollo<\/option><option  value=\"Logistique et transport\">Log\u00edstica y transporte<\/option><option  value=\"Luxe et mode\">Lujo y moda<\/option><option  value=\"M\u00e9dias et communication\">Medios y comunicaci\u00f3n<\/option><option  value=\"M\u00e9tallurgie et sid\u00e9rurgie\">Metalurgia y siderurgia<\/option><option  value=\"Chimie et pharmacie\">Qu\u00edmica y farmacia\n<\/option><option  value=\"Sant\u00e9 et bien-\u00eatre\">Salud y bienestar<\/option><option  value=\"S\u00e9curit\u00e9 et d\u00e9fense\">Seguridad y defensa<\/option><option  value=\"Services publics et administration\">Servicios p\u00fablicos y administraci\u00f3n<\/option><option  value=\"T\u00e9l\u00e9communications\">Telecomunicaciones<\/option><option  value=\"Textile et habillement\">Textiles y ropa<\/option><option  value=\"Tourisme\">Turismo<\/option><option  value=\"Other\">Otro sector (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_639_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order1\">\r\n\t<label for=\"field_6q8fw\" id=\"field_6q8fw_label\" class=\"frm_primary_label\">Has elegido \"Otro pa\u00eds\", \u00bfpuedes especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_6q8fw\" name=\"item_meta[639]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Completa el pa\u00eds de establecimiento\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Has elegido &quot;Otro pa\u00eds&quot;, \u00bfpuedes especificar? no es v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_640_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_alignright order3\">\r\n\t<label for=\"field_8yduw\" id=\"field_8yduw_label\" class=\"frm_primary_label\">Elegiste \"Otro sector\", \u00bfpod\u00e9s especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_8yduw\" name=\"item_meta[640]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Completa el sector de actividad\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Elegiste &quot;Otro sector&quot;, \u00bfpod\u00e9s especificar? no es v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<\/div>\n<div id=\"frm_field_637_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><strong>2\/ Tu necesidad<\/strong><\/div>\n<div id=\"frm_field_623_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 relative frm_first sort-alphabetically\">\r\n    <label for=\"field_l1biv3\" class=\"frm_primary_label\">\u00bfEn qu\u00e9 pa\u00eds deseas desarrollar tu empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[623]\" id=\"field_l1biv3\"  data-placeholder=\"Elige el pa\u00eds donde deseas expandirte (paso 1\/4)\"  placeholder=\"Elige el pa\u00eds donde deseas expandirte (paso 1\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfEn qu\u00e9 pa\u00eds deseas desarrollar tu empresa? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el pa\u00eds donde deseas expandirte (paso 1\/4)<\/option><option  value=\"DE\">Alemania<\/option><option  value=\"AT\">Austria\n<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CZ\">Chequia<\/option><option  value=\"CY\">Chipre\n<\/option><option  value=\"HR\">Croacia\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"ES\">Espa\u00f1a\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"HU\">Hungr\u00eda\n<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"LV\">Letonia\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"NL\">Pa\u00edses Bajos<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_681_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nqwnw\" id=\"field_nqwnw_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Espa\u00f1a?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[681]\" id=\"field_nqwnw\"  data-placeholder=\"Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Espa\u00f1a? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Espa\u00f1a (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_647_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_31i7k\" id=\"field_31i7k_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Alemania?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[647]\" id=\"field_31i7k\"  data-placeholder=\"Elige el \u00e1rea de servicio en Alemania (paso 2\/4)\"  placeholder=\"Elige el \u00e1rea de servicio en Alemania (paso 2\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Alemania? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Alemania (paso 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_648_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n\t<label for=\"field_2p88l\" id=\"field_2p88l_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Austria?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[648]\" id=\"field_2p88l\"  data-placeholder=\"Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Austria? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Austria (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_649_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_9i5uq\" id=\"field_9i5uq_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para B\u00e9lgica?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[649]\" id=\"field_9i5uq\"  data-placeholder=\"Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para B\u00e9lgica?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en B\u00e9lgica (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_677_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3n29\" id=\"field_v3n29_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Bulgaria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[677]\" id=\"field_v3n29\"  data-placeholder=\"Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Bulgaria?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Bulgaria (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_651_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7frx6\" id=\"field_7frx6_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Canad\u00e1?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[651]\" id=\"field_7frx6\"  data-placeholder=\"Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Canad\u00e1? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Canad\u00e1 (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_676_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xhngf\" id=\"field_xhngf_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Chipre?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[676]\" id=\"field_xhngf\"  data-placeholder=\"Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Chipre?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Chipre (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_675_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_iyrkx\" id=\"field_iyrkx_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Croacia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[675]\" id=\"field_iyrkx\"  data-placeholder=\"Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Croacia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Croacia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_674_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hh8ys\" id=\"field_hh8ys_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Dinamarca?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[674]\" id=\"field_hh8ys\"  data-placeholder=\"Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Dinamarca?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Dinamarca (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_673_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xk6v1\" id=\"field_xk6v1_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Estonia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[673]\" id=\"field_xk6v1\"  data-placeholder=\"Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Estonia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Estonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_650_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7127q\" id=\"field_7127q_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para los Estados Unidos?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[650]\" id=\"field_7127q\"  data-placeholder=\"Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para los Estados Unidos? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Estados Unidos (paso 2\/4)\n<\/option><option  value=\"Fiscal : Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_672_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hrplp\" id=\"field_hrplp_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Finlandia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[672]\" id=\"field_hrplp\"  data-placeholder=\"Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Finlandia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Finlandia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_671_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jw8ml\" id=\"field_jw8ml_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Francia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[671]\" id=\"field_jw8ml\"  data-placeholder=\"Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Francia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Francia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_670_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_3gqvi\" id=\"field_3gqvi_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Grecia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[670]\" id=\"field_3gqvi\"  data-placeholder=\"Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Grecia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Grecia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_669_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ajvsb\" id=\"field_ajvsb_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Hungr\u00eda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[669]\" id=\"field_ajvsb\"  data-placeholder=\"Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Hungr\u00eda?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Hungr\u00eda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_668_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r1kza\" id=\"field_r1kza_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Irlanda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[668]\" id=\"field_r1kza\"  data-placeholder=\"Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Irlanda?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Irlanda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_667_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_qo5nf\" id=\"field_qo5nf_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Italia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[667]\" id=\"field_qo5nf\"  data-placeholder=\"Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Italia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Italia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_666_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z3dfa\" id=\"field_z3dfa_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Letonia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[666]\" id=\"field_z3dfa\"  data-placeholder=\"Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Letonia?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Letonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_665_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mm4zs\" id=\"field_mm4zs_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Lituania?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[665]\" id=\"field_mm4zs\"  data-placeholder=\"Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Lituania?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Lituania (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_664_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_kel0x\" id=\"field_kel0x_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Luxemburgo?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[664]\" id=\"field_kel0x\"  data-placeholder=\"Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Luxemburgo?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Luxemburgo (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_663_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dcpyc\" id=\"field_dcpyc_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Malta?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[663]\" id=\"field_dcpyc\"  data-placeholder=\"Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Malta?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Malta (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_662_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zz48j\" id=\"field_zz48j_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para los Pa\u00edses Bajos?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[662]\" id=\"field_zz48j\"  data-placeholder=\"Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para los Pa\u00edses Bajos?\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en los Pa\u00edses Bajos (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_661_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ji2cs\" id=\"field_ji2cs_label\" class=\"frm_primary_label\">Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[661]\" id=\"field_ji2cs\"  data-placeholder=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Polonia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_659_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aepqm\" id=\"field_aepqm_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Portugal?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[659]\" id=\"field_aepqm\"  data-placeholder=\"Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Portugal? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Portugal (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_658_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_d1twg\" id=\"field_d1twg_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Chequia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[658]\" id=\"field_d1twg\"  data-placeholder=\"Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Chequia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en la Rep\u00fablica Checa (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_657_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3096\" id=\"field_v3096_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Ruman\u00eda?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[657]\" id=\"field_v3096\"  data-placeholder=\"Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Ruman\u00eda? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Ruman\u00eda (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_656_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hlo6e\" id=\"field_hlo6e_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para el Reino Unido?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[656]\" id=\"field_hlo6e\"  data-placeholder=\"Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para el Reino Unido? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en el Reino Unido (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_655_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_azerr\" id=\"field_azerr_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Eslovaquia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[655]\" id=\"field_azerr\"  data-placeholder=\"Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Eslovaquia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Eslovaquia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_654_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vtjje\" id=\"field_vtjje_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Eslovenia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[654]\" id=\"field_vtjje\"  data-placeholder=\"Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Eslovenia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Eslovenia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\"> Aduanas: Operaciones, formalidades y obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_653_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_e1wi2\" id=\"field_e1wi2_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Suecia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[653]\" id=\"field_e1wi2\"  data-placeholder=\"Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Suecia? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Suecia (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrategia: Desarrollo de empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_652_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mf65v\" id=\"field_mf65v_label\" class=\"frm_primary_label\">\u00bfCu\u00e1l es tu necesidad para Suiza?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[652]\" id=\"field_mf65v\"  data-placeholder=\"Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n\"  placeholder=\"Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"\u00bfCu\u00e1l es tu necesidad para Suiza? no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el \u00e1rea de servicio en Suiza (paso 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_678_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_19pbf\" id=\"field_19pbf_label\" class=\"frm_primary_label\">[Alemania] Fiscal: IVA, Impuestos, Formalidades & Obligacione\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[678]\" id=\"field_19pbf\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Fiscal: IVA, Impuestos, Formalidades &amp; Obligacione no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/ZM\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ ZM \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_679_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gz1w7\" id=\"field_gz1w7_label\" class=\"frm_primary_label\">[Alemania] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[679]\" id=\"field_gz1w7\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_798_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dego5\" id=\"field_dego5_label\" class=\"frm_primary_label\">[Alemania] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[798]\" id=\"field_dego5\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Alemania] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_682_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eeeq6\" id=\"field_eeeq6_label\" class=\"frm_primary_label\">[Austria] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[682]\" id=\"field_eeeq6\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_683_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r8c1d\" id=\"field_r8c1d_label\" class=\"frm_primary_label\">[Austria] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[683]\" id=\"field_r8c1d\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_799_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_95ick\" id=\"field_95ick_label\" class=\"frm_primary_label\">[Austria] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[799]\" id=\"field_95ick\"  data-placeholder=\"Elige el servicio en Austria (paso 3\/4)\"  placeholder=\"Elige el servicio en Austria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Austria] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Austria (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_684_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aw4s9\" id=\"field_aw4s9_label\" class=\"frm_primary_label\">[B\u00e9lgica] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[684]\" id=\"field_aw4s9\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_685_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8oi4a\" id=\"field_8oi4a_label\" class=\"frm_primary_label\">[B\u00e9lgica] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[685]\" id=\"field_8oi4a\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_686_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hnplb\" id=\"field_hnplb_label\" class=\"frm_primary_label\">[B\u00e9lgica] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[686]\" id=\"field_hnplb\"  data-placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\"  placeholder=\"Elija el servicio en B\u00e9lgica (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en B\u00e9lgica (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_687_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dsbn4\" id=\"field_dsbn4_label\" class=\"frm_primary_label\">[Bulgaria] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[687]\" id=\"field_dsbn4\"  data-placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\"  placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Bulgaria] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Bulgaria (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_800_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gbi4d\" id=\"field_gbi4d_label\" class=\"frm_primary_label\">[Bulgaria] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[800]\" id=\"field_gbi4d\"  data-placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\"  placeholder=\"Elige el servicio en Bulgaria (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Bulgaria] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Bulgaria (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_689_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_a9qen\" id=\"field_a9qen_label\" class=\"frm_primary_label\">[Canad\u00e1] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[689]\" id=\"field_a9qen\"  data-placeholder=\"Elija el servicio en Canad\u00e1 (paso 3\/4)\"  placeholder=\"Elija el servicio en Canad\u00e1 (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Canad\u00e1] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Canad\u00e1 (paso 3\/4)<\/option><option  value=\"Gestion des taxes TPS\/TVH\/TVP\">Gesti\u00f3n de los impuestos GST\/HST\/PST<\/option><option  value=\"Gestion de la certification employeur non-r\u00e9sident\">Gesti\u00f3n de la certificaci\u00f3n de empleadores no residentes<\/option><option  value=\"Gestion de la dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents\">Gesti\u00f3n de la exenci\u00f3n de retenci\u00f3n de impuestos para empleadores no residentes<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_646_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8yjzs\" id=\"field_8yjzs_label\" class=\"frm_primary_label\">[Espa\u00f1a] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[646]\" id=\"field_8yjzs\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Gestion de la taxe sur les emballages plastiques non r\u00e9utilisables\">Gesti\u00f3n del impuesto sobre envases de pl\u00e1stico no reutilizables<\/option><option  value=\"Gestion de la taxe sur les pneus usag\u00e9s\">Gesti\u00f3n del impuesto sobre neum\u00e1ticos usados<\/option><option  value=\"Gestion de l&#039;Eco Tax DEEE (WEEE)\">Gesti\u00f3n del Eco-Impuesto DEEE (WEEE)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_641_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_whqtx\" id=\"field_whqtx_label\" class=\"frm_primary_label\">[Espa\u00f1a] Aduanas: Operaciones, Tr\u00e1mites y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[641]\" id=\"field_whqtx\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Aduanas: Operaciones, Tr\u00e1mites y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_643_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_upzx7\" id=\"field_upzx7_label\" class=\"frm_primary_label\">[Espa\u00f1a] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[643]\" id=\"field_upzx7\"  data-placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\"  placeholder=\"Elige el servicio en Espa\u00f1a (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Espa\u00f1a] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Espa\u00f1a (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_691_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5vbnj\" id=\"field_5vbnj_label\" class=\"frm_primary_label\">[Francia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[691]\" id=\"field_5vbnj\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale immobili\u00e8re\">Representaci\u00f3n fiscal inmobiliaria<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_692_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y17z7\" id=\"field_y17z7_label\" class=\"frm_primary_label\">[Francia] Aduanas: Operaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[692]\" id=\"field_y17z7\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Aduanas: Operaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations EMEBI (ERTVA\u2026)\/DES\">Gesti\u00f3n de las declaraciones EMEBI (ERTVA\u2026)\/DES<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gesti\u00f3n de las operaciones aduaneras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires et SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de RTC et RCO\">Acompa\u00f1amiento para la obtenci\u00f3n de IAV y IVO<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de la certification OEA\">Acompa\u00f1amiento para la obtenci\u00f3n de la certificaci\u00f3n OEA<\/option><option  value=\"Gestion des DDR selon le RDUE\">Gesti\u00f3n de los DDD seg\u00fan EUDR<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas<\/option><option  value=\"Gestion de la taxe carbone (CBAM\/MACF)\">Gesti\u00f3n del impuesto al carbono (CBAM)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_693_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q9gx\" id=\"field_q9gx_label\" class=\"frm_primary_label\">[Francia] Social: Regulaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[693]\" id=\"field_q9gx\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Social: Regulaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion des missions de d\u00e9tachement de salari\u00e9s \u00e9trangers en France (ASD SPW)\">Gesti\u00f3n de las misiones de destacamento de empleados extranjeros en Francia (ASD SPW)<\/option><option  value=\"Gestion de la repr\u00e9sentation fiscale dans le cadre du pr\u00e9l\u00e8vement \u00e0 la source\">Gesti\u00f3n de la representaci\u00f3n fiscal en el marco de la retenci\u00f3n en la fuente<\/option><option  value=\"Gestion de repr\u00e9sentation de firme \u00e9trang\u00e8re\">Gesti\u00f3n de la representaci\u00f3n de una empresa extranjera<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_694_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5kh5i\" id=\"field_5kh5i_label\" class=\"frm_primary_label\">[Francia] Estrategia: Desarrollo de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[694]\" id=\"field_5kh5i\"  data-placeholder=\"Elige el servicio en Francia (paso 3\/4)\"  placeholder=\"Elige el servicio en Francia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Francia] Estrategia: Desarrollo de empresas no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Francia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Gestion de la domiciliation d&#039;entreprise\">Gesti\u00f3n de la domiciliaci\u00f3n de la empresa<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_698_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jlotu\" id=\"field_jlotu_label\" class=\"frm_primary_label\">[Estados Unidos] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[698]\" id=\"field_jlotu\"  data-placeholder=\"Elige el servicio en Estados Unidos (paso 3\/4)\"  placeholder=\"Elige el servicio en Estados Unidos (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estados Unidos] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estados Unidos (paso 3\/4)<\/option><option  value=\"Gestion de la &quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Gesti\u00f3n del &quot;Sales and Use Tax&quot; en Estados Unidos<\/option><option  value=\"Gestion des formulaires W-8 et W-9 aux \u00c9tats-Unis\">Gesti\u00f3n de los formularios W-8 y W-9 en Estados Unidos<\/option><option  value=\"Gestion des formalit\u00e9s li\u00e9es au Nexus aux \u00c9tats-Unis\">Gesti\u00f3n de las formalidades relacionadas con el Nexus en Estados Unidos<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_699_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_44svk\" id=\"field_44svk_label\" class=\"frm_primary_label\">[Italia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[699]\" id=\"field_44svk\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du Visto di Conformit\u00e0\">Gesti\u00f3n del Visto di Conformit\u00e0<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_700_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ys0xm\" id=\"field_ys0xm_label\" class=\"frm_primary_label\">[Italia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[700]\" id=\"field_ys0xm\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_701_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1anf4\" id=\"field_1anf4_label\" class=\"frm_primary_label\">[Italia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[701]\" id=\"field_1anf4\"  data-placeholder=\"Elige el servicio en Italia (paso 3\/4)\"  placeholder=\"Elige el servicio en Italia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Italia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Italia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_702_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zq0ua\" id=\"field_zq0ua_label\" class=\"frm_primary_label\">[Chipre] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[702]\" id=\"field_zq0ua\"  data-placeholder=\"Elige el servicio en Chipre (paso 3\/4)\"  placeholder=\"Elige el servicio en Chipre (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chipre] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Chipre (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_801_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q3a1e\" id=\"field_q3a1e_label\" class=\"frm_primary_label\">[Chipre] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[801]\" id=\"field_q3a1e\"  data-placeholder=\"Elige el servicio en Chipre (paso 3\/4)\"  placeholder=\"Elige el servicio en Chipre (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chipre] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Chipre (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_704_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_s06v4\" id=\"field_s06v4_label\" class=\"frm_primary_label\">[Croacia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[704]\" id=\"field_s06v4\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_705_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vjfrb\" id=\"field_vjfrb_label\" class=\"frm_primary_label\">[Croacia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[705]\" id=\"field_vjfrb\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_802_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xna4z\" id=\"field_xna4z_label\" class=\"frm_primary_label\">[Croacia] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[802]\" id=\"field_xna4z\"  data-placeholder=\"Elige el servicio en Croacia (paso 3\/4)\"  placeholder=\"Elige el servicio en Croacia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Croacia] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Croacia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_706_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2i1vf\" id=\"field_2i1vf_label\" class=\"frm_primary_label\">[Dinamarca] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[706]\" id=\"field_2i1vf\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List \/ EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_707_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_g3d2w\" id=\"field_g3d2w_label\" class=\"frm_primary_label\">[Dinamarca] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[707]\" id=\"field_g3d2w\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_803_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1df4u\" id=\"field_1df4u_label\" class=\"frm_primary_label\">[Dinamarca] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[803]\" id=\"field_1df4u\"  data-placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Dinamarca (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Dinamarca (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_708_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_cs0h5\" id=\"field_cs0h5_label\" class=\"frm_primary_label\">[Estonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[708]\" id=\"field_cs0h5\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_709_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2ahrq\" id=\"field_2ahrq_label\" class=\"frm_primary_label\">[Estonia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[709]\" id=\"field_2ahrq\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_804_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_urojq\" id=\"field_urojq_label\" class=\"frm_primary_label\">[Estonia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[804]\" id=\"field_urojq\"  data-placeholder=\"Elige el servicio en Estonia (paso 3\/4)\"  placeholder=\"Elige el servicio en Estonia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Estonia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Estonia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_710_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jz0iw\" id=\"field_jz0iw_label\" class=\"frm_primary_label\">[Finlandia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[710]\" id=\"field_jz0iw\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_711_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z5cpa\" id=\"field_z5cpa_label\" class=\"frm_primary_label\">[Finlandia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[711]\" id=\"field_z5cpa\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, especifique a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_805_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oyx7h\" id=\"field_oyx7h_label\" class=\"frm_primary_label\">[Finlandia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[805]\" id=\"field_oyx7h\"  data-placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Finlandia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Finlandia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Finlandia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_712_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6jrxn\" id=\"field_6jrxn_label\" class=\"frm_primary_label\">[Grecia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[712]\" id=\"field_6jrxn\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_713_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rgel6\" id=\"field_rgel6_label\" class=\"frm_primary_label\">[Grecia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[713]\" id=\"field_rgel6\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_806_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6ls28\" id=\"field_6ls28_label\" class=\"frm_primary_label\">[Grecia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[806]\" id=\"field_6ls28\"  data-placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Grecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Grecia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Grecia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_714_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_w6w9o\" id=\"field_w6w9o_label\" class=\"frm_primary_label\">[Hungr\u00eda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[714]\" id=\"field_w6w9o\"  data-placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Hungr\u00eda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Hungr\u00eda (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_807_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jxc2i\" id=\"field_jxc2i_label\" class=\"frm_primary_label\">[Hungr\u00eda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[807]\" id=\"field_jxc2i\"  data-placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Hungr\u00eda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Hungr\u00eda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Hungr\u00eda (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_716_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lhn0a\" id=\"field_lhn0a_label\" class=\"frm_primary_label\">[Irlanda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[716]\" id=\"field_lhn0a\"  data-placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Irlanda (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_808_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hpoqk\" id=\"field_hpoqk_label\" class=\"frm_primary_label\">[Irlanda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[808]\" id=\"field_hpoqk\"  data-placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Irlanda (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Irlanda (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_718_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eh4ic\" id=\"field_eh4ic_label\" class=\"frm_primary_label\">[Letonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[718]\" id=\"field_eh4ic\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_719_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4t4b4\" id=\"field_4t4b4_label\" class=\"frm_primary_label\">[Letonia] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[719]\" id=\"field_4t4b4\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_809_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_btj00\" id=\"field_btj00_label\" class=\"frm_primary_label\">[Letonia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[809]\" id=\"field_btj00\"  data-placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Letonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Letonia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Letonia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_720_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_62mpm\" id=\"field_62mpm_label\" class=\"frm_primary_label\">[Lituania] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[720]\" id=\"field_62mpm\"  data-placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Lituania (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_721_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_fqvcn\" id=\"field_fqvcn_label\" class=\"frm_primary_label\">[Lituania] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[721]\" id=\"field_fqvcn\"  data-placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Lituania (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Lituania (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_810_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_tahxc\" id=\"field_tahxc_label\" class=\"frm_primary_label\">[Lituania] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[810]\" id=\"field_tahxc\"  data-placeholder=\"Elige el servicio en Alemania (paso 3\/4)\"  placeholder=\"Elige el servicio en Alemania (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Lituania] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Alemania (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_722_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6asdz\" id=\"field_6asdz_label\" class=\"frm_primary_label\">[Luxemburgo] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[722]\" id=\"field_6asdz\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_723_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_uv0bx\" id=\"field_uv0bx_label\" class=\"frm_primary_label\">[Luxemburgo] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[723]\" id=\"field_uv0bx\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_811_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q5m9h\" id=\"field_q5m9h_label\" class=\"frm_primary_label\">[Luxemburgo] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[811]\" id=\"field_q5m9h\"  data-placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Luxemburgo (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Luxemburgo (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_725_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_de7m1\" id=\"field_de7m1_label\" class=\"frm_primary_label\">[Malta] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[725]\" id=\"field_de7m1\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_726_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_n2ufm\" id=\"field_n2ufm_label\" class=\"frm_primary_label\">[Malta] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[726]\" id=\"field_n2ufm\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Gestion des d\u00e9clarations europ\u00e9ennes de services (DES)\">Gesti\u00f3n de las declaraciones europeas de servicios (DES)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_813_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_l10m9\" id=\"field_l10m9_label\" class=\"frm_primary_label\">[Malta] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[813]\" id=\"field_l10m9\"  data-placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Malta (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Malta] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Malta (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_727_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2af4r\" id=\"field_2af4r_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[727]\" id=\"field_2af4r\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_728_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_za0r\" id=\"field_za0r_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Aduanas: Operaciones, formalidades y obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[728]\" id=\"field_za0r\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Aduanas: Operaciones, formalidades y obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_814_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_i16up\" id=\"field_i16up_label\" class=\"frm_primary_label\">[Pa\u00edses Bajos] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[814]\" id=\"field_i16up\"  data-placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\"  placeholder=\"Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Bajos] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en los Pa\u00edses Bajos (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_729_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_h5qk6\" id=\"field_h5qk6_label\" class=\"frm_primary_label\">[Polonia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[729]\" id=\"field_h5qk6\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_730_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_42afs\" id=\"field_42afs_label\" class=\"frm_primary_label\">[Polonia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[730]\" id=\"field_42afs\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_731_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rd7rn\" id=\"field_rd7rn_label\" class=\"frm_primary_label\">[Polonia] Estrategia: Desarrollo empresarial\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[731]\" id=\"field_rd7rn\"  data-placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Polonia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Polonia] Estrategia: Desarrollo empresarial\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Polonia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_733_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6wlea\" id=\"field_6wlea_label\" class=\"frm_primary_label\">[Portugal] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[733]\" id=\"field_6wlea\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Facturation \u00e9lectronique et\/ou e-reporting\">Facturaci\u00f3n electr\u00f3nica y\/o e-reporting<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_734_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_u9472\" id=\"field_u9472_label\" class=\"frm_primary_label\">[Portugal] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[734]\" id=\"field_u9472\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gesti\u00f3n de las operaciones aduaneras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires,SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accises pour la vente \u00e0 distance de boissons alcooliques au Portugal\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas en Portugal<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_815_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rlp4g\" id=\"field_rlp4g_label\" class=\"frm_primary_label\">[Portugal] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[815]\" id=\"field_rlp4g\"  data-placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Portugal (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Portugal] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Portugal (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Accompagnement certification logiciel facturation \u00e9lectronique\">Acompa\u00f1amiento en la certificaci\u00f3n del software de facturaci\u00f3n electr\u00f3nica<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_735_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5hg1m\" id=\"field_5hg1m_label\" class=\"frm_primary_label\">[Chequia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[735]\" id=\"field_5hg1m\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Chequia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_736_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_t8kbm\" id=\"field_t8kbm_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[736]\" id=\"field_t8kbm\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_816_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oawcf\" id=\"field_oawcf_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[816]\" id=\"field_oawcf\"  data-placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\"  placeholder=\"Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en la Rep\u00fablica Checa (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_739_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4y9dt\" id=\"field_4y9dt_label\" class=\"frm_primary_label\">[Ruman\u00eda] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[739]\" id=\"field_4y9dt\"  data-placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\"  placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Ruman\u00eda] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Ruman\u00eda (paso 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_817_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_69ksn\" id=\"field_69ksn_label\" class=\"frm_primary_label\">[Ruman\u00eda] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[817]\" id=\"field_69ksn\"  data-placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\"  placeholder=\"Elige el servicio en Ruman\u00eda (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Ruman\u00eda] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Ruman\u00eda (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_741_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ownk6\" id=\"field_ownk6_label\" class=\"frm_primary_label\">[Reino Unido] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[741]\" id=\"field_ownk6\"  data-placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\"  placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones\n no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en el Reino Unido (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_742_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ioidj\" id=\"field_ioidj_label\" class=\"frm_primary_label\">[Reino Unido] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[742]\" id=\"field_ioidj\"  data-placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\"  placeholder=\"Elige el servicio en el Reino Unido (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en el Reino Unido (paso 3\/4)<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res et d\u00e9douanements\">Gesti\u00f3n de operaciones aduaneras y despacho de aduanas<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gesti\u00f3n de las declaraciones en TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires, SPS avec SIVEP\">Asistencia durante las inspecciones veterinarias y SPS con SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Asistencia durante los controles aduaneros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gesti\u00f3n de los impuestos especiales para la venta a distancia de bebidas alcoh\u00f3licas<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_743_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v16pe\" id=\"field_v16pe_label\" class=\"frm_primary_label\">[Eslovaquia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[743]\" id=\"field_v16pe\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Devoluci\u00f3n del IVA (8.\u00aa, 13.\u00aa directiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_744_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_idpgs\" id=\"field_idpgs_label\" class=\"frm_primary_label\">[Eslovaquia] Aduanas: Operaciones, Formalidades y Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[744]\" id=\"field_idpgs\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Aduanas: Operaciones, Formalidades y Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_818_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nueuk\" id=\"field_nueuk_label\" class=\"frm_primary_label\">[Eslovaquia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[818]\" id=\"field_nueuk\"  data-placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\"  placeholder=\"Elija el servicio en Eslovaquia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovaquia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija el servicio en Eslovaquia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_745_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_11566a\" id=\"field_11566a_label\" class=\"frm_primary_label\">[Eslovenia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[745]\" id=\"field_11566a\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gesti\u00f3n de la EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_747_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lwwyc\" id=\"field_lwwyc_label\" class=\"frm_primary_label\">[Eslovenia] Aduanas: Operaciones, formalidades y obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[747]\" id=\"field_lwwyc\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Aduanas: Operaciones, formalidades y obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gesti\u00f3n de las declaraciones Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_819_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z7hx0\" id=\"field_z7hx0_label\" class=\"frm_primary_label\">[Eslovenia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[819]\" id=\"field_z7hx0\"  data-placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\"  placeholder=\"Elige el servicio en Eslovenia (paso 3\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Eslovenia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Eslovenia (paso 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_748_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_shkof\" id=\"field_shkof_label\" class=\"frm_primary_label\">[Suecia] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[748]\" id=\"field_shkof\"  data-placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suecia] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suecia (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gesti\u00f3n de la ventanilla \u00fanica del IVA (OSS<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_820_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hgxin\" id=\"field_hgxin_label\" class=\"frm_primary_label\">[Suecia] Estrategia: Desarrollo empresarial\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[820]\" id=\"field_hgxin\"  data-placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suecia (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suecia] Estrategia: Desarrollo empresarial no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suecia (paso 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gesti\u00f3n del RGPD (cumplimiento, representante, DPD\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_750_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y6l2p\" id=\"field_y6l2p_label\" class=\"frm_primary_label\">[Suiza] Fiscal: IVA, Impuestos, Formalidades & Obligaciones\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[750]\" id=\"field_y6l2p\"  data-placeholder=\"Elige el servicio en Suiza (paso 3\/4)\n\"  placeholder=\"Elige el servicio en Suiza (paso 3\/4)\n\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"[Suiza] Fiscal: IVA, Impuestos, Formalidades &amp; Obligaciones no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elige el servicio en Suiza (paso 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representaci\u00f3n fiscal<\/option><option  value=\"Remboursement TVA (13e)\">Devoluci\u00f3n del IVA (13.\u00aa directiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditor\u00eda \/ asesoramiento en IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">No estoy seguro\/a (por favor, espec\u00edfica a continuaci\u00f3n)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_626_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_bz8k12\" class=\"frm_primary_label\">Explique brevemente tu necesidad\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[626]\" id=\"field_bz8k12\" rows=\"5\"  placeholder=\"Ej.: Nuestra empresa desea recuperar el IVA en Alemania... (paso 4\/4)\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Explica brevemente tu necesidad&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_638_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\">\n<p><strong>3\/ Tus datos de contacto<\/strong><\/p>\n<\/div>\n<div id=\"frm_field_619_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_ocfup142\" class=\"frm_primary_label\">Nombre\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup142\" name=\"item_meta[619]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Nombre&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_618_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n    <label for=\"field_qh4icy42\" class=\"frm_primary_label\">Apellido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy42\" name=\"item_meta[618]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Apellido&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_620_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc3\" class=\"frm_primary_label\">Direcci\u00f3n de correo electr\u00f3nico\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc3\" name=\"item_meta[620]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_621_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa4\" class=\"frm_primary_label\">Tel\u00e9fono\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa4\" name=\"item_meta[621]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"El tel\u00e9fono no es v\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_627_container\" class=\"frm_form_field  frm_html_container form-field\">Este sitio est\u00e1 protegido por reCAPTCHA y se aplican la <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">pol\u00edtica de privacidad<\/a> y los <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">t\u00e9rminos del servicio<\/a> de Google.<\/div>\n<div id=\"frm_field_628_container\" class=\"frm_form_field form-field  frm_top_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Bolet\u00edn\n\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_628-0\">\t\t\t<label  for=\"field_e2sgs2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[628][]\" id=\"field_e2sgs2-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Bolet\u00edn\n no es v\u00e1lido\"   \/> Me gustar\u00eda recibir los boletines de noticias de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_629_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_629-0\">\t\t\t<label  for=\"field_y30e3-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[629][]\" id=\"field_y30e3-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"Este campo no puede estar vac\u00edo.\n\" data-invmsg=\"RGPD no es v\u00e1lido\"   aria-required=\"true\"  \/> Al solicitar el formulario, acepto que la  informaci\u00f3n sea procesada y pueda dar lugar a una relaci\u00f3n profesional. Para conocer y ejercer sus derechos y especialmente respeto al consentimiento y al uso de sus datos ,le invitamos a consultar nuestras menciones legales en la parte abajo de esa p\u00e1gina.<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_630_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\" \/><\/div>\n<div id=\"frm_field_631_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t2_label\" class=\"frm_primary_label\">CAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t2\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[632]\" id=\"field_8qg9b2\" value=\"\"     \/>\n\t\t<div id=\"frm_field_633_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">ENVIAR MI SOLICITUD<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_4jyhc\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_4jyhc\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg5PCdZGfasJaa7fNi5oUIxDi51mrZ78stY+1ViuSWtHE\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a73948 e-flex e-con-boxed e-con e-parent\" data-id=\"5a73948\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8c0cb elementor-widget elementor-widget-html\" data-id=\"4d8c0cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0a48b elementor-widget elementor-widget-html\" data-id=\"5c0a48b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dd4e8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dd4e8f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49b88e9\" data-id=\"49b88e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c88c3d8 e-con-full e-flex e-con e-child\" data-id=\"c88c3d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-530bf7d elementor-widget elementor-widget-html\" data-id=\"530bf7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95e44a1 elementor-widget elementor-widget-html\" data-id=\"95e44a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb8419f elementor-widget elementor-widget-heading\" data-id=\"cb8419f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1ndo es necesario recurrir a un agente de aduanas para tus operaciones de import-export?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-064dbda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"064dbda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3c8805\" data-id=\"a3c8805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef05880 elementor-widget elementor-widget-text-editor\" data-id=\"ef05880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00bfDudas en <strong>recurrir a un agente de aduanas<\/strong> para tus operaciones de <strong>transporte internacional<\/strong>? Desde env\u00edos complejos hasta mercanc\u00edas sujetas a normas estrictas, aqu\u00ed tienes las situaciones en las que un <strong>profesional de tr\u00e1mites aduaneros<\/strong> te acompa\u00f1a para garantizar conformidad, fluidez y eficiencia.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3387a6a e-con-full e-flex e-con e-parent\" data-id=\"3387a6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d2a2837 e-con-full e-flex e-con e-child\" data-id=\"d2a2837\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ddeb7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c3ddeb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-graduate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAusencia de competencias aduaneras internas\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSin experiencia en tr\u00e1mites aduaneros, la gesti\u00f3n del despacho y de los procedimientos de import-export puede ser compleja y arriesgada.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d35379\" data-id=\"7d35379\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07ff4b1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"07ff4b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"594\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/declaration-echanges-de-biens-intrastat-illustration-fr-768x787.png\" class=\"attachment-medium_large size-medium_large wp-image-95167\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/declaration-echanges-de-biens-intrastat-illustration-fr-768x787.png 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/declaration-echanges-de-biens-intrastat-illustration-fr-293x300.png 293w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/declaration-echanges-de-biens-intrastat-illustration-fr-999x1024.png 999w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/declaration-echanges-de-biens-intrastat-illustration-fr.png 1016w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3843ea6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3843ea6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2325824\" data-id=\"2325824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2541207 e-flex e-con-boxed e-con e-parent\" data-id=\"2541207\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f2abe6 e-con-full e-flex e-con e-child\" data-id=\"2f2abe6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1883f59 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1883f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-puzzle-piece\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFlujos log\u00edsticos complejos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOperaciones de transporte que implican varios pa\u00edses o normativas dif\u00edciles de gestionar.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e8b021 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2e8b021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-balance-scale\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConformidad con la legislaci\u00f3n aduanera\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPara evitar sanciones, multas o retenciones, es esencial garantizar que todos tus env\u00edos internacionales cumplan las normas y obligaciones aduaneras.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-677eef2 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"677eef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stopwatch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDespacho aduanero acelerado\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAprovecha las relaciones privilegiadas de tu agente de aduanas con las autoridades para un tratamiento r\u00e1pido y eficiente de tus mercanc\u00edas.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eeaaba elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5eeaaba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marked-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tExpansi\u00f3n hacia nuevos mercados\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa experiencia de un agente de aduanas te permite dominar las obligaciones aduaneras locales y garantizar un paso fluido de tus mercanc\u00edas en nuevos pa\u00edses.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c49fcb e-con-full e-flex e-con e-child\" data-id=\"8c49fcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0fa65a elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a0fa65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-truck\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGrandes vol\u00famenes que gestionar\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros equipos especializados garantizan una gesti\u00f3n fluida de tus env\u00edos incluso con un gran volumen de expediciones internacionales.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-294c4db elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"294c4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-folder-open\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGesti\u00f3n de documentos aduaneros\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros expertos te ayudan a preparar y controlar tus tr\u00e1mites aduaneros, garantizando conformidad y rapidez en tus expediciones internacionales\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9740f02 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9740f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-money-bill-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDominar tus derechos y tributos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tReduce los riesgos de sobrepagos y errores aduaneros gracias a un acompa\u00f1amiento profesional en la gesti\u00f3n de derechos y tributos ligados a tus flujos internacionales.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2690584 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2690584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hourglass-half\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEvita retrasos y sanciones\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDisminuye el riesgo de bloqueos, multas o rechazos de env\u00edos gracias a una gesti\u00f3n profesional de tus tr\u00e1mites aduaneros.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb4718 elementor-widget elementor-widget-spacer\" data-id=\"8fb4718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c28f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"87c28f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-287c2d1 e-con-full e-flex e-con e-child\" data-id=\"287c2d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d0a13 elementor-widget elementor-widget-html\" data-id=\"b1d0a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0659ffc elementor-widget elementor-widget-html\" data-id=\"0659ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f0f744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f0f744\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9638bc5\" data-id=\"9638bc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-376599e e-con-full e-flex e-con e-child\" data-id=\"376599e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec1f922 elementor-widget elementor-widget-html\" data-id=\"ec1f922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f536b4 elementor-widget elementor-widget-html\" data-id=\"7f536b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69a255a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"69a255a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASD Group es tu socio estrat\u00e9gico para tus flujos aduaneros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-815a6d1 elementor-widget elementor-widget-spacer\" data-id=\"815a6d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0bc7a elementor-widget elementor-widget-text-editor\" data-id=\"0c0bc7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ASD Group act\u00faa como <strong>el coordinador central de tus operaciones aduaneras y log\u00edsticas<\/strong>. Como <strong>enlace estrat\u00e9gico<\/strong> entre tu empresa, tus almacenes, tus transportistas y las autoridades aduaneras, garantizamos <strong>flujos internacionales fluidos y conformes en cada etapa<\/strong>.<\/p>\n<p>Trabajamos en <strong>estrecha colaboraci\u00f3n con tus transportistas y agentes de aduanas<\/strong> para asegurar una <strong>gesti\u00f3n \u00f3ptima de tus tr\u00e1mites aduaneros<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac3c089 elementor-widget__width-inherit elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ac3c089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Coordinaci\u00f3n con aduanas y tus equipos<\/strong>: gesti\u00f3n centralizada para un seguimiento simplificado de tus operaciones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Revisiones mensuales de rendimiento<\/strong>: an\u00e1lisis y recomendaciones para optimizar tus flujos internacionales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Auditor\u00edas e informes personalizados<\/strong>: identificaci\u00f3n de oportunidades de mejora y simplificaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Proceso aduanero \u00fanico<\/strong>: racionalizaci\u00f3n para mayor eficiencia y rapidez.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Centralizaci\u00f3n de operaciones multi-almac\u00e9n<\/strong>: simplificaci\u00f3n de la gesti\u00f3n y mejor visibilidad de tus flujos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a9ad05 elementor-widget elementor-widget-text-editor\" data-id=\"1a9ad05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias a un <strong>an\u00e1lisis profundo de tus flujos, su origen y las normativas aplicables<\/strong>, identificamos soluciones para <strong>simplificar y acelerar tus tr\u00e1mites aduaneros<\/strong>. Controlar tus flujos es <strong>ganar tiempo y reducir costes<\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a304229 elementor-widget__width-inherit elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a304229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Despacho nacional centralizado:<\/strong> tratamiento r\u00e1pido y simplificado de tus tr\u00e1mites aduaneros.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Derechos de accisa:<\/strong> gesti\u00f3n completa y segura de tus obligaciones fiscales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Solicitudes de locales autorizados:<\/strong> acompa\u00f1amiento completo para la obtenci\u00f3n de tus autorizaciones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Vigilancia normativa:<\/strong> mantente siempre conforme a las leyes aduaneras vigentes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Documentos justificativos (CO, EUR.1, etc.):<\/strong> preparaci\u00f3n, seguimiento y control.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Clasificaci\u00f3n arancelaria:<\/strong> precisi\u00f3n y optimizaci\u00f3n para tus mercanc\u00edas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Asistencia durante inspecciones aduaneras:<\/strong> apoyo experto ante las autoridades.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Enlace con la Direcci\u00f3n Regional de Aduanas:<\/strong> un contacto dedicado para facilitar la comunicaci\u00f3n y acelerar el tratamiento de los tr\u00e1mites.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Centralizaci\u00f3n multi-almac\u00e9n:<\/strong> simplifica la gesti\u00f3n y el seguimiento de tus flujos internacionales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Proceso aduanero \u00fanico:<\/strong> racionalizaci\u00f3n para mayor eficiencia y rapidez.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Centralizaci\u00f3n de operaciones multi-almac\u00e9n:<\/strong> simplificaci\u00f3n de la gesti\u00f3n y mejor visibilidad de tus flujos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-141b6a2 elementor-widget elementor-widget-spacer\" data-id=\"141b6a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0686666 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0686666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5bd912 elementor-widget elementor-widget-menu-anchor\" data-id=\"f5bd912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"que-hacemos-por-ti\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb295ad elementor-widget elementor-widget-html\" data-id=\"bb295ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cf8aee elementor-widget elementor-widget-html\" data-id=\"9cf8aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce8a2f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce8a2f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2469db\" data-id=\"a2469db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d7e08 e-con-full e-flex e-con e-child\" data-id=\"50d7e08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-376b6ba elementor-widget elementor-widget-html\" data-id=\"376b6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6891161 elementor-widget elementor-widget-html\" data-id=\"6891161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410bb75 elementor-widget elementor-widget-heading\" data-id=\"410bb75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo ASD Group optimiza tus operaciones y tu despacho aduanero<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bafdd7 elementor-widget elementor-widget-text-editor\" data-id=\"9bafdd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTe acompa\u00f1amos en la <strong>coordinaci\u00f3n de tus operaciones aduaneras<\/strong> y el <strong>tratamiento r\u00e1pido de tus tr\u00e1mites de import-export<\/strong>, para flujos internacionales fluidos y conformes.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e80428 e-flex e-con-boxed e-con e-parent\" data-id=\"7e80428\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de02b3 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1de02b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents.jpg\" class=\"attachment-full size-full wp-image-177606\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-768x512.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-1200x800.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Operaciones aduaneras y despacho simplificados<\/h3><p class=\"elementor-image-box-description\">Coordinamos todas tus operaciones de import-export, garantizando un <b>despacho r\u00e1pido, conforme y sin errores<\/b>, para flujos comerciales internacionales seguros.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d80870 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"0d80870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva.jpg\" class=\"attachment-full size-full wp-image-177628\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Gesti\u00f3n centralizada del despacho<\/h3><p class=\"elementor-image-box-description\">Gracias a nuestro enfoque centralizado, puedes presentar tus declaraciones aduaneras en varios despachos garantizando <b>rapidez, conformidad y simplicidad para tus flujos<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f9a350 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"4f9a350\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales.jpg\" class=\"attachment-full size-full wp-image-177639\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Creaci\u00f3n y seguimiento de documentos aduaneros<\/h3><p class=\"elementor-image-box-description\">Nos ocupamos de todos tus certificados y justificantes requeridos (CO, EUR.1, etc.), para <b>facilitar tus tr\u00e1mites aduaneros<\/b> y garantizar la conformidad de tus expediciones.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1dd345 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b1dd345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva.jpg\" class=\"attachment-full size-full wp-image-177617\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Acompa\u00f1amiento para la conformidad aduanera<\/h3><p class=\"elementor-image-box-description\">ASD Group te gu\u00eda en todos tus tr\u00e1mites aduaneros, garantizando una <b>conformidad total con las leyes y regulaciones<\/b> en tus operaciones internacionales.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-763d46a elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"763d46a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-customs-screenshot-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Almacenamiento seguro y acceso inmediato a tus expedientes aduaneros<\/h3><p class=\"elementor-image-box-description\">Conserva todos tus documentos oficiales de despacho de forma segura y <b>accede a ellos instant\u00e1neamente v\u00eda ASD Customs<\/b>, incluido en MyASD, para simplificar tus tr\u00e1mites aduaneros.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2ba6cc e-con-full e-flex e-con e-child\" data-id=\"a2ba6cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-099a7d2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"099a7d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82e3453 elementor-widget elementor-widget-html\" data-id=\"82e3453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad0491 elementor-widget elementor-widget-html\" data-id=\"bad0491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33e549f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33e549f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aadcddb\" data-id=\"aadcddb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abab426 elementor-widget elementor-widget-counter\" data-id=\"abab426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Un equipo de 25 expertos a tu servicio.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"25\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dc331ac\" data-id=\"dc331ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bdc783 elementor-widget elementor-widget-counter\" data-id=\"5bdc783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Gesti\u00f3n de tr\u00e1mites en 14 puntos de entrada en Francia<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"14\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25587c4\" data-id=\"25587c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a54982 elementor-widget elementor-widget-counter\" data-id=\"9a54982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Presencia en 3 sedes en Francia.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"3\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b92bab elementor-widget elementor-widget-menu-anchor\" data-id=\"9b92bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"razones-para-contar-con-nosotros\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc8501f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc8501f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e75129a\" data-id=\"e75129a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4c5ec e-con-full e-flex e-con e-child\" data-id=\"ff4c5ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb9bd0 elementor-widget elementor-widget-html\" data-id=\"fdb9bd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18fb6c3 elementor-widget elementor-widget-html\" data-id=\"18fb6c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0121818 elementor-widget elementor-widget-heading\" data-id=\"0121818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 elegir ASD Group Customs?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dee7ca7 elementor-widget elementor-widget-text-editor\" data-id=\"dee7ca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDisfruta de un <strong>acompa\u00f1amiento profesional<\/strong> para tus <strong>tr\u00e1mites aduaneros<\/strong>, el <strong>despacho r\u00e1pido de tus mercanc\u00edas<\/strong> y la gesti\u00f3n eficiente de tus flujos internacionales.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ed8ede e-flex e-con-boxed e-con e-parent\" data-id=\"1ed8ede\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f0cdd8b e-con-full e-flex e-con e-child\" data-id=\"f0cdd8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6893191 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6893191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-tie\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tExperiencia en tr\u00e1mites aduaneros\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDominamos las normativas aduaneras nacionales e internacionales para <b>garantizar la conformidad de tus flujos comerciales<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc6cc8f e-con-full e-flex e-con e-child\" data-id=\"dc6cc8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d871435 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d871435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shipping-fast\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProcedimientos aduaneros acelerados\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGestionamos tus tr\u00e1mites aduaneros de forma eficiente para evitar cualquier retraso log\u00edstico y <b>garantizar la fluidez de tus flujos<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcfae68 e-con-full e-flex e-con e-child\" data-id=\"dcfae68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c693fc4 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c693fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tReducci\u00f3n de errores aduaneros\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Nuestros expertos minimizan los errores<\/b> y los riesgos de sanciones, garantizando flujos internacionales fluidos y conformes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15e9cee e-flex e-con-boxed e-con e-parent\" data-id=\"15e9cee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a51241 e-con-full e-flex e-con e-child\" data-id=\"5a51241\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30dab4c elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"30dab4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-brain\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConocimientos t\u00e9cnicos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros conocimientos t\u00e9cnicos nos permiten ser un <b>interlocutor de confianza de las administraciones fiscales y aduaneras<\/b> europeas desde hace m\u00e1s de 20 a\u00f1os, garantizando tus actividades en la UE y tu reputaci\u00f3n ante los servicios fiscales y aduaneros europeos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-318f683 e-con-full e-flex e-con e-child\" data-id=\"318f683\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147ac8d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"147ac8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stopwatch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tReactividad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRespondemos a todas las solicitudes de nuestros clientes muy r\u00e1pidamente, garantizando una <b>comunicaci\u00f3n fluida<\/b> y eficaz durante todo el proceso.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90c133c e-con-full e-flex e-con e-child\" data-id=\"90c133c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6754c56 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6754c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-eye\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguimiento de normativas aduaneras\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros expertos identifican las modificaciones legales pr\u00f3ximas para que tus operaciones aduaneras sigan siendo fluidas y <b>conformes<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c15c11 e-flex e-con-boxed e-con e-parent\" data-id=\"6c15c11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e07b70 e-con-full e-flex e-con e-child\" data-id=\"6e07b70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d83615b elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d83615b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-piggy-bank\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOptimizaci\u00f3n financiera de los flujos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGracias a nuestra experiencia en reg\u00edmenes preferenciales y exenciones, <b>tus importaciones y exportaciones son conformes<\/b> mientras reduces tus derechos y tributos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13c74f4 e-con-full e-flex e-con e-child\" data-id=\"13c74f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-637aecd elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"637aecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAcompa\u00f1amiento aduanero a medida\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOfrecemos <b>consejos personalizados adaptados a las necesidades espec\u00edficas de tu sector<\/b> y de tus operaciones de import-export.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52887ad e-con-full e-flex e-con e-child\" data-id=\"52887ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76d3666 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"76d3666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-laptop\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguimiento digital de tr\u00e1mites aduaneros\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGracias a nuestras herramientas digitales, disfrutas de un <b>control en tiempo real<\/b> de tus operaciones de import-export para mayor transparencia y eficiencia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-504d6c0 e-flex e-con-boxed e-con e-parent\" data-id=\"504d6c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c0db635 e-con-full e-flex e-con e-child\" data-id=\"c0db635\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-184a71a elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"184a71a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bullseye\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConc\u00e9ntrate en tu actividad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNos ocupamos de todos tus tr\u00e1mites aduaneros y operaciones internacionales, ofreci\u00e9ndote <b>tiempo valioso para desarrollar tu empresa<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca74711 e-con-full e-flex e-con e-child\" data-id=\"ca74711\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff72268 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ff72268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRed s\u00f3lida y alianzas fiables\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAprovechamos <b>nuestras relaciones con las autoridades aduaneras<\/b> y socios log\u00edsticos para simplificar tus operaciones de import-export.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0508b57 e-con-full e-flex e-con e-child\" data-id=\"0508b57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed538ce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ed538ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cbe3b5 e-flex e-con-boxed e-con e-parent\" data-id=\"6cbe3b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87098f0 elementor-widget elementor-widget-html\" data-id=\"87098f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59ed99 elementor-widget elementor-widget-html\" data-id=\"e59ed99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-97f3100 e-con-full e-flex e-con e-parent\" data-id=\"97f3100\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-16b014c e-con-full e-flex e-con e-child\" data-id=\"16b014c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d00f6 elementor-widget elementor-widget-html\" data-id=\"23d00f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-771884d elementor-widget elementor-widget-html\" data-id=\"771884d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b051c5 e-con-full e-flex e-con e-child\" data-id=\"9b051c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb91997 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cb91997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apoyo operativo inmediato sobre el terreno<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-343ebbe elementor-widget elementor-widget-text-editor\" data-id=\"343ebbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro equipo experimentado, en el coraz\u00f3n de los <strong>flujos transmanche<\/strong>, en los <strong>sitios del Puerto de Calais y el Eurot\u00fanel<\/strong> entre otros, <br \/>garantiza una <strong>asistencia fiable y personalizada<\/strong>, disponible <strong>24\/7<\/strong> para asegurar tus operaciones.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77a462a elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"77a462a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;5&quot;,&quot;slides_per_view_tablet&quot;:&quot;4&quot;,&quot;slides_per_view_mobile&quot;:&quot;2&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-3.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-4.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-1-1.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-1-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-5.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-5.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-6.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-6.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"asd-group-aduanas-calais-agentes-2-1.jpg\" style=\"background-image: url(&#039;https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-group-customs-calais-commis-2-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ce58f8 e-flex e-con-boxed e-con e-parent\" data-id=\"3ce58f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-983a723 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"983a723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1da43d elementor-widget elementor-widget-html\" data-id=\"c1da43d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87064dd elementor-widget elementor-widget-html\" data-id=\"87064dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b809f40 e-flex e-con-boxed e-con e-parent\" data-id=\"b809f40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6aa6b01 e-con-full e-flex e-con e-child\" data-id=\"6aa6b01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5664543 elementor-widget elementor-widget-html\" data-id=\"5664543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af21fc9 elementor-widget elementor-widget-html\" data-id=\"af21fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b88ef2 elementor-widget elementor-widget-heading\" data-id=\"3b88ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Despacho para todo tipo de mercanc\u00edas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8381fa elementor-widget elementor-widget-text-editor\" data-id=\"f8381fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGestionamos <strong>todo tipo de productos<\/strong> que circulan entre <strong>Reino Unido, Francia y la Uni\u00f3n Europea<\/strong>, asegurando <strong>despacho y seguimiento operativo<\/strong>.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c8e9a7 e-con-full e-flex e-con e-child\" data-id=\"8c8e9a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-974ff5f e-grid e-con-full e-con e-child\" data-id=\"974ff5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c062eba elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c062eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-horse-head\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAnimales vivos\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a44f650 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a44f650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cheese\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProductos alimenticios\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3114475 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3114475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-car\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVeh\u00edculos\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2250751 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2250751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-truck\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMudanzas\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30274da elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"30274da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pallet\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOtras mercanc\u00edas\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cc9220 e-con-full e-flex e-con e-child\" data-id=\"7cc9220\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0cb148 elementor-widget elementor-widget-html\" data-id=\"e0cb148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73cc67d elementor-widget elementor-widget-html\" data-id=\"73cc67d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7798d69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7798d69\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-944c540\" data-id=\"944c540\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-babd53c elementor-widget-tablet__width-inherit elementor-widget elementor-widget-counter\" data-id=\"babd53c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">despachos<br \/>realizados en 2024<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"4200\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da7df47\" data-id=\"da7df47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3b0810 elementor-widget elementor-widget-counter\" data-id=\"a3b0810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">expedientes gestionados por<br \/>nuestros agentes aduaneros en 2024<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"3500\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e255ccf e-flex e-con-boxed e-con e-parent\" data-id=\"e255ccf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30f355c e-con-full e-flex e-con e-child\" data-id=\"30f355c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f403ea elementor-widget elementor-widget-html\" data-id=\"6f403ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db2fae3 elementor-widget elementor-widget-html\" data-id=\"db2fae3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c421f1b e-con-full e-flex e-con e-child\" data-id=\"c421f1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d38634d elementor-widget elementor-widget-heading\" data-id=\"d38634d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASD Customs: la soluci\u00f3n digital para el despacho aduanero<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-233dd5b elementor-widget elementor-widget-text-editor\" data-id=\"233dd5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNuestra <strong>plataforma a medida<\/strong> ASD Customs centraliza todos tus <strong>procedimientos aduaneros<\/strong>, ofreci\u00e9ndote un <strong>seguimiento claro, simplificado y conforme<\/strong> de todas tus operaciones de import-export.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53bc4b1 e-con-full e-flex e-con e-child\" data-id=\"53bc4b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a6475cc e-con-full e-flex e-con e-child\" data-id=\"a6475cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38abc40 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"38abc40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-sync-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Seguimiento en tiempo real<\/b>: visualiza el avance de tus tr\u00e1mites aduaneros y centraliza todos tus documentos oficiales para un despacho eficiente y transparente.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-rocketchat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Soporte v\u00eda chat en directo<\/b>: cada despacho cuenta con un chat dedicado, facilitando la comunicaci\u00f3n con nuestros equipos y asegurando un seguimiento preciso de tus operaciones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>24\/7<\/b>: disfruta de un seguimiento y gesti\u00f3n de tus despachos en continuo, a cualquier hora, para flujos internacionales fluidos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8053261 e-con-full e-flex e-con e-child\" data-id=\"8053261\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb8139 elementor-widget elementor-widget-image\" data-id=\"8fb8139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/asd-customs-screenshot-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-709abb7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"709abb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/asd-customs\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubrir ASD Customs<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6de1e0f e-con-full e-flex e-con e-child\" data-id=\"6de1e0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2804817 elementor-widget elementor-widget-html\" data-id=\"2804817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd1c6c7 elementor-widget elementor-widget-html\" data-id=\"fd1c6c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dbbcab7 e-con-full e-flex e-con e-parent\" data-id=\"dbbcab7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b961e65 e-con-full e-flex e-con e-child\" data-id=\"b961e65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2cc9b2 elementor-widget elementor-widget-html\" data-id=\"d2cc9b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd75bf9 elementor-widget elementor-widget-html\" data-id=\"cd75bf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3169e87 e-con-full e-flex e-con e-child\" data-id=\"3169e87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f780617 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f780617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Las ventajas de confiar en ASD Group<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a353f elementor-widget elementor-widget-text-editor\" data-id=\"d9a353f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDisfruta de un <strong>acompa\u00f1amiento profesional<\/strong> para tus <strong>despachos y tr\u00e1mites aduaneros<\/strong>, garantizando <strong>eficacia, conformidad y rapidez<\/strong>.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21ef474 e-flex e-con-boxed e-con e-child\" data-id=\"21ef474\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47699bf e-grid e-con-full e-con e-child\" data-id=\"47699bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1522bc2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1522bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t24\/7\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e302a elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"26e302a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-truck-moving\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTiempos de tr\u00e1nsito \r\nreducidos\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-129eaa0 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"129eaa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-head-side-virus\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tM\u00e1s de 25 a\u00f1os de experiencia\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b381947 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b381947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-award\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAutorizado por las autoridades aduaneras francesas\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d31b5 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d8d31b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe-africa\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMultiling\u00fce\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3873f69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3873f69\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef5790c\" data-id=\"ef5790c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-581c4a7 e-con-full e-flex e-con e-child\" data-id=\"581c4a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd7704b elementor-widget elementor-widget-html\" data-id=\"cd7704b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33f0ab7 elementor-widget elementor-widget-html\" data-id=\"33f0ab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d500b elementor-widget elementor-widget-heading\" data-id=\"94d500b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">conf\u00edan en nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8ba2e3 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-widget elementor-widget-testimonial-carousel\" data-id=\"a8ba2e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">01 \/ 05<\/span> <\/p>\n<p>Mi empresa est\u00e1 perfectamente conforme en materia de IVA e Intrastat<br \/>gracias a ASD Group, es todo lo que pido. Misi\u00f3n cumplida.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-ad-tyres-1.png\" alt=\"AD TYRES - Hugo LACASSE, CEO &amp; Fundador\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">AD TYRES - Hugo LACASSE, CEO & Fundador<\/span><span class=\"elementor-testimonial__title\">CEO & fundador<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">02 \/ 05<\/span> <\/p>\n<p>El valor a\u00f1adido de ASD Group ha sido la disponibilidad de los interlocutores, <br \/>el plazo de respuesta, el tratamiento de expedientes, en resumen equipos eficaces. <\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-sbm-offshore.png\" alt=\"GROUPE SBM - Alexandra BOCANGEL, Asesora Fiscal\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">GROUPE SBM - Alexandra BOCANGEL, Asesora Fiscal<\/span><span class=\"elementor-testimonial__title\">Asesora fiscal<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">03 \/ 05<\/span> <\/p>\n<p>Para completar nuestra oferta, necesit\u00e1bamos un especialista <br \/>en problem\u00e1ticas fiscales relacionadas con intercambios internacionales.<\/p>\n<p>Nos pareci\u00f3 natural contactar con ASD Group, reconocida <br \/>por su competencia en fiscalidad internacional. <\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-rhenus-logistics.png\" alt=\"RHENUS - St\u00e9phane DIELAINE, Responsable Aduanas Francia\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">RHENUS - St\u00e9phane DIELAINE, Responsable Aduanas Francia<\/span><span class=\"elementor-testimonial__title\">Responsable aduanas Francia<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">04 \/ 05<\/span> <\/p>\n<p>Queremos agradecerles de coraz\u00f3n el esfuerzo especial que ponen en la gesti\u00f3n de nuestros expedientes (\u00a1sobre todo este fin de semana!). <\/p>\n<p>Podemos ser muy exigentes, pero estamos realmente contentos de colaborar con ustedes y su equipo!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/yormax-logo.png\" alt=\"YORMAX LOGISTIC SERVICES B.V - Marcel van Hengel\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">YORMAX LOGISTIC SERVICES B.V - Marcel van Hengel<\/span><span class=\"elementor-testimonial__title\">Fundador<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">05 \/ 05<\/span> <\/p>\n<p>ASD Group ha sabido aportarnos su experiencia tanto en la conformidad de nuestras declaraciones de IVA como en la conformidad de nuestras facturas de venta y sus particularidades en los pa\u00edses de Europa.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/robotshop-logo.png\" alt=\"ROBOTSHOP (Canad\u00e1) - Luc Pr\u00e9vost-Fournier\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">ROBOTSHOP (Canad\u00e1) - Luc Pr\u00e9vost-Fournier<\/span><span class=\"elementor-testimonial__title\">Contable adjunto<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51ac600 e-con-full e-flex e-con e-child\" data-id=\"51ac600\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7c651 elementor-widget elementor-widget-html\" data-id=\"4f7c651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a980db elementor-widget elementor-widget-html\" data-id=\"1a980db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f243fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f243fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb66925\" data-id=\"fb66925\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b7ef1 e-flex e-con-boxed e-con e-parent\" data-id=\"97b7ef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d55061c elementor-widget elementor-widget-html\" data-id=\"d55061c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06ff6e0 elementor-widget elementor-widget-html\" data-id=\"06ff6e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f38003a elementor-widget elementor-widget-heading\" data-id=\"f38003a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soluciones complementarias para acelerar tu crecimiento internacional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-699f893 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"699f893\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-463be6b\" data-id=\"463be6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e0e25c elementor-widget elementor-widget-heading\" data-id=\"3e0e25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">01<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4568719 elementor-widget elementor-widget-heading\" data-id=\"4568719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/controles-veterinaires-sanitaires-et-phytosanitaires-sps-sivep\/\">Acompa\u00f1amiento en controles veterinarios, SPS ante el SIVEP<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be2d518\" data-id=\"be2d518\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f13d8e elementor-widget elementor-widget-heading\" data-id=\"5f13d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">02<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f6ceae elementor-widget elementor-widget-heading\" data-id=\"0f6ceae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/intrastat-emebi\/\">Gesti\u00f3n de declaraciones Intrastat\/EMEBI<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-87814dc\" data-id=\"87814dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60507a0 elementor-widget elementor-widget-heading\" data-id=\"60507a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">03<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8d11d elementor-widget elementor-widget-heading\" data-id=\"1b8d11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/operateur-economique-agree-oea\/\">Asistencia para solicitudes de estatus OEA<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-918d638 e-flex e-con-boxed e-con e-parent\" data-id=\"918d638\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bf0aeb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8bf0aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asegura tus tr\u00e1mites aduaneros hoy mismo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1d99fb4 e-flex e-con-boxed e-con e-parent\" data-id=\"1d99fb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b850c8 elementor-widget elementor-widget-html\" data-id=\"3b850c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7450d2 elementor-widget elementor-widget-html\" data-id=\"b7450d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>INICIO &gt; NUESTROS SERVICIOS &gt; OPERACIONES Y OBLIGACIONES ADUANERAS &gt; TR\u00c1MITES Y DESPACHOS ADUANEROS Conf\u00eda en expertos para la gesti\u00f3n de tus tr\u00e1mites aduaneros TR\u00c1MITES&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"pays":[],"activites":[],"type_service":[],"class_list":["post-203310","service","type-service","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00e1mites aduaneros gestionados por expertos OEA &amp; RDE | ASD Group<\/title>\n<meta name=\"description\" content=\"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00e1mites aduaneros gestionados por expertos OEA &amp; RDE | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T11:04:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/\",\"name\":\"Tr\u00e1mites aduaneros gestionados por expertos OEA & RDE | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AEO-logo.png\",\"datePublished\":\"2026-01-30T08:05:38+00:00\",\"dateModified\":\"2026-04-30T11:04:47+00:00\",\"description\":\"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AEO-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AEO-logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/gestion-de-formalidades-y-despachos-aduaneros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conf\u00eda en expertos para gestionar tus tr\u00e1mites aduaneros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique su desarrollo internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00e1mites aduaneros gestionados por expertos OEA & RDE | ASD Group","description":"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/","og_locale":"es_ES","og_type":"article","og_title":"Tr\u00e1mites aduaneros gestionados por expertos OEA & RDE | ASD Group","og_description":"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.","og_url":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/","og_site_name":"ASD","article_modified_time":"2026-04-30T11:04:47+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/","url":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/","name":"Tr\u00e1mites aduaneros gestionados por expertos OEA & RDE | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png","datePublished":"2026-01-30T08:05:38+00:00","dateModified":"2026-04-30T11:04:47+00:00","description":"Tr\u00e1mites aduaneros, despacho aduanero, import-export: ASD Group te acompa\u00f1a con experiencia para operaciones r\u00e1pidas y sin complicaciones.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2026\/01\/AEO-logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/es\/gestion-de-formalidades-y-despachos-aduaneros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/es\/"},{"@type":"ListItem","position":2,"name":"Conf\u00eda en expertos para gestionar tus tr\u00e1mites aduaneros"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/es\/#website","url":"https:\/\/www.asd-int.com\/es\/","name":"ASD","description":"Simplifique su desarrollo internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/es\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/203310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":10,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/203310\/revisions"}],"predecessor-version":[{"id":212946,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/203310\/revisions\/212946"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/media?parent=203310"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/pays?post=203310"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/activites?post=203310"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/type_service?post=203310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}