{"id":45686,"date":"2019-08-09T17:26:38","date_gmt":"2019-08-09T15:26:38","guid":{"rendered":"https:\/\/www.asd-int.com\/service\/lintrastat-en-suede\/"},"modified":"2026-04-08T14:46:35","modified_gmt":"2026-04-08T12:46:35","slug":"intrastat-en-suecia","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/","title":{"rendered":"El Intrastat en Suecia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"45686\" class=\"elementor elementor-45686 elementor-43211\" data-elementor-post-type=\"service\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32cb18e8 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32cb18e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6da7d041\" data-id=\"6da7d041\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc6f1ae\" data-id=\"fc6f1ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79faf18a elementor-widget elementor-widget-text-editor\" data-id=\"79faf18a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.asd-int.com\/es\/\">ASD GROUP<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/es\/nuestros-servicios-por-pais\/\">NUESTROS SERVICIOS POR PA\u00cdS<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/es\/nuestros-servicios-en-suecia\/\">NUESTROS SERVICIOS EN SUECIA<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/es\/aduana\/\">ADUANA<\/a> &gt; INTRASTAT EN SUECIA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23408487 elementor-widget elementor-widget-heading\" data-id=\"23408487\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">El Intrastat en Suecia<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df3be72 elementor-widget elementor-widget-button\" data-id=\"5df3be72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfNecesita ayuda?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a05bbd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a05bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2770311d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2770311d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64d60370\" data-id=\"64d60370\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3808ae1a elementor-widget elementor-widget-html\" data-id=\"3808ae1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66ec01d5 elementor-widget elementor-widget-html\" data-id=\"66ec01d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ce150de elementor-widget elementor-widget-heading\" data-id=\"7ce150de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfEn qu\u00e9 consiste una declaraci\u00f3n Intrastat?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34e79106 elementor-widget elementor-widget-image\" data-id=\"34e79106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"193\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg\" class=\"attachment-large size-large wp-image-35774\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg 690w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203-300x100.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-496a5531 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"496a5531\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a619d75\" data-id=\"1a619d75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4cc564 elementor-widget elementor-widget-text-editor\" data-id=\"3b4cc564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<p>Les empresas establecidas o registradas en un Estado miembro de la Uni\u00f3n Europea que realizan intercambios intracomunitarios, tanto adquisiciones como entregas intracomunitarias, deben presentar INTRASTAT siempre cuando hayan superado los umbrales en dicho pa\u00eds, o sea el importe de compra o venta en dichas <strong>transacciones realizadas dentro del Mercado interior de la UE<\/strong>.<\/p>\n<p>Las declaraciones Intrastat est\u00e1n controladas por las autoridades estad\u00edsticas. Las declaraciones Intrastat deben presentarse de forma mensual y remitidas seg\u00fan un calendario definido por la Administraci\u00f3n Aduanas de cada pa\u00eds.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0cd9e6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f0cd9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/es\/umbrales-intrastat-deb-en-ue-2019\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONSULTAR LOS UMBRALES INTRASTAT EN VIGOR EN LA UNI\u00d3N EUROPEA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a317655 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a317655\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7992117b\" data-id=\"7992117b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c257682 elementor-widget elementor-widget-html\" data-id=\"3c257682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9c9eed elementor-widget elementor-widget-heading\" data-id=\"3b9c9eed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Intrastat en Suecia: informaci\u00f3n espec\u00edfica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-516f0e86 elementor-widget elementor-widget-text-editor\" data-id=\"516f0e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element  bloc_txt\"><div class=\"wpb_wrapper\"><p>Todos los a\u00f1os la \u00ab<a href=\"https:\/\/www.scb.se\/en\/\">Statistiska centralbyr\u00e5n<\/a>\u00bb (Statistics Sweden) publica un calendario indicando todos los plazos de presentaci\u00f3n de las declaraciones. Las declaraciones Intrastat alemanas deben presentarse en cuanto el <strong>importe de las transacciones intracomunitarias supera el umbral fijado por el c\u00f3digo aduanero INTRASTAT<\/strong>.<\/p><p>Si se supera el umbral de las entregas o de las adquisiciones intracomunitarias durante el a\u00f1o en curso, deber\u00e1n presentarse las declaraciones Intrastat durante el mes en el cual se super\u00f3 el umbral.<\/p><p>El hecho de no hacer un seguimiento de la evoluci\u00f3n de las adquisiciones (Flujo de mercanc\u00eda: Estado miembro de la \u2019UE hacia Suecia) o entregas intracomunitarias (Flujo de mercanc\u00eda: Suecia hacia otro Estado miembro de la UE) es exponerse a sanciones.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-610451fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"610451fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cec148a\" data-id=\"4cec148a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79c71175 elementor-widget elementor-widget-html\" data-id=\"79c71175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd33c92 elementor-widget elementor-widget-html\" data-id=\"3fd33c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73af20e4 elementor-widget elementor-widget-heading\" data-id=\"73af20e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Elegir ASD Group es elegir la seguridad y la simplicidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34cb8a4e elementor-widget elementor-widget-text-editor\" data-id=\"34cb8a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Uds tienen obligaci\u00f3n de presentar Intrastat en <span style=\"color: #000000;\">Suecia<\/span>, remirtirle sus facturas a ASD Group en plazo, por correo postal, email o subi\u00e9ndolas en nuestra plataforma y tendr\u00e1n presentados sus Intrastat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a99783 elementor-widget elementor-widget-image\" data-id=\"63a99783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"193\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_213291067.jpg\" class=\"attachment-large size-large wp-image-35787\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_213291067.jpg 690w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_213291067-300x100.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b29d906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b29d906\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-104187da\" data-id=\"104187da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ec9a4e elementor-widget elementor-widget-html\" data-id=\"37ec9a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74ddc848 elementor-widget elementor-widget-html\" data-id=\"74ddc848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff30bb4 elementor-widget elementor-widget-heading\" data-id=\"2ff30bb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASD Group les garantiza tranquilidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7177d6cc elementor-widget elementor-widget-text-editor\" data-id=\"7177d6cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos encargamos de todo; tanto de la conformidad de los datos como de los contactos con la Administraci\u00f3n Aduanas sueca.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd13846 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4fd13846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/asd-int.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Externalizar mi DEB\/Intrastat con ASD Group<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27f7f871 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27f7f871\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4314046a\" data-id=\"4314046a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9939141 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9939141\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59650834\" data-id=\"59650834\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce3ba0 elementor-widget elementor-widget-html\" data-id=\"3ce3ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f59bc6 elementor-widget elementor-widget-heading\" data-id=\"7f59bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ASD Group es elegir una empresa capaz de adaptarse a sus necesidades<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c6b1950 elementor-widget elementor-widget-text-editor\" data-id=\"1c6b1950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La forma de remitir sus datos, el nivel de intervenci\u00f3n, Uds deciden en funci\u00f3n de su capacidad a transmitir los datos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d98bccb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d98bccb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26569eb7\" data-id=\"26569eb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-262fe7e1 elementor-widget elementor-widget-html\" data-id=\"262fe7e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc02d18 elementor-widget elementor-widget-heading\" data-id=\"4bc02d18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n t\u00e9cnica<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77d44945 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77d44945\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5eb0045d\" data-id=\"5eb0045d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68ff6e0f elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68ff6e0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El <b>umbral Intrastat sueco<\/b> de las adquisiciones es de 15 000 000 SEK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El umbral Intrastat sueco de las entregas es de <span style=\"letter-spacing: -0.27px\">12 0<\/span>00 000 SEK<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La fecha l\u00edmite de presentaci\u00f3n es el d\u00eda 10 del mes siguiente al per\u00edodo de informe en papel y el d\u00eda 13 del mes siguiente al per\u00edodo de informe electr\u00f3nico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La no presentaci\u00f3n de las declaraciones Intrastat podr\u00e1 ocasionar sanciones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-890a175 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"890a175\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b80bf9a\" data-id=\"7b80bf9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1023b6aa elementor-widget elementor-widget-html\" data-id=\"1023b6aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b68a1ef elementor-widget elementor-widget-html\" data-id=\"2b68a1ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59445619 elementor-widget elementor-widget-heading\" data-id=\"59445619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contacte con nuestros expertos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352b9531 elementor-widget elementor-widget-heading\" data-id=\"352b9531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u00bfQuiere saber m\u00e1s sobre nuestras ofertas?<br \/>Contacte con nosotros y nuestros expertos responder\u00e1n r\u00e1pidamente.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274d1435 elementor-widget elementor-widget-shortcode\" data-id=\"274d1435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_18_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form3\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Mini contact<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"18\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_18\" id=\"frm_hide_fields_18\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form3\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_18\" name=\"frm_submit_entry_18\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/service\/45686\" \/><div id=\"frm_field_281_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_i41ef\" class=\"frm_primary_label\">Empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef\" name=\"item_meta[281]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_280_container\" class=\"frm_form_field form-field  frm_top_container frm_half relative frm_other_container\">\r\n    <label for=\"field_85w6d\" class=\"frm_primary_label\">Sector de actividad\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[280]\" id=\"field_85w6d\"  data-placeholder=\"\u00bfCu\u00e1l es su sector de actividad?\"  placeholder=\"\u00bfCu\u00e1l es su sector de actividad?\" data-invmsg=\"Sector de actividad no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">\u00bfCu\u00e1l es su sector de actividad?<\/option><option  value=\"Agroalimentaire\">Comida<\/option><option  value=\"Bois \/ Papier \/ Carton \/ Imprimerie\">Madera \/ Papel \/ Cart\u00f3n \/ Impresi\u00f3n<\/option><option  value=\"Chimie \/ Parachimie\">Chimie \/ Parachimie<\/option><option  value=\"Editions \/ Communication \/ Multim\u00e9dia\">Edici\u00f3n \/ Comunicaci\u00f3n \/ Multimedia<\/option><option  value=\"Etudes et conseils\">Etudes et conseils<\/option><option  value=\"Informatique \/ T\u00e9l\u00e9coms\">IT \/ Telecom<\/option><option  value=\"M\u00e9tallurgie \/ Travail du m\u00e9tal\">Metalurgia<\/option><option  value=\"Service aux entreprises\">Servicio de negocios<\/option><option  value=\"Transports \/ Logistique\">Transporte \/ Log\u00edstica<\/option><option  value=\"Banque \/ Assurance\">Banco \/ seguro<\/option><option  value=\"BTP \/ Mat\u00e9riaux de construction\">Construcci\u00f3n \/ Materiales de construcci\u00f3n<\/option><option  value=\"Commerce \/ N\u00e9goce \/ Distribution\">Comercio \/ Distribuci\u00f3n<\/option><option  value=\"Electronique \/ Electricit\u00e9\">Electr\u00f3nica \/ Electricidad<\/option><option  value=\"Industrie pharmaceutique\">Industria farmaceutica<\/option><option  value=\"Machine et \u00e9quipements \/ Automobile\">M\u00e1quinas y Equipos \/ Automoci\u00f3n<\/option><option  value=\"Plastique \/ Caoutchouc\">Pl\u00e1stico \/ caucho<\/option><option  value=\"Textile \/ Habillement \/ Chaussure\">Textil \/ Ropa<\/option><option  value=\"Otro sector\" class=\"frm_other_trigger\">Otro sector<\/option>\t<\/select>\n\t<label for=\"field_85w6d-otext\" class=\"frm_screen_reader frm_hidden\">Sector de actividad<\/label><input type=\"text\" id=\"field_85w6d-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][280]\" value=\"\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_246_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy4\" class=\"frm_primary_label\">Apellido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy4\" name=\"item_meta[246]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Apellido&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_247_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_ocfup14\" class=\"frm_primary_label\">Nombre\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup14\" name=\"item_meta[247]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Nombre&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_270_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc\" class=\"frm_primary_label\">Direcci\u00f3n de correo electr\u00f3nico\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc\" name=\"item_meta[270]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_279_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa2\" class=\"frm_primary_label\">Tel\u00e9fono\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa2\" name=\"item_meta[279]\" value=\"\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"El tel\u00e9fono no es v\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_276_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half relative\">\r\n    <label for=\"field_okuhn\" class=\"frm_primary_label\">Pa\u00eds de establecimiento de su empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[276]\" id=\"field_okuhn\"  data-placeholder=\"\u00bfD\u00f3nde est\u00e1 establecida su empresa?\"  placeholder=\"\u00bfD\u00f3nde est\u00e1 establecida su empresa?\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Pa\u00eds de establecimiento de su empresa no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">\u00bfD\u00f3nde est\u00e1 establecida su empresa?<\/option><option  value=\"AF\">Afganist\u00e1n<\/option><option  value=\"Afrique du Sud\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Alemania\n<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguila<\/option><option  value=\"AG\">Antigua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaiy\u00e1n<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Ben\u00edn<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botsuana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brun\u00e9i<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croacia\n<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chipre\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"Djibouti\">Yibuti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espa\u00f1a\n<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"Gabon\">Gab\u00f3n<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Hait\u00ed<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hungr\u00eda\n<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islandia\n<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Ir\u00e1n<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazajist\u00e1n<\/option><option  value=\"Kenya\">Kenia<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Letonia\n<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesoto<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malaui<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldivas<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malta<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavia<\/option><option  value=\"MA\">M\u00f3naco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambic<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">N\u00edger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"Oman\">Om\u00e1n<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakist\u00e1n<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestina<\/option><option  value=\"Panama\">Panam\u00e1<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Pap\u00faa Nueva Guinea<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Pa\u00edses Bajos<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Filipinas<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Katar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Ruanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Santo Tom\u00e9 y Pr\u00edncipe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leona<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Suazilandia<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiw\u00e1n<\/option><option  value=\"Tadjikistan\">Tadjikist\u00e1n<\/option><option  value=\"Tanzanie\">Tanzania<\/option><option  value=\"TD\">Chad<\/option><option  value=\"Tha\u00eflande\">Tailandia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinidad y Tobago<\/option><option  value=\"Tunisie\">T\u00fanez<\/option><option  value=\"Turquie\">Turqu\u00eda<\/option><option  value=\"Turkm\u00e9nistan\">Turkmenist\u00e1n<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucrania<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Yemen<\/option><option  value=\"Zambie\">Zambia<\/option><option  value=\"Zimbabwe\">Zimbabue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_278_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half relative\">\r\n    <label for=\"field_l1biv\" class=\"frm_primary_label\">Pa\u00eds donde quieres desarrollarte\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[278]\" id=\"field_l1biv\"  data-placeholder=\"\u00bfD\u00f3nde desea expandirse?\"  placeholder=\"\u00bfD\u00f3nde desea expandirse?\" data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"Pa\u00eds donde quieres desarrollarte no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">\u00bfD\u00f3nde desea expandirse?<\/option><option  value=\"AF\">Afganist\u00e1n<\/option><option  value=\"ZAF\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Alemania\n<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguila<\/option><option  value=\"AG\">Antigua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaiy\u00e1n<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Ben\u00edn<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botsuana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brun\u00e9i<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croacia\n<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chipre\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"Djibouti\">Yibuti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espa\u00f1a\n<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"Gabon\">Gab\u00f3n<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Hait\u00ed<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hungr\u00eda\n<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islandia\n<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Ir\u00e1n<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazajist\u00e1n<\/option><option  value=\"Kenya\">Kenia<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Letonia\n<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesoto<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malaui<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldivas<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malta<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavia<\/option><option  value=\"MA\">M\u00f3naco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambic<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">N\u00edger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"Oman\">Om\u00e1n<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakist\u00e1n<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestina<\/option><option  value=\"Panama\">Panam\u00e1<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Pap\u00faa Nueva Guinea<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Pa\u00edses Bajos<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Filipinas<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Katar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Ruman\u00eda<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Ruanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Santo Tom\u00e9 y Pr\u00edncipe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leona<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Eslovaquia<\/option><option  value=\"SI\">Eslovenia<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Suazilandia<\/option><option  value=\"SE\">Suecia<\/option><option  value=\"CH\">Suiza<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiw\u00e1n<\/option><option  value=\"Tadjikistan\">Tadjikist\u00e1n<\/option><option  value=\"Tanzanie\">Tanzania<\/option><option  value=\"TD\">Chad<\/option><option  value=\"Tha\u00eflande\">Tailandia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinidad y Tobago<\/option><option  value=\"Tunisie\">T\u00fanez<\/option><option  value=\"Turquie\">Turqu\u00eda<\/option><option  value=\"Turkm\u00e9nistan\">Turkmenist\u00e1n<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucrania<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Yemen<\/option><option  value=\"Zambie\">Zambia<\/option><option  value=\"Zimbabwe\">Zimbabue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_271_container\" class=\"frm_form_field form-field  frm_top_container frm_half frm_first\">\r\n    <label for=\"field_wtev7\" class=\"frm_primary_label\">Area de servicio\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[271]\" id=\"field_wtev7\"  data-placeholder=\"Elija un \u00e1rea de servicio\"  placeholder=\"Elija un \u00e1rea de servicio\" data-invmsg=\"Area de servicio no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija un \u00e1rea de servicio<\/option><option  value=\"Fiscal\">Fiscal<\/option><option  value=\"Douane\">Aduana<\/option><option  value=\"Social\">Normativa social<\/option><option  value=\"Strat\u00e9gie d&#039;entreprise\">Estrategia empresarial<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_272_container\" class=\"frm_form_field form-field  frm_top_container frm_half\">\r\n    <label for=\"field_rltwo\" class=\"frm_primary_label\">Tipo de servicio\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[272]\" id=\"field_rltwo\"  data-placeholder=\"Elija un tipo de servicio\"  placeholder=\"Elija un tipo de servicio\" data-invmsg=\"Tipo de servicio no es v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Elija un tipo de servicio<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representante Fiscal <\/option><option  value=\"Mandataire fiscal\">Mandatario Fiscal<\/option><option  value=\"Remboursement de TVA\">Reembolso de IVA<\/option><option  value=\"Vente \u00e0 distance \/ e-commerce\">Venta a Distancia \/ E-Commerce<\/option><option  value=\"Formation TVA intracommunautaire\">Formaci\u00f3n sobre IVA Intracomunitario<\/option><option  value=\"Audit fiscal TVA\">Auditor\u00eda Fiscal de IVA<\/option><option  value=\"Cr\u00e9ation d&#039;entreprise\">Creaci\u00f3n de empresa<\/option><option  value=\"Domiciliation\">Domiciliaci\u00f3n<\/option><option  value=\"Droits d&#039;accises\">Droits d&#039;accises<\/option><option  value=\"DEB \/ Intrastat\">Intrastat \/ Declaraci\u00f3n de intercambio de bienes<\/option><option  value=\"D\u00e9claration europ\u00e9enne de services\">Declaraci\u00f3n Europea de Servicios<\/option><option  value=\"Formation DEB\">Formaci\u00f3n DEB \/ DES \/ Intrastat<\/option><option  value=\"D\u00e9claration taxe TGAP\">TGAP (Declaraci\u00f3n Impuesto General Sobre Las Actividades Contaminantes)<\/option><option  value=\"Accompagnement op\u00e9rations douani\u00e8res\">Obligaciones Aduaneras<\/option><option  value=\"Remboursement taxe TICPE (ex TIPP)\">El impuesto interno de consumo sobre los productos energ\u00e9ticos (TICPE, por sus iniciales en franc\u00e9s)<\/option><option  value=\"D\u00e9tachement de travailleurs \u00e9trangers\">Desplazamiento de trabajadores<\/option><option  value=\"Repr\u00e9sentation de firme \u00e9trang\u00e8re\">Representaci\u00f3n de una empresa extranjera<\/option><option  value=\"Le pr\u00e9l\u00e8vement \u00e0 la source en France pour les entreprises \u00e9trang\u00e8res\">La retenci\u00f3n fiscal en francia<\/option><option  value=\"Repr\u00e9sentation\/Conformit\u00e9 RGPD\">Repr\u00e9sentation\/Conformit\u00e9 RGPD<\/option><option  value=\"Contr\u00f4les SIVEP\/SPS\">Contr\u00f4les SIVEP\/SPS<\/option><option  value=\"Formulaires W-8 et W-9 aux \u00c9tats-Unis\">Formularios W-8 y W-9 en los Estados Unidos<\/option><option  value=\"&quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Impuesto sobre ventas y uso en Estados Unidos<\/option><option  value=\"Certification employeur non-r\u00e9sident au Canada\">Certificaci\u00f3n de empleador no residente en Canad\u00e1<\/option><option  value=\"Dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents au Canada\">Exenci\u00f3n de retenci\u00f3n de impuestos para empleadores no residentes en Canad\u00e1<\/option><option  value=\"Taxes TPS\/TVH\/TVP au Canada\">Taxes TPS\/TVH\/TVP au Canada<\/option><option  value=\"Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne\">Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne<\/option><option  value=\"Autre service\">Otro servicio<\/option><option  value=\"Je ne suis pas s\u00fbr (e)\">No estoy seguro<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_275_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_bz8k1\" class=\"frm_primary_label\">Describe tu necesidad\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[275]\" id=\"field_bz8k1\" rows=\"5\"  data-reqmsg=\"Este campo es obligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Explica brevemente tu necesidad&quot; no es v\u00e1lido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_476_container\" class=\"frm_form_field  frm_html_container form-field\">Este sitio est\u00e1 protegido por reCAPTCHA y se aplican la <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">pol\u00edtica de privacidad<\/a> y los <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">t\u00e9rminos del servicio<\/a> de Google.<\/div>\n<div id=\"frm_field_299_container\" class=\"frm_form_field form-field  frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Bolet\u00edn\n\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_299-0\">\t\t\t<label  for=\"field_e2sgs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[299][]\" id=\"field_e2sgs-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Bolet\u00edn\n no es v\u00e1lido\"   \/> Me gustar\u00eda recibir los boletines de noticias de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_300_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">GDPR\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_300-0\">\t\t\t<label  for=\"field_y30e2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[300][]\" id=\"field_y30e2-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"Este campo no puede estar vac\u00edo.\n\" data-invmsg=\"GDPR no es v\u00e1lido\"   aria-required=\"true\"  \/> Al solicitar el formulario, acepto que la  informaci\u00f3n sea procesada y pueda dar lugar a una relaci\u00f3n profesional. Para conocer y ejercer sus derechos y especialmente respeto al consentimiento y al uso de sus datos ,le invitamos a consultar nuestras menciones legales en la parte abajo de esa p\u00e1gina.<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_404_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\"><\/div>\n<div id=\"frm_field_509_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[519]\" id=\"field_8qg9b\" value=\"\"     \/>\n\t\t<div id=\"frm_field_573_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Enviar<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_3grqc\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_3grqc\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg5zcco4tBF6TZPoEOTS7G94Rf47cWeREW\/Dr8\/hOmUqx\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt; NUESTROS SERVICIOS POR PA\u00cdS &gt; NUESTROS SERVICIOS EN SUECIA &gt; ADUANA &gt; INTRASTAT EN SUECIA El Intrastat en Suecia \u00bfNecesita ayuda? \u00bfEn&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"pays":[1191],"activites":[1193],"type_service":[1335],"class_list":["post-45686","service","type-service","status-publish","format-standard","hentry","pays-suede-es","activites-douane-es","type_service-deb-declaracion-de-intercambio-de-bienes-intrastat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Intrastat en Suecia | ASD Group<\/title>\n<meta name=\"description\" content=\"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\/Intrastat con ASD Group.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Intrastat en Suecia | ASD Group\" \/>\n<meta property=\"og:description\" content=\"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\/Intrastat con ASD Group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T12:46:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/\",\"name\":\"El Intrastat en Suecia | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_218105203.jpg\",\"datePublished\":\"2019-08-09T15:26:38+00:00\",\"dateModified\":\"2026-04-08T12:46:35+00:00\",\"description\":\"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\\\/Intrastat con ASD Group.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_218105203.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_218105203.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/intrastat-suecia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intrastat en Suecia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique su desarrollo internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Intrastat en Suecia | ASD Group","description":"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\/Intrastat con ASD Group.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/","og_locale":"es_ES","og_type":"article","og_title":"El Intrastat en Suecia | ASD Group","og_description":"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\/Intrastat con ASD Group.","og_url":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/","og_site_name":"ASD","article_modified_time":"2026-04-08T12:46:35+00:00","og_image":[{"width":690,"height":230,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/","url":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/","name":"El Intrastat en Suecia | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg","datePublished":"2019-08-09T15:26:38+00:00","dateModified":"2026-04-08T12:46:35+00:00","description":"\u00bfUds tienen obligaci\u00f3n de presentar Intrastat en Suecia? Externalice su DEB\/Intrastat con ASD Group.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/es\/intrastat-suecia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_218105203.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/es\/intrastat-suecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/es\/"},{"@type":"ListItem","position":2,"name":"Intrastat en Suecia"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/es\/#website","url":"https:\/\/www.asd-int.com\/es\/","name":"ASD","description":"Simplifique su desarrollo internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/es\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/45686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":8,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/45686\/revisions"}],"predecessor-version":[{"id":209628,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/service\/45686\/revisions\/209628"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/media?parent=45686"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/pays?post=45686"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/activites?post=45686"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/es\/wp-json\/wp\/v2\/type_service?post=45686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}