{"id":3509,"date":"2018-03-22T23:14:50","date_gmt":"2018-03-22T22:14:50","guid":{"rendered":"https:\/\/www.asd-int.com\/?page_id=3509"},"modified":"2022-06-23T11:48:39","modified_gmt":"2022-06-23T09:48:39","slug":"sedi-canada-servizio-fiscale-doganale-gestione-dipendenti-all-estero","status":"publish","type":"page","link":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/","title":{"rendered":"I nostri servizi in Canada"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3509\" class=\"elementor elementor-3509 elementor-525\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6884fe52 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6884fe52\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c1ff5a5\" data-id=\"5c1ff5a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66433aea\" data-id=\"66433aea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-733bcd4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"733bcd4\" data-element_type=\"section\" data-e-type=\"section\" id=\"asd_title_country\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-42ff921c\" data-id=\"42ff921c\" data-element_type=\"column\" data-e-type=\"column\" id=\"asd_discover_title\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1e4fb elementor-widget elementor-widget-text-editor\" data-id=\"0d1e4fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asd-int.com\/it\/\">ASD GROUP<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-per-paese\/\">I NOSTRI SERVIZI PER PAESE<\/a> &gt; CANADA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0863ab elementor-widget elementor-widget-heading\" data-id=\"7b0863ab\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"asd_title_discover\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Scoprite i nostri servizi:<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-34dd72a9\" data-id=\"34dd72a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a031043 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"5a031043\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"pays_menu_country_asd\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-5a031043\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58345\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Pays<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-144981\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-australia\/\" class=\"elementor-sub-item\">Australia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58347\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-austria\/\" class=\"elementor-sub-item\">Austria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58383\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-belgio\/\" class=\"elementor-sub-item\">Belgio<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58384\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-bulgaria\/\" class=\"elementor-sub-item\">Bulgaria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58385\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/\" class=\"elementor-sub-item\">Canada<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129215\"><a href=\"https:\/\/www.asd-int.com\/it\/?page_id=116474\" class=\"elementor-sub-item\">Cina<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58386\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-cipro\/\" class=\"elementor-sub-item\">Cipro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58429\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-croazia\/\" class=\"elementor-sub-item\">Croazia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58430\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-danimarca\/\" class=\"elementor-sub-item\">Danimarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58465\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-estonia\/\" class=\"elementor-sub-item\">Estonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58467\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-finlandia\/\" class=\"elementor-sub-item\">Finlandia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58468\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-francia\/\" class=\"elementor-sub-item\">Francia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58346\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-germania\/\" class=\"elementor-sub-item\">Germania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58469\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-grecia\/\" class=\"elementor-sub-item\">Grecia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129214\"><a href=\"https:\/\/www.asd-int.com\/it\/?page_id=116544\" class=\"elementor-sub-item\">Indonesia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58551\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-irlanda\/\" class=\"elementor-sub-item\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58552\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-italia\/\" class=\"elementor-sub-item\">Italia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58587\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lettonia\/\" class=\"elementor-sub-item\">Lettonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58588\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lituania\/\" class=\"elementor-sub-item\">Lituania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129217\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lussemburgo\/\" class=\"elementor-sub-item\">Lussemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58589\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-malta\/\" class=\"elementor-sub-item\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58590\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-marocco\/\" class=\"elementor-sub-item\">Marocco<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58650\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-norvegia\/\" class=\"elementor-sub-item\">Norvegia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58651\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-nei-paesi-bassi\/\" class=\"elementor-sub-item\">Paesi Bassi<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58652\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-polonia\/\" class=\"elementor-sub-item\">Polonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58653\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-portogallo\/\" class=\"elementor-sub-item\">Portogallo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58693\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-nel-regno-unito\/\" class=\"elementor-sub-item\">Regno Unito<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58691\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-repubblica-ceca\/\" class=\"elementor-sub-item\">Repubblica Ceca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58692\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-romania\/\" class=\"elementor-sub-item\">Romania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129213\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-singapore\/\" class=\"elementor-sub-item\">Singapore<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58694\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-slovacchia\/\" class=\"elementor-sub-item\">Slovacchia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58723\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-slovenia\/\" class=\"elementor-sub-item\">Slovenia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58432\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-spagna\/\" class=\"elementor-sub-item\">Spagna<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58466\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-negli-stati-uniti\/\" class=\"elementor-sub-item\">Stati Uniti<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58724\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-svezia\/\" class=\"elementor-sub-item\">Svezia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58725\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-svizzera\/\" class=\"elementor-sub-item\">Svizzera<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58549\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-ungheria\/\" class=\"elementor-sub-item\">Ungheria<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu di commutazione\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5a031043\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58345\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Pays<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-144981\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-australia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Australia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58347\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-austria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Austria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58383\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-belgio\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Belgio<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58384\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-bulgaria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bulgaria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58385\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Canada<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129215\"><a href=\"https:\/\/www.asd-int.com\/it\/?page_id=116474\" class=\"elementor-sub-item\" tabindex=\"-1\">Cina<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58386\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-cipro\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cipro<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58429\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-croazia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Croazia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58430\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-danimarca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Danimarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58465\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-estonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Estonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58467\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-finlandia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Finlandia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58468\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-francia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Francia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58346\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-germania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Germania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58469\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-grecia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Grecia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129214\"><a href=\"https:\/\/www.asd-int.com\/it\/?page_id=116544\" class=\"elementor-sub-item\" tabindex=\"-1\">Indonesia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58551\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-irlanda\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58552\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-italia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Italia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58587\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lettonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lettonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58588\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lituania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lituania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129217\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-lussemburgo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lussemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58589\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-malta\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58590\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-marocco\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Marocco<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58650\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-norvegia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Norvegia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58651\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-nei-paesi-bassi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Paesi Bassi<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58652\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-polonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Polonia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58653\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-portogallo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Portogallo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58693\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-nel-regno-unito\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Regno Unito<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58691\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-repubblica-ceca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Repubblica Ceca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58692\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-romania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Romania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129213\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-a-singapore\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Singapore<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58694\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-slovacchia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Slovacchia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58723\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-slovenia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Slovenia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58432\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-spagna\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Spagna<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58466\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-negli-stati-uniti\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Stati Uniti<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58724\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-svezia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Svezia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58725\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-svizzera\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Svizzera<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58549\"><a href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-ungheria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ungheria<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c0fe137 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2c0fe137\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-25c12f05\" data-id=\"25c12f05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f72dc2b elementor-widget elementor-widget-text-editor\" data-id=\"2f72dc2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tASD Group ti supporta in ogni fase<br \/>del processo del tuo sviluppo internazionale<br \/>offrendo una competenza su misura.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f220a28\" data-id=\"7f220a28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2cc1dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2cc1dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c8f8f1c\" data-id=\"3c8f8f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e28b649 elementor-widget elementor-widget-image\" data-id=\"7e28b649\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54182\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7d3b4d test-caca elementor-widget elementor-widget-heading\" data-id=\"5d7d3b4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Servizi disponibili in Canada<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1031cab4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1031cab4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d49baf\" data-id=\"6d49baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-594c3f2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"594c3f2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-61808046\" data-id=\"61808046\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-312a14ab elementor-tabs-view-vertical menu_service_asd elementor-widget elementor-widget-tabs\" data-id=\"312a14ab\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"menu_service_3\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-8241\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8241\" aria-expanded=\"false\">FISCALIT\u00c0<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-8241\" aria-expanded=\"false\">FISCALIT\u00c0<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8241\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8241\" tabindex=\"0\" hidden=\"false\"><div class=\"menu-canada-fiscal-it-container\"><ul id=\"menu-canada-fiscal-it\" class=\"menu\"><li id=\"menu-item-117239\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-117239\"><a href=\"https:\/\/www.asd-int.com\/it\/identificarsi-fiscalmente-in-un-paese-al-di-fuori-dell-unione-europea\/\">Identificarsi fiscalmente in un paese al di fuori dell\u2019Unione Europea<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3930ba71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3930ba71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36cdbf54\" data-id=\"36cdbf54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b95d670 elementor-widget elementor-widget-image\" data-id=\"2b95d670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54182\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d056fdc test-caca elementor-widget elementor-widget-heading\" data-id=\"d056fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contatta i nostri esperti<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78269e83 elementor-widget elementor-widget-heading\" data-id=\"78269e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Vuoi\u00a0saperne di pi\u00f9\u00a0sulle nostre offerte?<br \/>Contattaci\u00a0e i nostri esperti risponderanno il prima possibile.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ac3579 elementor-widget elementor-widget-shortcode\" data-id=\"36ac3579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_18_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form3\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Mini contact<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"18\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_18\" id=\"frm_hide_fields_18\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form3\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_18\" name=\"frm_submit_entry_18\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/3509\" \/><div id=\"frm_field_281_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_i41ef\" class=\"frm_primary_label\">Azienda\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef\" name=\"item_meta[281]\" value=\"\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_280_container\" class=\"frm_form_field form-field  frm_top_container frm_half relative frm_other_container\">\r\n    <label for=\"field_85w6d\" class=\"frm_primary_label\">Settore di attivit\u00e0\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[280]\" id=\"field_85w6d\"  data-placeholder=\"Qual \u00e8 il tuo settore di attivit\u00e0?\"  placeholder=\"Qual \u00e8 il tuo settore di attivit\u00e0?\" data-invmsg=\"Settore di attivit\u00e0 non \u00e8 valido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Qual \u00e8 il tuo settore di attivit\u00e0?<\/option><option  value=\"Agroalimentaire\">Cibo<\/option><option  value=\"Bois \/ Papier \/ Carton \/ Imprimerie\">Legno \/ Carta \/ Cartone \/ Stampa<\/option><option  value=\"Chimie \/ Parachimie\">Chimie \/ Parachimie<\/option><option  value=\"Editions \/ Communication \/ Multim\u00e9dia\">Edizione \/ Comunicazione \/ Multimedia<\/option><option  value=\"Etudes et conseils\">Etudes et conseils<\/option><option  value=\"Informatique \/ T\u00e9l\u00e9coms\">IT \/ Telecom<\/option><option  value=\"M\u00e9tallurgie \/ Travail du m\u00e9tal\">Metallurgia<\/option><option  value=\"Service aux entreprises\">Servizio commerciale<\/option><option  value=\"Transports \/ Logistique\">Trasporto \/ Logistica<\/option><option  value=\"Banque \/ Assurance\">Banca \/ Assicurazione<\/option><option  value=\"BTP \/ Mat\u00e9riaux de construction\">Costruzione \/ materiali da costruzione<\/option><option  value=\"Commerce \/ N\u00e9goce \/ Distribution\">Commercio \/ Distribuzione<\/option><option  value=\"Electronique \/ Electricit\u00e9\">Elettronica \/ Elettricit\u00e0<\/option><option  value=\"Industrie pharmaceutique\">Industria farmaceutica<\/option><option  value=\"Machine et \u00e9quipements \/ Automobile\">Macchine e attrezzature \/ Automotive<\/option><option  value=\"Plastique \/ Caoutchouc\">Plastica \/ gomma<\/option><option  value=\"Textile \/ Habillement \/ Chaussure\">Tessile \/ Abbigliamento<\/option><option  value=\"Altro settore\" class=\"frm_other_trigger\">Altro settore<\/option>\t<\/select>\n\t<label for=\"field_85w6d-otext\" class=\"frm_screen_reader frm_hidden\">Settore di attivit\u00e0<\/label><input type=\"text\" id=\"field_85w6d-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][280]\" value=\"\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_246_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy4\" class=\"frm_primary_label\">Cognome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy4\" name=\"item_meta[246]\" value=\"\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Cognome&quot; non \u00e8 valido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_247_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_ocfup14\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup14\" name=\"item_meta[247]\" value=\"\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Nome&quot; non \u00e8 valido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_270_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc\" class=\"frm_primary_label\">Indirizzo e-mail\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc\" name=\"item_meta[270]\" value=\"\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_279_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa2\" class=\"frm_primary_label\">Telefono\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa2\" name=\"item_meta[279]\" value=\"\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"Il numero di telefono non \u00e8 valido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_276_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half relative\">\r\n    <label for=\"field_okuhn\" class=\"frm_primary_label\"> Paese di stabilimento della tua azienda\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[276]\" id=\"field_okuhn\"  data-placeholder=\"Dove \u00e8 stabilita la tua azienda?\"  placeholder=\"Dove \u00e8 stabilita la tua azienda?\" data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\" Paese di stabilimento della tua azienda non \u00e8 valido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Dove \u00e8 stabilita la tua azienda?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"Afrique du Sud\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Germania\n<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Antigua-Et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgio\n<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Cile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croazia\n<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Cipro\n<\/option><option  value=\"DK\">Danimarca\n<\/option><option  value=\"Djibouti\">Gibuti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Spagna\n<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"US\">stati Uniti<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibilterra<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Ungheria\n<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islanda\n<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakistan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonia\n<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Lussemburgo<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldive<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malta<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavia<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambico<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norvegia<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestina<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nuova Guinea<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Olanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Filippine<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portogallo<\/option><option  value=\"Puerto Rico\">Porto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Romania<\/option><option  value=\"GB\">UK<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Ruanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome e Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovacchia<\/option><option  value=\"SI\">Slovenia<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Svezia<\/option><option  value=\"CH\">Svizzera<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanzania<\/option><option  value=\"TD\">Chad<\/option><option  value=\"Tha\u00eflande\">Tailandia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinity e Tobago<\/option><option  value=\"Tunisie\">Tunisia<\/option><option  value=\"Turquie\">Turchia<\/option><option  value=\"Turkm\u00e9nistan\">Turkmenistan<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucraina<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Yemen<\/option><option  value=\"Zambie\">Zambia<\/option><option  value=\"Zimbabwe\">Zimbabwe<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_278_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half relative\">\r\n    <label for=\"field_l1biv\" class=\"frm_primary_label\">Paese in cui vuoi svilupparti\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[278]\" id=\"field_l1biv\"  data-placeholder=\"Dove desideri espanderti?\"  placeholder=\"Dove desideri espanderti?\" data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"Paese in cui vuoi svilupparti non \u00e8 valido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Dove desideri espanderti?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"ZAF\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Germania\n<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Antigua-Et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgio\n<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgaria\n<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Cile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croazia\n<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Cipro\n<\/option><option  value=\"DK\">Danimarca\n<\/option><option  value=\"Djibouti\">Gibuti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Spagna\n<\/option><option  value=\"EE\">Estonia\n<\/option><option  value=\"US\">stati Uniti<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlandia\n<\/option><option  value=\"FR\">Francia\n<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibilterra<\/option><option  value=\"GR\">Grecia\n<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Ungheria\n<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islanda\n<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italia\n<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakistan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonia\n<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein\n<\/option><option  value=\"LT\">Lituania\n<\/option><option  value=\"LU\">Lussemburgo<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldive<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malta<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavia<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambico<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norvegia<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestina<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nuova Guinea<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Olanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Filippine<\/option><option  value=\"PL\">Polonia<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portogallo<\/option><option  value=\"Puerto Rico\">Porto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Romania<\/option><option  value=\"GB\">UK<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Ruanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome e Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovacchia<\/option><option  value=\"SI\">Slovenia<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Svezia<\/option><option  value=\"CH\">Svizzera<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanzania<\/option><option  value=\"TD\">Chad<\/option><option  value=\"Tha\u00eflande\">Tailandia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinity e Tobago<\/option><option  value=\"Tunisie\">Tunisia<\/option><option  value=\"Turquie\">Turchia<\/option><option  value=\"Turkm\u00e9nistan\">Turkmenistan<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucraina<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Yemen<\/option><option  value=\"Zambie\">Zambia<\/option><option  value=\"Zimbabwe\">Zimbabwe<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_271_container\" class=\"frm_form_field form-field  frm_top_container frm_half frm_first\">\r\n    <label for=\"field_wtev7\" class=\"frm_primary_label\">Area di servizio\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[271]\" id=\"field_wtev7\"  data-placeholder=\"Scegliere un&#039;area di servizio\"  placeholder=\"Scegliere un&#039;area di servizio\" data-invmsg=\"Area di servizio non \u00e8 valido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Scegliere un&#039;area di servizio<\/option><option  value=\"Fiscal\">Fiscalit\u00e0<\/option><option  value=\"Douane\">Dogana<\/option><option  value=\"Social\">Regolamenti sociali<\/option><option  value=\"Strat\u00e9gie d&#039;entreprise\">Strategia d&#039;impresa<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_272_container\" class=\"frm_form_field form-field  frm_top_container frm_half\">\r\n    <label for=\"field_rltwo\" class=\"frm_primary_label\">Tipo di servizio\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[272]\" id=\"field_rltwo\"  data-placeholder=\"Scegliere un tipo di servizio\"  placeholder=\"Scegliere un tipo di servizio\" data-invmsg=\"Tipo di servizio non \u00e8 valido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Scegliere un tipo di servizio<\/option><option  value=\"Repr\u00e9sentation fiscale\">Rappresentante fiscale<\/option><option  value=\"Mandataire fiscal\"> intermediario per l&#039;identificazione diretta<\/option><option  value=\"Remboursement de TVA\">Rimborso IVA<\/option><option  value=\"Vente \u00e0 distance \/ e-commerce\">Vendite a distanza - E-Commerce<\/option><option  value=\"Formation TVA intracommunautaire\">Formazione IVA intracomunitaria<\/option><option  value=\"Audit fiscal TVA\">Auditing IVA<\/option><option  value=\"Cr\u00e9ation d&#039;entreprise\">Creazione di Societa<\/option><option  value=\"Domiciliation\">Domiciliazone<\/option><option  value=\"Droits d&#039;accises\">Accise per la vendita a distanza di bevande alcoliche <\/option><option  value=\"DEB \/ Intrastat\">Intrastat DEB Dichiarazione di scambio di beni<\/option><option  value=\"D\u00e9claration europ\u00e9enne de services\">Dichiarazione di scambio di servizi<\/option><option  value=\"Formation DEB\">Formazione DEB \/ DES \/ Intrastat<\/option><option  value=\"D\u00e9claration taxe TGAP\">Imposta generale sulle attivita inquinanti (TGAP)<\/option><option  value=\"Accompagnement op\u00e9rations douani\u00e8res\">Adempimenti Doganali <\/option><option  value=\"Remboursement taxe TICPE (ex TIPP)\">Imposta interna francese sul consumo di prodotti energetici<\/option><option  value=\"D\u00e9tachement de travailleurs \u00e9trangers\">Distacco di dipendenti<\/option><option  value=\"Repr\u00e9sentation de firme \u00e9trang\u00e8re\">Rappresentanza di un&#039;azienda straniera<\/option><option  value=\"Le pr\u00e9l\u00e8vement \u00e0 la source en France pour les entreprises \u00e9trang\u00e8res\">La ritenuta di imposta alla fonte in francia<\/option><option  value=\"Repr\u00e9sentation\/Conformit\u00e9 RGPD\">Repr\u00e9sentation\/Conformit\u00e9 RGPD<\/option><option  value=\"Contr\u00f4les SIVEP\/SPS\">Contr\u00f4les SIVEP\/SPS<\/option><option  value=\"Formulaires W-8 et W-9 aux \u00c9tats-Unis\">Moduli W-8 e W-9 negli Stati Uniti<\/option><option  value=\"&quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Tassa sulle vendite e sull\u2019uso negli Stati Uniti<\/option><option  value=\"Certification employeur non-r\u00e9sident au Canada\">Certificazione datore di lavoro non residente in Canada<\/option><option  value=\"Dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents au Canada\">Esenzione dalla ritenuta fiscale per datori di lavoro non residenti in Canada<\/option><option  value=\"Taxes TPS\/TVH\/TVP au Canada\">Taxes TPS\/TVH\/TVP au Canada<\/option><option  value=\"Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne\">Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne<\/option><option  value=\"Autre service\">Altro servizio<\/option><option  value=\"Je ne suis pas s\u00fbr (e)\">Non sono sicuro<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_275_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_bz8k1\" class=\"frm_primary_label\">Descrivi le tue necessit\u00e0\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[275]\" id=\"field_bz8k1\" rows=\"5\"  data-reqmsg=\"Il campo \u00e8 obbligatorio\" aria-required=\"true\" data-invmsg=\"&quot;Spiega brevemente la tua esigenza&quot; non \u00e8 valido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_476_container\" class=\"frm_form_field  frm_html_container form-field\">Questo sito \u00e8 protetto da reCAPTCHA e la <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">Privacy Policy<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">Terms of Service<\/a> di Google.<\/div>\n<div id=\"frm_field_299_container\" class=\"frm_form_field form-field  frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_299-0\">\t\t\t<label  for=\"field_e2sgs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[299][]\" id=\"field_e2sgs-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter non \u00e8 valido\"   \/> Desidero ricevere informazioni di qualit\u00e0<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_300_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_300-0\">\t\t\t<label  for=\"field_y30e2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[300][]\" id=\"field_y30e2-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"Questo campo non pu\u00f2 essere vuoto.\n\" data-invmsg=\"RGPD non \u00e8 valido\"   aria-required=\"true\"  \/> Inviando il presente modulo, acconsento all'utilizzo delle informazioni nel contesto dell'applicazione o di eventualli partnership lavorative. Per conoscere o esercitare i Suoi diritti, incluso i ritiro dell consenso all'utilizzo dei dati nel presente, La preghiamo di leggere l'avvertenza legale in fondo alla presente pagina.<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_404_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\"><\/div>\n<div id=\"frm_field_509_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[519]\" id=\"field_8qg9b\" value=\"\"     \/>\n\t\t<div id=\"frm_field_573_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Consegnare<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_tokna\" >\n\t\t\t\tSe sei un essere umano, lascia questo campo vuoto.\t\t\t<\/label>\n\t\t\t<input  id=\"field_tokna\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg+Zsno\/8GzoZv\/Bj\/xxzkRdtP3dNP4JcUpwDCQwP9r6x\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cc70bcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cc70bcd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7093cdb1\" data-id=\"7093cdb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0ce6b elementor-widget elementor-widget-shortcode\" data-id=\"1f0ce6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script type=\"text\/javascript\">\r\n\r\nlet defaultMenu = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"elementor-item-anchor\");\r\nlet current_item = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"current_page_item \");\r\n\r\ndefaultMenu[0].innerText = current_item[0].innerText;\r\n\r\n<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt; I NOSTRI SERVIZI PER PAESE &gt; CANADA Scoprite i nostri servizi: ASD Group ti supporta in ogni fasedel processo del tuo sviluppo&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"parent":3047,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"class_list":["post-3509","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I nostri servizi in Canada | ASD Group<\/title>\n<meta name=\"description\" content=\"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all&#039;estero, ti propone un servizio di rappresentanza fiscale nel Canada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I nostri servizi in Canada | ASD Group\" \/>\n<meta property=\"og:description\" content=\"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all&#039;estero, ti propone un servizio di rappresentanza fiscale nel Canada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-23T09:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/\",\"name\":\"I nostri servizi in Canada | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"datePublished\":\"2018-03-22T22:14:50+00:00\",\"dateModified\":\"2022-06-23T09:48:39+00:00\",\"description\":\"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all'estero, ti propone un servizio di rappresentanza fiscale nel Canada\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/i-nostri-servizi-in-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenzie\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/agenzie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I nostri servizi in Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"name\":\"ASD\",\"description\":\"Semplifica il tuo sviluppo nel mondo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I nostri servizi in Canada | ASD Group","description":"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all'estero, ti propone un servizio di rappresentanza fiscale nel Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/","og_locale":"it_IT","og_type":"article","og_title":"I nostri servizi in Canada | ASD Group","og_description":"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all'estero, ti propone un servizio di rappresentanza fiscale nel Canada","og_url":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/","og_site_name":"ASD","article_modified_time":"2022-06-23T09:48:39+00:00","og_image":[{"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/","url":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/","name":"I nostri servizi in Canada | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","datePublished":"2018-03-22T22:14:50+00:00","dateModified":"2022-06-23T09:48:39+00:00","description":"ASD Group, specializzata nei settori fiscale, doganale e nella gestione di dipendenti all'estero, ti propone un servizio di rappresentanza fiscale nel Canada","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/it\/i-nostri-servizi-in-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/it\/"},{"@type":"ListItem","position":2,"name":"Agenzie","item":"https:\/\/www.asd-int.com\/it\/agenzie\/"},{"@type":"ListItem","position":3,"name":"I nostri servizi in Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/it\/#website","url":"https:\/\/www.asd-int.com\/it\/","name":"ASD","description":"Semplifica il tuo sviluppo nel mondo","publisher":{"@id":"https:\/\/www.asd-int.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/it\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pages\/3509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/comments?post=3509"}],"version-history":[{"count":2,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pages\/3509\/revisions"}],"predecessor-version":[{"id":137805,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pages\/3509\/revisions\/137805"}],"up":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pages\/3047"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/media?parent=3509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}