{"id":124895,"date":"2022-02-18T15:16:49","date_gmt":"2022-02-18T14:16:49","guid":{"rendered":"https:\/\/www.asd-int.com\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/"},"modified":"2022-02-21T13:55:51","modified_gmt":"2022-02-21T12:55:51","slug":"nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022","status":"publish","type":"post","link":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/","title":{"rendered":"Nuova normativa in materia di distacco dei trasportatori su strada in vigore a decorrere dal 2 febbraio 2022"},"content":{"rendered":"\n<p>Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?<\/p>\n\n<!--more-->\n\n<p>Come annunciato il 31 luglio 2020, in occasione della pubblicazione nella Gazzetta ufficiale dell&#8217;UE, le <strong>misure previste dalla riforma del pacchetto mobilit\u00e0 sono entrate in vigore il 2 febbraio 2022 influendo sui professionisti del settore dei trasporti<\/strong>.<\/p>\n\n<p>In effetti, questa nuova normativa apporta dei profondi cambiamenti alle norme che disciplinano il settore del trasporto su strada. Uno degli obiettivi delle nuove norme \u00e8 quello di combattere l&#8217;evasione e il lavoro illegale per proteggere i trasportatori su strada.<\/p>\n\n<p>La <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/?uri=CELEX%3A32020L1057\">direttiva 2020\/1057<\/a> (nota come &#8220;LEX SPECIALIS&#8221;) <em>(in francese)<\/em> del Parlamento europeo e del Consiglio del 15\/07\/2020 stabilisce norme specifiche sul distacco dei conducenti nel settore del trasporto su strada e rappresenta un elemento cruciale del &#8220;Pacchetto mobilit\u00e0 I&#8221;.<\/p>\n\n<h2 class=\"wp-block-heading\">Qual \u00e8 l&#8217;ambito di applicazione di questa nuova direttiva?<\/h2>\n\n<h3 class=\"wp-block-heading\">A chi si applica la direttiva?<\/h3>\n\n<p>La direttiva si applica a tutti i conducenti nel settore del trasporto su strada di merci o passeggeri.<\/p>\n\n<h3 class=\"wp-block-heading\">Eccezioni alla direttiva<\/h3>\n\n<p><strong>Un conducente non \u00e8 considerato distaccato ai fini della direttiva<\/strong>, ovvero non \u00e8 tenuto a trasmettere una dichiarazione di distacco attraverso la nuova interfaccia europea, nei seguenti casi:<\/p>\n\n<ul class=\"wp-block-list\"><li>Quando effettua operazioni di trasporto bilaterale con riguardo alle merci (trasporto bilaterale di merci);<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Quando transita attraverso uno Stato membro senza effettuarvi operazioni di carico e\/o scarico merci.<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\">Quali sono le novit\u00e0 introdotte da questa nuova normativa in materia di distacco dei trasportatori su strada?<\/h2>\n\n<p>A decorrere dal 2 febbraio 2022, sono entrate in vigore le seguenti misure:<\/p>\n\n<ul class=\"wp-block-list\"><li>Tutti i conducenti distaccati dovranno essere retribuiti secondo le norme retributive dello Stato membro ospitante in cui svolgono le loro attivit\u00e0 quando queste rientrano nel campo di applicazione della presente normativa; \u00a0<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li><strong>Abolizione della nomina di un rappresentante nel paese ospitante<\/strong> fluente nella lingua delle autorit\u00e0, in caso di controlli sull&#8217;impresa che impone il distacco e sul conducente distaccato;<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Abolizione della dichiarazione\/attestazione di distacco presentata tramite i sistemi nazionali del paese ospitante o del paese in cui avviene il distacco (SIPSI per la Francia);<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Creazione di una nuova <a href=\"https:\/\/www.postingdeclaration.eu\/\">interfaccia europea<\/a> al fine di armonizzare le formalit\u00e0 amministrative dell&#8217;Unione attraverso un&#8217;unica interfaccia pubblica sicura, connessa al sistema di informazione del mercato interno (&#8220;IMI&#8221;). Si potr\u00e0 accedere all&#8217;interfaccia solo dal 2 febbraio 2022.<\/li><\/ul>\n\n<p>Osservazioni:<\/p>\n\n<ul class=\"wp-block-list\"><li>I sistemi nazionali non saranno pi\u00f9 applicabili a decorrere dal 2 febbraio 2022 per i conducenti distaccati che rientrano nel campo di applicazione del sistema armonizzato europeo;<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Le dichiarazioni di distacco rilasciate attraverso i sistemi nazionali rimangono valide solo fino al 2 febbraio 2022. Tuttavia, le dichiarazioni e gli avvisi di ricevimento rimarranno accessibili nei sistemi nazionali anche dopo tale data per essere utilizzati come prova in caso di controversia su un controllo precedente;<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>A decorrere dal 2 febbraio 2022, \u00e8 obbligatorio presentare una nuova dichiarazione di distacco tramite la nuova interfaccia europea per tutti i distacchi che risultano in corso al 2 febbraio 2022.<\/li><\/ul>\n\n<p><\/p>\n\n<p>Per maggiori informazioni: <a href=\"https:\/\/www.soposting-worker.com\/fr\/blog-content\/paquet-mobilite-reforme-du-secteur-transport-routier\" target=\"_blank\" rel=\"noreferrer noopener\">Pacchetto mobilit\u00e0: riforma nel settore del trasporto su strada<\/a> <em>(in francese)<\/em><\/p>\n\n<p><\/p>\n\n<h3 class=\"wp-block-heading\">A che cosa serve la nuova interfaccia europea?<\/h3>\n\n<p><strong>Qualsiasi richiesta di distacco di lavoratori deve essere accompagnata da una dichiarazione preventiva presentata attraverso la nuova interfaccia europea.<\/strong><\/p>\n\n<p>L&#8217;interfaccia si propone di:\u00a0<\/p>\n\n<ul class=\"wp-block-list\"><li>Essere uno strumento di gestione in grado di permettere al trasportatore di conducenti distaccati di raccogliere facilmente tutti i documenti obbligatori in caso di controllo da parte delle autorit\u00e0 competenti del paese ospitante tramite notifiche ricevute direttamente sul suo account personale. Ogni societ\u00e0 dispone di un unico account di accesso, ma pu\u00f2 avere diversi utenti che gestiscono l&#8217;account della societ\u00e0. Ogni utente ha le stesse responsabilit\u00e0.<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Facilitare i controlli da parte delle autorit\u00e0 competenti dello Stato membro ospitante in collegamento diretto con le autorit\u00e0 competenti dello Stato membro di stabilimento. I controlli saranno effettuati esclusivamente attraverso l&#8217;interfaccia tramite l&#8217;invio di notifiche.<\/li><\/ul>\n\n<ul class=\"wp-block-list\"><li>Facilitare gli scambi multilingue tra la societ\u00e0 che impone il distacco e le autorit\u00e0 di controllo e tra le autorit\u00e0 stesse. L&#8217;interfaccia fornisce un modulo multilingue che permette di presentare una dichiarazione in una delle 24 lingue ufficiali dell&#8217;UE. La societ\u00e0 che dichiara il distacco potr\u00e0 scegliere di presentare la dichiarazione nella propria lingua e non \u00e8 obbligata a scegliere di presentarla nella lingua dello Stato membro in cui viene effettuato il distacco. L&#8217;autorit\u00e0 di vigilanza dello Stato membro ospitante pu\u00f2 far tradurre la dichiarazione in una lingua a sua scelta. Allo stesso modo, qualsiasi comunicazione inoltrata tramite l&#8217;interfaccia sar\u00e0 automaticamente tradotta nella lingua desiderata, sia per la societ\u00e0 che impiega il conducente che per le autorit\u00e0 di controllo dello Stato membro di stabilimento o dello Stato membro ospitante.<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\">Quali sono gli obblighi dei datori di lavoro?<\/h2>\n\n<h3 class=\"wp-block-heading\">Quali sono gli adempimenti dichiarativi dei datori di lavoro per disporre il distacco dei conducenti?<\/h3>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs-1024x683.jpg\" alt=\"\" class=\"wp-image-122135\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs-1200x801.jpg 1200w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-declaratives-employeur-detachement-chauffeurs.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Gli adempimenti dichiarativi dei datori di lavoro per disporre il distacco dei conducenti sono.<\/figcaption><\/figure>\n\n<p>Il trasportatore (datore di lavoro) del conducente distaccato ha l&#8217;obbligo di trasmettere una dichiarazione di distacco tramite un codice QR, per un periodo compreso tra 1 giorno e un massimo di 6 mesi, alle autorit\u00e0 competenti dello Stato membro in cui il conducente \u00e8 distaccato al pi\u00f9 tardi all&#8217;inizio del periodo di distacco tramite <a href=\"https:\/\/www.postingdeclaration.eu\/\">l&#8217;interfaccia unica europea<\/a>. Anche se il distacco dovesse durare solo 24 ore, deve essere comunque trasmessa una dichiarazione che lo copra.<\/p>\n\n<p>Deve essere presentata una dichiarazione per ogni conducente. \u00c8 dunque possibile trasmettere: o una dichiarazione della durata di 6 mesi per un singolo conducente che riporta tutti i distacchi che verranno disposti in tale periodo per il suddetto conducente, oppure trasmettere una singola dichiarazione per conducente per ogni singolo distacco.<\/p>\n\n<p>Attenzione: se \u00e8 previsto il distacco di un conducente in diversi Stati membri, la societ\u00e0 che ha disposto il distacco deve trasmettere una dichiarazione di distacco relativa a ogni singolo stato.<\/p>\n\n<p>Per riassumere, <strong>\u00e8 consigliabile trasmettere una dichiarazione per conducente, per Stato membro e per distacco<\/strong> (tenendo presente che la societ\u00e0 che ha disposto il distacco pu\u00f2 registrare pi\u00f9 distacchi se ha gi\u00e0 pianificato distacchi per lo stesso conducente nel suddetto Stato membro per un periodo di 6 mesi).<\/p>\n\n<p>La dichiarazione di distacco deve contenere le seguenti informazioni:<\/p>\n\n<ul class=\"wp-block-list\"><li>l&#8217;identit\u00e0 del trasportatore;<\/li><li>i recapiti di un gestore dei trasporti o di un&#8217;altra persona di contatto nello Stato membro di stabilimento;<\/li><li>l&#8217;identit\u00e0, l&#8217;indirizzo del luogo di residenza e il numero della patente di guida del conducente;<\/li><li>la data di inizio del contratto di lavoro del conducente e la legge ad esso applicabile;<\/li><li>la data di inizio e di fine del distacco previste;<\/li><li>il numero di targa dei veicoli a motore;<\/li><li>l&#8217;indicazione se i servizi di trasporto effettuati sono trasporto di merci, trasporto di passeggeri, trasporto internazionale o trasporto di cabotaggio.<\/li><\/ul>\n\n<p>Grazie all&#8217;interfaccia, modificare, aggiungere, aggiornare o correggere le informazioni contenute in una dichiarazione \u00e8 molto semplice. \u00c8 altrettanto facile copiare gli elementi da una dichiarazione quando se ne crea una nuova o se ne aggiorna una esistente, al fine di evitare di perdere tempo a inserire una nuova dichiarazione ex novo contenente essenzialmente le stesse informazioni. Sar\u00e0 sufficiente modificare i nuovi elementi.<\/p>\n\n<p>Nota: secondo la <strong>direttiva sul distacco, il trasportatore ha 8 settimane di tempo, dalla data della richiesta, per inviare la documentazione necessaria al distacco dei trasportatori su strada. <\/strong><\/p>\n\n<p>Qualora la documentazione richiesta non venga presentata entro detto termine, le autorit\u00e0 competenti dello Stato membro in cui ha avuto luogo il distacco lo comunicheranno alle autorit\u00e0 competenti dello Stato membro di stabilimento. Le suddette autorit\u00e0 contatteranno l&#8217;impresa di trasporto per ottenere la documentazione mancante.<\/p>\n\n<h3 class=\"wp-block-heading\">Quali sono gli obblighi dei datori di lavoro nei confronti del conducente?<\/h3>\n\n<p>Il trasportatore \u00e8 obbligato ad assicurare che il conducente distaccato abbia a disposizione in formato cartaceo o elettronico:<\/p>\n\n<ul class=\"wp-block-list\"><li>Una copia della dichiarazione di distacco contenente il codice QR usato per la trasmissione;<\/li><li>la prova delle autorizzazioni al trasporto;<\/li><li>Le registrazioni del tachigrafo.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\">Quali sono gli obblighi del datore di lavoro ai fini di controllo?<\/h3>\n\n<p>A fini di controllo da parte delle autorit\u00e0 competenti, il trasportatore provvede a trasmettere attraverso l&#8217;interfaccia pubblica i seguenti documenti obbligatori:<\/p>\n\n<ul class=\"wp-block-list\"><li>la prova delle autorizzazioni al trasporto;<\/li><li>le registrazioni del tachigrafo;<\/li><li>la documentazione riguardante la retribuzione percepita dal conducente relativamente al periodo di distacco;<\/li><li>il contratto di lavoro o un documento equivalente, i prospetti orari relativi alle attivit\u00e0 di lavoro del conducente;<\/li><li>le prove del pagamento.<\/li><\/ul>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur-1024x683.jpg\" alt=\"\" class=\"wp-image-122168\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur-768x512.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur-1200x800.jpg 1200w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/obligations-employeur-controle-chauffeur.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Obblighi del datore di lavoro ai fini di controllo<\/figcaption><\/figure>\n\n<p>La Commissione europea e l&#8217;Autorit\u00e0 europea del lavoro si impegnano a fornire regolarmente informazioni pi\u00f9 dettagliate possibili.<\/p>\n\n<p>ASD SPW vi assister\u00e0 in questo cambiamento normativo, <a href=\"https:\/\/www.soposting-worker.com\/it\/aiuto-contatto\">contattate i nostri esperti per maggiori informazioni.<\/a><\/p>\n\n<p>Inoltre, grazie al <a href=\"https:\/\/www.soposting-worker.com\/it\" target=\"_blank\" rel=\"noreferrer noopener\">servizio online dedicato al distacco dei lavoratori<\/a>, ASD SPW pu\u00f2 gestire per tuo conto tutti gli adempimenti relativi al distacco dei lavoratori in molti settori di attivit\u00e0 come l&#8217;edilizia, la viticoltura o il commercio. Tramite questa piattaforma, appositamente progettata per il distacco dei dipendenti, \u00e8 possibile gestire le seguenti procedure amministrative:<\/p>\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.soposting-worker.com\/it\/dichiarazione-sipsi\" target=\"_blank\" rel=\"noreferrer noopener\">Dichiarazione SIPSI<\/a> o richiesta di carta BTP;<\/li><li>Gestione del distacco dei dipendenti;<\/li><li>Conservazione dei documenti obbligatori ;<\/li><li>Monitoraggio delle missioni di distacco;<\/li><li>Informazioni e promemoria su difetti normativi del distacco al fine di evitare eventuali sanzioni.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?<\/p>\n","protected":false},"author":36,"featured_media":122103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[3739],"tags":[2046,2043],"pays":[3357,3451],"class_list":["post-124895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-distacco-dei-lavoratori","tag-distacco-di-dipendenti-it","tag-tutti-it","pays-union-europeenne","pays-unione-europea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuova normativa: distacco del trasporto su strada | ASD Group<\/title>\n<meta name=\"description\" content=\"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuova normativa: distacco del trasporto su strada | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T14:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-21T12:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9mie Almot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9mie Almot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/\"},\"author\":{\"name\":\"No\u00e9mie Almot\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/person\\\/ce2b34c81cda744c0b6ce91648ab367b\"},\"headline\":\"Nuova normativa in materia di distacco dei trasportatori su strada in vigore a decorrere dal 2 febbraio 2022\",\"datePublished\":\"2022-02-18T14:16:49+00:00\",\"dateModified\":\"2022-02-21T12:55:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/\"},\"wordCount\":1501,\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg\",\"keywords\":[\"Distacco di dipendenti\",\"Tutti\"],\"articleSection\":[\"Distacco dei lavoratori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/\",\"name\":\"Nuova normativa: distacco del trasporto su strada | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg\",\"datePublished\":\"2022-02-18T14:16:49+00:00\",\"dateModified\":\"2022-02-21T12:55:51+00:00\",\"description\":\"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg\",\"width\":1440,\"height\":724,\"caption\":\"Nuova normativa in materia di distacco dei trasportatori su strada in vigore a decorrere dal 2 febbraio 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Distacco dei lavoratori\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/category\\\/distacco-dei-lavoratori\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuova normativa: distacco del trasporto su strada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"name\":\"ASD\",\"description\":\"Semplifica il tuo sviluppo nel mondo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/person\\\/ce2b34c81cda744c0b6ce91648ab367b\",\"name\":\"No\u00e9mie Almot\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/author\\\/nalmot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuova normativa: distacco del trasporto su strada | ASD Group","description":"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Nuova normativa: distacco del trasporto su strada | ASD Group","og_description":"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?","og_url":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/","og_site_name":"ASD","article_published_time":"2022-02-18T14:16:49+00:00","article_modified_time":"2022-02-21T12:55:51+00:00","og_image":[{"width":1440,"height":724,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg","type":"image\/jpeg"}],"author":"No\u00e9mie Almot","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"No\u00e9mie Almot","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#article","isPartOf":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/"},"author":{"name":"No\u00e9mie Almot","@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/person\/ce2b34c81cda744c0b6ce91648ab367b"},"headline":"Nuova normativa in materia di distacco dei trasportatori su strada in vigore a decorrere dal 2 febbraio 2022","datePublished":"2022-02-18T14:16:49+00:00","dateModified":"2022-02-21T12:55:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/"},"wordCount":1501,"publisher":{"@id":"https:\/\/www.asd-int.com\/it\/#organization"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg","keywords":["Distacco di dipendenti","Tutti"],"articleSection":["Distacco dei lavoratori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/","url":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/","name":"Nuova normativa: distacco del trasporto su strada | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg","datePublished":"2022-02-18T14:16:49+00:00","dateModified":"2022-02-21T12:55:51+00:00","description":"Quali sono le nuove norme in materia di distacco del trasporto su strada entrate in vigore il 2 febbraio 2022?","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2022\/02\/nouvelle-reglementation-detachement-transporteurs-routiers-fevrier-2022.jpg","width":1440,"height":724,"caption":"Nuova normativa in materia di distacco dei trasportatori su strada in vigore a decorrere dal 2 febbraio 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/it\/nuova-normativa-in-materia-di-distacco-dei-trasportatori-su-strada-in-vigore-a-decorrere-dal-2-febbraio-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/it\/"},{"@type":"ListItem","position":2,"name":"Distacco dei lavoratori","item":"https:\/\/www.asd-int.com\/it\/category\/distacco-dei-lavoratori\/"},{"@type":"ListItem","position":3,"name":"Nuova normativa: distacco del trasporto su strada"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/it\/#website","url":"https:\/\/www.asd-int.com\/it\/","name":"ASD","description":"Semplifica il tuo sviluppo nel mondo","publisher":{"@id":"https:\/\/www.asd-int.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/it\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/person\/ce2b34c81cda744c0b6ce91648ab367b","name":"No\u00e9mie Almot","url":"https:\/\/www.asd-int.com\/it\/author\/nalmot\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/posts\/124895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/comments?post=124895"}],"version-history":[{"count":0,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/posts\/124895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/media\/122103"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/media?parent=124895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/categories?post=124895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/tags?post=124895"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/pays?post=124895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}