{"id":1347,"count":31,"description":"","link":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/","name":"Rappresentante Fiscale","slug":"rappresentante-fiscale","taxonomy":"type_service","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rappresentante Fiscale Archives | ASD<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rappresentante Fiscale Archives | ASD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1054\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/type_service\\\/rappresentante-fiscale\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/type_service\\\/rappresentante-fiscale\\\/\",\"name\":\"Rappresentante Fiscale Archives | ASD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/type_service\\\/rappresentante-fiscale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/type_service\\\/rappresentante-fiscale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rappresentante Fiscale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"name\":\"ASD\",\"description\":\"Semplifica il tuo sviluppo nel mondo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rappresentante Fiscale Archives | ASD","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Rappresentante Fiscale Archives | ASD","og_url":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/","og_site_name":"ASD","og_image":[{"width":1054,"height":714,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/","url":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/","name":"Rappresentante Fiscale Archives | ASD","isPartOf":{"@id":"https:\/\/www.asd-int.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/it\/type_service\/rappresentante-fiscale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rappresentante Fiscale"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/it\/#website","url":"https:\/\/www.asd-int.com\/it\/","name":"ASD","description":"Semplifica il tuo sviluppo nel mondo","publisher":{"@id":"https:\/\/www.asd-int.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/it\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/type_service\/1347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/type_service"}],"about":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/taxonomies\/type_service"}],"wp:post_type":[{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/service?type_service=1347"},{"href":"https:\/\/www.asd-int.com\/it\/wp-json\/wp\/v2\/presse?type_service=1347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}