{"id":182356,"date":"2024-10-21T11:53:19","date_gmt":"2024-10-21T09:53:19","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=mini_blog&#038;p=182356"},"modified":"2024-10-21T11:53:39","modified_gmt":"2024-10-21T09:53:39","slug":"asd-spw-2-0-chegou","status":"publish","type":"mini_blog","link":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/","title":{"rendered":"ASD SPW 2.0 chegou!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Uma vers\u00e3o ainda mais poderosa para as suas formalidades relacionadas com o destacamento!<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-2-0-Screenshot-Dashboard-768x461-PT-1.png\" alt=\"\" class=\"wp-image-182358\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-2-0-Screenshot-Dashboard-768x461-PT-1.png 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-2-0-Screenshot-Dashboard-768x461-PT-1-300x180.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Descubra uma atualiza\u00e7\u00e3o chave com uma interface completamente renovada e in\u00fameras novas funcionalidades que enriquecem a sua experi\u00eancia de utilizador. Temos a certeza de que voc\u00ea vai adorar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Melhore a sua efici\u00eancia no dia-a-dia!<\/h2>\n\n\n\n<p>Otimize a gest\u00e3o dos seus colaboradores destacados com uma plataforma r\u00e1pida e f\u00e1cil de usar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aceda \u00e0 nossa nova plataforma com suporte online 100%.<\/h2>\n\n\n\n<p>A ASD SPW oferece-lhe uma valiosa poupan\u00e7a de tempo para a gest\u00e3o das miss\u00f5es dos seus colaboradores destacados, acompanhada de um suporte online multil\u00edngue, especializado em formalidades de destacamento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Otimiza\u00e7\u00f5es e novas funcionalidades reformuladas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Interface repensada<\/h3>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-4-768x461-1.png\" alt=\"\" class=\"wp-image-182218 size-full\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-4-768x461-1.png 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-4-768x461-1-300x180.png 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>A interface e a ergonomia da ASD SPW foram revistas para tornar a plataforma ainda mais fluida e intuitiva.<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Simplicidade e centraliza\u00e7\u00e3o<\/h3>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-1.png\" alt=\"\" class=\"wp-image-182229 size-full\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-1.png 1000w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-1-300x180.png 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-1-768x461.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Simplific\u00e1mos a configura\u00e7\u00e3o das miss\u00f5es centralizando todos os elementos, sejam pedidos, miss\u00f5es ou inspe\u00e7\u00f5es. Novos estados de progresso das miss\u00f5es tamb\u00e9m est\u00e3o dispon\u00edveis.<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Novas funcionalidades<\/h3>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-3.png\" alt=\"\" class=\"wp-image-182240 size-full\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-3.png 1000w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-3-300x180.png 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/ASD-SPW-Screenshot-3-768x461.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Foi implementada uma fun\u00e7\u00e3o de backup seguro para os seus documentos e colaboradores, facilitando a sua reutiliza\u00e7\u00e3o para diferentes miss\u00f5es.<\/p>\n<\/div><\/div>\n\n\n\n<p>Estamos ansiosos por receb\u00ea-lo nesta nova vers\u00e3o e <a href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">permanecemos dispon\u00edveis<\/a> para qualquer quest\u00e3o ou necessidade que possa ter.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-primary-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.soposting-worker.com\/pt\/\" style=\"border-radius:5px;background-color:#ffd500\" target=\"_blank\" rel=\"noreferrer noopener\">Descubra a nossa nova plataforma ASD SPW<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma vers\u00e3o ainda mais poderosa para as suas formalidades relacionadas com o destacamento! Descubra uma atualiza\u00e7\u00e3o chave com uma interface completamente renovada e in\u00fameras novas&#8230;<\/p>\n","protected":false},"author":36,"featured_media":182262,"menu_order":0,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[4367,4470,4634],"tags":[3749,1975],"pays":[],"class_list":["post-182356","mini_blog","type-mini_blog","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-asd-group","category-noticias-asd-group","category-social-pt-pt","tag-destacamento-de-trabalhadores","tag-detachement-de-travailleurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASD SPW 2.0 chegou! | ASD Group<\/title>\n<meta name=\"description\" content=\"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASD SPW 2.0 chegou! | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T09:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/asd-spw-2-0-worker-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/\",\"name\":\"ASD SPW 2.0 chegou! | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/asd-spw-2-0-worker-1.jpg\",\"datePublished\":\"2024-10-21T09:53:19+00:00\",\"dateModified\":\"2024-10-21T09:53:39+00:00\",\"description\":\"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/asd-spw-2-0-worker-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/asd-spw-2-0-worker-1.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/asd-spw-2-0-chegou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASD SPW 2.0 chegou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASD SPW 2.0 chegou! | ASD Group","description":"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/","og_locale":"pt_PT","og_type":"article","og_title":"ASD SPW 2.0 chegou! | ASD Group","og_description":"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!","og_url":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/","og_site_name":"ASD","article_modified_time":"2024-10-21T09:53:39+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/asd-spw-2-0-worker-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/","url":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/","name":"ASD SPW 2.0 chegou! | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/asd-spw-2-0-worker-1.jpg","datePublished":"2024-10-21T09:53:19+00:00","dateModified":"2024-10-21T09:53:39+00:00","description":"Destacamento de trabalhadores: a nova plataforma ASD SPW 2.0 chegou! Optimize os seus processos para mais efici\u00eancia!","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/asd-spw-2-0-worker-1.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/10\/asd-spw-2-0-worker-1.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/asd-spw-2-0-chegou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"ASD SPW 2.0 chegou"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/182356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/mini_blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":2,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/182356\/revisions"}],"predecessor-version":[{"id":182369,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/182356\/revisions\/182369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media\/182262"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=182356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=182356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=182356"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pays?post=182356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}