{"id":193667,"date":"2025-05-09T11:09:54","date_gmt":"2025-05-09T09:09:54","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=mini_blog&#038;p=193667"},"modified":"2025-07-02T10:36:37","modified_gmt":"2025-07-02T08:36:37","slug":"declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros","status":"publish","type":"mini_blog","link":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/","title":{"rendered":"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros"},"content":{"rendered":"\n<p>Em resposta \u00e0 emerg\u00eancia clim\u00e1tica e \u00e0 degrada\u00e7\u00e3o massiva das florestas a n\u00edvel mundial, a Uni\u00e3o Europeia aplicar\u00e1, a partir de 30 de dezembro de 2025 (30 de junho de 2026 para micro e pequenas empresas), o Regulamento (UE) 2023\/1115, que<strong> pro\u00edbe a coloca\u00e7\u00e3o no mercado ou exporta\u00e7\u00e3o a partir da UE de produtos que tenham contribu\u00eddo para a desfloresta\u00e7\u00e3o ou degrada\u00e7\u00e3o florestal<\/strong> ap\u00f3s 30 de dezembro de 2020.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Quais produtos est\u00e3o abrangidos?<\/strong><\/h2>\n\n<p>Produtos de base como <strong>caf\u00e9, cacau, borracha, \u00f3leo de palma, soja, carne bovina e madeira<\/strong>, bem como alguns dos seus derivados (<strong>couro, papel impresso, carv\u00e3o vegetal,<\/strong> etc.), ter\u00e3o de ser acompanhados de uma <strong>declara\u00e7\u00e3o de dilig\u00eancia devida <\/strong>(DDD).<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>O que muda para as empresas:<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Obriga\u00e7\u00e3o de provar que os produtos s\u00e3o \u201c<strong>livres de desfloresta\u00e7\u00e3o<\/strong>\u201d e conformes com a legisla\u00e7\u00e3o do pa\u00eds de origem.<\/li>\n\n\n\n<li>Entrega de uma DDD com a geolocaliza\u00e7\u00e3o das parcelas de produ\u00e7\u00e3o, rastreabilidade completa da cadeia de abastecimento e assinatura oficial assumindo a responsabilidade legal.<\/li>\n\n\n\n<li>Obrigatoriedade de indicar o n\u00famero da DDD nas <strong>formalidades aduaneiras<\/strong>.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Antecipe as consequ\u00eancias!<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Risco de recusa de entrada no mercado para produtos n\u00e3o conformes.<\/li>\n\n\n\n<li>Aumento da complexidade das cadeias log\u00edsticas.<\/li>\n\n\n\n<li>Necessidade de rever parcerias com fornecedores para garantir a conformidade ambiental.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Como preparar-se para estas mudan\u00e7as:<\/strong><\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Implementar um sistema interno de dilig\u00eancia devida em conformidade com os artigos 8.\u00ba a 11.\u00ba do RDUE.<\/li>\n\n\n\n<li>Identificar e avaliar os riscos associados \u00e0s zonas de produ\u00e7\u00e3o.<\/li>\n\n\n\n<li>Recolher os dados e documentos necess\u00e1rios junto dos fornecedores.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>A ASD Group apoia-o<\/strong><\/h2>\n\n<p>A ASD Group oferece um acompanhamento personalizado para integrar estas novas obriga\u00e7\u00f5es aduaneiras. Os nossos especialistas est\u00e3o \u00e0 sua disposi\u00e7\u00e3o para garantir a seguran\u00e7a das suas cadeias de abastecimento e assegurar a conformidade regulamentar.<\/p>\n\n<p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">Contacte-nos hoje<\/a> para antecipar esta transforma\u00e7\u00e3o!<\/p>\n\n<p>Fonte: <a href=\"https:\/\/www.deforestationimportee.ecologie.gouv.fr\/reglement-europeen-contre-la-deforestation-et-la-degradation-des-forets\/article\/reglement-europeen-contre-la-deforestation-et-la-degradation-des-forets\" target=\"_blank\" rel=\"noopener\">Minist\u00e9rio do Ordenamento do Territ\u00f3rio e da Transi\u00e7\u00e3o Ecol\u00f3gica<\/a> (em franc\u00eas)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em resposta \u00e0 emerg\u00eancia clim\u00e1tica e \u00e0 degrada\u00e7\u00e3o massiva das florestas a n\u00edvel mundial, a Uni\u00e3o Europeia aplicar\u00e1, a partir de 30 de dezembro de&#8230;<\/p>\n","protected":false},"author":36,"featured_media":193475,"menu_order":0,"template":"","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[4429],"tags":[4750,4548],"pays":[3458],"class_list":["post-193667","mini_blog","type-mini_blog","status-publish","format-standard","has-post-thumbnail","hentry","category-alfandega-pt-pt","tag-declaracao-de-diligencia-razoavel","tag-obrigacoes-aduaneiras","pays-uniao-europeia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group<\/title>\n<meta name=\"description\" content=\"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group\" \/>\n<meta property=\"og:description\" content=\"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T08:36:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/05\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/\",\"name\":\"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg\",\"datePublished\":\"2025-05-09T09:09:54+00:00\",\"dateModified\":\"2025-07-02T08:36:37+00:00\",\"description\":\"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg\",\"width\":1440,\"height\":810,\"caption\":\"D\u00e9forestation : l\u2019Union europ\u00e9enne renforce ses exigences douani\u00e8res\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group","description":"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/","og_locale":"pt_PT","og_type":"article","og_title":"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group","og_description":"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/","og_site_name":"ASD","article_modified_time":"2025-07-02T08:36:37+00:00","og_image":[{"width":1440,"height":810,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/05\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/","url":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/","name":"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/05\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg","datePublished":"2025-05-09T09:09:54+00:00","dateModified":"2025-07-02T08:36:37+00:00","description":"A Uni\u00e3o Europeia ir\u00e1 instaurar obriga\u00e7\u00f5es aduaneiras sobre os produtos sujeitos \u00e0 Declara\u00e7\u00e3o de due diligence para combater a desfloresta\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/05\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2025\/05\/Deforestation-lUnion-europeenne-renforce-ses-exigences-douanieres.jpg","width":1440,"height":810,"caption":"D\u00e9forestation : l\u2019Union europ\u00e9enne renforce ses exigences douani\u00e8res"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/declaracao-de-due-diligence-e-desflorestacao-a-ue-reforca-os-requisitos-aduaneiros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Declara\u00e7\u00e3o de due diligence e desfloresta\u00e7\u00e3o: a UE refor\u00e7a os requisitos aduaneiros"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/193667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/mini_blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":5,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/193667\/revisions"}],"predecessor-version":[{"id":195309,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/mini_blog\/193667\/revisions\/195309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media\/193475"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=193667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=193667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=193667"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pays?post=193667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}