{"id":3306,"date":"2018-03-21T13:00:43","date_gmt":"2018-03-21T12:00:43","guid":{"rendered":"https:\/\/www.asd-int.com\/?page_id=3306"},"modified":"2023-01-30T15:50:04","modified_gmt":"2023-01-30T14:50:04","slug":"nossos-servicos-em-italia","status":"publish","type":"page","link":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/","title":{"rendered":"Nossos servi\u00e7os em It\u00e1lia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3306\" class=\"elementor elementor-3306 elementor-701\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e71ea4 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40e71ea4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-369b9ccc\" data-id=\"369b9ccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1861b54d\" data-id=\"1861b54d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5033e361 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5033e361\" data-element_type=\"section\" data-e-type=\"section\" id=\"asd_title_country\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-48fa31b4\" data-id=\"48fa31b4\" data-element_type=\"column\" data-e-type=\"column\" id=\"asd_discover_title\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56f188c elementor-widget elementor-widget-text-editor\" data-id=\"56f188c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asd-int.com\/pt-pt\/\">ASD GROUP<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/pt-pt\/os-nossos-servicos-por-pais\/\">OS NOSSOS SERVI\u00c7OS POR PA\u00cdS<\/a> &gt; IT\u00c1LIA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2562d921 elementor-widget elementor-widget-heading\" data-id=\"2562d921\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"asd_title_discover\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Descubra nossos servi\u00e7os:<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1bbc4443\" data-id=\"1bbc4443\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fc50cf3 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"7fc50cf3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"pays_menu_country_asd\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-7fc50cf3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58351\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Pays<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58352\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" class=\"elementor-sub-item\">Alemanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129289\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-australia\/\" class=\"elementor-sub-item\">Austr\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58353\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-austria\/\" class=\"elementor-sub-item\">\u00c1ustria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58391\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-belgica\/\" class=\"elementor-sub-item\">B\u00e9lgica<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58392\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-bulgaria\/\" class=\"elementor-sub-item\">Bulg\u00e1ria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58393\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-canada\/\" class=\"elementor-sub-item\">Canad\u00e1<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129288\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116490\" class=\"elementor-sub-item\">China<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58394\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-chipre\/\" class=\"elementor-sub-item\">Chipre<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58437\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-croacia\/\" class=\"elementor-sub-item\">Cro\u00e1cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58438\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-dinamarca\/\" class=\"elementor-sub-item\">Dinamarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58702\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovaquia\/\" class=\"elementor-sub-item\">Eslov\u00e1quia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58729\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovenia\/\" class=\"elementor-sub-item\">Eslov\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58440\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-espanha\/\" class=\"elementor-sub-item\">Espanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58475\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-estonia\/\" class=\"elementor-sub-item\">Est\u00f4nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58476\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-estados-unidos\/\" class=\"elementor-sub-item\">Estados Unidos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58477\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-finlandia\/\" class=\"elementor-sub-item\">Finl\u00e2ndia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58478\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-franca\/\" class=\"elementor-sub-item\">Fran\u00e7a<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58479\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-grecia\/\" class=\"elementor-sub-item\">Gr\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58557\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-hungria\/\" class=\"elementor-sub-item\">Hungria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129287\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116549\" class=\"elementor-sub-item\">Indon\u00e9sia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58559\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-irlanda\/\" class=\"elementor-sub-item\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58560\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" class=\"elementor-sub-item\">It\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58597\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-letonia\/\" class=\"elementor-sub-item\">Let\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58598\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-lituania\/\" class=\"elementor-sub-item\">Litu\u00e2nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129290\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-luxemburgo\/\" class=\"elementor-sub-item\">Luxemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58599\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-malta\/\" class=\"elementor-sub-item\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58611\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-marrocos\/\" class=\"elementor-sub-item\">Marrocos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58612\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-noruega\/\" class=\"elementor-sub-item\">Noruega<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58613\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-paises-baixos\/\" class=\"elementor-sub-item\">Pa\u00edses Baixos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58614\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-polonia\/\" class=\"elementor-sub-item\">Pol\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58615\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-portugal\/\" class=\"elementor-sub-item\">Portugal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58699\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-republica-checa\/\" class=\"elementor-sub-item\">Rep\u00fablica Checa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58700\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-romania\/\" class=\"elementor-sub-item\">Rom\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58701\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-reino-unido\/\" class=\"elementor-sub-item\">Reino Unido<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129286\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-singapura\/\" class=\"elementor-sub-item\">Singapura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58730\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suecia\/\" class=\"elementor-sub-item\">Su\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58731\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suica\/\" class=\"elementor-sub-item\">Su\u00ed\u00e7a<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7fc50cf3\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58351\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Pays<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58352\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Alemanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129289\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-australia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Austr\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58353\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-austria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c1ustria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58391\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-belgica\/\" class=\"elementor-sub-item\" tabindex=\"-1\">B\u00e9lgica<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58392\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-bulgaria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bulg\u00e1ria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58393\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-canada\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Canad\u00e1<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129288\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116490\" class=\"elementor-sub-item\" tabindex=\"-1\">China<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58394\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-chipre\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chipre<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58437\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-croacia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cro\u00e1cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58438\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-dinamarca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Dinamarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58702\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovaquia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Eslov\u00e1quia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58729\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovenia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Eslov\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58440\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-espanha\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Espanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58475\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-estonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Est\u00f4nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58476\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-estados-unidos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Estados Unidos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58477\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-finlandia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Finl\u00e2ndia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58478\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-franca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fran\u00e7a<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58479\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-grecia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gr\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58557\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-hungria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hungria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129287\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116549\" class=\"elementor-sub-item\" tabindex=\"-1\">Indon\u00e9sia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58559\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-irlanda\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58560\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">It\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58597\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-letonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Let\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58598\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-lituania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Litu\u00e2nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129290\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-luxemburgo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Luxemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58599\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-malta\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58611\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-marrocos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Marrocos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58612\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-noruega\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Noruega<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58613\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-paises-baixos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pa\u00edses Baixos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58614\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-polonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pol\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58615\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-portugal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Portugal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58699\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-republica-checa\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Rep\u00fablica Checa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58700\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-romania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Rom\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58701\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-reino-unido\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Reino Unido<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129286\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-singapura\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Singapura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58730\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suecia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Su\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58731\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suica\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Su\u00ed\u00e7a<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-432252a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"432252a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-862ed29\" data-id=\"862ed29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-455336f5 elementor-widget elementor-widget-text-editor\" data-id=\"455336f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O ASD Group ajuda-o em todas as fases do desenvolvimento das suas actividades em It\u00e1lia nas \u00e1reas do IVA, fiscalidade e impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamenta\u00e7\u00e3o social e estrat\u00e9gia empresarial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b2ec186\" data-id=\"6b2ec186\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab16a03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab16a03\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28a45d9b\" data-id=\"28a45d9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a35b41 elementor-widget elementor-widget-image\" data-id=\"3a35b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54184\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36453653 test-caca elementor-widget elementor-widget-heading\" data-id=\"36453653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Servi\u00e7os dispon\u00edveis em It\u00e1lia<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-107827fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"107827fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-700f7e17\" data-id=\"700f7e17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-56934bd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56934bd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5857c851\" data-id=\"5857c851\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f39dadc elementor-tabs-view-vertical menu_service_asd elementor-widget elementor-widget-tabs\" data-id=\"4f39dadc\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"menu_service_3\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1321\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">FISCAL<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1322\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">ALF\u00c2NDEGA<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1323\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1323\" aria-expanded=\"false\">SOCIAL<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1324\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1324\" aria-expanded=\"false\">ESTRAT\u00c9GIA EMPRESARIAL<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">FISCAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1321\" tabindex=\"0\" hidden=\"false\"><div class=\"menu-italie-fiscal-pt-container\"><ul id=\"menu-italie-fiscal-pt\" class=\"menu\"><li id=\"menu-item-152697\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152697\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/obter-um-numero-de-iva-intracomunitario\/\">Como obter um n\u00famero de IVA intracomunit\u00e1rio?<\/a><\/li>\n<li id=\"menu-item-152698\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152698\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/mandatario-fiscal-italia\/\">Nomear um mandat\u00e1rio fiscal em It\u00e1lia<\/a><\/li>\n<li id=\"menu-item-152699\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152699\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representacao-fiscal-italia\/\">Representa\u00e7\u00e3o Fiscal, gest\u00e3o de IVA em It\u00e1lia<\/a><\/li>\n<li id=\"menu-item-152700\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152700\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/service\/como-receber-o-reembolso-do-iva-intracomunitario\/\">Como receber o reembolso do IVA intracomunit\u00e1rio?<\/a><\/li>\n<li id=\"menu-item-152701\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152701\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-italia\/\">Reembolso de IVA italiano para as empresas estabelecidas fora da UE \u2013 13\u00aa Diretiva<\/a><\/li>\n<li id=\"menu-item-152702\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152702\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/provas-de-transporte\/\">Provas de transporte &#8211; ASD QuickProof<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">ALF\u00c2NDEGA<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1322\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-italie-douane-pt-container\"><ul id=\"menu-italie-douane-pt\" class=\"menu\"><li id=\"menu-item-68332\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-68332\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/intrastat-italia\/\">Intrastat em It\u00e1lia<\/a><\/li>\n<li id=\"menu-item-63014\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-63014\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/declaracao-europeia-de-servicos\/\">Porqu\u00ea externalizar as suas declara\u00e7\u00f5es europeias de servi\u00e7os?<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1323\" aria-expanded=\"false\">SOCIAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1323\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-italie-social-pt-container\"><ul id=\"menu-italie-social-pt\" class=\"menu\"><li id=\"menu-item-63032\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-63032\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-estrangeiros-em-franca\/\">Quais s\u00e3o as regras sobre o destacamento de trabalhadores em Fran\u00e7a?<\/a><\/li>\n<li id=\"menu-item-63033\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-63033\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representacao-empresa-estrangeira\/\">Representa\u00e7\u00e3o de uma empresa estrangeira: recrutamento para contratar pessoal no estrangeiro<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1324\" aria-expanded=\"false\">ESTRAT\u00c9GIA EMPRESARIAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1324\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1324\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-italie-strategie-dentreprise-pt-container\"><ul id=\"menu-italie-strategie-dentreprise-pt\" class=\"menu\"><li id=\"menu-item-128823\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128823\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/servicos-consultoria-rgpd\/\">Servi\u00e7os \u2013 consultoria RGPD \u2013 externalize a gest\u00e3o das suas problem\u00e1ticas RGPD<\/a><\/li>\n<li id=\"menu-item-128824\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128824\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/encarregado-da-protecao-de-dados-epd\/\">Encarregado da Prote\u00e7\u00e3o de Dados (EPD): terceirize a gest\u00e3o das suas problem\u00e1ticas de RGPD<\/a><\/li>\n<li id=\"menu-item-128825\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128825\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representante-rgpd\/\">Representante RGPD: externalize a gest\u00e3o das suas problem\u00e1ticas RGPD<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1efebce3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1efebce3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24e4071f\" data-id=\"24e4071f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18171bd2 elementor-widget elementor-widget-image\" data-id=\"18171bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54184\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e183283 test-caca elementor-widget elementor-widget-heading\" data-id=\"5e183283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contacte os nossos peritos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2728fbba elementor-widget elementor-widget-heading\" data-id=\"2728fbba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Quer\u00a0saber mais\u00a0sobre as nossas ofertas?<br \/> Contacte-nose nossos peritos entrar\u00e3o em contato com voc\u00ea em breve.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80c0375 elementor-widget elementor-widget-shortcode\" data-id=\"80c0375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_18_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form3\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Mini contact<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"18\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_18\" id=\"frm_hide_fields_18\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form3\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_18\" name=\"frm_submit_entry_18\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/pages\/3306\" \/><div id=\"frm_field_281_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_i41ef\" class=\"frm_primary_label\">Empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef\" name=\"item_meta[281]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_280_container\" class=\"frm_form_field form-field  frm_top_container frm_half relative frm_other_container\">\r\n    <label for=\"field_85w6d\" class=\"frm_primary_label\">Setor de atividade\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[280]\" id=\"field_85w6d\"  data-placeholder=\"Qual \u00e9 o seu setor de atividade?\"  placeholder=\"Qual \u00e9 o seu setor de atividade?\" data-invmsg=\"Setor de atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Qual \u00e9 o seu setor de atividade?<\/option><option  value=\"Agroalimentaire\">Alimentar<\/option><option  value=\"Bois \/ Papier \/ Carton \/ Imprimerie\">Madeira \/ Papel \/ Cart\u00e3o \/ Impress\u00e3o<\/option><option  value=\"Chimie \/ Parachimie\">Chimie \/ Parachimie<\/option><option  value=\"Editions \/ Communication \/ Multim\u00e9dia\">Edi\u00e7\u00e3o \/ Comunica\u00e7\u00e3o \/ Multim\u00eddia<\/option><option  value=\"Etudes et conseils\">Etudes et conseils<\/option><option  value=\"Informatique \/ T\u00e9l\u00e9coms\">Tecnologias de Informa\u00e7\u00e3o\/Telecomunica\u00e7\u00f5es;<\/option><option  value=\"M\u00e9tallurgie \/ Travail du m\u00e9tal\">Metalurgia<\/option><option  value=\"Service aux entreprises\">Servi\u00e7o de neg\u00f3cios<\/option><option  value=\"Transports \/ Logistique\">Transporte \/ Log\u00edstica<\/option><option  value=\"Banque \/ Assurance\">Banco \/ Seguros<\/option><option  value=\"BTP \/ Mat\u00e9riaux de construction\">Constru\u00e7\u00e3o \/ Materiais de Constru\u00e7\u00e3o<\/option><option  value=\"Commerce \/ N\u00e9goce \/ Distribution\">Com\u00e9rcio \/ Distribui\u00e7\u00e3o<\/option><option  value=\"Electronique \/ Electricit\u00e9\">Eletr\u00f4nica \/ Eletricidade<\/option><option  value=\"Industrie pharmaceutique\">Ind\u00fastria farmac\u00eautica<\/option><option  value=\"Machine et \u00e9quipements \/ Automobile\">M\u00e1quina e Equipamentos \/ Automotivo<\/option><option  value=\"Plastique \/ Caoutchouc\">Pl\u00e1stico \/ Borracha<\/option><option  value=\"Textile \/ Habillement \/ Chaussure\">T\u00eaxtil \/ Vestu\u00e1rio<\/option><option  value=\"Outro setor\" class=\"frm_other_trigger\">Outro setor<\/option>\t<\/select>\n\t<label for=\"field_85w6d-otext\" class=\"frm_screen_reader frm_hidden\">Setor de atividade<\/label><input type=\"text\" id=\"field_85w6d-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][280]\" value=\"\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_246_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy4\" class=\"frm_primary_label\">Apelido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy4\" name=\"item_meta[246]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_247_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_ocfup14\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup14\" name=\"item_meta[247]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pr\u00e9nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_270_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc\" name=\"item_meta[270]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_279_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa2\" class=\"frm_primary_label\">Telefone\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa2\" name=\"item_meta[279]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"T\u00e9l\u00e9phone est non valide\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_276_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half relative\">\r\n    <label for=\"field_okuhn\" class=\"frm_primary_label\"> Pa\u00eds de estabelecimento da sua empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[276]\" id=\"field_okuhn\"  data-placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\"  placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\" Pa\u00eds de estabelecimento da sua empresa is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde est\u00e1 estabelecida a sua empresa?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"Afrique du Sud\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanz\u00e2nia<\/option><option  value=\"TD\">Chade<\/option><option  value=\"Tha\u00eflande\">Tail\u00e2ndia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinity e Tobago<\/option><option  value=\"Tunisie\">Tun\u00edsia<\/option><option  value=\"Turquie\">Turquia<\/option><option  value=\"Turkm\u00e9nistan\">Turquemenist\u00e3o<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucr\u00e2nia<\/option><option  value=\"Uruguay\">Uruguai<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietn\u00e3<\/option><option  value=\"Y\u00e9men\">I\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_278_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half relative\">\r\n    <label for=\"field_l1biv\" class=\"frm_primary_label\">Pa\u00eds onde deseja desenvolver atividade\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[278]\" id=\"field_l1biv\"  data-placeholder=\"Onde deseja expandir-se?\"  placeholder=\"Onde deseja expandir-se?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pa\u00eds onde deseja desenvolver atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde deseja expandir-se?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"ZAF\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanzanie<\/option><option  value=\"TD\">Tchad<\/option><option  value=\"Tha\u00eflande\">Tha\u00eflande<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinit\u00e9 et Tobago<\/option><option  value=\"Tunisie\">Tunisie<\/option><option  value=\"Turquie\">Turquie<\/option><option  value=\"Turkm\u00e9nistan\">Turkm\u00e9nistan<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ukraine<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">V\u00e9n\u00e9zu\u00e9la<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Y\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_271_container\" class=\"frm_form_field form-field  frm_top_container frm_half frm_first\">\r\n    <label for=\"field_wtev7\" class=\"frm_primary_label\">\u00c1rea de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[271]\" id=\"field_wtev7\"  data-placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\"  placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\" data-invmsg=\"\u00c1rea de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha uma \u00e1rea de servi\u00e7o<\/option><option  value=\"Fiscal\">Fiscal<\/option><option  value=\"Douane\">Quest\u00f5es Aduaneiras<\/option><option  value=\"Social\">Regulamenta\u00e7\u00e3o social<\/option><option  value=\"Strat\u00e9gie d&#039;entreprise\">Estrat\u00e9gia empresarial<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_272_container\" class=\"frm_form_field form-field  frm_top_container frm_half\">\r\n    <label for=\"field_rltwo\" class=\"frm_primary_label\">Tipo de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[272]\" id=\"field_rltwo\"  data-placeholder=\"Escolha um tipo de servi\u00e7o\"  placeholder=\"Escolha um tipo de servi\u00e7o\" data-invmsg=\"Tipo de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha um tipo de servi\u00e7o<\/option><option  value=\"Repr\u00e9sentation fiscale\">representante fiscal<\/option><option  value=\"Mandataire fiscal\">Consultor Fiscal<\/option><option  value=\"Remboursement de TVA\">Reembolso de IVA<\/option><option  value=\"Vente \u00e0 distance \/ e-commerce\">Vendas \u00e0 Dist\u00e2ncia \/ E-commerce<\/option><option  value=\"Formation TVA intracommunautaire\">Forma\u00e7\u00e3o IVA Intracomunit\u00e1rio<\/option><option  value=\"Audit fiscal TVA\">Auditoria Fiscal IVA<\/option><option  value=\"Cr\u00e9ation d&#039;entreprise\">Cria\u00e7\u00e3o de empresa <\/option><option  value=\"Domiciliation\">Domicilia\u00e7\u00e3o<\/option><option  value=\"Droits d&#039;accises\">Imposto especial sobre a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"DEB \/ Intrastat\">Instrastat \/ Declara\u00e7\u00e3o de Troca de Bens<\/option><option  value=\"D\u00e9claration europ\u00e9enne de services\">Declara\u00e7\u00e3o Europeia de Servi\u00e7os<\/option><option  value=\"Formation DEB\">Forma\u00e7\u00e3o DEB \/ DES \/ INTRASTAT<\/option><option  value=\"D\u00e9claration taxe TGAP\">Taxa geral sobre as Actividades Poluentes (TGAP) <\/option><option  value=\"Accompagnement op\u00e9rations douani\u00e8res\">Obriga\u00e7\u00f5es Aduaneiras<\/option><option  value=\"Remboursement taxe TICPE (ex TIPP)\">TICPE ( taxa interior de consumo sobre os produtos energ\u00e9ticos\/combust\u00edveis) <\/option><option  value=\"D\u00e9tachement de travailleurs \u00e9trangers\">Destacamento de Trabalhadores<\/option><option  value=\"Repr\u00e9sentation de firme \u00e9trang\u00e8re\">Repr\u00e9sentation de firme \u00e9trang\u00e8re<\/option><option  value=\"Le pr\u00e9l\u00e8vement \u00e0 la source en France pour les entreprises \u00e9trang\u00e8res\">Reten\u00e7\u00e3o na fonte em fran\u00e7a<\/option><option  value=\"Repr\u00e9sentation\/Conformit\u00e9 RGPD\">Repr\u00e9sentation\/Conformit\u00e9 RGPD<\/option><option  value=\"Contr\u00f4les SIVEP\/SPS\">Contr\u00f4les SIVEP\/SPS<\/option><option  value=\"Formulaires W-8 et W-9 aux \u00c9tats-Unis\">Formul\u00e1rios W-8 e W-9 nos Estados Unidos<\/option><option  value=\"&quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Imposto sobre Vendas e Uso nos Estados Unidos<\/option><option  value=\"Certification employeur non-r\u00e9sident au Canada\">Certifica\u00e7\u00e3o de empregador n\u00e3o residente no Canad\u00e1<\/option><option  value=\"Dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents au Canada\">Isen\u00e7\u00e3o de reten\u00e7\u00e3o de impostos para empregadores n\u00e3o residentes no Canad\u00e1<\/option><option  value=\"Taxes TPS\/TVH\/TVP au Canada\">Taxes TPS\/TVH\/TVP au Canada<\/option><option  value=\"Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne\">Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne<\/option><option  value=\"Autre service\">Outro servi\u00e7o<\/option><option  value=\"Je ne suis pas s\u00fbr (e)\">N\u00e3o tenho a certeza<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_275_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_bz8k1\" class=\"frm_primary_label\">Descreva as suas necessidades\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[275]\" id=\"field_bz8k1\" rows=\"5\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"D\u00e9crivez votre besoin est non valide\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_476_container\" class=\"frm_form_field  frm_html_container form-field\">Este site \u00e9 protegido pelo Google reCAPTCHA. Aplicam-se a <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">Pol\u00edtica de Privacidade<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">Termos de Servi\u00e7o<\/a>.<\/div>\n<div id=\"frm_field_299_container\" class=\"frm_form_field form-field  frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_299-0\">\t\t\t<label  for=\"field_e2sgs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[299][]\" id=\"field_e2sgs-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter is invalid\"   \/> Quero subscrever a newsletter de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_300_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_300-0\">\t\t\t<label  for=\"field_y30e2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[300][]\" id=\"field_y30e2-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"RGPD cannot be blank.\" data-invmsg=\"RGPD is invalid\"   aria-required=\"true\"  \/> Ao enviar este formul\u00e1rio, voc\u00ea aceita que as informa\u00e7\u00f5es inseridas sejam usadas no contexto da rela\u00e7\u00e3o comercial que pode resultar. Para conhecer e exercer os seus direitos, inclu\u00edndo a retirada de seu consentimento para o uso dos dadaos coletados por este formul\u00e1rio consulte nossa <a href=\"\/en\/legal-notice\/\">Informa\u00e7\u00e3o legal<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_404_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\"><\/div>\n<div id=\"frm_field_509_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[519]\" id=\"field_8qg9b\" value=\"\"     \/>\n\t\t<div id=\"frm_field_573_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Enviar<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_8nbz4\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_8nbz4\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg2O8p1pcVDZ4\/12lNEZQmL5tP3dNP4JcUpwDCQwP9r6x\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-608aa4ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"608aa4ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-157c232d\" data-id=\"157c232d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca64011 elementor-widget elementor-widget-shortcode\" data-id=\"ca64011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script type=\"text\/javascript\">\r\n\r\nlet defaultMenu = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"elementor-item-anchor\");\r\nlet current_item = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"current_page_item \");\r\n\r\ndefaultMenu[0].innerText = current_item[0].innerText;\r\n\r\n<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt; OS NOSSOS SERVI\u00c7OS POR PA\u00cdS &gt; IT\u00c1LIA Descubra nossos servi\u00e7os: O ASD Group ajuda-o em todas as fases do desenvolvimento das suas&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"parent":3043,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"class_list":["post-3306","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nossos servi\u00e7os em It\u00e1lia | ASD Group<\/title>\n<meta name=\"description\" content=\"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nossos servi\u00e7os em It\u00e1lia | ASD Group\" \/>\n<meta property=\"og:description\" content=\"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T14:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/\",\"name\":\"Nossos servi\u00e7os em It\u00e1lia | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"datePublished\":\"2018-03-21T12:00:43+00:00\",\"dateModified\":\"2023-01-30T14:50:04+00:00\",\"description\":\"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ag\u00eancias\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/agencias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nossos servi\u00e7os em It\u00e1lia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nossos servi\u00e7os em It\u00e1lia | ASD Group","description":"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/","og_locale":"pt_PT","og_type":"article","og_title":"Nossos servi\u00e7os em It\u00e1lia | ASD Group","og_description":"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/","og_site_name":"ASD","article_modified_time":"2023-01-30T14:50:04+00:00","og_image":[{"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/","url":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/","name":"Nossos servi\u00e7os em It\u00e1lia | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","datePublished":"2018-03-21T12:00:43+00:00","dateModified":"2023-01-30T14:50:04+00:00","description":"O ASD Group assiste-o em It\u00e1lia com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Ag\u00eancias","item":"https:\/\/www.asd-int.com\/pt-pt\/agencias\/"},{"@type":"ListItem","position":3,"name":"Nossos servi\u00e7os em It\u00e1lia"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3306"}],"version-history":[{"count":5,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3306\/revisions"}],"predecessor-version":[{"id":160516,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3306\/revisions\/160516"}],"up":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3043"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}