{"id":3329,"date":"2018-03-21T16:46:35","date_gmt":"2018-03-21T15:46:35","guid":{"rendered":"https:\/\/www.asd-int.com\/?page_id=3329"},"modified":"2026-05-20T10:33:49","modified_gmt":"2026-05-20T08:33:49","slug":"nossos-servicos-na-alemanha","status":"publish","type":"page","link":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/","title":{"rendered":"Nossos servi\u00e7os na Alemanha"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3329\" class=\"elementor elementor-3329 elementor-426\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d74cfe elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5d74cfe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d75f5fa\" data-id=\"1d75f5fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e621b1c\" data-id=\"7e621b1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ef855a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ef855a\" data-element_type=\"section\" data-e-type=\"section\" id=\"asd_title_country\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-1e337bc\" data-id=\"1e337bc\" data-element_type=\"column\" data-e-type=\"column\" id=\"asd_discover_title\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8003c2e elementor-widget elementor-widget-text-editor\" data-id=\"8003c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asd-int.com\/pt-pt\/\">ASD GROUP<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/pt-pt\/os-nossos-servicos-por-pais\/\">OS NOSSOS SERVI\u00c7OS POR PA\u00cdS<\/a> &gt; ALEMANHA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d13937a elementor-widget elementor-widget-heading\" data-id=\"7d13937a\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"asd_title_discover\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Descubra nossos servi\u00e7os:<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-af3e2f5\" data-id=\"af3e2f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c68d606 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"c68d606\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"pays_menu_country_asd\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-c68d606\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58351\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Pays<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58352\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" class=\"elementor-sub-item\">Alemanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129289\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-australia\/\" class=\"elementor-sub-item\">Austr\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58353\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-austria\/\" class=\"elementor-sub-item\">\u00c1ustria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58391\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-belgica\/\" class=\"elementor-sub-item\">B\u00e9lgica<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58392\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-bulgaria\/\" class=\"elementor-sub-item\">Bulg\u00e1ria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58393\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-canada\/\" class=\"elementor-sub-item\">Canad\u00e1<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129288\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116490\" class=\"elementor-sub-item\">China<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58394\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-chipre\/\" class=\"elementor-sub-item\">Chipre<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58437\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-croacia\/\" class=\"elementor-sub-item\">Cro\u00e1cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58438\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-dinamarca\/\" class=\"elementor-sub-item\">Dinamarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58702\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovaquia\/\" class=\"elementor-sub-item\">Eslov\u00e1quia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58729\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovenia\/\" class=\"elementor-sub-item\">Eslov\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58440\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-espanha\/\" class=\"elementor-sub-item\">Espanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58475\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-estonia\/\" class=\"elementor-sub-item\">Est\u00f4nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58476\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-estados-unidos\/\" class=\"elementor-sub-item\">Estados Unidos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58477\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-finlandia\/\" class=\"elementor-sub-item\">Finl\u00e2ndia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58478\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-franca\/\" class=\"elementor-sub-item\">Fran\u00e7a<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58479\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-grecia\/\" class=\"elementor-sub-item\">Gr\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58557\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-hungria\/\" class=\"elementor-sub-item\">Hungria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129287\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116549\" class=\"elementor-sub-item\">Indon\u00e9sia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58559\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-irlanda\/\" class=\"elementor-sub-item\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58560\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" class=\"elementor-sub-item\">It\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58597\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-letonia\/\" class=\"elementor-sub-item\">Let\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58598\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-lituania\/\" class=\"elementor-sub-item\">Litu\u00e2nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129290\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-luxemburgo\/\" class=\"elementor-sub-item\">Luxemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58599\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-malta\/\" class=\"elementor-sub-item\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58611\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-marrocos\/\" class=\"elementor-sub-item\">Marrocos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58612\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-noruega\/\" class=\"elementor-sub-item\">Noruega<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58613\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-paises-baixos\/\" class=\"elementor-sub-item\">Pa\u00edses Baixos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58614\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-polonia\/\" class=\"elementor-sub-item\">Pol\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58615\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-portugal\/\" class=\"elementor-sub-item\">Portugal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58699\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-republica-checa\/\" class=\"elementor-sub-item\">Rep\u00fablica Checa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58700\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-romania\/\" class=\"elementor-sub-item\">Rom\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58701\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-reino-unido\/\" class=\"elementor-sub-item\">Reino Unido<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129286\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-singapura\/\" class=\"elementor-sub-item\">Singapura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58730\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suecia\/\" class=\"elementor-sub-item\">Su\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58731\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suica\/\" class=\"elementor-sub-item\">Su\u00ed\u00e7a<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-c68d606\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-58351\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Pays<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58352\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Alemanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129289\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-australia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Austr\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58353\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-austria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">\u00c1ustria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58391\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-belgica\/\" class=\"elementor-sub-item\" tabindex=\"-1\">B\u00e9lgica<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58392\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-bulgaria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bulg\u00e1ria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58393\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-canada\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Canad\u00e1<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129288\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116490\" class=\"elementor-sub-item\" tabindex=\"-1\">China<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58394\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-chipre\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Chipre<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58437\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-croacia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Cro\u00e1cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58438\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-dinamarca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Dinamarca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58702\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovaquia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Eslov\u00e1quia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58729\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-eslovenia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Eslov\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58440\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-espanha\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Espanha<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58475\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-estonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Est\u00f4nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58476\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-estados-unidos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Estados Unidos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58477\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-finlandia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Finl\u00e2ndia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58478\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-franca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Fran\u00e7a<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58479\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-grecia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gr\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58557\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-hungria\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hungria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129287\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=116549\" class=\"elementor-sub-item\" tabindex=\"-1\">Indon\u00e9sia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58559\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-irlanda\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Irlanda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58560\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-italia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">It\u00e1lia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58597\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-letonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Let\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58598\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-lituania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Litu\u00e2nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129290\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-luxemburgo\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Luxemburgo<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58599\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-malta\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Malta<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58611\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-marrocos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Marrocos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58612\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-noruega\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Noruega<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58613\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-nos-paises-baixos\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pa\u00edses Baixos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58614\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-polonia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pol\u00f3nia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58615\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-portugal\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Portugal<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58699\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-republica-checa\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Rep\u00fablica Checa<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58700\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-romania\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Rom\u00eania<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58701\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-no-reino-unido\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Reino Unido<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-129286\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-em-singapura\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Singapura<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58730\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suecia\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Su\u00e9cia<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58731\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-suica\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Su\u00ed\u00e7a<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd62463 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cd62463\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e53a45c\" data-id=\"e53a45c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccc2c42 elementor-widget elementor-widget-text-editor\" data-id=\"ccc2c42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O ASD Group ajuda-o em todas as fases do desenvolvimento das suas actividades em Alemanha nas \u00e1reas do IVA, fiscalidade e impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamenta\u00e7\u00e3o social e estrat\u00e9gia empresarial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d72f445\" data-id=\"d72f445\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7768449a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7768449a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10f71793\" data-id=\"10f71793\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65f23a42 elementor-widget elementor-widget-image\" data-id=\"65f23a42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54184\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c07def test-caca elementor-widget elementor-widget-heading\" data-id=\"74c07def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Servi\u00e7os dispon\u00edveis na Alemanha<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bf2241 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3bf2241\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-314f981\" data-id=\"314f981\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dfe08da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfe08da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c88206\" data-id=\"3c88206\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7b6348 elementor-tabs-view-vertical menu_service_asd elementor-widget elementor-widget-tabs\" data-id=\"f7b6348\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"menu_service_3\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2591\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2591\" aria-expanded=\"false\">FISCAL<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2592\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2592\" aria-expanded=\"false\">ALF\u00c2NDEGA<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2593\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2593\" aria-expanded=\"false\">SOCIAL<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2594\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2594\" aria-expanded=\"false\">ESTRAT\u00c9GIA EMPRESARIAL<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2591\" aria-expanded=\"false\">FISCAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2591\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2591\" tabindex=\"0\" hidden=\"false\"><div class=\"menu-allemagne-fiscal-pt-container\"><ul id=\"menu-allemagne-fiscal-pt\" class=\"menu\"><li id=\"menu-item-152606\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152606\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/obter-um-numero-de-iva-intracomunitario\/\">Como obter um n\u00famero de IVA intracomunit\u00e1rio?<\/a><\/li>\n<li id=\"menu-item-152607\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152607\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/mandatario-fiscal-alemanha\/\">Nomear um mandat\u00e1rio fiscal na Alemanha<\/a><\/li>\n<li id=\"menu-item-152608\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152608\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representacao-fiscal-alemanha\/\">Representa\u00e7\u00e3o Fiscal na Alemanha<\/a><\/li>\n<li id=\"menu-item-152609\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152609\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/service\/como-receber-o-reembolso-do-iva-intracomunitario\/\">Como receber o reembolso do IVA intracomunit\u00e1rio?<\/a><\/li>\n<li id=\"menu-item-152610\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152610\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-alemanha\/\">Reembolso de IVA alem\u00e3o para as empresas estabelecidas fora da UE \u2013 13\u00aa Diretiva<\/a><\/li>\n<li id=\"menu-item-152611\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-152611\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/provas-de-transporte\/\">Provas de transporte &#8211; ASD QuickProof<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2592\" aria-expanded=\"false\">ALF\u00c2NDEGA<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2592\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2592\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-allemagne-douane-pt-container\"><ul id=\"menu-allemagne-douane-pt\" class=\"menu\"><li id=\"menu-item-59443\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-59443\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/operacoes-aduaneiras\/\">Desalfandegamento: como gerir as suas opera\u00e7\u00f5es aduaneiras ?<\/a><\/li>\n<li id=\"menu-item-59444\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-59444\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/como-obter-um-numero-eori\/\">Como obter um n\u00famero EORI?<\/a><\/li>\n<li id=\"menu-item-83860\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-83860\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/imposto-especial-sobre-a-venda-a-distancia-de-bebidas-alcoolicas\/old\">Imposto especial sobre a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/a><\/li>\n<li id=\"menu-item-85106\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-85106\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/intrastat-alemanha\/\">Intrastat na Alemanha<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2593\" aria-expanded=\"false\">SOCIAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2593\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2593\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-allemagne-social-pt-container\"><ul id=\"menu-allemagne-social-pt\" class=\"menu\"><li id=\"menu-item-59647\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-59647\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representacao-empresa-estrangeira\/\">Representa\u00e7\u00e3o de uma empresa estrangeira: recrutamento para contratar pessoal no estrangeiro<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2594\" aria-expanded=\"false\">ESTRAT\u00c9GIA EMPRESARIAL<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2594\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2594\" tabindex=\"0\" hidden=\"hidden\"><div class=\"menu-allemagne-strategie-dentreprise-pt-container\"><ul id=\"menu-allemagne-strategie-dentreprise-pt\" class=\"menu\"><li id=\"menu-item-128575\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128575\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/servicos-consultoria-rgpd\/\">Servi\u00e7os \u2013 consultoria RGPD \u2013 externalize a gest\u00e3o das suas problem\u00e1ticas RGPD<\/a><\/li>\n<li id=\"menu-item-128576\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128576\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/encarregado-da-protecao-de-dados-epd\/\">Encarregado da Prote\u00e7\u00e3o de Dados (EPD): terceirize a gest\u00e3o das suas problem\u00e1ticas de RGPD<\/a><\/li>\n<li id=\"menu-item-128577\" class=\"menu-item menu-item-type-post_type menu-item-object-service menu-item-128577\"><a href=\"https:\/\/www.asd-int.com\/pt-pt\/representante-rgpd\/\">Representante RGPD: externalize a gest\u00e3o das suas problem\u00e1ticas RGPD<\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25d33f8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d33f8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c30d7be\" data-id=\"3c30d7be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eeec9b1 elementor-widget elementor-widget-image\" data-id=\"3eeec9b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2\" height=\"111\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" class=\"attachment-large size-large wp-image-54184\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356a7396 test-caca elementor-widget elementor-widget-heading\" data-id=\"356a7396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contacte os nossos peritos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-175ff3d6 elementor-widget elementor-widget-heading\" data-id=\"175ff3d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Quer\u00a0saber mais\u00a0sobre as nossas ofertas?<br \/> Contacte-nose nossos peritos entrar\u00e3o em contato com voc\u00ea em breve.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5d8ae8 elementor-widget elementor-widget-shortcode\" data-id=\"5a5d8ae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=813829' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_style_asd frm_full_submit\" id=\"frm_form_49_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form-2026\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Contact 2026<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"49\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_49\" id=\"frm_hide_fields_49\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form-2026\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_49\" name=\"frm_submit_entry_49\" value=\"efb20ca2da\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/pages\/3329\" \/><div id=\"frm_field_696_container\" class=\"frm_form_field  frm12 frm_first formcontact-require frm_html_container form-field\">* Os campos marcados com um asterisco s\u00e3o obrigat\u00f3rios para nos permitir processar o seu pedido. Alguns dos nossos servi\u00e7os n\u00e3o est\u00e3o dispon\u00edveis em todas as regi\u00f5es e\/ou em todos os sectores.\n<\/div>\n<div id=\"frm_field_635_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">1<\/span><span class=\"subtitle-title\">A sua empresa<\/span><\/div>\n<div id=\"frm_field_616_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_i41ef2\" class=\"frm_primary_label\">Qual \u00e9 o nome da sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef2\" name=\"item_meta[616]\" value=\"\"  placeholder=\"Nome da sua empresa\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_759_container\" class=\"frm_form_field frm_section_heading form-field  section-hidden frm_hide_section\">\r\n\r\n\r\n\r\n<div id=\"frm_field_622_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order0 sort-alphabetically\">\r\n    <label for=\"field_okuhn3\" class=\"frm_primary_label\">Em que pa\u00eds est\u00e1 estabelecida a sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[622]\" id=\"field_okuhn3\"  data-sectionid=\"759\"  data-placeholder=\"Escolha o pa\u00eds onde deseja estabelecer-se\"  placeholder=\"Escolha o pa\u00eds onde deseja estabelecer-se\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Em que pa\u00eds est\u00e1 estabelecida a sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o pa\u00eds onde deseja estabelecer-se<\/option><option  value=\"DE\">Alemanha<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AR\">Argentina<\/option><option  value=\"BR\">Brasil<\/option><option  value=\"BG\">Bulg\u00e1ria<\/option><option  value=\"BE\">B\u00e9lgica<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CY\">Chipre<\/option><option  value=\"CZ\">Ch\u00e9quia<\/option><option  value=\"HR\">Cro\u00e1cia<\/option><option  value=\"DK\">Dinamarca<\/option><option  value=\"SK\">Eslov\u00e1quia<\/option><option  value=\"SI\">Eslov\u00e9nia<\/option><option  value=\"ES\">Espanha<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Est\u00f3nia<\/option><option  value=\"FI\">Finl\u00e2ndia<\/option><option  value=\"FR\">Fran\u00e7a<\/option><option  value=\"GR\">Gr\u00e9cia<\/option><option  value=\"HU\">Hungria<\/option><option  value=\"IE\">Irlanda<\/option><option  value=\"IS\">Isl\u00e2ndia<\/option><option  value=\"IT\">It\u00e1lia<\/option><option  value=\"LV\">Let\u00f4nia<\/option><option  value=\"LI\">Liechtenstein<\/option><option  value=\"LT\">Litu\u00e2nia<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"MD\">Mold\u00e1via<\/option><option  value=\"MX\">M\u00e9xico<\/option><option  value=\"MC\">M\u00f3naco<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"NL\">Pa\u00edses Baixos<\/option><option  value=\"PL\">Pol\u00f3nia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Rom\u00e9nia<\/option><option  value=\"SE\">Su\u00e9cia<\/option><option  value=\"CH\">Su\u00ed\u00e7a<\/option><option  value=\"RS\">S\u00e9rvia<\/option><option  value=\"TR\">Turquia<\/option><option  value=\"UA\">Ucr\u00e2nia<\/option><option  value=\"AT\">\u00c1ustria<\/option><option  value=\"Other\">Outro pa\u00eds (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_617_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 order2 sort-alphabetically\">\r\n    <label for=\"field_85w6d2\" class=\"frm_primary_label\">Qual \u00e9 o sector de atividade da sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[617]\" id=\"field_85w6d2\"  data-sectionid=\"759\"  data-placeholder=\"Escolha o seu setor de atividade\"  placeholder=\"Escolha o seu setor de atividade\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 o sector de atividade da sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o seu setor de atividade<\/option><option  value=\"Agriculture\">Agricultura\n<\/option><option  value=\"Agroalimentaire\">Agroalimentar<\/option><option  value=\"Automobile\">Autom\u00f3vel\n<\/option><option  value=\"Banque et assurances\">Bancos e seguros\n<\/option><option  value=\"Commerce\">Com\u00e9rcio\n<\/option><option  value=\"B\u00e2timent et travaux publics (BTP)\">Constru\u00e7\u00e3o e obras p\u00fablicas\n<\/option><option  value=\"Conseil et services aux entreprises\">Consultoria e servi\u00e7os \u00e0s empresas\n<\/option><option  value=\"Culture et loisirs\">Cultura e lazer<\/option><option  value=\"Sport et \u00e9v\u00e9nements\">Desporto e eventos<\/option><option  value=\"Distribution\">Distribui\u00e7\u00e3o<\/option><option  value=\"\u00c9ducation et formation\">Educa\u00e7\u00e3o e forma\u00e7\u00e3o<\/option><option  value=\"\u00c9nergie\">Energia<\/option><option  value=\"H\u00f4tellerie et restauration\">Hotelaria e restaura\u00e7\u00e3o<\/option><option  value=\"Immobilier\">Imobili\u00e1rio<\/option><option  value=\"Industrie manufacturi\u00e8re\">Ind\u00fastria manufatureira<\/option><option  value=\"Informatique et num\u00e9rique\">Inform\u00e1tica e tecnologia digital<\/option><option  value=\"Logistique et transport\">Log\u00edstica e transporte<\/option><option  value=\"Luxe et mode\">Luxo e moda<\/option><option  value=\"M\u00e9dias et communication\">Meios de comunica\u00e7\u00e3o<\/option><option  value=\"M\u00e9tallurgie et sid\u00e9rurgie\">Metalurgia e siderurgia<\/option><option  value=\"Recherche et d\u00e9veloppement\">Pesquisa e desenvolvimento<\/option><option  value=\"Chimie et pharmacie\">Qu\u00edmica e farm\u00e1cia\n<\/option><option  value=\"Sant\u00e9 et bien-\u00eatre\">Sa\u00fade e bem-estar<\/option><option  value=\"S\u00e9curit\u00e9 et d\u00e9fense\">Seguran\u00e7a e defesa<\/option><option  value=\"Services publics et administration\">Servi\u00e7os p\u00fablicos e administra\u00e7\u00e3o<\/option><option  value=\"T\u00e9l\u00e9communications\">Telecomunica\u00e7\u00f5es<\/option><option  value=\"Tourisme\">Turismo<\/option><option  value=\"Textile et habillement\">T\u00eaxteis e vestu\u00e1rio<\/option><option  value=\"Other\">Outro setor (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_639_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order1\">\r\n\t<label for=\"field_6q8fw\" id=\"field_6q8fw_label\" class=\"frm_primary_label\">Escolheu \"Outro pa\u00eds\", pode especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_6q8fw\" name=\"item_meta[639]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Preencha o pa\u00eds de estabelecimento\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolheu &quot;Outro pa\u00eds&quot;, pode especificar? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_640_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_alignright order3\">\r\n\t<label for=\"field_8yduw\" id=\"field_8yduw_label\" class=\"frm_primary_label\">Escolheu \"Outro setor\", pode especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_8yduw\" name=\"item_meta[640]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Preencha o setor de atividade\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolheu &quot;Outro setor&quot;, pode especificar? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<\/div>\n<div id=\"frm_field_637_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">2<\/span><span class=\"subtitle-title\">As suas necessidades<\/span><\/div>\n<div id=\"frm_field_623_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 relative frm_first sort-alphabetically\">\r\n    <label for=\"field_l1biv3\" class=\"frm_primary_label\">Em que pa\u00eds deseja desenvolver a sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[623]\" id=\"field_l1biv3\"  data-placeholder=\"Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)\"  placeholder=\"Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Em que pa\u00eds deseja desenvolver a sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)<\/option><option  value=\"DE\">Alemanha<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"BG\">B\u00e9lgica\n<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CY\">Chipre\n<\/option><option  value=\"CZ\">Ch\u00e9quia<\/option><option  value=\"HR\">Cro\u00e1cia\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"SK\">Eslov\u00e1quia<\/option><option  value=\"SI\">Eslov\u00e9nia<\/option><option  value=\"ES\">Espanha\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Est\u00f3nia\n<\/option><option  value=\"FI\">Finl\u00e2ndia\n<\/option><option  value=\"FR\">Fran\u00e7a\n<\/option><option  value=\"GR\">Gr\u00e9cia\n<\/option><option  value=\"HU\">Hungria\n<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"IT\">It\u00e1lia\n<\/option><option  value=\"LV\">Let\u00f4nia\n<\/option><option  value=\"LT\">Litu\u00e2nia\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"NL\">Pa\u00edses Baixos<\/option><option  value=\"PL\">Pol\u00f3nia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Rom\u00e9nia<\/option><option  value=\"SE\">Su\u00e9cia<\/option><option  value=\"CH\">Su\u00ed\u00e7a<\/option><option  value=\"AT\">\u00c1ustria\n<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_681_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nqwnw\" id=\"field_nqwnw_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Espanha?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[681]\" id=\"field_nqwnw\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Espanha? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_647_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_31i7k\" id=\"field_31i7k_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Alemanha?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[647]\" id=\"field_31i7k\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Alemanha? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_648_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n\t<label for=\"field_2p88l\" id=\"field_2p88l_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a \u00c1ustria?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[648]\" id=\"field_2p88l\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n\" data-invmsg=\"Qual \u00e9 a sua necessidade para a \u00c1ustria? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_649_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_9i5uq\" id=\"field_9i5uq_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a B\u00e9lgica?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[649]\" id=\"field_9i5uq\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a B\u00e9lgica?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_677_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3n29\" id=\"field_v3n29_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Bulg\u00e1ria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[677]\" id=\"field_v3n29\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Bulg\u00e1ria?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_651_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7frx6\" id=\"field_7frx6_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para o Canad\u00e1?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[651]\" id=\"field_7frx6\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para o Canad\u00e1? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_676_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xhngf\" id=\"field_xhngf_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade em Chipre?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[676]\" id=\"field_xhngf\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade em Chipre? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_675_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_iyrkx\" id=\"field_iyrkx_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Cro\u00e1cia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[675]\" id=\"field_iyrkx\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Cro\u00e1cia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_674_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hh8ys\" id=\"field_hh8ys_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Dinamarca?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[674]\" id=\"field_hh8ys\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Dinamarca?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_673_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xk6v1\" id=\"field_xk6v1_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Est\u00f3nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[673]\" id=\"field_xk6v1\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Est\u00f3nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_650_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7127q\" id=\"field_7127q_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para os Estados Unidos?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[650]\" id=\"field_7127q\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para os Estados Unidos? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n<\/option><option  value=\"Fiscal : Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_672_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hrplp\" id=\"field_hrplp_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Finl\u00e2ndia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[672]\" id=\"field_hrplp\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Finl\u00e2ndia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_671_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jw8ml\" id=\"field_jw8ml_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Fran\u00e7a?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[671]\" id=\"field_jw8ml\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Fran\u00e7a?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_670_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_3gqvi\" id=\"field_3gqvi_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Gr\u00e9cia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[670]\" id=\"field_3gqvi\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Gr\u00e9cia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_669_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ajvsb\" id=\"field_ajvsb_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Hungria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[669]\" id=\"field_ajvsb\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Hungria?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_668_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r1kza\" id=\"field_r1kza_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Irlanda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[668]\" id=\"field_r1kza\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Irlanda?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_667_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_qo5nf\" id=\"field_qo5nf_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a It\u00e1lia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[667]\" id=\"field_qo5nf\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a It\u00e1lia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_666_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z3dfa\" id=\"field_z3dfa_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Let\u00f3nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[666]\" id=\"field_z3dfa\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Let\u00f3nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_665_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mm4zs\" id=\"field_mm4zs_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Litu\u00e2nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[665]\" id=\"field_mm4zs\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Litu\u00e2nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_664_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_kel0x\" id=\"field_kel0x_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para o Luxemburgo?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[664]\" id=\"field_kel0x\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para o Luxemburgo?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_663_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dcpyc\" id=\"field_dcpyc_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para Malta?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[663]\" id=\"field_dcpyc\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para Malta?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_662_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zz48j\" id=\"field_zz48j_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para os Pa\u00edses Baixos?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[662]\" id=\"field_zz48j\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para os Pa\u00edses Baixos?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_661_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ji2cs\" id=\"field_ji2cs_label\" class=\"frm_primary_label\">Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[661]\" id=\"field_ji2cs\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_659_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aepqm\" id=\"field_aepqm_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para Portugal?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[659]\" id=\"field_aepqm\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para Portugal? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_658_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_d1twg\" id=\"field_d1twg_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Ch\u00e9quia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[658]\" id=\"field_d1twg\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Ch\u00e9quia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_657_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3096\" id=\"field_v3096_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Rom\u00e9nia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[657]\" id=\"field_v3096\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Rom\u00e9nia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_656_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hlo6e\" id=\"field_hlo6e_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para o Reino Unido?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[656]\" id=\"field_hlo6e\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para o Reino Unido? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_655_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_azerr\" id=\"field_azerr_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Eslov\u00e1quia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[655]\" id=\"field_azerr\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Eslov\u00e1quia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_654_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vtjje\" id=\"field_vtjje_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Eslov\u00eania?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[654]\" id=\"field_vtjje\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Eslov\u00eania? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_653_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_e1wi2\" id=\"field_e1wi2_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Su\u00e9cia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[653]\" id=\"field_e1wi2\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Su\u00e9cia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_652_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mf65v\" id=\"field_mf65v_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Su\u00ed\u00e7a?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[652]\" id=\"field_mf65v\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Su\u00ed\u00e7a? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_678_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_19pbf\" id=\"field_19pbf_label\" class=\"frm_primary_label\">[Alemanha] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[678]\" id=\"field_19pbf\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/ZM\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ ZM \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_679_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gz1w7\" id=\"field_gz1w7_label\" class=\"frm_primary_label\">[Alemanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[679]\" id=\"field_gz1w7\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_798_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dego5\" id=\"field_dego5_label\" class=\"frm_primary_label\">[Alemanha] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[798]\" id=\"field_dego5\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_682_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eeeq6\" id=\"field_eeeq6_label\" class=\"frm_primary_label\">[\u00c1ustria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[682]\" id=\"field_eeeq6\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_683_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r8c1d\" id=\"field_r8c1d_label\" class=\"frm_primary_label\">[\u00c1ustria] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[683]\" id=\"field_r8c1d\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_799_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_95ick\" id=\"field_95ick_label\" class=\"frm_primary_label\">[\u00c1ustria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[799]\" id=\"field_95ick\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_684_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aw4s9\" id=\"field_aw4s9_label\" class=\"frm_primary_label\">[B\u00e9lgica] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[684]\" id=\"field_aw4s9\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_685_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8oi4a\" id=\"field_8oi4a_label\" class=\"frm_primary_label\">[B\u00e9lgica] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[685]\" id=\"field_8oi4a\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_686_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hnplb\" id=\"field_hnplb_label\" class=\"frm_primary_label\">[B\u00e9lgica] Estrat\u00e9gia: Desenvolvimento de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[686]\" id=\"field_hnplb\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Estrat\u00e9gia: Desenvolvimento de empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_687_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dsbn4\" id=\"field_dsbn4_label\" class=\"frm_primary_label\">[Bulg\u00e1ria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[687]\" id=\"field_dsbn4\"  data-placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Bulg\u00e1ria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_800_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gbi4d\" id=\"field_gbi4d_label\" class=\"frm_primary_label\">[Bulg\u00e1ria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[800]\" id=\"field_gbi4d\"  data-placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Bulg\u00e1ria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_689_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_a9qen\" id=\"field_a9qen_label\" class=\"frm_primary_label\">[Canad\u00e1] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[689]\" id=\"field_a9qen\"  data-placeholder=\"Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Canad\u00e1] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)<\/option><option  value=\"Gestion des taxes TPS\/TVH\/TVP\">Gest\u00e3o dos impostos GST\/HST\/PST<\/option><option  value=\"Gestion de la certification employeur non-r\u00e9sident\">Gest\u00e3o da certifica\u00e7\u00e3o de empregadores n\u00e3o residentes<\/option><option  value=\"Gestion de la dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents\">Gest\u00e3o da isen\u00e7\u00e3o de reten\u00e7\u00e3o na fonte para empregadores n\u00e3o residentes<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_646_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8yjzs\" id=\"field_8yjzs_label\" class=\"frm_primary_label\">[Espanha] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[646]\" id=\"field_8yjzs\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Gestion de la taxe sur les emballages plastiques non r\u00e9utilisables\">Gest\u00e3o da taxa sobre embalagens de pl\u00e1stico n\u00e3o reutiliz\u00e1veis<\/option><option  value=\"Gestion de la taxe sur les pneus usag\u00e9s\">Gest\u00e3o da taxa sobre pneus usados<\/option><option  value=\"Gestion de l&#039;Eco Tax DEEE (WEEE)\">Gest\u00e3o da Eco Tax DEEE (WEEE)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_641_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_whqtx\" id=\"field_whqtx_label\" class=\"frm_primary_label\">[Espanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[641]\" id=\"field_whqtx\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_643_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_upzx7\" id=\"field_upzx7_label\" class=\"frm_primary_label\">[Espanha] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[643]\" id=\"field_upzx7\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_691_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5vbnj\" id=\"field_5vbnj_label\" class=\"frm_primary_label\">[Fran\u00e7a] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[691]\" id=\"field_5vbnj\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale immobili\u00e8re\">Representa\u00e7\u00e3o fiscal imobili\u00e1ria<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"E-Reporting France\">E-Reporting em Fran\u00e7a<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_692_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y17z7\" id=\"field_y17z7_label\" class=\"frm_primary_label\">[Fran\u00e7a] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[692]\" id=\"field_y17z7\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations EMEBI (ERTVA\u2026)\/DES\">Gest\u00e3o das declara\u00e7\u00f5es EMEBI (ERTVA\u2026)\/DES<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires et SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de RTC et RCO\">Acompanhamento na obten\u00e7\u00e3o de IPV e IVO<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de la certification OEA\">Acompanhamento na obten\u00e7\u00e3o da certifica\u00e7\u00e3o AEO<\/option><option  value=\"Gestion des DDR selon le RDUE\">Gest\u00e3o dos DDS de acordo com o EUDR<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gest\u00e3o dos direitos de consumo para vendas \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"Gestion de la taxe carbone (CBAM\/MACF)\">Gest\u00e3o do imposto de carbono (CBAM)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_693_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q9gx\" id=\"field_q9gx_label\" class=\"frm_primary_label\">[Fran\u00e7a] Social: Regulamentos, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[693]\" id=\"field_q9gx\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Social: Regulamentos, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion des missions de d\u00e9tachement de salari\u00e9s \u00e9trangers en France (ASD SPW)\">Gest\u00e3o das miss\u00f5es de destacamento de trabalhadores estrangeiros em Fran\u00e7a (ASD SPW)<\/option><option  value=\"Gestion de la repr\u00e9sentation fiscale dans le cadre du pr\u00e9l\u00e8vement \u00e0 la source\">Gest\u00e3o da representa\u00e7\u00e3o fiscal no \u00e2mbito da reten\u00e7\u00e3o na fonte<\/option><option  value=\"Gestion de repr\u00e9sentation de firme \u00e9trang\u00e8re\">Gest\u00e3o da representa\u00e7\u00e3o de empresa estrangeira<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_694_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5kh5i\" id=\"field_5kh5i_label\" class=\"frm_primary_label\">[Fran\u00e7a] Estrat\u00e9gia: Desenvolvimento de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[694]\" id=\"field_5kh5i\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Estrat\u00e9gia: Desenvolvimento de empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Gestion de la domiciliation d&#039;entreprise\">Gest\u00e3o da domicilia\u00e7\u00e3o da empresa<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_698_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jlotu\" id=\"field_jlotu_label\" class=\"frm_primary_label\">[Estados Unidos] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[698]\" id=\"field_jlotu\"  data-placeholder=\"Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Estados Unidos] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)<\/option><option  value=\"Gestion de la &quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Gest\u00e3o do &quot;Sales and Use Tax&quot; nos Estados Unidos<\/option><option  value=\"Gestion des formulaires W-8 et W-9 aux \u00c9tats-Unis\">Gest\u00e3o dos formul\u00e1rios W-8 e W-9 nos Estados Unidos<\/option><option  value=\"Gestion des formalit\u00e9s li\u00e9es au Nexus aux \u00c9tats-Unis\">Gest\u00e3o das formalidades relacionadas com o Nexus nos Estados Unidos<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_699_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_44svk\" id=\"field_44svk_label\" class=\"frm_primary_label\">[It\u00e1lia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[699]\" id=\"field_44svk\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du Visto di Conformit\u00e0\">Gest\u00e3o do Visto di Conformit\u00e0<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_700_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ys0xm\" id=\"field_ys0xm_label\" class=\"frm_primary_label\">[It\u00e1lia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[700]\" id=\"field_ys0xm\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_701_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1anf4\" id=\"field_1anf4_label\" class=\"frm_primary_label\">[It\u00e1lia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[701]\" id=\"field_1anf4\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_702_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zq0ua\" id=\"field_zq0ua_label\" class=\"frm_primary_label\">[Chipre] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[702]\" id=\"field_zq0ua\"  data-placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Chipre] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Chipre (etapa 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_801_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q3a1e\" id=\"field_q3a1e_label\" class=\"frm_primary_label\">[Chipre] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[801]\" id=\"field_q3a1e\"  data-placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Chipre] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Chipre (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_704_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_s06v4\" id=\"field_s06v4_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[704]\" id=\"field_s06v4\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_705_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vjfrb\" id=\"field_vjfrb_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[705]\" id=\"field_vjfrb\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_802_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xna4z\" id=\"field_xna4z_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[802]\" id=\"field_xna4z\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_706_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2i1vf\" id=\"field_2i1vf_label\" class=\"frm_primary_label\">[Dinamarca] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[706]\" id=\"field_2i1vf\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List \/ EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_707_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_g3d2w\" id=\"field_g3d2w_label\" class=\"frm_primary_label\">[Dinamarca] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[707]\" id=\"field_g3d2w\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_803_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1df4u\" id=\"field_1df4u_label\" class=\"frm_primary_label\">[Dinamarca] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[803]\" id=\"field_1df4u\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_708_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_cs0h5\" id=\"field_cs0h5_label\" class=\"frm_primary_label\">[Est\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[708]\" id=\"field_cs0h5\"  data-placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_709_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2ahrq\" id=\"field_2ahrq_label\" class=\"frm_primary_label\">[Est\u00f3nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[709]\" id=\"field_2ahrq\"  data-placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_804_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_urojq\" id=\"field_urojq_label\" class=\"frm_primary_label\">[Est\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[804]\" id=\"field_urojq\"  data-placeholder=\"Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_710_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jz0iw\" id=\"field_jz0iw_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[710]\" id=\"field_jz0iw\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_711_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z5cpa\" id=\"field_z5cpa_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[711]\" id=\"field_z5cpa\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_805_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oyx7h\" id=\"field_oyx7h_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[805]\" id=\"field_oyx7h\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_712_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6jrxn\" id=\"field_6jrxn_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[712]\" id=\"field_6jrxn\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_713_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rgel6\" id=\"field_rgel6_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[713]\" id=\"field_rgel6\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_806_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6ls28\" id=\"field_6ls28_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[806]\" id=\"field_6ls28\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_714_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_w6w9o\" id=\"field_w6w9o_label\" class=\"frm_primary_label\">[Hungria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[714]\" id=\"field_w6w9o\"  data-placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Hungria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_807_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jxc2i\" id=\"field_jxc2i_label\" class=\"frm_primary_label\">[Hungria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[807]\" id=\"field_jxc2i\"  data-placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Hungria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_716_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lhn0a\" id=\"field_lhn0a_label\" class=\"frm_primary_label\">[Irlanda] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[716]\" id=\"field_lhn0a\"  data-placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_808_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hpoqk\" id=\"field_hpoqk_label\" class=\"frm_primary_label\">[Irlanda] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[808]\" id=\"field_hpoqk\"  data-placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_718_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eh4ic\" id=\"field_eh4ic_label\" class=\"frm_primary_label\">[Let\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[718]\" id=\"field_eh4ic\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5 n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_719_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4t4b4\" id=\"field_4t4b4_label\" class=\"frm_primary_label\">[Let\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[719]\" id=\"field_4t4b4\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_809_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_btj00\" id=\"field_btj00_label\" class=\"frm_primary_label\">[Let\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[809]\" id=\"field_btj00\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_720_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_62mpm\" id=\"field_62mpm_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[720]\" id=\"field_62mpm\"  data-placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_721_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_fqvcn\" id=\"field_fqvcn_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[721]\" id=\"field_fqvcn\"  data-placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_810_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_tahxc\" id=\"field_tahxc_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[810]\" id=\"field_tahxc\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_722_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6asdz\" id=\"field_6asdz_label\" class=\"frm_primary_label\">[Luxemburgo] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[722]\" id=\"field_6asdz\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_723_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_uv0bx\" id=\"field_uv0bx_label\" class=\"frm_primary_label\">[Luxemburgo] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[723]\" id=\"field_uv0bx\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_811_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q5m9h\" id=\"field_q5m9h_label\" class=\"frm_primary_label\">[Luxemburgo] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[811]\" id=\"field_q5m9h\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_725_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_de7m1\" id=\"field_de7m1_label\" class=\"frm_primary_label\">[Malta] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[725]\" id=\"field_de7m1\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_726_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_n2ufm\" id=\"field_n2ufm_label\" class=\"frm_primary_label\">[Malta] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[726]\" id=\"field_n2ufm\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Gestion des d\u00e9clarations europ\u00e9ennes de services (DES)\">Gest\u00e3o das declara\u00e7\u00f5es europeias de servi\u00e7os (DES)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_813_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_l10m9\" id=\"field_l10m9_label\" class=\"frm_primary_label\">[Malta] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[813]\" id=\"field_l10m9\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_727_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2af4r\" id=\"field_2af4r_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[727]\" id=\"field_2af4r\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_728_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_za0r\" id=\"field_za0r_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[728]\" id=\"field_za0r\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_814_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_i16up\" id=\"field_i16up_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[814]\" id=\"field_i16up\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_729_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_h5qk6\" id=\"field_h5qk6_label\" class=\"frm_primary_label\">[Pol\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[729]\" id=\"field_h5qk6\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_730_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_42afs\" id=\"field_42afs_label\" class=\"frm_primary_label\">[Pol\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[730]\" id=\"field_42afs\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_731_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rd7rn\" id=\"field_rd7rn_label\" class=\"frm_primary_label\">[Pol\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[731]\" id=\"field_rd7rn\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_733_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6wlea\" id=\"field_6wlea_label\" class=\"frm_primary_label\">[Portugal] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[733]\" id=\"field_6wlea\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Facturation \u00e9lectronique et\/ou e-reporting\">Fatura\u00e7\u00e3o eletr\u00f3nica e\/ou e-reporting<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_734_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_u9472\" id=\"field_u9472_label\" class=\"frm_primary_label\">[Portugal] Aduana: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[734]\" id=\"field_u9472\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Aduana: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires,SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accises pour la vente \u00e0 distance de boissons alcooliques au Portugal\">Gest\u00e3o dos impostos especiais de consumo para a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas em Portugal<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_815_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rlp4g\" id=\"field_rlp4g_label\" class=\"frm_primary_label\">[Portugal] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[815]\" id=\"field_rlp4g\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Accompagnement certification logiciel facturation \u00e9lectronique\">Acompanhamento na certifica\u00e7\u00e3o de software de fatura\u00e7\u00e3o eletr\u00f3nica<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_735_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5hg1m\" id=\"field_5hg1m_label\" class=\"frm_primary_label\">[Ch\u00e9quia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[735]\" id=\"field_5hg1m\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Ch\u00e9quia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_736_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_t8kbm\" id=\"field_t8kbm_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[736]\" id=\"field_t8kbm\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_816_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oawcf\" id=\"field_oawcf_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[816]\" id=\"field_oawcf\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_739_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4y9dt\" id=\"field_4y9dt_label\" class=\"frm_primary_label\">[Rom\u00e9nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[739]\" id=\"field_4y9dt\"  data-placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rom\u00e9nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_817_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_69ksn\" id=\"field_69ksn_label\" class=\"frm_primary_label\">[Rom\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[817]\" id=\"field_69ksn\"  data-placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rom\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_741_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ownk6\" id=\"field_ownk6_label\" class=\"frm_primary_label\">[Reino Unido] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[741]\" id=\"field_ownk6\"  data-placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Reino Unido (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_742_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ioidj\" id=\"field_ioidj_label\" class=\"frm_primary_label\">[Reino Unido] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[742]\" id=\"field_ioidj\"  data-placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Reino Unido (passo 3\/4)<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res et d\u00e9douanements\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras e desalfandegamento<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires, SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gest\u00e3o dos direitos de consumo para vendas \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_743_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v16pe\" id=\"field_v16pe_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[743]\" id=\"field_v16pe\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_744_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_idpgs\" id=\"field_idpgs_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[744]\" id=\"field_idpgs\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_818_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nueuk\" id=\"field_nueuk_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[818]\" id=\"field_nueuk\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_745_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_11566a\" id=\"field_11566a_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[745]\" id=\"field_11566a\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_747_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lwwyc\" id=\"field_lwwyc_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[747]\" id=\"field_lwwyc\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_819_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z7hx0\" id=\"field_z7hx0_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[819]\" id=\"field_z7hx0\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_748_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_shkof\" id=\"field_shkof_label\" class=\"frm_primary_label\">[Su\u00e9cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[748]\" id=\"field_shkof\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00e9cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_820_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hgxin\" id=\"field_hgxin_label\" class=\"frm_primary_label\">[Su\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[820]\" id=\"field_hgxin\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_750_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y6l2p\" id=\"field_y6l2p_label\" class=\"frm_primary_label\">[Su\u00ed\u00e7a] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[750]\" id=\"field_y6l2p\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00ed\u00e7a] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Remboursement TVA (13e)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_626_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_bz8k12\" class=\"frm_primary_label\">Explique brevemente a sua necessidade\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[626]\" id=\"field_bz8k12\" rows=\"5\"  placeholder=\"Ex.: A nossa empresa deseja reembolsar o IVA na Alemanha... (passo 4\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Explique brevemente a sua necessidade&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_638_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><span class=\"subtitle-pretitle\">3<\/span><span class=\"subtitle-title\">Os seus contactos<\/span><\/div>\n<div id=\"frm_field_619_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_ocfup142\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup142\" name=\"item_meta[619]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Primeiro nome&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_618_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n    <label for=\"field_qh4icy42\" class=\"frm_primary_label\">Apelido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy42\" name=\"item_meta[618]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Apelido&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_620_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc3\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc3\" name=\"item_meta[620]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_621_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa4\" class=\"frm_primary_label\">Telefone\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa4\" name=\"item_meta[621]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"O n\u00famero de telefone \u00e9 inv\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_628_container\" class=\"frm_form_field form-field  frm_none_container checkbox formcontact-newsletter vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_628-0\">\t\t\t<label  for=\"field_e2sgs2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[628][]\" id=\"field_e2sgs2-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter n\u00e3o \u00e9 v\u00e1lido\"   \/> Quero subscrever a newsletter de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_629_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox formcontact-rgpd vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_629-0\">\t\t\t<label  for=\"field_y30e3-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[629][]\" id=\"field_y30e3-0\" value=\"J&#039;accepte que mes donn\u00e9es soient utilis\u00e9es pour traiter ma demande, conform\u00e9ment \u00e0 la &lt;a href=&quot;https:\/\/www.asd-int.com\/confidentialite-et-donnees-personnelles\/&quot; target=&quot;_blank&quot; rel=&quot;noopener noreferrer&quot;&gt;politique de confidentialit\u00e9.&lt;\/a&gt;\"  data-reqmsg=\"Este campo n\u00e3o pode estar vazio.\n\" data-invmsg=\"RGPD n\u00e3o \u00e9 v\u00e1lido\"   aria-required=\"true\"  \/> Aceito que os meus dados sejam utilizados para tratar o seu pedido, em conformidade com a <a href=\"https:\/\/www.asd-int.com\/confidentialite-et-donnees-personnelles\/\" target=\"_blank\" rel=\"noopener noreferrer\">pol\u00edtica de privacidade.<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_630_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\" \/><\/div>\n<div id=\"frm_field_631_container\" class=\"frm_form_field form-field  frm_none_container\"><div  id=\"field_koj6t2\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[632]\" id=\"field_8qg9b2\" value=\"\"     \/>\n\t\t<div id=\"frm_field_627_container\" class=\"frm_form_field  formcontact-recaptcha frm_html_container form-field\">Este site est\u00e1 protegido pelo reCAPTCHA.<\/div>\n<div id=\"frm_field_633_container\" class=\"frm_form_field form-field  frm12 frm_first\">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">ENVIAR A MINHA SOLICITA\u00c7\u00c3O<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_936_container\">\n\t\t\t<label for=\"field_nzjgf\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_nzjgf\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[936]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg\/+eAXslVGZydqnmzTElPmB5KMmbttKKm7c1eI55MVwa\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fe15c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fe15c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-402c551\" data-id=\"402c551\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-701cdbe elementor-widget elementor-widget-shortcode\" data-id=\"701cdbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script type=\"text\/javascript\">\r\n\r\nlet defaultMenu = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"elementor-item-anchor\");\r\nlet current_item = document.getElementById(\"pays_menu_country_asd\").getElementsByClassName(\"current_page_item \");\r\n\r\ndefaultMenu[0].innerText = current_item[0].innerText;\r\n\r\n<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt; OS NOSSOS SERVI\u00c7OS POR PA\u00cdS &gt; ALEMANHA Descubra nossos servi\u00e7os: O ASD Group ajuda-o em todas as fases do desenvolvimento das suas&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"parent":3043,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_eb_attr":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"class_list":["post-3329","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nossos servi\u00e7os na Alemanha | ASD Group<\/title>\n<meta name=\"description\" content=\"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nossos servi\u00e7os na Alemanha | ASD Group\" \/>\n<meta property=\"og:description\" content=\"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T08:33:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2\" \/>\n\t<meta property=\"og:image:height\" content=\"111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/\",\"name\":\"Nossos servi\u00e7os na Alemanha | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"datePublished\":\"2018-03-21T15:46:35+00:00\",\"dateModified\":\"2026-05-20T08:33:49+00:00\",\"description\":\"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/trait-bas.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/nossos-servicos-na-alemanha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ag\u00eancias\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/agencias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nossos servi\u00e7os na Alemanha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nossos servi\u00e7os na Alemanha | ASD Group","description":"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/","og_locale":"pt_PT","og_type":"article","og_title":"Nossos servi\u00e7os na Alemanha | ASD Group","og_description":"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/","og_site_name":"ASD","article_modified_time":"2026-05-20T08:33:49+00:00","og_image":[{"width":2,"height":111,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/","url":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/","name":"Nossos servi\u00e7os na Alemanha | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","datePublished":"2018-03-21T15:46:35+00:00","dateModified":"2026-05-20T08:33:49+00:00","description":"O ASD Group assiste-o na Alemanha com IVA, impostos internacionais, opera\u00e7\u00f5es aduaneiras, regulamentos sociais e estrat\u00e9gia empresarial.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/01\/trait-bas.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos-na-alemanha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Ag\u00eancias","item":"https:\/\/www.asd-int.com\/pt-pt\/agencias\/"},{"@type":"ListItem","position":3,"name":"Nossos servi\u00e7os na Alemanha"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3329"}],"version-history":[{"count":8,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3329\/revisions"}],"predecessor-version":[{"id":214128,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3329\/revisions\/214128"}],"up":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3043"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}