{"id":205001,"date":"2026-02-19T08:16:54","date_gmt":"2026-02-19T07:16:54","guid":{"rendered":"https:\/\/www.asd-int.com\/?post_type=service&#038;p=205001"},"modified":"2026-04-29T14:16:45","modified_gmt":"2026-04-29T12:16:45","slug":"reembolso-de-iva-intracomunitario-recupere-rapidamente-o-seu-iva-estrangeiro-na-uniao-europeia","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/","title":{"rendered":"Reembolso de IVA intracomunit\u00e1rio: recupere rapidamente o seu IVA estrangeiro na Uni\u0101o Europeia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"205001\" class=\"elementor elementor-205001 elementor-204845\" data-elementor-post-type=\"service\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9f14e e-con-full hero-template-services e-flex e-con e-parent\" data-id=\"5b9f14e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9392d90 e-con-full e-flex e-con e-child\" data-id=\"9392d90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99098c8 elementor-widget elementor-widget-text-editor\" data-id=\"99098c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><a href=\"\/\">IN\u00cdCIO<\/a> &gt; <a href=\"\/tous-nos-services\/\">OS NOSSOS SERVI\u00c7OS<\/a> &gt; <a href=\"https:\/\/www.asd-int.com\/pt-pt\/servicos-fiscal\/\">IVA E FISCALIDADE<\/a> &gt; REEMBOLSO IVA INTRACOMUNIT\u00c1RIO<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df7da18 e-con-full e-flex e-con e-child\" data-id=\"df7da18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-452d477 e-con-full e-flex e-con e-child\" data-id=\"452d477\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ada481 elementor-widget elementor-widget-heading\" data-id=\"6ada481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Reembolso de IVA intracomunit\u00e1rio: recupere rapidamente o seu IVA estrangeiro na Uni\u00e3o Europeia<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77cfa66 elementor-widget elementor-widget-text-editor\" data-id=\"77cfa66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA SUA EMPRESA PAGOU IVA NOUTRO ESTADO-MEMBRO DA UNI\u00c3O EUROPEIA?<br \/>A ASD GROUP APOIA-O NA RECUPERA\u00c7\u00c3O DO IVA NO ESTRANGEIRO DE FORMA R\u00c1PIDA, SEGURA E EFICIENTE.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4554750 e-con-full e-flex e-con e-child\" data-id=\"4554750\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30cb860 elementor-tablet-align-justify elementor-widget elementor-widget-button\" data-id=\"30cb860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/servicos-fiscal\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">As nossas solu\u00e7\u00f5es em IVA e fiscalidade<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd1a5a6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dd1a5a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de001ba e-flex e-con-boxed e-con e-parent\" data-id=\"de001ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b30a638 elementor-widget elementor-widget-menu-anchor\" data-id=\"b30a638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"reembolso-iva-intracomunitario\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbfd1cc menu-template-services service-fiscal e-flex e-con-boxed e-con e-parent\" data-id=\"fbfd1cc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:134,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70dc3e8 menu-services-liste e-flex e-con-boxed e-con e-child\" data-id=\"70dc3e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-834bac1 e-flex e-con-boxed e-con e-child\" data-id=\"834bac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b2ac2 elementor-widget elementor-widget-heading\" data-id=\"e0b2ac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#reembolso-iva-intracomunitario\">Reembolso de IVA<br \/>intracomunit\u00e1rio<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dae3ef e-flex e-con-boxed e-con e-child\" data-id=\"2dae3ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94c1b36 elementor-widget elementor-widget-heading\" data-id=\"94c1b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#o-que-fazemos-por-si\">O que fazemos por si<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83d5f87 e-flex e-con-boxed e-con e-child\" data-id=\"83d5f87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c829f5b elementor-widget elementor-widget-heading\" data-id=\"c829f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#razoes-para-nos-contactar\">Raz\u00f5es para nos contactar<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6726c99 e-con-full e-flex e-con e-child\" data-id=\"6726c99\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97c018f elementor-widget elementor-widget-heading\" data-id=\"97c018f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"#payscouvertsparceservice\">Pa\u00edses abrangidos por este servi\u00e7o<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d77319e e-flex e-con-boxed e-con e-parent\" data-id=\"d77319e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-411bef1 e-con-full e-flex e-con e-child\" data-id=\"411bef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-91974b7 e-con-full e-flex e-con e-child\" data-id=\"91974b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4fe582 elementor-widget elementor-widget-html\" data-id=\"f4fe582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37b0995 elementor-widget elementor-widget-html\" data-id=\"37b0995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc3f86 elementor-widget elementor-widget-heading\" data-id=\"2fc3f86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O princ\u00edpio do reembolso do IVA intracomunit\u00e1rio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f17f470 elementor-widget elementor-widget-text-editor\" data-id=\"f17f470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>O reembolso de IVA intracomunit\u00e1rio permite \u00e0s empresas estabelecidas na Uni\u00e3o Europeia ou fora da UE recuperar o IVA pago num pa\u00eds onde n\u00e3o est\u00e3o registadas<\/b>.<\/p>\n<p>As formalidades variam consoante a empresa esteja abrangida pela 8.\u00aa ou pela 13.\u00aa Diretiva europeia, e as condi\u00e7\u00f5es de dedu\u00e7\u00e3o diferem de Estado-Membro para Estado-Membro.<\/p>\n<ul>\n<li>Se a empresa estiver estabelecida na Uni\u00e3o Europeia, <a href=\"https:\/\/www.asd-int.com\/remboursement-tva-8e-directive\/\">o reembolso processa-se atrav\u00e9s do procedimento denominado \u00ab8.\u00aa Diretiva\u00bb<\/a>, mediante apresenta\u00e7\u00e3o de um pedido atrav\u00e9s do portal eletr\u00f3nico acess\u00edvel no Estado-Membro de estabelecimento. O pedido pode ser apresentado diretamente pela empresa ou por interm\u00e9dio de um mandat\u00e1rio fiscal.<\/li>\n<li>Se a empresa estiver estabelecida fora da Uni\u00e3o Europeia, o <a href=\"https:\/\/www.asd-int.com\/remboursement-tva-13eme-directive\/\">reembolso processa-se atrav\u00e9s do procedimento denominado \u00ab13.\u00aa Diretiva\u00bb<\/a>, mediante apresenta\u00e7\u00e3o do pedido diretamente junto da administra\u00e7\u00e3o tribut\u00e1ria do Estado-Membro onde o reembolso \u00e9 solicitado.<\/li>\n<\/ul>\n<p>Entre a verifica\u00e7\u00e3o das faturas, a an\u00e1lise das despesas dedut\u00edveis, o cumprimento das regras locais e os contactos com as administra\u00e7\u00f5es fiscais estrangeiras, o procedimento pode tornar-se rapidamente complexo.<\/p>\n<p><strong>A ASD Group encarrega-se de todas as suas formalidades<\/strong> para garantir a seguran\u00e7a e acelerar o reembolso do seu IVA estrangeiro.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b6f5d3 e-con-full form-template-services elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0b6f5d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-service=\"fiscal\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b59b4e elementor-widget elementor-widget-heading\" data-id=\"3b59b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">N\u00c3O CORRA RISCOS!\u2028<br \/><br \/>CONFIEM O REEMBOLSO DO SEU IVA AOS NOSSOS ESPECIALISTAS E CONCENTRE-SE NA SUA ATIVIDADE!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9636c e-transform elementor-widget elementor-widget-shortcode\" data-id=\"3b9636c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_49_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form-2026\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Contact 2026<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"49\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_49\" id=\"frm_hide_fields_49\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form-2026\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_49\" name=\"frm_submit_entry_49\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/service\/205001\" \/><div id=\"frm_field_696_container\" class=\"frm_form_field  frm12 frm_first formcontact-require frm_html_container form-field\"><em>* Os campos marcados com um asterisco s\u00e3o obrigat\u00f3rios para nos permitir processar o seu pedido.<\/em> <em>Alguns dos nossos servi\u00e7os n\u00e3o est\u00e3o dispon\u00edveis em todas as regi\u00f5es e\/ou em todos os sectores.<\/em>\n<\/div>\n<div id=\"frm_field_635_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><strong>1\/ A sua empresa<\/strong><\/div>\n<div id=\"frm_field_616_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_i41ef2\" class=\"frm_primary_label\">Qual \u00e9 o nome da sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef2\" name=\"item_meta[616]\" value=\"\"  placeholder=\"Nome da sua empresa\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_759_container\" class=\"frm_form_field frm_section_heading form-field  section-hidden frm_hide_section\">\r\n<h3 class=\"frm_pos_none frm_section_spacing\"><\/h3>\r\n\r\n\r\n<div id=\"frm_field_622_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order0 sort-alphabetically\">\r\n    <label for=\"field_okuhn3\" class=\"frm_primary_label\">Em que pa\u00eds est\u00e1 estabelecida a sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[622]\" id=\"field_okuhn3\"  data-sectionid=\"759\"  data-placeholder=\"Escolha o pa\u00eds onde deseja estabelecer-se\"  placeholder=\"Escolha o pa\u00eds onde deseja estabelecer-se\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Em que pa\u00eds est\u00e1 estabelecida a sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o pa\u00eds onde deseja estabelecer-se<\/option><option  value=\"DE\">Alemanha<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AR\">Argentina<\/option><option  value=\"BR\">Brasil<\/option><option  value=\"BG\">Bulg\u00e1ria<\/option><option  value=\"BE\">B\u00e9lgica<\/option><option  value=\"CY\">Chipre<\/option><option  value=\"CZ\">Ch\u00e9quia<\/option><option  value=\"HR\">Cro\u00e1cia<\/option><option  value=\"DK\">Dinamarca<\/option><option  value=\"SK\">Eslov\u00e1quia<\/option><option  value=\"SI\">Eslov\u00e9nia<\/option><option  value=\"ES\">Espanha<\/option><option  value=\"EE\">Est\u00f3nia<\/option><option  value=\"FI\">Finl\u00e2ndia<\/option><option  value=\"FR\">Fran\u00e7a<\/option><option  value=\"GR\">Gr\u00e9cia<\/option><option  value=\"HU\">Hungria<\/option><option  value=\"IE\">Irlanda<\/option><option  value=\"IS\">Isl\u00e2ndia<\/option><option  value=\"IT\">It\u00e1lia<\/option><option  value=\"LV\">Let\u00f4nia<\/option><option  value=\"LI\">Liechtenstein<\/option><option  value=\"LT\">Litu\u00e2nia<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"MD\">Mold\u00e1via<\/option><option  value=\"MX\">M\u00e9xico<\/option><option  value=\"MC\">M\u00f3naco<\/option><option  value=\"NO\">Noruega<\/option><option  value=\"NL\">Pa\u00edses Baixos<\/option><option  value=\"PL\">Pol\u00f3nia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Rom\u00e9nia<\/option><option  value=\"SE\">Su\u00e9cia<\/option><option  value=\"CH\">Su\u00ed\u00e7a<\/option><option  value=\"RS\">S\u00e9rvia<\/option><option  value=\"TR\">Turquia<\/option><option  value=\"UA\">Ucr\u00e2nia<\/option><option  value=\"AT\">\u00c1ustria<\/option><option  value=\"Other\">Outro pa\u00eds (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_617_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 order2 sort-alphabetically\">\r\n    <label for=\"field_85w6d2\" class=\"frm_primary_label\">Qual \u00e9 o sector de atividade da sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[617]\" id=\"field_85w6d2\"  data-sectionid=\"759\"  data-placeholder=\"Escolha o seu setor de atividade\"  placeholder=\"Escolha o seu setor de atividade\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 o sector de atividade da sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o seu setor de atividade<\/option><option  value=\"Agriculture\">Agricultura\n<\/option><option  value=\"Agroalimentaire\">Agroalimentar<\/option><option  value=\"Automobile\">Autom\u00f3vel\n<\/option><option  value=\"Banque et assurances\">Bancos e seguros\n<\/option><option  value=\"Commerce\">Com\u00e9rcio\n<\/option><option  value=\"B\u00e2timent et travaux publics (BTP)\">Constru\u00e7\u00e3o e obras p\u00fablicas\n<\/option><option  value=\"Conseil et services aux entreprises\">Consultoria e servi\u00e7os \u00e0s empresas\n<\/option><option  value=\"Culture et loisirs\">Cultura e lazer<\/option><option  value=\"Sport et \u00e9v\u00e9nements\">Desporto e eventos<\/option><option  value=\"Distribution\">Distribui\u00e7\u00e3o<\/option><option  value=\"\u00c9ducation et formation\">Educa\u00e7\u00e3o e forma\u00e7\u00e3o<\/option><option  value=\"\u00c9nergie\">Energia<\/option><option  value=\"H\u00f4tellerie et restauration\">Hotelaria e restaura\u00e7\u00e3o<\/option><option  value=\"Immobilier\">Imobili\u00e1rio<\/option><option  value=\"Industrie manufacturi\u00e8re\">Ind\u00fastria manufatureira<\/option><option  value=\"Informatique et num\u00e9rique\">Inform\u00e1tica e tecnologia digital<\/option><option  value=\"Logistique et transport\">Log\u00edstica e transporte<\/option><option  value=\"Luxe et mode\">Luxo e moda<\/option><option  value=\"M\u00e9dias et communication\">Meios de comunica\u00e7\u00e3o<\/option><option  value=\"M\u00e9tallurgie et sid\u00e9rurgie\">Metalurgia e siderurgia<\/option><option  value=\"Recherche et d\u00e9veloppement\">Pesquisa e desenvolvimento<\/option><option  value=\"Chimie et pharmacie\">Qu\u00edmica e farm\u00e1cia\n<\/option><option  value=\"Sant\u00e9 et bien-\u00eatre\">Sa\u00fade e bem-estar<\/option><option  value=\"S\u00e9curit\u00e9 et d\u00e9fense\">Seguran\u00e7a e defesa<\/option><option  value=\"Services publics et administration\">Servi\u00e7os p\u00fablicos e administra\u00e7\u00e3o<\/option><option  value=\"T\u00e9l\u00e9communications\">Telecomunica\u00e7\u00f5es<\/option><option  value=\"Tourisme\">Turismo<\/option><option  value=\"Textile et habillement\">T\u00eaxteis e vestu\u00e1rio<\/option><option  value=\"Other\">Outro setor (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_639_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first order1\">\r\n\t<label for=\"field_6q8fw\" id=\"field_6q8fw_label\" class=\"frm_primary_label\">Escolheu \"Outro pa\u00eds\", pode especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_6q8fw\" name=\"item_meta[639]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Preencha o pa\u00eds de estabelecimento\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolheu &quot;Outro pa\u00eds&quot;, pode especificar? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_640_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_alignright order3\">\r\n\t<label for=\"field_8yduw\" id=\"field_8yduw_label\" class=\"frm_primary_label\">Escolheu \"Outro setor\", pode especificar?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_8yduw\" name=\"item_meta[640]\" value=\"\"  data-sectionid=\"759\"  placeholder=\"Preencha o setor de atividade\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolheu &quot;Outro setor&quot;, pode especificar? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<\/div>\n<div id=\"frm_field_637_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\"><strong>2\/ A sua necessidade<\/strong><\/div>\n<div id=\"frm_field_623_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 relative frm_first sort-alphabetically\">\r\n    <label for=\"field_l1biv3\" class=\"frm_primary_label\">Em que pa\u00eds deseja desenvolver a sua empresa?\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[623]\" id=\"field_l1biv3\"  data-placeholder=\"Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)\"  placeholder=\"Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Em que pa\u00eds deseja desenvolver a sua empresa? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o pa\u00eds onde deseja desenvolver-se (passo 1\/4)<\/option><option  value=\"DE\">Alemanha<\/option><option  value=\"BE\">B\u00e9lgica\n<\/option><option  value=\"BG\">B\u00e9lgica\n<\/option><option  value=\"CA\">Canad\u00e1<\/option><option  value=\"CY\">Chipre\n<\/option><option  value=\"CZ\">Ch\u00e9quia<\/option><option  value=\"HR\">Cro\u00e1cia\n<\/option><option  value=\"DK\">Dinamarca\n<\/option><option  value=\"SK\">Eslov\u00e1quia<\/option><option  value=\"SI\">Eslov\u00e9nia<\/option><option  value=\"ES\">Espanha\n<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"EE\">Est\u00f3nia\n<\/option><option  value=\"FI\">Finl\u00e2ndia\n<\/option><option  value=\"FR\">Fran\u00e7a\n<\/option><option  value=\"GR\">Gr\u00e9cia\n<\/option><option  value=\"HU\">Hungria\n<\/option><option  value=\"IE\">Irlanda\n<\/option><option  value=\"IT\">It\u00e1lia\n<\/option><option  value=\"LV\">Let\u00f4nia\n<\/option><option  value=\"LT\">Litu\u00e2nia\n<\/option><option  value=\"LU\">Luxemburgo<\/option><option  value=\"MT\">Malta<\/option><option  value=\"NL\">Pa\u00edses Baixos<\/option><option  value=\"PL\">Pol\u00f3nia<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RO\">Rom\u00e9nia<\/option><option  value=\"SE\">Su\u00e9cia<\/option><option  value=\"CH\">Su\u00ed\u00e7a<\/option><option  value=\"AT\">\u00c1ustria\n<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_681_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nqwnw\" id=\"field_nqwnw_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Espanha?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[681]\" id=\"field_nqwnw\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Espanha? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Espanha (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_647_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_31i7k\" id=\"field_31i7k_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Alemanha?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[647]\" id=\"field_31i7k\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Alemanha? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Alemanha (passo 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_648_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n\t<label for=\"field_2p88l\" id=\"field_2p88l_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a \u00c1ustria?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[648]\" id=\"field_2p88l\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n\" data-invmsg=\"Qual \u00e9 a sua necessidade para a \u00c1ustria? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na \u00c1ustria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_649_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_9i5uq\" id=\"field_9i5uq_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a B\u00e9lgica?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[649]\" id=\"field_9i5uq\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a B\u00e9lgica?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na B\u00e9lgica (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_677_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3n29\" id=\"field_v3n29_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Bulg\u00e1ria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[677]\" id=\"field_v3n29\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Bulg\u00e1ria?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Bulg\u00e1ria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_651_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7frx6\" id=\"field_7frx6_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para o Canad\u00e1?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[651]\" id=\"field_7frx6\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para o Canad\u00e1? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o no Canad\u00e1 (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_676_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xhngf\" id=\"field_xhngf_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade em Chipre?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[676]\" id=\"field_xhngf\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade em Chipre? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Chipre (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_675_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_iyrkx\" id=\"field_iyrkx_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Cro\u00e1cia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[675]\" id=\"field_iyrkx\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Cro\u00e1cia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Cro\u00e1cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_674_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hh8ys\" id=\"field_hh8ys_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Dinamarca?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[674]\" id=\"field_hh8ys\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Dinamarca?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Dinamarca (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_673_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xk6v1\" id=\"field_xk6v1_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Est\u00f3nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[673]\" id=\"field_xk6v1\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Est\u00f3nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Est\u00f3nia (passo 2\/4)<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_650_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_7127q\" id=\"field_7127q_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para os Estados Unidos?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[650]\" id=\"field_7127q\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para os Estados Unidos? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o nos Estados Unidos (passo 2\/4)\n<\/option><option  value=\"Fiscal : Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_672_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hrplp\" id=\"field_hrplp_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Finl\u00e2ndia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[672]\" id=\"field_hrplp\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Finl\u00e2ndia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Finl\u00e2ndia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_671_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jw8ml\" id=\"field_jw8ml_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Fran\u00e7a?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[671]\" id=\"field_jw8ml\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Fran\u00e7a?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Fran\u00e7a (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_670_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_3gqvi\" id=\"field_3gqvi_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Gr\u00e9cia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[670]\" id=\"field_3gqvi\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Gr\u00e9cia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Gr\u00e9cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_669_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ajvsb\" id=\"field_ajvsb_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Hungria?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[669]\" id=\"field_ajvsb\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Hungria?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Hungria (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_668_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r1kza\" id=\"field_r1kza_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Irlanda?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[668]\" id=\"field_r1kza\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Irlanda?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Irlanda (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_667_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_qo5nf\" id=\"field_qo5nf_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a It\u00e1lia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[667]\" id=\"field_qo5nf\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a It\u00e1lia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em It\u00e1lia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_666_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z3dfa\" id=\"field_z3dfa_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Let\u00f3nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[666]\" id=\"field_z3dfa\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Let\u00f3nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Let\u00f3nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_665_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mm4zs\" id=\"field_mm4zs_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para a Litu\u00e2nia?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[665]\" id=\"field_mm4zs\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para a Litu\u00e2nia?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Litu\u00e2nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_664_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_kel0x\" id=\"field_kel0x_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para o Luxemburgo?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[664]\" id=\"field_kel0x\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para o Luxemburgo?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Luxemburgo (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Social : R\u00e9glementation, Formalit\u00e9s &amp; Obligations\">Social: Regulamenta\u00e7\u00e3o, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_663_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dcpyc\" id=\"field_dcpyc_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para Malta?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[663]\" id=\"field_dcpyc\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para Malta?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Malta (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_662_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zz48j\" id=\"field_zz48j_label\" class=\"frm_primary_label\">Qual \u00e9 a tua necessidade para os Pa\u00edses Baixos?\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[662]\" id=\"field_zz48j\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a tua necessidade para os Pa\u00edses Baixos?\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o nos Pa\u00edses Baixos (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_661_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ji2cs\" id=\"field_ji2cs_label\" class=\"frm_primary_label\">Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[661]\" id=\"field_ji2cs\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Pol\u00f3nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_659_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aepqm\" id=\"field_aepqm_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para Portugal?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[659]\" id=\"field_aepqm\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para Portugal? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o em Portugal (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_658_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_d1twg\" id=\"field_d1twg_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Ch\u00e9quia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[658]\" id=\"field_d1twg\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Ch\u00e9quia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Rep\u00fablica Checa (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_657_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v3096\" id=\"field_v3096_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Rom\u00e9nia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[657]\" id=\"field_v3096\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Rom\u00e9nia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Rom\u00e9nia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_656_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hlo6e\" id=\"field_hlo6e_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para o Reino Unido?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[656]\" id=\"field_hlo6e\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para o Reino Unido? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o no Reino Unido (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_655_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_azerr\" id=\"field_azerr_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Eslov\u00e1quia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[655]\" id=\"field_azerr\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Eslov\u00e1quia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Eslov\u00e1quia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_654_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vtjje\" id=\"field_vtjje_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Eslov\u00eania?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[654]\" id=\"field_vtjje\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Eslov\u00eania? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Eslov\u00eania (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Douane : Op\u00e9rations, Formalit\u00e9s &amp; Obligations\">Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_653_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_e1wi2\" id=\"field_e1wi2_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Su\u00e9cia?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[653]\" id=\"field_e1wi2\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Su\u00e9cia? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Su\u00e9cia (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Strat\u00e9gie : D\u00e9veloppement des Entreprises\">Estrat\u00e9gia: Desenvolvimento das empresas<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_652_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_mf65v\" id=\"field_mf65v_label\" class=\"frm_primary_label\">Qual \u00e9 a sua necessidade para a Su\u00ed\u00e7a?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[652]\" id=\"field_mf65v\"  data-placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n\"  placeholder=\"Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Qual \u00e9 a sua necessidade para a Su\u00ed\u00e7a? n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha a \u00e1rea de servi\u00e7o na Su\u00ed\u00e7a (passo 2\/4)\n<\/option><option  value=\"Fiscal : TVA, Taxes, Formalit\u00e9s &amp; Obligations\">Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es<\/option><option  value=\"Je ne suis pas s\u00fbr(e)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_678_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_19pbf\" id=\"field_19pbf_label\" class=\"frm_primary_label\">[Alemanha] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[678]\" id=\"field_19pbf\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/ZM\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ ZM \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_679_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gz1w7\" id=\"field_gz1w7_label\" class=\"frm_primary_label\">[Alemanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[679]\" id=\"field_gz1w7\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_798_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dego5\" id=\"field_dego5_label\" class=\"frm_primary_label\">[Alemanha] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[798]\" id=\"field_dego5\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Alemanha] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_682_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eeeq6\" id=\"field_eeeq6_label\" class=\"frm_primary_label\">[\u00c1ustria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[682]\" id=\"field_eeeq6\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_683_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_r8c1d\" id=\"field_r8c1d_label\" class=\"frm_primary_label\">[\u00c1ustria] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[683]\" id=\"field_r8c1d\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_799_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_95ick\" id=\"field_95ick_label\" class=\"frm_primary_label\">[\u00c1ustria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[799]\" id=\"field_95ick\"  data-placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[\u00c1ustria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na \u00c1ustria (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_684_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_aw4s9\" id=\"field_aw4s9_label\" class=\"frm_primary_label\">[B\u00e9lgica] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[684]\" id=\"field_aw4s9\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_685_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8oi4a\" id=\"field_8oi4a_label\" class=\"frm_primary_label\">[B\u00e9lgica] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[685]\" id=\"field_8oi4a\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_686_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hnplb\" id=\"field_hnplb_label\" class=\"frm_primary_label\">[B\u00e9lgica] Estrat\u00e9gia: Desenvolvimento de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[686]\" id=\"field_hnplb\"  data-placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[B\u00e9lgica] Estrat\u00e9gia: Desenvolvimento de empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na B\u00e9lgica (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_687_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_dsbn4\" id=\"field_dsbn4_label\" class=\"frm_primary_label\">[Bulg\u00e1ria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[687]\" id=\"field_dsbn4\"  data-placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Bulg\u00e1ria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_800_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_gbi4d\" id=\"field_gbi4d_label\" class=\"frm_primary_label\">[Bulg\u00e1ria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[800]\" id=\"field_gbi4d\"  data-placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Bulg\u00e1ria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Bulg\u00e1ria (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_689_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_a9qen\" id=\"field_a9qen_label\" class=\"frm_primary_label\">[Canad\u00e1] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[689]\" id=\"field_a9qen\"  data-placeholder=\"Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Canad\u00e1] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Canad\u00e1 (passo 3\/4)<\/option><option  value=\"Gestion des taxes TPS\/TVH\/TVP\">Gest\u00e3o dos impostos GST\/HST\/PST<\/option><option  value=\"Gestion de la certification employeur non-r\u00e9sident\">Gest\u00e3o da certifica\u00e7\u00e3o de empregadores n\u00e3o residentes<\/option><option  value=\"Gestion de la dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents\">Gest\u00e3o da isen\u00e7\u00e3o de reten\u00e7\u00e3o na fonte para empregadores n\u00e3o residentes<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_646_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_8yjzs\" id=\"field_8yjzs_label\" class=\"frm_primary_label\">[Espanha] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[646]\" id=\"field_8yjzs\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Gestion de la taxe sur les emballages plastiques non r\u00e9utilisables\">Gest\u00e3o da taxa sobre embalagens de pl\u00e1stico n\u00e3o reutiliz\u00e1veis<\/option><option  value=\"Gestion de la taxe sur les pneus usag\u00e9s\">Gest\u00e3o da taxa sobre pneus usados<\/option><option  value=\"Gestion de l&#039;Eco Tax DEEE (WEEE)\">Gest\u00e3o da Eco Tax DEEE (WEEE)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_641_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_whqtx\" id=\"field_whqtx_label\" class=\"frm_primary_label\">[Espanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[641]\" id=\"field_whqtx\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_643_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_upzx7\" id=\"field_upzx7_label\" class=\"frm_primary_label\">[Espanha] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[643]\" id=\"field_upzx7\"  data-placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Espanha (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Espanha] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Espanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_691_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5vbnj\" id=\"field_5vbnj_label\" class=\"frm_primary_label\">[Fran\u00e7a] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[691]\" id=\"field_5vbnj\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Repr\u00e9sentation fiscale immobili\u00e8re\">Representa\u00e7\u00e3o fiscal imobili\u00e1ria<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_692_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y17z7\" id=\"field_y17z7_label\" class=\"frm_primary_label\">[Fran\u00e7a] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[692]\" id=\"field_y17z7\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations EMEBI (ERTVA\u2026)\/DES\">Gest\u00e3o das declara\u00e7\u00f5es EMEBI (ERTVA\u2026)\/DES<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires et SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de RTC et RCO\">Acompanhamento na obten\u00e7\u00e3o de IPV e IVO<\/option><option  value=\"Accompagnement \u00e0 l&#039;obtention de la certification OEA\">Acompanhamento na obten\u00e7\u00e3o da certifica\u00e7\u00e3o AEO<\/option><option  value=\"Gestion des DDR selon le RDUE\">Gest\u00e3o dos DDS de acordo com o EUDR<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gest\u00e3o dos direitos de consumo para vendas \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"Gestion de la taxe carbone (CBAM\/MACF)\">Gest\u00e3o do imposto de carbono (CBAM)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_693_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q9gx\" id=\"field_q9gx_label\" class=\"frm_primary_label\">[Fran\u00e7a] Social: Regulamentos, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[693]\" id=\"field_q9gx\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Social: Regulamentos, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion des missions de d\u00e9tachement de salari\u00e9s \u00e9trangers en France (ASD SPW)\">Gest\u00e3o das miss\u00f5es de destacamento de trabalhadores estrangeiros em Fran\u00e7a (ASD SPW)<\/option><option  value=\"Gestion de la repr\u00e9sentation fiscale dans le cadre du pr\u00e9l\u00e8vement \u00e0 la source\">Gest\u00e3o da representa\u00e7\u00e3o fiscal no \u00e2mbito da reten\u00e7\u00e3o na fonte<\/option><option  value=\"Gestion de repr\u00e9sentation de firme \u00e9trang\u00e8re\">Gest\u00e3o da representa\u00e7\u00e3o de empresa estrangeira<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_694_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5kh5i\" id=\"field_5kh5i_label\" class=\"frm_primary_label\">[Fran\u00e7a] Estrat\u00e9gia: Desenvolvimento de empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[694]\" id=\"field_5kh5i\"  data-placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Fran\u00e7a] Estrat\u00e9gia: Desenvolvimento de empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Fran\u00e7a (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Gestion de la domiciliation d&#039;entreprise\">Gest\u00e3o da domicilia\u00e7\u00e3o da empresa<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_698_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jlotu\" id=\"field_jlotu_label\" class=\"frm_primary_label\">[Estados Unidos] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[698]\" id=\"field_jlotu\"  data-placeholder=\"Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Estados Unidos] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Estados Unidos (etapa 3\/4)<\/option><option  value=\"Gestion de la &quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Gest\u00e3o do &quot;Sales and Use Tax&quot; nos Estados Unidos<\/option><option  value=\"Gestion des formulaires W-8 et W-9 aux \u00c9tats-Unis\">Gest\u00e3o dos formul\u00e1rios W-8 e W-9 nos Estados Unidos<\/option><option  value=\"Gestion des formalit\u00e9s li\u00e9es au Nexus aux \u00c9tats-Unis\">Gest\u00e3o das formalidades relacionadas com o Nexus nos Estados Unidos<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_699_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_44svk\" id=\"field_44svk_label\" class=\"frm_primary_label\">[It\u00e1lia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[699]\" id=\"field_44svk\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du Visto di Conformit\u00e0\">Gest\u00e3o do Visto di Conformit\u00e0<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_700_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ys0xm\" id=\"field_ys0xm_label\" class=\"frm_primary_label\">[It\u00e1lia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[700]\" id=\"field_ys0xm\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4\/<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_701_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1anf4\" id=\"field_1anf4_label\" class=\"frm_primary_label\">[It\u00e1lia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[701]\" id=\"field_1anf4\"  data-placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[It\u00e1lia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em It\u00e1lia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_702_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_zq0ua\" id=\"field_zq0ua_label\" class=\"frm_primary_label\">[Chipre] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[702]\" id=\"field_zq0ua\"  data-placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Chipre] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Chipre (etapa 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_801_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q3a1e\" id=\"field_q3a1e_label\" class=\"frm_primary_label\">[Chipre] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[801]\" id=\"field_q3a1e\"  data-placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Chipre (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Chipre] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Chipre (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_704_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_s06v4\" id=\"field_s06v4_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[704]\" id=\"field_s06v4\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_705_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_vjfrb\" id=\"field_vjfrb_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[705]\" id=\"field_vjfrb\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_802_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_xna4z\" id=\"field_xna4z_label\" class=\"frm_primary_label\">[Cro\u00e1cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[802]\" id=\"field_xna4z\"  data-placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Cro\u00e1cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Cro\u00e1cia (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_706_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2i1vf\" id=\"field_2i1vf_label\" class=\"frm_primary_label\">[Dinamarca] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[706]\" id=\"field_2i1vf\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List \/ EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_707_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_g3d2w\" id=\"field_g3d2w_label\" class=\"frm_primary_label\">[Dinamarca] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[707]\" id=\"field_g3d2w\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_803_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_1df4u\" id=\"field_1df4u_label\" class=\"frm_primary_label\">[Dinamarca] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[803]\" id=\"field_1df4u\"  data-placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Dinamarca] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Dinamarca (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_708_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_cs0h5\" id=\"field_cs0h5_label\" class=\"frm_primary_label\">[Est\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[708]\" id=\"field_cs0h5\"  data-placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_709_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2ahrq\" id=\"field_2ahrq_label\" class=\"frm_primary_label\">[Est\u00f3nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[709]\" id=\"field_2ahrq\"  data-placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolhe o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_804_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_urojq\" id=\"field_urojq_label\" class=\"frm_primary_label\">[Est\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[804]\" id=\"field_urojq\"  data-placeholder=\"Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Est\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Est\u00f3nia (etapa 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_710_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jz0iw\" id=\"field_jz0iw_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[710]\" id=\"field_jz0iw\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_711_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z5cpa\" id=\"field_z5cpa_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[711]\" id=\"field_z5cpa\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_805_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oyx7h\" id=\"field_oyx7h_label\" class=\"frm_primary_label\">[Finl\u00e2ndia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[805]\" id=\"field_oyx7h\"  data-placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Finl\u00e2ndia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Finl\u00e2ndia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_712_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6jrxn\" id=\"field_6jrxn_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[712]\" id=\"field_6jrxn\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_713_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rgel6\" id=\"field_rgel6_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[713]\" id=\"field_rgel6\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_806_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6ls28\" id=\"field_6ls28_label\" class=\"frm_primary_label\">[Gr\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[806]\" id=\"field_6ls28\"  data-placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Gr\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Gr\u00e9cia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_714_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_w6w9o\" id=\"field_w6w9o_label\" class=\"frm_primary_label\">[Hungria] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[714]\" id=\"field_w6w9o\"  data-placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Hungria] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_807_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_jxc2i\" id=\"field_jxc2i_label\" class=\"frm_primary_label\">[Hungria] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[807]\" id=\"field_jxc2i\"  data-placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Hungria] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Hungria (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_716_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lhn0a\" id=\"field_lhn0a_label\" class=\"frm_primary_label\">[Irlanda] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[716]\" id=\"field_lhn0a\"  data-placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_808_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hpoqk\" id=\"field_hpoqk_label\" class=\"frm_primary_label\">[Irlanda] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[808]\" id=\"field_hpoqk\"  data-placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Irlanda] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Irlanda (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_718_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_eh4ic\" id=\"field_eh4ic_label\" class=\"frm_primary_label\">[Let\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[718]\" id=\"field_eh4ic\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5 n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_719_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4t4b4\" id=\"field_4t4b4_label\" class=\"frm_primary_label\">[Let\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[719]\" id=\"field_4t4b4\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_809_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_btj00\" id=\"field_btj00_label\" class=\"frm_primary_label\">[Let\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[809]\" id=\"field_btj00\"  data-placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Let\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Let\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_720_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_62mpm\" id=\"field_62mpm_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[720]\" id=\"field_62mpm\"  data-placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\u2028Identification fiscale hors Union europ\u00e9enne\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_721_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_fqvcn\" id=\"field_fqvcn_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[721]\" id=\"field_fqvcn\"  data-placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Litu\u00e2nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_810_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_tahxc\" id=\"field_tahxc_label\" class=\"frm_primary_label\">[Litu\u00e2nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[810]\" id=\"field_tahxc\"  data-placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Alemanha (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Litu\u00e2nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Alemanha (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_722_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6asdz\" id=\"field_6asdz_label\" class=\"frm_primary_label\">[Luxemburgo] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[722]\" id=\"field_6asdz\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_723_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_uv0bx\" id=\"field_uv0bx_label\" class=\"frm_primary_label\">[Luxemburgo] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[723]\" id=\"field_uv0bx\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_811_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_q5m9h\" id=\"field_q5m9h_label\" class=\"frm_primary_label\">[Luxemburgo] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[811]\" id=\"field_q5m9h\"  data-placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Luxemburgo] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Luxemburgo (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_725_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_de7m1\" id=\"field_de7m1_label\" class=\"frm_primary_label\">[Malta] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[725]\" id=\"field_de7m1\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_726_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_n2ufm\" id=\"field_n2ufm_label\" class=\"frm_primary_label\">[Malta] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[726]\" id=\"field_n2ufm\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Gestion des d\u00e9clarations europ\u00e9ennes de services (DES)\">Gest\u00e3o das declara\u00e7\u00f5es europeias de servi\u00e7os (DES)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_813_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_l10m9\" id=\"field_l10m9_label\" class=\"frm_primary_label\">[Malta] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[813]\" id=\"field_l10m9\"  data-placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Malta (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Malta] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Malta (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_727_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_2af4r\" id=\"field_2af4r_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[727]\" id=\"field_2af4r\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_728_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_za0r\" id=\"field_za0r_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[728]\" id=\"field_za0r\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_814_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_i16up\" id=\"field_i16up_label\" class=\"frm_primary_label\">[Pa\u00edses Baixos] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[814]\" id=\"field_i16up\"  data-placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pa\u00edses Baixos] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o nos Pa\u00edses Baixos (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_729_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_h5qk6\" id=\"field_h5qk6_label\" class=\"frm_primary_label\">[Pol\u00f3nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[729]\" id=\"field_h5qk6\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f3nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_730_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_42afs\" id=\"field_42afs_label\" class=\"frm_primary_label\">[Pol\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[730]\" id=\"field_42afs\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f4nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_731_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rd7rn\" id=\"field_rd7rn_label\" class=\"frm_primary_label\">[Pol\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\n\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[731]\" id=\"field_rd7rn\"  data-placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Pol\u00f3nia] Estrat\u00e9gia: Desenvolvimento das empresas\n n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Pol\u00f4nia (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_733_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_6wlea\" id=\"field_6wlea_label\" class=\"frm_primary_label\">[Portugal] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[733]\" id=\"field_6wlea\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Facturation \u00e9lectronique et\/ou e-reporting\">Fatura\u00e7\u00e3o eletr\u00f3nica e\/ou e-reporting<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_734_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_u9472\" id=\"field_u9472_label\" class=\"frm_primary_label\">[Portugal] Aduana: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[734]\" id=\"field_u9472\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Aduana: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires,SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accises pour la vente \u00e0 distance de boissons alcooliques au Portugal\">Gest\u00e3o dos impostos especiais de consumo para a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas em Portugal<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_815_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_rlp4g\" id=\"field_rlp4g_label\" class=\"frm_primary_label\">[Portugal] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[815]\" id=\"field_rlp4g\"  data-placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Portugal] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o em Portugal (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Accompagnement certification logiciel facturation \u00e9lectronique\">Acompanhamento na certifica\u00e7\u00e3o de software de fatura\u00e7\u00e3o eletr\u00f3nica<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_735_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_5hg1m\" id=\"field_5hg1m_label\" class=\"frm_primary_label\">[Ch\u00e9quia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[735]\" id=\"field_5hg1m\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Ch\u00e9quia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_736_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_t8kbm\" id=\"field_t8kbm_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[736]\" id=\"field_t8kbm\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_816_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_oawcf\" id=\"field_oawcf_label\" class=\"frm_primary_label\">[Rep\u00fablica Checa] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[816]\" id=\"field_oawcf\"  data-placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rep\u00fablica Checa] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rep\u00fablica Checa (etapa 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_739_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_4y9dt\" id=\"field_4y9dt_label\" class=\"frm_primary_label\">[Rom\u00e9nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[739]\" id=\"field_4y9dt\"  data-placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rom\u00e9nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_817_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_69ksn\" id=\"field_69ksn_label\" class=\"frm_primary_label\">[Rom\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[817]\" id=\"field_69ksn\"  data-placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Rom\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Rom\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_741_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ownk6\" id=\"field_ownk6_label\" class=\"frm_primary_label\">[Reino Unido] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[741]\" id=\"field_ownk6\"  data-placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Reino Unido (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (13e\u2026)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_742_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_ioidj\" id=\"field_ioidj_label\" class=\"frm_primary_label\">[Reino Unido] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[742]\" id=\"field_ioidj\"  data-placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o no Reino Unido (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Reino Unido] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o no Reino Unido (passo 3\/4)<\/option><option  value=\"Gestion des op\u00e9rations douani\u00e8res et d\u00e9douanements\">Gest\u00e3o das opera\u00e7\u00f5es aduaneiras e desalfandegamento<\/option><option  value=\"Gestion des d\u00e9clarations dans TRACES NT\">Gest\u00e3o das declara\u00e7\u00f5es no TRACES NT<\/option><option  value=\"Assistance lors des inspections v\u00e9t\u00e9rinaires, SPS avec SIVEP\">Assist\u00eancia durante as inspe\u00e7\u00f5es veterin\u00e1rias e SPS com SIVEP<\/option><option  value=\"Assistance lors des contr\u00f4les douane\">Assist\u00eancia durante os controlos aduaneiros<\/option><option  value=\"Gestion des droits d\u2019accise pour la vente \u00e0 distance de boissons alcoolis\u00e9es\">Gest\u00e3o dos direitos de consumo para vendas \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_743_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_v16pe\" id=\"field_v16pe_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[743]\" id=\"field_v16pe\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Remboursement TVA (8e, 13e\u2026)\">Reembolso do IVA (8.\u00aa, 13.\u00aa diretiva\u2026)<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_744_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_idpgs\" id=\"field_idpgs_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[744]\" id=\"field_idpgs\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Alf\u00e2ndega: Opera\u00e7\u00f5es, Formalidades e Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_818_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_nueuk\" id=\"field_nueuk_label\" class=\"frm_primary_label\">[Eslov\u00e1quia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[818]\" id=\"field_nueuk\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e1quia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e1quia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_745_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_11566a\" id=\"field_11566a_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[745]\" id=\"field_11566a\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion des EC Sales List\/EC Purchase List\">Gest\u00e3o da EC Sales List \/ EC Purchase List<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_747_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_lwwyc\" id=\"field_lwwyc_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[747]\" id=\"field_lwwyc\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Alf\u00e2ndega: Opera\u00e7\u00f5es, formalidades e obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion des d\u00e9clarations Intrastat\">Gest\u00e3o das declara\u00e7\u00f5es Intrastat<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_819_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_z7hx0\" id=\"field_z7hx0_label\" class=\"frm_primary_label\">[Eslov\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[819]\" id=\"field_z7hx0\"  data-placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\"  placeholder=\"Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Eslov\u00e9nia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Eslov\u00e9nia (passo 3\/4)<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_748_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_shkof\" id=\"field_shkof_label\" class=\"frm_primary_label\">[Su\u00e9cia] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[748]\" id=\"field_shkof\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00e9cia] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Mandat fiscal\">Mandato fiscal<\/option><option  value=\"Gestion du guichet unique TVA (OSS)\">Gest\u00e3o do balc\u00e3o \u00fanico do IVA (OSS)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_820_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_hgxin\" id=\"field_hgxin_label\" class=\"frm_primary_label\">[Su\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[820]\" id=\"field_hgxin\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00e9cia] Estrat\u00e9gia: Desenvolvimento das empresas n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00e9cia (passo 3\/4)\n<\/option><option  value=\"Gestion du RGPD (Conformit\u00e9, repr\u00e9sentant, DPO\u2026)\">Gest\u00e3o do RGPD (conformidade, representante, EPD\/DPO\u2026)<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especificar abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_750_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_y6l2p\" id=\"field_y6l2p_label\" class=\"frm_primary_label\">[Su\u00ed\u00e7a] Fiscal: IVA, Impostos, Formalidades & Obriga\u00e7\u00f5es\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[750]\" id=\"field_y6l2p\"  data-placeholder=\"Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n\"  placeholder=\"Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"[Su\u00ed\u00e7a] Fiscal: IVA, Impostos, Formalidades &amp; Obriga\u00e7\u00f5es n\u00e3o \u00e9 v\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha o servi\u00e7o na Su\u00ed\u00e7a (etapa 3\/4)\n<\/option><option  value=\"Repr\u00e9sentation fiscale\">Representa\u00e7\u00e3o fiscal<\/option><option  value=\"Remboursement TVA (13e)\">Reembolso do IVA (13.\u00aa diretiva\u2026)<\/option><option  value=\"Audit\/Expertise TVA\">Auditoria \/ consultoria em IVA<\/option><option  value=\"Je ne suis pas s\u00fbr(e) (merci de pr\u00e9ciser ci-dessous)\">N\u00e3o tenho a certeza (por favor, especifique abaixo)<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_626_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm12 frm_first\">\r\n    <label for=\"field_bz8k12\" class=\"frm_primary_label\">Explique brevemente a sua necessidade\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[626]\" id=\"field_bz8k12\" rows=\"5\"  placeholder=\"Ex.: A nossa empresa deseja reembolsar o IVA na Alemanha... (passo 4\/4)\" data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Explique brevemente a sua necessidade&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_638_container\" class=\"frm_form_field  formcontact-subtitle frm_html_container form-field\">\n<p><strong>3\/ Os seus dados de contacto<\/strong><\/p>\n<\/div>\n<div id=\"frm_field_619_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n    <label for=\"field_ocfup142\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup142\" name=\"item_meta[619]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Primeiro nome&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_618_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n    <label for=\"field_qh4icy42\" class=\"frm_primary_label\">Apelido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy42\" name=\"item_meta[618]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"&quot;Apelido&quot; \u00e9 inv\u00e1lido\n\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_620_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc3\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc3\" name=\"item_meta[620]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_621_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa4\" class=\"frm_primary_label\">Telefone\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa4\" name=\"item_meta[621]\" value=\"\"  data-reqmsg=\" Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"O n\u00famero de telefone \u00e9 inv\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_627_container\" class=\"frm_form_field  frm_html_container form-field\">Este site \u00e9 protegido pelo Google reCAPTCHA. Aplicam-se a <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">Pol\u00edtica de Privacidade<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">Termos de Servi\u00e7o<\/a>.<\/div>\n<div id=\"frm_field_628_container\" class=\"frm_form_field form-field  frm_top_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_628-0\">\t\t\t<label  for=\"field_e2sgs2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[628][]\" id=\"field_e2sgs2-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter est non valide\"   \/> Quero subscrever a newsletter de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_629_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_629-0\">\t\t\t<label  for=\"field_y30e3-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[629][]\" id=\"field_y30e3-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"Este campo n\u00e3o pode estar vazio.\n\" data-invmsg=\"RGPD est non valide\"   aria-required=\"true\"  \/> Ao enviar este formul\u00e1rio, voc\u00ea aceita que as informa\u00e7\u00f5es inseridas sejam usadas no contexto da rela\u00e7\u00e3o comercial que pode resultar. Para conhecer e exercer os seus direitos, inclu\u00edndo a retirada de seu consentimento para o uso dos dadaos coletados por este formul\u00e1rio consulte nossa <a href=\"\/en\/legal-notice\/\">Informa\u00e7\u00e3o legal<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_630_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\" \/><\/div>\n<div id=\"frm_field_631_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t2_label\" class=\"frm_primary_label\">CAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t2\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[632]\" id=\"field_8qg9b2\" value=\"\"     \/>\n\t\t<div id=\"frm_field_633_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">ENVIAR A MINHA SOLICITA\u00c7\u00c3O<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_uzug6\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_uzug6\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg44KsaYgxnAo6ituPxxo8STi51mrZ78stY+1ViuSWtHE\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a73948 e-flex e-con-boxed e-con e-parent\" data-id=\"5a73948\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8c0cb elementor-widget elementor-widget-html\" data-id=\"4d8c0cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0a48b elementor-widget elementor-widget-html\" data-id=\"5c0a48b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dd4e8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dd4e8f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49b88e9\" data-id=\"49b88e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c88c3d8 e-con-full e-flex e-con e-child\" data-id=\"c88c3d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-530bf7d elementor-widget elementor-widget-html\" data-id=\"530bf7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95e44a1 elementor-widget elementor-widget-html\" data-id=\"95e44a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb8419f elementor-widget elementor-widget-heading\" data-id=\"cb8419f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais s\u00e3o as condi\u00e7\u00f5es para o reembolso do IVA intracomunit\u00e1rio?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-064dbda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"064dbda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a3c8805\" data-id=\"a3c8805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef05880 elementor-widget elementor-widget-text-editor\" data-id=\"ef05880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O <b>reembolso do IVA estrangeiro<\/b> s\u00f3 \u00e9 poss\u00edvel se estiverem preenchidas as seguintes condi\u00e7\u00f5es:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b67bf8d e-flex e-con-boxed e-con e-parent\" data-id=\"b67bf8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b596db5 e-grid e-con-full e-con e-child\" data-id=\"b596db5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f058f5d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f058f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDurante o per\u00edodo abrangido pelo pedido de reembolso, a empresa <b>n\u00e3o realizou nenhuma opera\u00e7\u00e3o pela qual seja devedora de IVA nesse Estado<\/b> (exceto importa\u00e7\u00f5es) e que a obrigasse a se registar para efeitos de IVA.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e64c7f elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3e64c7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>O IVA foi regularmente faturado<\/b> pelo fornecedor ou prestador de servi\u00e7os.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad75c7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9ad75c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cart-arrow-down\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tO IVA diz respeito a <b>despesas de aquisi\u00e7\u00e3o de bens ou servi\u00e7os<\/b> utilizados em opera\u00e7\u00f5es que conferem direito a dedu\u00e7\u00e3o.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1ca61 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8c1ca61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tO IVA n\u00e3o diz respeito a despesas para as quais <b>a dedu\u00e7\u00e3o do IVA est\u00e1 exclu\u00edda pela regulamenta\u00e7\u00e3o local<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c28f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"87c28f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-287c2d1 e-con-full e-flex e-con e-child\" data-id=\"287c2d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d0a13 elementor-widget elementor-widget-html\" data-id=\"b1d0a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0659ffc elementor-widget elementor-widget-html\" data-id=\"0659ffc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f0f744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f0f744\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9638bc5\" data-id=\"9638bc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-376599e e-con-full e-flex e-con e-child\" data-id=\"376599e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec1f922 elementor-widget elementor-widget-html\" data-id=\"ec1f922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f536b4 elementor-widget elementor-widget-html\" data-id=\"7f536b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69a255a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"69a255a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O princ\u00edpio do reembolso de IVA na Uni\u00e3o Europeia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-628ee33 elementor-widget elementor-widget-text-editor\" data-id=\"628ee33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recuperar o IVA pago noutro Estado-Membro da UE n\u00e3o \u00e9 autom\u00e1tico: devem ser respeitadas condi\u00e7\u00f5es estritas e as formalidades diferem consoante v\u00e1rios fatores. <strong>As regras variam nomeadamente consoante:<\/strong><span style=\"color: #ffffff; font-family: -webkit-standard; font-size: medium; letter-spacing: normal; caret-color: #ffffff;\">As regras variam nomeadamente consoante:<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87b2cdf e-grid e-con-boxed e-con e-parent\" data-id=\"87b2cdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9eba7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2c9eba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe-europe\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tO pa\u00eds de estabelecimento da empresa\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tConsoante a empresa estar estabelecida na UE ou fora da UE, <b>o procedimento aplic\u00e1vel (8.\u00aa ou 13.\u00aa Diretiva) difere<\/b> e influencia a forma de apresenta\u00e7\u00e3o do pedido.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4a0771 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d4a0771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marked\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tO pa\u00eds no qual o IVA \u00e9 solicitado\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Cada Estado-Membro possui as suas pr\u00f3prias regras<\/b> de reembolso, prazos e obriga\u00e7\u00f5es documentais, que devem ser escrupulosamente respeitadas.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfaa858 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dfaa858\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-credit-card\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tA natureza das despesas\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Apenas determinadas despesas profissionais conferem direito a recupera\u00e7\u00e3o<\/b>: aquisi\u00e7\u00e3o de bens ou servi\u00e7os relacionados com a atividade da empresa e eleg\u00edveis para dedu\u00e7\u00e3o segundo a regulamenta\u00e7\u00e3o local.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-255a219 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"255a219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOs acordos de reciprocidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>O reembolso depende tamb\u00e9m dos acordos entre Estados<\/b>: alguns pa\u00edses exigem condi\u00e7\u00f5es espec\u00edficas ou a designa\u00e7\u00e3o de um representante fiscal.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0686666 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0686666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb295ad elementor-widget elementor-widget-html\" data-id=\"bb295ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cf8aee elementor-widget elementor-widget-html\" data-id=\"9cf8aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f041407 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f041407\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28fb135\" data-id=\"28fb135\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14d7d17 e-con-full e-flex e-con e-child\" data-id=\"14d7d17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9acb3f elementor-widget elementor-widget-html\" data-id=\"e9acb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad31d3 elementor-widget elementor-widget-html\" data-id=\"7ad31d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-677b2fa elementor-widget elementor-widget-heading\" data-id=\"677b2fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Porqu\u00ea solicitar o reembolso de IVA estrangeiro?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d0a087 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d0a087\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f4ed8b\" data-id=\"6f4ed8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f97778 elementor-widget elementor-widget-text-editor\" data-id=\"7f97778\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Algumas empresas pagam IVA noutro Estado-Membro da Uni\u00e3o Europeia sem poder deduzi-lo diretamente. Recuperar este IVA permite <strong>otimizar os seus custos e garantir a seguran\u00e7a das suas opera\u00e7\u00f5es internacionais<\/strong>. Est\u00e1 abrangido se a sua empresa realizar uma das seguintes opera\u00e7\u00f5es:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0cf3560\" data-id=\"0cf3560\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71479c4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"71479c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"780\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-768x1033.png\" class=\"attachment-medium_large size-medium_large wp-image-94811\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-768x1033.png 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-223x300.png 223w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-761x1024.png 761w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr.png 774w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c3771ec e-flex e-con-boxed e-con e-parent\" data-id=\"c3771ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-014b6e9 e-con-full e-flex e-con e-child\" data-id=\"014b6e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efb3a69 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"efb3a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"600\" height=\"467\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-import.png\" class=\"attachment-full size-full wp-image-177562\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-import.png 600w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-import-300x234.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Compra de mercadorias armazenadas temporariamente noutro pa\u00eds<\/h3><p class=\"elementor-image-box-description\">Se adquirir bens num Estado-Membro da UE para armazenamento ou utiliza\u00e7\u00e3o tempor\u00e1ria, <b>o IVA sobre essas aquisi\u00e7\u00f5es pode ser recuperado sob certas condi\u00e7\u00f5es<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5f15f9 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"c5f15f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"600\" height=\"467\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange.png\" class=\"attachment-full size-full wp-image-177573\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange.png 600w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange-300x234.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Desloca\u00e7\u00f5es profissionais (hot\u00e9is, combust\u00edvel, portagens)<\/h3><p class=\"elementor-image-box-description\">As despesas incorridas em desloca\u00e7\u00f5es profissionais ao estrangeiro, como alojamento, combust\u00edvel ou portagens, <b>podem dar origem a um reembolso de IVA<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c60f512 e-con-full e-flex e-con e-child\" data-id=\"c60f512\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac3e7a elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"2ac3e7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"467\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-export.png\" class=\"attachment-full size-full wp-image-177584\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-export.png 600w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-export-300x234.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Presta\u00e7\u00f5es de servi\u00e7os realizadas fora do seu Estado de estabelecimento<\/h3><p class=\"elementor-image-box-description\">Os servi\u00e7os prestados por fornecedores estrangeiros (consultores, subcontratantes, transportes, etc.) podem <b>gerar cr\u00e9ditos de IVA recuper\u00e1veis<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba6eb49 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"ba6eb49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"600\" height=\"467\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange.png\" class=\"attachment-full size-full wp-image-177573\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange.png 600w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/europe-echange-300x234.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Participa\u00e7\u00e3o em feiras profissionais no estrangeiro<\/h3><p class=\"elementor-image-box-description\">O IVA pago sobre as despesas relacionadas com a aluguer de stand, inscri\u00e7\u00e3o em feiras ou organiza\u00e7\u00e3o de eventos <b>pode ser recuperado se estas despesas forem profissionais<\/b>.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e75baa4 elementor-widget elementor-widget-spacer\" data-id=\"e75baa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f70e724 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f70e724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e398eb e-con-full e-flex e-con e-child\" data-id=\"6e398eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-faefe30 elementor-widget elementor-widget-html\" data-id=\"faefe30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f798a9 elementor-widget elementor-widget-html\" data-id=\"3f798a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ef8ce2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ef8ce2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7fe746\" data-id=\"c7fe746\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-662288a e-con-full e-flex e-con e-child\" data-id=\"662288a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa9170 elementor-widget elementor-widget-html\" data-id=\"1fa9170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2ffef elementor-widget elementor-widget-html\" data-id=\"3c2ffef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80e12b4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"80e12b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais s\u00e3o as etapas do reembolso de IVA na Uni\u00e3o Europeia?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1598bc5 elementor-widget elementor-widget-text-editor\" data-id=\"1598bc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recuperar o IVA pago noutro Estado-Membro da UE implica v\u00e1rias etapas precisas. Cada uma deve ser executada com rigor para garantir o sucesso do pedido e evitar qualquer recusa ou atraso. <strong>A ASD Group acompanha-o em cada fase para garantir a seguran\u00e7a dos seus cr\u00e9ditos de IVA<\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2068c1 e-grid e-con-boxed e-con e-parent\" data-id=\"a2068c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1831439 e-con-full e-flex e-con e-child\" data-id=\"1831439\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae76e81 elementor-widget elementor-widget-heading\" data-id=\"ae76e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">01<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b5f935 elementor-widget elementor-widget-heading\" data-id=\"2b5f935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Auditoria dos fluxos e an\u00e1lise das despesas recuper\u00e1veis<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-176af08 elementor-widget elementor-widget-text-editor\" data-id=\"176af08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Antes de qualquer formalidade, <strong>analisamos as suas transa\u00e7\u00f5es e identificamos as despesas eleg\u00edveis para reembolso<\/strong> de modo a maximizar os seus cr\u00e9ditos de IVA.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-586b6fc e-con-full e-flex e-con e-child\" data-id=\"586b6fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70502d6 elementor-widget elementor-widget-heading\" data-id=\"70502d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">02<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81b39ee elementor-widget elementor-widget-heading\" data-id=\"81b39ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Verifica\u00e7\u00e3o dos comprovativos<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dea10d elementor-widget elementor-widget-text-editor\" data-id=\"9dea10d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">N\u00f3s <strong>controlamos todas as faturas e documentos necess\u00e1rios<\/strong> para garantir que cumprem as men\u00e7\u00f5es obrigat\u00f3rias e os requisitos locais.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20c4c72 e-con-full e-flex e-con e-child\" data-id=\"20c4c72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0731ca7 elementor-widget elementor-widget-heading\" data-id=\"0731ca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">03<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd112a1 elementor-widget elementor-widget-heading\" data-id=\"bd112a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Prepara\u00e7\u00e3o e submiss\u00e3o do pedido<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2104701 elementor-widget elementor-widget-text-editor\" data-id=\"2104701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Os nossos especialistas <strong>preparam o pedido de reembolso em conformidade com as regras do Estado-Membro<\/strong> em causa e submetem-no junto da administra\u00e7\u00e3o tribut\u00e1ria.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0f246a e-grid e-con-boxed e-con e-parent\" data-id=\"e0f246a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cd68636 e-con-full e-flex e-con e-child\" data-id=\"cd68636\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac032d elementor-widget elementor-widget-heading\" data-id=\"7ac032d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">04<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b394780 elementor-widget elementor-widget-heading\" data-id=\"b394780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Contactos com a administra\u00e7\u00e3o tribut\u00e1ria local<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f794958 elementor-widget elementor-widget-text-editor\" data-id=\"f794958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>O reembolso depende tamb\u00e9m dos acordos entre Estados<\/b>: alguns pa\u00edses exigem condi\u00e7\u00f5es espec\u00edficas ou a designa\u00e7\u00e3o de um representante fiscal.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f0d348 e-con-full e-flex e-con e-child\" data-id=\"0f0d348\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-917bcb1 elementor-widget elementor-widget-heading\" data-id=\"917bcb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">05<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26ec2ad elementor-widget elementor-widget-heading\" data-id=\"26ec2ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Obten\u00e7\u00e3o do reembolso<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b42c78b elementor-widget elementor-widget-text-editor\" data-id=\"b42c78b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Acompanhamos o seu processo <strong>at\u00e9 ao efetivo pagamento do IVA recuperado<\/strong>, garantindo-lhe um processo completo e seguro.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aedc53 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1aedc53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb9abf6 elementor-widget elementor-widget-html\" data-id=\"fb9abf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d834efe elementor-widget elementor-widget-html\" data-id=\"d834efe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88b08fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88b08fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bac4499\" data-id=\"bac4499\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a02f80 e-con-full e-flex e-con e-child\" data-id=\"9a02f80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-176ab3a elementor-widget elementor-widget-html\" data-id=\"176ab3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53b231b elementor-widget elementor-widget-html\" data-id=\"53b231b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e60e09 elementor-widget elementor-widget-heading\" data-id=\"5e60e09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desafios e implica\u00e7\u00f5es do reembolso do IVA intracomunit\u00e1rio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe0fe6 elementor-widget elementor-widget-text-editor\" data-id=\"4fe0fe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recuperar o IVA noutro Estado-Membro pode parecer simples, mas para uma empresa sem experi\u00eancia especializada, <strong>muitas restri\u00e7\u00f5es e riscos podem complicar o procedimento<\/strong>. Identificar estes desafios desde o in\u00edcio permite garantir a seguran\u00e7a do processo e evitar perdas financeiras.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-beae608 e-flex e-con-boxed e-con e-parent\" data-id=\"beae608\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3a395d e-con-full e-flex e-con e-child\" data-id=\"f3a395d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-001eec2 e-con-full e-flex e-con e-child\" data-id=\"001eec2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2411bba elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2411bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-balance-scale\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tComplexidade das regulamenta\u00e7\u00f5es locais\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCada pa\u00eds da UE tem as suas pr\u00f3prias regras fiscais, prazos e documentos exigidos, o que pode <b>tornar o procedimento dif\u00edcil de compreender para quem n\u00e3o est\u00e1 familiarizado<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46e94ec e-con-full e-flex e-con e-child\" data-id=\"46e94ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b671469 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b671469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stopwatch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPrazos e riscos de rejei\u00e7\u00e3o do pedido\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUm erro na submiss\u00e3o ou a falta de um documento pode levar \u00e0 <b>rejei\u00e7\u00e3o do pedido de reembolso e atrasar a recupera\u00e7\u00e3o do IVA<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-acb88fd e-con-full e-flex e-con e-child\" data-id=\"acb88fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92f72bb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"92f72bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-tie\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObriga\u00e7\u00e3o eventual de designar um representante fiscal\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEm certos pa\u00edses como a Fran\u00e7a, <b>apenas uma empresa representada por um <a href=\"https:\/\/www.asd-int.com\/pt-pt\/representacao-fiscal\/\">representante fiscal acreditado<\/a> pode apresentar o pedido<\/b>, caso contr\u00e1rio o reembolso \u00e9 imposs\u00edvel.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08d5303 e-flex e-con-boxed e-con e-parent\" data-id=\"08d5303\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1cd745d e-con-full e-flex e-con e-child\" data-id=\"1cd745d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d409cf8 e-con-full e-flex e-con e-child\" data-id=\"d409cf8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42af251 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"42af251\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEvolu\u00e7\u00e3o da regulamenta\u00e7\u00e3o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9 necess\u00e1rio um \n<b>acompanhamento e adapta\u00e7\u00e3o cont\u00ednuos \u00e0s altera\u00e7\u00f5es\n<\/b> frequentes da regulamenta\u00e7\u00e3o fiscal.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74558bc e-con-full e-flex e-con e-child\" data-id=\"74558bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc1e099 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fc1e099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDeclara\u00e7\u00f5es e pagamentos peri\u00f3dicos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9 necess\u00e1rio <b>apresentar regularmente declara\u00e7\u00f5es de IVA<\/b> e efetuar os respetivos pagamentos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-763683f e-con-full e-flex e-con e-child\" data-id=\"763683f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7eefeb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d7eefeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTempo e recursos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTem a <b>necessidade de dedicar tempo e recursos significativos<\/b> para gerir as suas pr\u00f3prias atividades enquanto delega a gest\u00e3o das suas obriga\u00e7\u00f5es fiscais \u00e0 dist\u00e2ncia.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51ed9af e-flex e-con-boxed e-con e-parent\" data-id=\"51ed9af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-431dad0 e-con-full e-flex e-con e-child\" data-id=\"431dad0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f79313f e-con-full e-flex e-con e-child\" data-id=\"f79313f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5430aeb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5430aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVerifica\u00e7\u00e3o e conformidade das faturas\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAs faturas devem conter men\u00e7\u00f5es precisas para serem aceites; <b>um erro pode bloquear o reembolso ou originar uma recusa<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3de352b e-con-full e-flex e-con e-child\" data-id=\"3de352b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51743b2 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"51743b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAcompanhamento administrativo complexo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOs contactos com a administra\u00e7\u00e3o tribut\u00e1ria estrangeira exigem tempo, capacidade de resposta e um <b>conhecimento preciso dos procedimentos<\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37b4627 e-con-full e-flex e-con e-child\" data-id=\"37b4627\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9f74f elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7a9f74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-coins\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRiscos financeiros e san\u00e7\u00f5es\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUma m\u00e1 gest\u00e3o ou uma submiss\u00e3o incorreta pode levar \u00e0 <b>perda do IVA recuper\u00e1vel<\/b> e, em alguns casos, a penalidades.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac42531 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ac42531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6802bb e-flex e-con-boxed e-con e-parent\" data-id=\"f6802bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc3165 elementor-widget elementor-widget-html\" data-id=\"5fc3165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61dd3b6 elementor-widget elementor-widget-html\" data-id=\"61dd3b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fd4a0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fd4a0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2103d28\" data-id=\"2103d28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-732951b elementor-widget-tablet__width-inherit elementor-widget elementor-widget-counter\" data-id=\"732951b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Rede de 20 ag\u00eancias <br \/>na Europa e no mundo<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"20\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ccedb13\" data-id=\"ccedb13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1449f35 elementor-widget elementor-widget-counter\" data-id=\"1449f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Presen\u00e7a em 18 pa\u00edses <br \/>na Europa e no mundo<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"18\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c535483\" data-id=\"c535483\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c381a82 elementor-widget elementor-widget-counter\" data-id=\"c381a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">colaboradores em todo o mundo<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-57d856a\" data-id=\"57d856a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68b25ff elementor-widget elementor-widget-counter\" data-id=\"68b25ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">empresas clientes na ind\u00fastria, grande distribui\u00e7\u00e3o, e-commerce...<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"7000\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bd2721 elementor-widget elementor-widget-menu-anchor\" data-id=\"0bd2721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"o-que-fazemos-por-si\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce8a2f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce8a2f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2469db\" data-id=\"a2469db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d7e08 e-con-full e-flex e-con e-child\" data-id=\"50d7e08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-376b6ba elementor-widget elementor-widget-html\" data-id=\"376b6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6891161 elementor-widget elementor-widget-html\" data-id=\"6891161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410bb75 elementor-widget elementor-widget-heading\" data-id=\"410bb75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como \u00e9 que a ASD Group facilita as suas formalidades de IVA gra\u00e7as aos seus especialistas?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bafdd7 elementor-widget elementor-widget-text-editor\" data-id=\"9bafdd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A ASD Group simplifica as suas formalidades administrativas e regulamentares <b>colocando \u00e0 sua disposi\u00e7\u00e3o uma equipa de especialistas em IVA qualificados<\/b>. Gra\u00e7as ao seu <b>profundo conhecimento das regulamenta\u00e7\u00f5es locais e internacionais<\/b>, acompanham-no em cada etapa, <b>permitindo-lhe poupar tempo, evitar erros<\/b> dispendiosos e concentrar-se no desenvolvimento da sua atividade.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e80428 e-flex e-con-boxed e-con e-parent\" data-id=\"7e80428\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de02b3 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1de02b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents.jpg\" class=\"attachment-full size-full wp-image-177604\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-768x512.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-collecte-information-documents-1200x800.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Recolha de informa\u00e7\u00f5es e documentos<\/h3><p class=\"elementor-image-box-description\">Recolhemos todos os documentos necess\u00e1rios do cliente, tais como certificados de registo da empresa, informa\u00e7\u00f5es de contacto e detalhes das opera\u00e7\u00f5es comerciais. Obtemos as autoriza\u00e7\u00f5es necess\u00e1rias para atuar em nome do cliente junto das autoridades fiscais locais.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d80870 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"0d80870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales.jpg\" class=\"attachment-full size-full wp-image-177637\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-enregistrement-aupres-des-autorites-fiscales-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Registo junto das autoridades fiscais<\/h3><p class=\"elementor-image-box-description\">Apresentamos os formul\u00e1rios de registo necess\u00e1rios \u00e0s autoridades fiscais do pa\u00eds em causa. Garantimos que o cliente fica corretamente registado para efeitos de IVA e outros impostos relevantes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f9a350 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"4f9a350\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva.jpg\" class=\"attachment-full size-full wp-image-177626\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-evaluation-des-obligations-fiscales-et-tva-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Avalia\u00e7\u00e3o das obriga\u00e7\u00f5es fiscais e do IVA<\/h3><p class=\"elementor-image-box-description\">Analisamos as transa\u00e7\u00f5es comerciais do cliente para determinar as obriga\u00e7\u00f5es fiscais espec\u00edficas e as faturas. Identificamos as taxas de IVA aplic\u00e1veis e outros requisitos fiscais em fun\u00e7\u00e3o do tipo de bens ou servi\u00e7os fornecidos.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1dd345 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b1dd345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"961\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva.jpg\" class=\"attachment-full size-full wp-image-177615\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-768x513.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/07\/representation-fiscale-asd-group-declarations-et-paiements-de-tva-1200x801.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Submiss\u00e3o dos pedidos de reembolso de IVA<\/h3><p class=\"elementor-image-box-description\">Preparamos e submetemos os pedidos de reembolso de IVA em conformidade com os requisitos locais.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-919ae29 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"919ae29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement.jpg\" class=\"attachment-full size-full wp-image-177469\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement.jpg 1440w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement-300x200.jpg 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement-1024x683.jpg 1024w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement-768x512.jpg 768w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/representation-fiscale-accompagnement-1200x800.jpg 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Apoio durante as inspe\u00e7\u00f5es<\/h3><p class=\"elementor-image-box-description\">Enquanto representante fiscal, acompanhamos-no durante as inspe\u00e7\u00f5es, preparando os documentos, gerindo as intera\u00e7\u00f5es com os inspetores e assegurando o cumprimento das regulamenta\u00e7\u00f5es, minimizando assim os riscos de penaliza\u00e7\u00f5es.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2ba6cc e-con-full e-flex e-con e-child\" data-id=\"a2ba6cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-099a7d2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"099a7d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82e3453 elementor-widget elementor-widget-html\" data-id=\"82e3453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad0491 elementor-widget elementor-widget-html\" data-id=\"bad0491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33e549f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33e549f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-aadcddb\" data-id=\"aadcddb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abab426 elementor-widget elementor-widget-counter\" data-id=\"abab426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">parceiros em todo o mundo<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"75\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6c1d91d\" data-id=\"6c1d91d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4116ece elementor-widget elementor-widget-counter\" data-id=\"4116ece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">anos de experi\u00eancia <br \/>em desenvolvimento internacional<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"26\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-dc331ac\" data-id=\"dc331ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bdc783 elementor-widget elementor-widget-counter\" data-id=\"5bdc783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">ano de cria\u00e7\u00e3o da ASD Group<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"14\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-25587c4\" data-id=\"25587c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a54982 elementor-widget elementor-widget-counter\" data-id=\"9a54982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">dos nossos clientes <br \/>nos recomendam<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"98\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b92bab elementor-widget elementor-widget-menu-anchor\" data-id=\"9b92bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"razoes-para-nos-contactar\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc8501f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc8501f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e75129a\" data-id=\"e75129a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4c5ec e-con-full e-flex e-con e-child\" data-id=\"ff4c5ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb9bd0 elementor-widget elementor-widget-html\" data-id=\"fdb9bd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18fb6c3 elementor-widget elementor-widget-html\" data-id=\"18fb6c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0121818 elementor-widget elementor-widget-heading\" data-id=\"0121818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Raz\u00f5es para contactar a ASD Group<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ed8ede e-flex e-con-boxed e-con e-parent\" data-id=\"1ed8ede\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f0cdd8b e-con-full e-flex e-con e-child\" data-id=\"f0cdd8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6893191 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6893191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-tie\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEspecializa\u00e7\u00e3o avan\u00e7ada\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tA nossa equipa composta por <strong>fiscalistas especializados em IVA intracomunit\u00e1rio<\/strong> est\u00e1 ao seu dispor para lhe fornecer aconselhamento especializado e acompanhamento personalizado.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc6cc8f e-con-full e-flex e-con e-child\" data-id=\"dc6cc8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d871435 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d871435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFiabilidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUma garantia da qualidade do trabalho e da <strong>seguran\u00e7a das suas opera\u00e7\u00f5es<\/strong> para proteger as suas atividades e minimizar os riscos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcfae68 e-con-full e-flex e-con e-child\" data-id=\"dcfae68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c693fc4 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c693fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-laptop-code\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDigitaliza\u00e7\u00e3o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>Desenvolvemos os nossos pr\u00f3prios softwares espec\u00edficos<\/b> que permitem o controlo de fluxos e limiares, a gest\u00e3o eletr\u00f3nica de dados, lembretes de prazos, etc. Tudo dispon\u00edvel na <b><u><a href=\"https:\/\/www.asd-int.com\/pt-pt\/?page_id=172234\" style=\"color:#FFFFFF\">nossa plataforma multisservi\u00e7os 100% online MyASD<\/a><\/u><\/b>.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15e9cee e-flex e-con-boxed e-con e-parent\" data-id=\"15e9cee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a51241 e-con-full e-flex e-con e-child\" data-id=\"5a51241\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30dab4c elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"30dab4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKnow-how\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tO nosso know-how permite-nos ser um <b>interlocutor de confian\u00e7a das administra\u00e7\u00f5es fiscais<\/b> europeias h\u00e1 mais de 20 anos, garantindo as suas atividades na UE e a sua reputa\u00e7\u00e3o junto dos servi\u00e7os fiscais europeus.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-318f683 e-con-full e-flex e-con e-child\" data-id=\"318f683\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-147ac8d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"147ac8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stopwatch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tReatividade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRespondemos a todos os pedidos dos nossos clientes num <b>prazo de 48 horas \u00fateis<\/b>, garantindo uma comunica\u00e7\u00e3o fluida e eficaz ao longo de todo o processo.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90c133c e-con-full e-flex e-con e-child\" data-id=\"90c133c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0037702 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0037702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-eye\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVigil\u00e2ncia regulamentar constante\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOs nossos especialistas mant\u00eam uma <b>vigil\u00e2ncia constante das evolu\u00e7\u00f5es regulamentares<\/b>, permitindo-lhe permanecer informado e adaptar-se rapidamente \u00e0s altera\u00e7\u00f5es.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c15c11 e-flex e-con-boxed e-con e-parent\" data-id=\"6c15c11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e07b70 e-con-full e-flex e-con e-child\" data-id=\"6e07b70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb5f815 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bb5f815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConsultor dedicado\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCada cliente \u00e9 atribu\u00eddo a um <b>gestor de conta dedicado<\/b> que o acompanha ao longo de todo o percurso connosco, assegurando um servi\u00e7o personalizado e uma rela\u00e7\u00e3o de confian\u00e7a.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13c74f4 e-con-full e-flex e-con e-child\" data-id=\"13c74f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52887ad e-con-full e-flex e-con e-child\" data-id=\"52887ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed538ce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ed538ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cbe3b5 e-flex e-con-boxed e-con e-parent\" data-id=\"6cbe3b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87098f0 elementor-widget elementor-widget-html\" data-id=\"87098f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b6dd4 elementor-widget elementor-widget-menu-anchor\" data-id=\"57b6dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"paises-abrangidos\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59ed99 elementor-widget elementor-widget-html\" data-id=\"e59ed99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73ce7d37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73ce7d37\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c68d06e\" data-id=\"c68d06e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d8b7b e-con-full e-flex e-con e-child\" data-id=\"d0d8b7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c37df3 elementor-widget elementor-widget-html\" data-id=\"7c37df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91de207 elementor-widget elementor-widget-html\" data-id=\"91de207\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44dd5e20 elementor-widget elementor-widget-heading\" data-id=\"44dd5e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Opte pelas nossas solu\u00e7\u00f5es de representa\u00e7\u00e3o fiscal<br \/>nestes pa\u00edses agora mesmo!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b2f7941 elementor-widget elementor-widget-heading\" data-id=\"1b2f7941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Na Uni\u00e3o Europeia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e71cdb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e71cdb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bd44059\" data-id=\"bd44059\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a9dd60d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a9dd60d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5065c7d5\" data-id=\"5065c7d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14160111 elementor-widget elementor-widget-image\" data-id=\"14160111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-allemagne-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-alemanha\" alt=\"drapeau-rond-alemanha\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2cb45ffe\" data-id=\"2cb45ffe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-150653bf elementor-widget elementor-widget-text-editor\" data-id=\"150653bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA alem\u00e3o &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-alemanha\/\">Reembolso IVA alem\u00e3o &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6859e26d\" data-id=\"6859e26d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a70fe5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a70fe5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4011ef4f\" data-id=\"4011ef4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a0d223 elementor-widget elementor-widget-image\" data-id=\"68a0d223\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-autriche-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-austria\" alt=\"drapeau-rond-austria\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71244f2d\" data-id=\"71244f2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ea10bd3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3ea10bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA austr\u00edaco &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-austria\/\">Reembolso IVA austr\u00edaco &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c1f2729\" data-id=\"6c1f2729\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50a06bbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50a06bbc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4eca4660\" data-id=\"4eca4660\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e6ad843 elementor-widget elementor-widget-image\" data-id=\"7e6ad843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-belgique-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-belgica\" alt=\"drapeau-rond-belgica\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b8f7ccd\" data-id=\"b8f7ccd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-182fda44 elementor-widget elementor-widget-text-editor\" data-id=\"182fda44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA belga &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-belgica\/\">Reembolso IVA belga &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a89e923 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a89e923\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-25e35df5\" data-id=\"25e35df5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3dae8c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dae8c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f6553f5\" data-id=\"6f6553f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fb7d931 elementor-widget elementor-widget-image\" data-id=\"2fb7d931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-bulgarie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-bulgaria\" alt=\"drapeau-rond-bulgaria\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fb155e2\" data-id=\"fb155e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eee9f40 elementor-widget elementor-widget-text-editor\" data-id=\"2eee9f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA b\u00falgaro &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-bulgaria\/\">Reembolso IVA b\u00falgaro &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-627fc428\" data-id=\"627fc428\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ba202fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ba202fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-70c72950\" data-id=\"70c72950\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7ab758 elementor-widget elementor-widget-image\" data-id=\"3d7ab758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-chypre-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-chipre\" alt=\"drapeau-rond-chipre\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65e1b31c\" data-id=\"65e1b31c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3392a5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7d3392a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA cipriota &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-chipre\/\">Reembolso IVA cipriota &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-220fd6ba\" data-id=\"220fd6ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53674a5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53674a5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33405681\" data-id=\"33405681\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b320dee elementor-widget elementor-widget-image\" data-id=\"3b320dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-croatie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-croacia\" alt=\"drapeau-rond-croacia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49220c98\" data-id=\"49220c98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73d1346 elementor-widget elementor-widget-text-editor\" data-id=\"73d1346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA croata &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-croacia\/\">Reembolso IVA croata &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b885aed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b885aed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-10c99728\" data-id=\"10c99728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3df6171c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3df6171c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ed1fc8\" data-id=\"4ed1fc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2264afe elementor-widget elementor-widget-image\" data-id=\"2264afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-danemark-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-dinamarca\" alt=\"drapeau-rond-dinamarca\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58c7df20\" data-id=\"58c7df20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33d2995f elementor-widget elementor-widget-text-editor\" data-id=\"33d2995f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA dinamarqu\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-dinamarca\/\">Reembolso IVA dinamarqu\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-719cb4d\" data-id=\"719cb4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-31d8e7d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31d8e7d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-76248768\" data-id=\"76248768\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b41712a elementor-widget elementor-widget-image\" data-id=\"2b41712a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-espagne-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-espanha\" alt=\"drapeau-rond-espanha\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b2b7b4b\" data-id=\"4b2b7b4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50cb6827 elementor-widget elementor-widget-text-editor\" data-id=\"50cb6827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA espanhol &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-espanha\/\">Reembolso IVA espanhol &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-74f0acd2\" data-id=\"74f0acd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-609e45e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"609e45e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-253d8292\" data-id=\"253d8292\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44a2eca4 elementor-widget elementor-widget-image\" data-id=\"44a2eca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-estonie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-estonia\" alt=\"drapeau-rond-estonia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e143ba3\" data-id=\"1e143ba3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a4a530a elementor-widget elementor-widget-text-editor\" data-id=\"3a4a530a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA est\u00f3nio &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-estonia\/\">Reembolso IVA est\u00f3nio &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d7e8fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d7e8fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56effda7\" data-id=\"56effda7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d80f80b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d80f80b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c41bcbe\" data-id=\"c41bcbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18d08dc4 elementor-widget elementor-widget-image\" data-id=\"18d08dc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-finlande-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-finlandia\" alt=\"drapeau-rond-finlandia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-371aead7\" data-id=\"371aead7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-594e5d6 elementor-widget elementor-widget-text-editor\" data-id=\"594e5d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA finland\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-finlandia\/\">Reembolso IVA finland\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-14e6fad8\" data-id=\"14e6fad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6504f035 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6504f035\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f263254\" data-id=\"2f263254\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47c439ce elementor-widget elementor-widget-image\" data-id=\"47c439ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-france-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-franca\" alt=\"drapeau-rond-franca\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35db45f8\" data-id=\"35db45f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d6fa126 elementor-widget elementor-widget-text-editor\" data-id=\"1d6fa126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA franc\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-franca\/\">Reembolso IVA franc\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-41a2cac5\" data-id=\"41a2cac5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-628ee4d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"628ee4d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7660badb\" data-id=\"7660badb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-120234c1 elementor-widget elementor-widget-image\" data-id=\"120234c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-grece-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-grecia\" alt=\"drapeau-rond-grecia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-242d699e\" data-id=\"242d699e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7180f4d6 elementor-widget elementor-widget-text-editor\" data-id=\"7180f4d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA grego &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-grecia\/\">Reembolso IVA grego &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22abec86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22abec86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-83d8fc4\" data-id=\"83d8fc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-42b4b6d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42b4b6d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b5f9c7b\" data-id=\"4b5f9c7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a97415 elementor-widget elementor-widget-image\" data-id=\"8a97415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-hongrie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-hungria\" alt=\"drapeau-rond-hungria\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-132dbcb5\" data-id=\"132dbcb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fff6aee elementor-widget elementor-widget-text-editor\" data-id=\"2fff6aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA h\u00fangaro &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-hungria\/\">Reembolso IVA h\u00fangaro &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7bebed9\" data-id=\"7bebed9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a85a60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a85a60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7106f602\" data-id=\"7106f602\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ee7ec8 elementor-widget elementor-widget-image\" data-id=\"63ee7ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-irlande-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-irlanda\" alt=\"drapeau-rond-irlanda\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1fecb763\" data-id=\"1fecb763\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-788ca884 elementor-widget elementor-widget-text-editor\" data-id=\"788ca884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA irland\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-irlanda\/\">Reembolso IVA irland\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33db56d4\" data-id=\"33db56d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d01846a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d01846a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-379a8242\" data-id=\"379a8242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1432d08d elementor-widget elementor-widget-image\" data-id=\"1432d08d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-italie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-italia\" alt=\"drapeau-rond-italia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-64903e6b\" data-id=\"64903e6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b07b639 elementor-widget elementor-widget-text-editor\" data-id=\"2b07b639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA italiano &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-italia\/\">Reembolso IVA italiano &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f8c9da9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f8c9da9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6b0b3ff8\" data-id=\"6b0b3ff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1787935e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1787935e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-402ab8c5\" data-id=\"402ab8c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39d51b00 elementor-widget elementor-widget-image\" data-id=\"39d51b00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-lettonie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-letonia\" alt=\"drapeau-rond-letonia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63d66269\" data-id=\"63d66269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13022aca elementor-widget elementor-widget-text-editor\" data-id=\"13022aca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA let\u00e3o &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-letunia\/\">Reembolso IVA let\u00e3o &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-414cfdfb\" data-id=\"414cfdfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5481738d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5481738d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f919075\" data-id=\"f919075\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-290b0a0b elementor-widget elementor-widget-image\" data-id=\"290b0a0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-lituanie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-lituania\" alt=\"drapeau-rond-lituania\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c78ab55\" data-id=\"5c78ab55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c9a5c92 elementor-widget elementor-widget-text-editor\" data-id=\"1c9a5c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA lituano &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-lituania\/\">Reembolso IVA lituano &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9e70d0b\" data-id=\"9e70d0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29ddea24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29ddea24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-188da0f0\" data-id=\"188da0f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1092a11c elementor-widget elementor-widget-image\" data-id=\"1092a11c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-luxembourg-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-luxemburgo\" alt=\"drapeau-rond-luxemburgo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a94ab78\" data-id=\"a94ab78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb52755 elementor-widget elementor-widget-text-editor\" data-id=\"4eb52755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA luxemburgu\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-luxemburgo\/\">Reembolso IVA luxemburgu\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41701b88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41701b88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7be0d961\" data-id=\"7be0d961\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c7532a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c7532a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62565ba7\" data-id=\"62565ba7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a547a03 elementor-widget elementor-widget-image\" data-id=\"6a547a03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-malte-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-malta\" alt=\"drapeau-rond-malta\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33fdc809\" data-id=\"33fdc809\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58ccc815 elementor-widget elementor-widget-text-editor\" data-id=\"58ccc815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA malt\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-malta\/\">Reembolso IVA malt\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-23919873\" data-id=\"23919873\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f54361a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f54361a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d6e615e\" data-id=\"3d6e615e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7c1069 elementor-widget elementor-widget-image\" data-id=\"1b7c1069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-pays-bas-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-paises-baixos\" alt=\"drapeau-rond-paises-baixos\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-653986cb\" data-id=\"653986cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b416c56 elementor-widget elementor-widget-text-editor\" data-id=\"4b416c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA neerland\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-paises-baixos\/\">Reembolso IVA neerland\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-29fe4b33\" data-id=\"29fe4b33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c385788 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c385788\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f064eab\" data-id=\"2f064eab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a353fc1 elementor-widget elementor-widget-image\" data-id=\"2a353fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-pologne-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-polonia\" alt=\"drapeau-rond-polonia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a2f61aa\" data-id=\"5a2f61aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1960336c elementor-widget elementor-widget-text-editor\" data-id=\"1960336c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA polaco &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-polonia\/\">Reembolso IVA polaco &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53d97cc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53d97cc1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2d0fcaa9\" data-id=\"2d0fcaa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-695250fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"695250fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42ceb482\" data-id=\"42ceb482\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-564b8db0 elementor-widget elementor-widget-image\" data-id=\"564b8db0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-portugal-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-portugal\" alt=\"drapeau-rond-portugal\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26e52b7e\" data-id=\"26e52b7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2611fbd6 elementor-widget elementor-widget-text-editor\" data-id=\"2611fbd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA portugu\u00eas &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-portugal\/\">Reembolso IVA portugu\u00eas &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-865e8ff\" data-id=\"865e8ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-114197f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"114197f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-22800a26\" data-id=\"22800a26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17ccf1d0 elementor-widget elementor-widget-image\" data-id=\"17ccf1d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-republique-tcheque-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-republica-checa\" alt=\"drapeau-rond-republica-checa\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6f9841\" data-id=\"c6f9841\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-185b3757 elementor-widget elementor-widget-text-editor\" data-id=\"185b3757\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA checo &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-republica-checa\/\">Reembolso IVA checo &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6450849\" data-id=\"6450849\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34f55afd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34f55afd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d82612b\" data-id=\"d82612b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1485dc0d elementor-widget elementor-widget-image\" data-id=\"1485dc0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-roumanie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-romenia\" alt=\"drapeau-rond-romenia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ce6a211\" data-id=\"5ce6a211\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23ccac4b elementor-widget elementor-widget-text-editor\" data-id=\"23ccac4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA romeno &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-romenia\/\">Reembolso IVA romeno &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cc0667a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cc0667a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-143a9805\" data-id=\"143a9805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f01b4e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f01b4e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ed4ad8b\" data-id=\"4ed4ad8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c97b370 elementor-widget elementor-widget-image\" data-id=\"3c97b370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-slovaquie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-eslovaquia\" alt=\"drapeau-rond-eslovaquia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63c41733\" data-id=\"63c41733\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43813ef1 elementor-widget elementor-widget-text-editor\" data-id=\"43813ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA eslovaco &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-eslovaquia\/\">Reembolso IVA eslovaco &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56d12564\" data-id=\"56d12564\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ac156f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ac156f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32a8388e\" data-id=\"32a8388e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46e1a48a elementor-widget elementor-widget-image\" data-id=\"46e1a48a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-slovenie-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-eslovenia\" alt=\"drapeau-rond-eslovenia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51101511\" data-id=\"51101511\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4defef6e elementor-widget elementor-widget-text-editor\" data-id=\"4defef6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA esloveno &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-eslovenia\/\">Reembolso IVA esloveno &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3249d68b\" data-id=\"3249d68b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f9c6d9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f9c6d9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b501401\" data-id=\"5b501401\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65535f08 elementor-widget elementor-widget-image\" data-id=\"65535f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/elementor\/thumbs\/drapeau-rond-suede-r4vidnv84qnvqv4e20mhn43u24hd08i8qstdts56yc.png\" title=\"drapeau-rond-suecia\" alt=\"drapeau-rond-suecia\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-230e3880\" data-id=\"230e3880\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-513456df elementor-widget elementor-widget-text-editor\" data-id=\"513456df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reembolso IVA sueco &#8211; 8.\u00aa Diretiva<\/p><p><a href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-13a-diretiva-suecia\/\">Reembolso IVA sueco &#8211; 13.\u00aa Diretiva<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3ce58f8 e-flex e-con-boxed e-con e-parent\" data-id=\"3ce58f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-983a723 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"983a723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1da43d elementor-widget elementor-widget-html\" data-id=\"c1da43d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87064dd elementor-widget elementor-widget-html\" data-id=\"87064dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3873f69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3873f69\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef5790c\" data-id=\"ef5790c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-740d749 e-con-full e-flex e-con e-child\" data-id=\"740d749\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70cef3b elementor-widget elementor-widget-html\" data-id=\"70cef3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dab49ce elementor-widget elementor-widget-html\" data-id=\"dab49ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d500b elementor-widget elementor-widget-heading\" data-id=\"94d500b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ELES CONFIAM EM N\u00d3S<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8ba2e3 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-widget elementor-widget-testimonial-carousel\" data-id=\"a8ba2e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">01 \/ 05<\/span> <\/p>\n<p>A minha empresa est\u00e1 perfeitamente em conformidade em mat\u00e9ria de IVA e Intrastat<br \/>gra\u00e7as \u00e0 ASD Group, \u00e9 tudo o que pe\u00e7o. Miss\u00e3o cumprida.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-ad-tyres-1.png\" alt=\"AD TYRES - Hugo Lacasse, CEO &amp; fundador\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">AD TYRES - Hugo Lacasse, CEO & fundador<\/span><span class=\"elementor-testimonial__title\">CEO & fundador<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">02 \/ 05<\/span> <\/p>\n<p>O grande valor acrescentado da ASD Group foi a disponibilidade dos interlocutores, <br \/>o prazo de resposta, o tratamento dos processos, em resumo, equipas eficientes.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-sbm-offshore.png\" alt=\"GROUPE SBM - Alexandra Bocangel, Consultora fiscal\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">GROUPE SBM - Alexandra Bocangel, Consultora fiscal<\/span><span class=\"elementor-testimonial__title\">Consultora fiscal<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">03 \/ 05<\/span> <\/p>\n<p>Para completar a nossa oferta, precis\u00e1vamos de um especialista <br \/>nas problem\u00e1ticas fiscais relacionadas com as trocas internacionais.<\/p>\n<p>Pareceu-nos natural contactar a ASD Group, empresa reconhecida <br \/>pelas suas compet\u00eancias em mat\u00e9ria de fiscalidade internacional.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/logo-rhenus-logistics.png\" alt=\"RHENUS - St\u00e9phane Dielaine, Respons\u00e1vel Alf\u00e2ndega Fran\u00e7a\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">RHENUS - St\u00e9phane Dielaine, Respons\u00e1vel Alf\u00e2ndega Fran\u00e7a<\/span><span class=\"elementor-testimonial__title\">Respons\u00e1vel Alf\u00e2ndega Fran\u00e7a<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">04 \/ 05<\/span> <\/p>\n<p>Queremos realmente agradecer-vos a todos pelo esfor\u00e7o especial que colocam na gest\u00e3o dos nossos processos (especialmente neste fim de semana!). <\/p>\n<p>Podemos ser muito exigentes, mas estamos verdadeiramente satisfeitos por cooperar convosco e com a vossa equipa!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/yormax-logo.png\" alt=\"YORMAX LOGISTIC SERVICES B.V - Marcel van Hengel\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">YORMAX LOGISTIC SERVICES B.V - Marcel van Hengel<\/span><span class=\"elementor-testimonial__title\">Fundador<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p><span class=\"slide-number\">05 \/ 05<\/span> <\/p>\n<p>A ASD Group soube trazer-nos a sua expertise tanto na conformidade das nossas declara\u00e7\u00f5es de IVA como na conformidade das nossas faturas de vendas e nas suas particularidades nos pa\u00edses da Europa.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2024\/06\/robotshop-logo.png\" alt=\"ROBOTSHOP (Canad\u00e1) - Luc Pr\u00e9vost-Fournier\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">ROBOTSHOP (Canad\u00e1) - Luc Pr\u00e9vost-Fournier<\/span><span class=\"elementor-testimonial__title\">Assistente de Contabilidade<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94c5d98 e-con-full e-flex e-con e-child\" data-id=\"94c5d98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80e1771 elementor-widget elementor-widget-html\" data-id=\"80e1771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b453e5 elementor-widget elementor-widget-html\" data-id=\"3b453e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f243fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f243fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb66925\" data-id=\"fb66925\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b7ef1 e-flex e-con-boxed e-con e-parent\" data-id=\"97b7ef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d55061c elementor-widget elementor-widget-html\" data-id=\"d55061c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06ff6e0 elementor-widget elementor-widget-html\" data-id=\"06ff6e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f38003a elementor-widget elementor-widget-heading\" data-id=\"f38003a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubra as nossas Solu\u00e7\u00f5es Complementares para <br \/>impulsionar o seu neg\u00f3cio internacional j\u00e1!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-699f893 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"699f893\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-463be6b\" data-id=\"463be6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e0e25c elementor-widget elementor-widget-heading\" data-id=\"3e0e25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">01<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fed418 elementor-widget elementor-widget-heading\" data-id=\"1fed418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/representant-fiscal-et-tva-internationale\/\">Representa\u00e7\u00e3o fiscal<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be2d518\" data-id=\"be2d518\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f13d8e elementor-widget elementor-widget-heading\" data-id=\"5f13d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">02<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c1ba77 elementor-widget elementor-widget-heading\" data-id=\"5c1ba77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/mandataire-fiscal\/\">Mandato fiscal<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-87814dc\" data-id=\"87814dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60507a0 elementor-widget elementor-widget-heading\" data-id=\"60507a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">03<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32cfae5 taux-tva-year elementor-widget elementor-widget-heading\" data-id=\"32cfae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asd-int.com\/expertise-tva-ameliorez-votre-flux-de-tresorerie-avec-nos-conseils-sur-mesure\/\">\nEspecializa\u00e7\u00e3o em IVA: Conselhos para impulsionar a sua tesouraria<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-918d638 e-flex e-con-boxed e-con e-parent\" data-id=\"918d638\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bf0aeb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8bf0aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Recupere o seu IVA agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1d99fb4 e-flex e-con-boxed e-con e-parent\" data-id=\"1d99fb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b850c8 elementor-widget elementor-widget-html\" data-id=\"3b850c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7450d2 elementor-widget elementor-widget-html\" data-id=\"b7450d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>IN\u00cdCIO &gt; OS NOSSOS SERVI\u00c7OS &gt; IVA E FISCALIDADE &gt; REEMBOLSO IVA INTRACOMUNIT\u00c1RIO Reembolso de IVA intracomunit\u00e1rio: recupere rapidamente o seu IVA estrangeiro na Uni\u00e3o&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"pays":[],"activites":[],"type_service":[],"class_list":["post-205001","service","type-service","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reembolso de IVA da U.E. | ASD Group<\/title>\n<meta name=\"description\" content=\"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reembolso de IVA da U.E. | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T12:16:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"774\" \/>\n\t<meta property=\"og:image:height\" content=\"1041\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/\",\"name\":\"Reembolso de IVA da U.E. | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/remboursement-tva-illustration-fr-768x1033.png\",\"datePublished\":\"2026-02-19T07:16:54+00:00\",\"dateModified\":\"2026-04-29T12:16:45+00:00\",\"description\":\"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/remboursement-tva-illustration-fr-768x1033.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/remboursement-tva-illustration-fr-768x1033.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reembolso-de-iva-da-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reembolso de IVA da U.E.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reembolso de IVA da U.E. | ASD Group","description":"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/","og_locale":"pt_PT","og_type":"article","og_title":"Reembolso de IVA da U.E. | ASD Group","og_description":"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/","og_site_name":"ASD","article_modified_time":"2026-04-29T12:16:45+00:00","og_image":[{"width":774,"height":1041,"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/","url":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/","name":"Reembolso de IVA da U.E. | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-768x1033.png","datePublished":"2026-02-19T07:16:54+00:00","dateModified":"2026-04-29T12:16:45+00:00","description":"Recupere o IVA pago na UE com total seguran\u00e7a. Auditoria, conformidade e gest\u00e3o integral pelos especialistas da ASD Group.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-768x1033.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/remboursement-tva-illustration-fr-768x1033.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/reembolso-de-iva-da-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Reembolso de IVA da U.E."}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/205001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":15,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/205001\/revisions"}],"predecessor-version":[{"id":212291,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/205001\/revisions\/212291"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=205001"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pays?post=205001"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/activites?post=205001"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/type_service?post=205001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}