{"id":43119,"date":"2019-06-12T17:11:01","date_gmt":"2019-06-12T15:11:01","guid":{"rendered":"https:\/\/devvitrine.asd-int.com\/service\/detachement-de-salaries-en-france\/"},"modified":"2020-03-26T13:54:27","modified_gmt":"2020-03-26T12:54:27","slug":"destacamento-de-trabalhadores-em-franca","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/","title":{"rendered":"Destacamento de trabalhadores em Fran\u00e7a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43119\" class=\"elementor elementor-43119 elementor-34530\" data-elementor-post-type=\"service\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39010340 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"39010340\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70d1c31\" data-id=\"70d1c31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cf37b8\" data-id=\"3cf37b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6432dfe5 elementor-widget elementor-widget-text-editor\" data-id=\"6432dfe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"\/pt-pt\/\">ASD GROUP<\/a> &gt;\u00a0<a href=\"\/pt-pt\/servicos-social\/\">SERVI\u00c7OS SOCIAL<\/a> &gt; DESTACAMENTO DE TRABALHADORES<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7be802ff elementor-widget elementor-widget-heading\" data-id=\"7be802ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Destacamento de trabalhadores<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323c6804 elementor-widget elementor-widget-button\" data-id=\"323c6804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Precisa de ajuda?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d79dbd7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3d79dbd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e060a76 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e060a76\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64fb91d8\" data-id=\"64fb91d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a85bb79 elementor-widget elementor-widget-html\" data-id=\"6a85bb79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b09b111 elementor-widget elementor-widget-html\" data-id=\"1b09b111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2329dcf1 elementor-widget elementor-widget-heading\" data-id=\"2329dcf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O que \u00e9 o destacamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-503d43b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"503d43b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3229b1b6\" data-id=\"3229b1b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05d56ed elementor-widget elementor-widget-image\" data-id=\"05d56ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"193\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg\" class=\"attachment-large size-large wp-image-35951\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg 690w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230-300x100.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e834a1 elementor-widget elementor-widget-text-editor\" data-id=\"24e834a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<p>O destacamento transnacional de trabalhadores consiste, para uma empresa estrangeira, mover temporariamente os seus trabalhadores, para uma empresa em Fran\u00e7a numa situa\u00e7\u00e3o precisa.<br \/>\nEsta pr\u00e1tica de recrutamento espec\u00edfico permite de controlar a presen\u00e7a e a conformidade dos trabalhadores estrangeiros em Fran\u00e7a.<\/p>\n<p>Foi posto em pr\u00e1tica medidas para controlar o trabalho ilegal. O destacamento de trabalhadores em Fran\u00e7a faz-se sobre certas condi\u00e7\u00f5es que todas as empresas estrangeiras devem respeitar:<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11cf68d1 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"11cf68d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designa\u00e7\u00e3o de um representante social em Fran\u00e7a;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Realiza\u00e7\u00e3o de uma declara\u00e7\u00e3o de SIPSI para cada trabalhador e para cada miss\u00e3o;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Disponibilizar, atrav\u00e9s do seu representante, toda a documenta\u00e7\u00e3o relativa \u00e0 atividade em Fran\u00e7a;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25186da elementor-widget elementor-widget-text-editor\" data-id=\"25186da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\"><div class=\"wpb_wrapper\">Ao utilizar a plataforma ADD dedicada ao destacamento de trabalhadores: \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.<\/div><div class=\"wpb_wrapper\">Um acesso espec\u00edfico com um painel de controlo que permite ao contratante de conferir a conformidade das obriga\u00e7\u00f5es dos seus subcontratados. ASD \u00e9 um servi\u00e7o especializado respons\u00e1vel pelas rela\u00e7\u00f5es com a DIRECCTE em caso de fiscaliza\u00e7\u00f5es.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2b919 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4b2b919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.soposting-worker.com\/#\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Come\u00e7ar os meus destacamentos online com So Posting Worker<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d536b57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d536b57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66be2698\" data-id=\"66be2698\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95a1c9c elementor-widget elementor-widget-html\" data-id=\"95a1c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5915cecd elementor-widget elementor-widget-heading\" data-id=\"5915cecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A DIRECCTE efetua in\u00fameras fiscaliza\u00e7\u00f5es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69647026 elementor-widget elementor-widget-text-editor\" data-id=\"69647026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<p>A DIRECTE \u00e9 um organismo franc\u00eas respons\u00e1vel pela inspe\u00e7\u00e3o do trabalho, est\u00e1 autorizado a entrar nas empresas ou nas obras, sem pr\u00e9-aviso e a controlar a conformidade de todos os trabalhadores presentes, nomeadamente ao n\u00edvel do contrato de destacamento. Em caso de inexist\u00eancia do mesmo, podem ser aplicadas san\u00e7\u00f5es como por exemplo:<\/p>\n<p><em>Aten\u00e7\u00e3o: As san\u00e7\u00f5es s\u00e3o altas: 4000\u20ac por infra\u00e7\u00e3o e por trabalhador. O que, dependendo do tipo de destacamento, se nada for feito, pode dar origem a uma coima de entre 12000\u20ac e 16000\u20ac por trabalhador destacado.\u00a0 <\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abeb41a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abeb41a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e3b57f\" data-id=\"1e3b57f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caebef6 elementor-widget elementor-widget-heading\" data-id=\"caebef6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Escolher a ASD Group \u00e9 escolher a Seguran\u00e7a<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b52070 elementor-widget elementor-widget-text-editor\" data-id=\"8b52070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">Em certos casos, o contratante \u00e9 respons\u00e1vel solid\u00e1rio das empresas estrangeiras que contrata. Ele deve verificar a conformidade das obriga\u00e7\u00f5es dos subcontratados no pa\u00eds de destacamento.<br \/>\nO contratante \u00e9 solid\u00e1rio do pagamento de penalidades em casa de falha do seus subcontratados.<br \/>\n\u00c9 por esta raz\u00e3o que a ASD implementou uma solu\u00e7\u00e3o simples de acompanhamento e de alertar as empresas contratantes.<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c2405e elementor-widget elementor-widget-heading\" data-id=\"4c2405e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Escolher a ASD Group \u00e9 escolher a simplicidade<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21fbb55 elementor-widget elementor-widget-text-editor\" data-id=\"21fbb55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">\n<p>O destacamento de trabalhadores em Fran\u00e7a trata-se em 3 partes:<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e28abfc elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4e28abfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>O pr\u00e9-destacamento: <\/b>fazer todas as declara\u00e7\u00f5es de destacamento antecipadamente antes do in\u00edcio da miss\u00e3o no pa\u00eds de destino.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>O destacamento: <\/b>gest\u00e3o da documenta\u00e7\u00e3o obrigat\u00f3ria relativa a cada trabalhador durante o destacamento.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>O p\u00f3s-destacamento: <\/b>arquivo dos dados e fiscaliza\u00e7\u00f5es dos trabalhadores destacados em Fran\u00e7a.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3078520 elementor-widget elementor-widget-image\" data-id=\"3078520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"234\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/03\/logo-couleur.png\" class=\"attachment-large size-large wp-image-27047\" alt=\"\" srcset=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/03\/logo-couleur.png 983w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/03\/logo-couleur-300x121.png 300w, https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/03\/logo-couleur-768x310.png 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6619ec elementor-widget elementor-widget-text-editor\" data-id=\"d6619ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element bloc_txt\">\n<div class=\"wpb_wrapper\">Com a plataforma \u00ab So Poting Worker\u201d consegue gerir todos os dados \u201cpasso a passo\u201d sem esquecimentos, com um painel de controlo de alertas, em fun\u00e7\u00e3o do tipo de destacamento de pessoal, quer seja tempor\u00e1rio ou do mesmo grupo, e da qualidade da categoria dos trabalhadores.<br \/>\nAinda mais simples, com o \u201cservi\u00e7o conforto\u201d fornece os elementos e a ASD ocupa-se do resto.<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7903ecb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7903ecb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19307703\" data-id=\"19307703\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66509d1b elementor-widget elementor-widget-html\" data-id=\"66509d1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37a13498 elementor-widget elementor-widget-html\" data-id=\"37a13498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-776ea681 elementor-widget elementor-widget-heading\" data-id=\"776ea681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">INFORMA\u00c7\u00d5ES T\u00c9CNICAS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b87b1b9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7b87b1b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Designa\u00e7\u00e3o de um representante legal em Fran\u00e7a: Obrigat\u00f3rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Declara\u00e7\u00e3o SIPSI: obrigat\u00f3ria por trabalhador e por destacamento;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">V\u00e1rios tipos de destacamento e de SIPSI em fun\u00e7\u00e3o do setor de atividade;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No setor da constru\u00e7\u00e3o civil, um cart\u00e3o BTP para cada trabalhador e por obra \u00e9 obrigat\u00f3rio;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Uma gest\u00e3o de documenta\u00e7\u00e3o antes, durante e depois da miss\u00e3o.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14492a0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"14492a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.soposting-worker.com\/#\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quais s\u00e3o minhas obriga\u00e7\u00f5es?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-614a5cc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"614a5cc0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d1844b2\" data-id=\"5d1844b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1715ef9d elementor-widget elementor-widget-html\" data-id=\"1715ef9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28495701 elementor-widget elementor-widget-heading\" data-id=\"28495701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vantagens e porqu\u00ea passar pela ASD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3f728 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8d3f728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Uma equipa de especialistas ao seu dispor;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ferramentas espec\u00edficas que permitem o controle de fluxos de documentos, gest\u00e3o de dados eletr\u00f3nicos, avisos dos prazos;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">N\u00e3o corra riscos, confie os seus destacamentos aos nossos especialistas e concentre-se na sua atividade.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f3cdfb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f3cdfb3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c5322d8\" data-id=\"6c5322d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d78ddd elementor-widget elementor-widget-html\" data-id=\"8d78ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6757eac0 elementor-widget elementor-widget-html\" data-id=\"6757eac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b620ef elementor-widget elementor-widget-heading\" data-id=\"13b620ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Os servi\u00e7os anexos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1621719c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1621719c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12365af2\" data-id=\"12365af2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-046bc7d elementor-widget elementor-widget-heading\" data-id=\"046bc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">01<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3413da elementor-widget elementor-widget-heading\" data-id=\"f3413da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"\/pt-pt\/nossos-servicos\/social\/representacao-social\/representacao-social\/\">Representa\u00e7\u00e3o Social<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-728b61fb\" data-id=\"728b61fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82d4db6 elementor-widget elementor-widget-heading\" data-id=\"82d4db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">02<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b749a94 elementor-widget elementor-widget-heading\" data-id=\"1b749a94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"\/pt-pt\/nossos-servicos\/fiscal\/mandatario-fiscal\/porque-designar-um-mandatario-fiscal\/\">Mandat\u00e1rio fiscal<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-440346\" data-id=\"440346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38c93ae2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38c93ae2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e966862\" data-id=\"5e966862\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-884611a elementor-widget elementor-widget-html\" data-id=\"884611a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298605e0 elementor-widget elementor-widget-html\" data-id=\"298605e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380f5bc7 elementor-widget elementor-widget-heading\" data-id=\"380f5bc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Entre em contato com nossos especialistas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19301fdf elementor-widget elementor-widget-heading\" data-id=\"19301fdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Gostaria de saber mais sobre nossas ofertas?<br \/>Entre em contato conosco e nossos especialistas responder\u00e3o o mais breve poss\u00edvel.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b1a007 elementor-widget elementor-widget-shortcode\" data-id=\"56b1a007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_18_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form3\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Mini contact<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"18\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_18\" id=\"frm_hide_fields_18\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form3\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_18\" name=\"frm_submit_entry_18\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/service\/43119\" \/><div id=\"frm_field_281_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_i41ef\" class=\"frm_primary_label\">Empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef\" name=\"item_meta[281]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_280_container\" class=\"frm_form_field form-field  frm_top_container frm_half relative frm_other_container\">\r\n    <label for=\"field_85w6d\" class=\"frm_primary_label\">Setor de atividade\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[280]\" id=\"field_85w6d\"  data-placeholder=\"Qual \u00e9 o seu setor de atividade?\"  placeholder=\"Qual \u00e9 o seu setor de atividade?\" data-invmsg=\"Setor de atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Qual \u00e9 o seu setor de atividade?<\/option><option  value=\"Agroalimentaire\">Alimentar<\/option><option  value=\"Bois \/ Papier \/ Carton \/ Imprimerie\">Madeira \/ Papel \/ Cart\u00e3o \/ Impress\u00e3o<\/option><option  value=\"Chimie \/ Parachimie\">Chimie \/ Parachimie<\/option><option  value=\"Editions \/ Communication \/ Multim\u00e9dia\">Edi\u00e7\u00e3o \/ Comunica\u00e7\u00e3o \/ Multim\u00eddia<\/option><option  value=\"Etudes et conseils\">Etudes et conseils<\/option><option  value=\"Informatique \/ T\u00e9l\u00e9coms\">Tecnologias de Informa\u00e7\u00e3o\/Telecomunica\u00e7\u00f5es;<\/option><option  value=\"M\u00e9tallurgie \/ Travail du m\u00e9tal\">Metalurgia<\/option><option  value=\"Service aux entreprises\">Servi\u00e7o de neg\u00f3cios<\/option><option  value=\"Transports \/ Logistique\">Transporte \/ Log\u00edstica<\/option><option  value=\"Banque \/ Assurance\">Banco \/ Seguros<\/option><option  value=\"BTP \/ Mat\u00e9riaux de construction\">Constru\u00e7\u00e3o \/ Materiais de Constru\u00e7\u00e3o<\/option><option  value=\"Commerce \/ N\u00e9goce \/ Distribution\">Com\u00e9rcio \/ Distribui\u00e7\u00e3o<\/option><option  value=\"Electronique \/ Electricit\u00e9\">Eletr\u00f4nica \/ Eletricidade<\/option><option  value=\"Industrie pharmaceutique\">Ind\u00fastria farmac\u00eautica<\/option><option  value=\"Machine et \u00e9quipements \/ Automobile\">M\u00e1quina e Equipamentos \/ Automotivo<\/option><option  value=\"Plastique \/ Caoutchouc\">Pl\u00e1stico \/ Borracha<\/option><option  value=\"Textile \/ Habillement \/ Chaussure\">T\u00eaxtil \/ Vestu\u00e1rio<\/option><option  value=\"Outro setor\" class=\"frm_other_trigger\">Outro setor<\/option>\t<\/select>\n\t<label for=\"field_85w6d-otext\" class=\"frm_screen_reader frm_hidden\">Setor de atividade<\/label><input type=\"text\" id=\"field_85w6d-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][280]\" value=\"\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_246_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy4\" class=\"frm_primary_label\">Apelido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy4\" name=\"item_meta[246]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_247_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_ocfup14\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup14\" name=\"item_meta[247]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pr\u00e9nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_270_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc\" name=\"item_meta[270]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_279_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa2\" class=\"frm_primary_label\">Telefone\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa2\" name=\"item_meta[279]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"T\u00e9l\u00e9phone est non valide\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_276_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half relative\">\r\n    <label for=\"field_okuhn\" class=\"frm_primary_label\"> Pa\u00eds de estabelecimento da sua empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[276]\" id=\"field_okuhn\"  data-placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\"  placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\" Pa\u00eds de estabelecimento da sua empresa is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde est\u00e1 estabelecida a sua empresa?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"Afrique du Sud\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanz\u00e2nia<\/option><option  value=\"TD\">Chade<\/option><option  value=\"Tha\u00eflande\">Tail\u00e2ndia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinity e Tobago<\/option><option  value=\"Tunisie\">Tun\u00edsia<\/option><option  value=\"Turquie\">Turquia<\/option><option  value=\"Turkm\u00e9nistan\">Turquemenist\u00e3o<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucr\u00e2nia<\/option><option  value=\"Uruguay\">Uruguai<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietn\u00e3<\/option><option  value=\"Y\u00e9men\">I\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_278_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half relative\">\r\n    <label for=\"field_l1biv\" class=\"frm_primary_label\">Pa\u00eds onde deseja desenvolver atividade\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[278]\" id=\"field_l1biv\"  data-placeholder=\"Onde deseja expandir-se?\"  placeholder=\"Onde deseja expandir-se?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pa\u00eds onde deseja desenvolver atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde deseja expandir-se?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"ZAF\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanzanie<\/option><option  value=\"TD\">Tchad<\/option><option  value=\"Tha\u00eflande\">Tha\u00eflande<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinit\u00e9 et Tobago<\/option><option  value=\"Tunisie\">Tunisie<\/option><option  value=\"Turquie\">Turquie<\/option><option  value=\"Turkm\u00e9nistan\">Turkm\u00e9nistan<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ukraine<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">V\u00e9n\u00e9zu\u00e9la<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Y\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_271_container\" class=\"frm_form_field form-field  frm_top_container frm_half frm_first\">\r\n    <label for=\"field_wtev7\" class=\"frm_primary_label\">\u00c1rea de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[271]\" id=\"field_wtev7\"  data-placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\"  placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\" data-invmsg=\"\u00c1rea de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha uma \u00e1rea de servi\u00e7o<\/option><option  value=\"Fiscal\">Fiscal<\/option><option  value=\"Douane\">Quest\u00f5es Aduaneiras<\/option><option  value=\"Social\">Regulamenta\u00e7\u00e3o social<\/option><option  value=\"Strat\u00e9gie d&#039;entreprise\">Estrat\u00e9gia empresarial<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_272_container\" class=\"frm_form_field form-field  frm_top_container frm_half\">\r\n    <label for=\"field_rltwo\" class=\"frm_primary_label\">Tipo de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[272]\" id=\"field_rltwo\"  data-placeholder=\"Escolha um tipo de servi\u00e7o\"  placeholder=\"Escolha um tipo de servi\u00e7o\" data-invmsg=\"Tipo de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha um tipo de servi\u00e7o<\/option><option  value=\"Repr\u00e9sentation fiscale\">representante fiscal<\/option><option  value=\"Mandataire fiscal\">Consultor Fiscal<\/option><option  value=\"Remboursement de TVA\">Reembolso de IVA<\/option><option  value=\"Vente \u00e0 distance \/ e-commerce\">Vendas \u00e0 Dist\u00e2ncia \/ E-commerce<\/option><option  value=\"Formation TVA intracommunautaire\">Forma\u00e7\u00e3o IVA Intracomunit\u00e1rio<\/option><option  value=\"Audit fiscal TVA\">Auditoria Fiscal IVA<\/option><option  value=\"Cr\u00e9ation d&#039;entreprise\">Cria\u00e7\u00e3o de empresa <\/option><option  value=\"Domiciliation\">Domicilia\u00e7\u00e3o<\/option><option  value=\"Droits d&#039;accises\">Imposto especial sobre a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"DEB \/ Intrastat\">Instrastat \/ Declara\u00e7\u00e3o de Troca de Bens<\/option><option  value=\"D\u00e9claration europ\u00e9enne de services\">Declara\u00e7\u00e3o Europeia de Servi\u00e7os<\/option><option  value=\"Formation DEB\">Forma\u00e7\u00e3o DEB \/ DES \/ INTRASTAT<\/option><option  value=\"D\u00e9claration taxe TGAP\">Taxa geral sobre as Actividades Poluentes (TGAP) <\/option><option  value=\"Accompagnement op\u00e9rations douani\u00e8res\">Obriga\u00e7\u00f5es Aduaneiras<\/option><option  value=\"Remboursement taxe TICPE (ex TIPP)\">TICPE ( taxa interior de consumo sobre os produtos energ\u00e9ticos\/combust\u00edveis) <\/option><option  value=\"D\u00e9tachement de travailleurs \u00e9trangers\">Destacamento de Trabalhadores<\/option><option  value=\"Repr\u00e9sentation de firme \u00e9trang\u00e8re\">Repr\u00e9sentation de firme \u00e9trang\u00e8re<\/option><option  value=\"Le pr\u00e9l\u00e8vement \u00e0 la source en France pour les entreprises \u00e9trang\u00e8res\">Reten\u00e7\u00e3o na fonte em fran\u00e7a<\/option><option  value=\"Repr\u00e9sentation\/Conformit\u00e9 RGPD\">Repr\u00e9sentation\/Conformit\u00e9 RGPD<\/option><option  value=\"Contr\u00f4les SIVEP\/SPS\">Contr\u00f4les SIVEP\/SPS<\/option><option  value=\"Formulaires W-8 et W-9 aux \u00c9tats-Unis\">Formul\u00e1rios W-8 e W-9 nos Estados Unidos<\/option><option  value=\"&quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Imposto sobre Vendas e Uso nos Estados Unidos<\/option><option  value=\"Certification employeur non-r\u00e9sident au Canada\">Certifica\u00e7\u00e3o de empregador n\u00e3o residente no Canad\u00e1<\/option><option  value=\"Dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents au Canada\">Isen\u00e7\u00e3o de reten\u00e7\u00e3o de impostos para empregadores n\u00e3o residentes no Canad\u00e1<\/option><option  value=\"Taxes TPS\/TVH\/TVP au Canada\">Taxes TPS\/TVH\/TVP au Canada<\/option><option  value=\"Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne\">Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne<\/option><option  value=\"Autre service\">Outro servi\u00e7o<\/option><option  value=\"Je ne suis pas s\u00fbr (e)\">N\u00e3o tenho a certeza<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_275_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_bz8k1\" class=\"frm_primary_label\">Descreva as suas necessidades\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[275]\" id=\"field_bz8k1\" rows=\"5\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"D\u00e9crivez votre besoin est non valide\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_476_container\" class=\"frm_form_field  frm_html_container form-field\">Este site \u00e9 protegido pelo Google reCAPTCHA. Aplicam-se a <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">Pol\u00edtica de Privacidade<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">Termos de Servi\u00e7o<\/a>.<\/div>\n<div id=\"frm_field_299_container\" class=\"frm_form_field form-field  frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_299-0\">\t\t\t<label  for=\"field_e2sgs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[299][]\" id=\"field_e2sgs-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter is invalid\"   \/> Quero subscrever a newsletter de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_300_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_300-0\">\t\t\t<label  for=\"field_y30e2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[300][]\" id=\"field_y30e2-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"RGPD cannot be blank.\" data-invmsg=\"RGPD is invalid\"   aria-required=\"true\"  \/> Ao enviar este formul\u00e1rio, voc\u00ea aceita que as informa\u00e7\u00f5es inseridas sejam usadas no contexto da rela\u00e7\u00e3o comercial que pode resultar. Para conhecer e exercer os seus direitos, inclu\u00edndo a retirada de seu consentimento para o uso dos dadaos coletados por este formul\u00e1rio consulte nossa <a href=\"\/en\/legal-notice\/\">Informa\u00e7\u00e3o legal<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_404_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\"><\/div>\n<div id=\"frm_field_509_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[519]\" id=\"field_8qg9b\" value=\"\"     \/>\n\t\t<div id=\"frm_field_573_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Enviar<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_nebry\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_nebry\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg\/MvraogtqM4CFO7oEhCFuYRf47cWeREW\/Dr8\/hOmUqx\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt;&nbsp;SERVI\u00c7OS SOCIAL &gt; DESTACAMENTO DE TRABALHADORES Destacamento de trabalhadores Precisa de ajuda? O que \u00e9 o destacamento O destacamento transnacional de trabalhadores consiste,&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"pays":[1073],"activites":[1091],"type_service":[1415],"class_list":["post-43119","service","type-service","status-publish","format-standard","hentry","pays-france-pt","activites-social-pt","type_service-destacamento-de-trabalhadores-estrangeiros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destacamento de trabalhadores em Fran\u00e7a | ASD Group<\/title>\n<meta name=\"description\" content=\"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destacamento de trabalhadores em Fran\u00e7a | ASD Group\" \/>\n<meta property=\"og:description\" content=\"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-26T12:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/\",\"name\":\"Destacamento de trabalhadores em Fran\u00e7a | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_283233230.jpg\",\"datePublished\":\"2019-06-12T15:11:01+00:00\",\"dateModified\":\"2020-03-26T12:54:27+00:00\",\"description\":\"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_283233230.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_283233230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/destacamento-de-trabalhadores-em-franca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destacamento de trabalhadores em Fran\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destacamento de trabalhadores em Fran\u00e7a | ASD Group","description":"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/","og_locale":"pt_PT","og_type":"article","og_title":"Destacamento de trabalhadores em Fran\u00e7a | ASD Group","og_description":"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/","og_site_name":"ASD","article_modified_time":"2020-03-26T12:54:27+00:00","og_image":[{"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/","url":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/","name":"Destacamento de trabalhadores em Fran\u00e7a | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg","datePublished":"2019-06-12T15:11:01+00:00","dateModified":"2020-03-26T12:54:27+00:00","description":"Como destacar trabalhadores em Fran\u00e7a? Ao utilizar a plataforma \u201cSo Posting Worker\u201d, poder\u00e1 gerir e acompanhar todas as suas obriga\u00e7\u00f5es.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_283233230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/destacamento-de-trabalhadores-em-franca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Destacamento de trabalhadores em Fran\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/43119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":0,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/43119\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=43119"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pays?post=43119"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/activites?post=43119"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/type_service?post=43119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}