{"id":74014,"date":"2020-03-30T10:11:54","date_gmt":"2020-03-30T08:11:54","guid":{"rendered":"https:\/\/devvitrine.asd-int.com\/service\/reforma-do-iva-aplicada-ao-e-commerce-e-as-vendas-a-distancia-para-2021\/"},"modified":"2020-11-26T13:23:13","modified_gmt":"2020-11-26T12:23:13","slug":"reforma-do-iva-aplicada-ao-e-commerce-e-as-vendas-a-distancia-para-2021","status":"publish","type":"service","link":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/","title":{"rendered":"Reforma do IVA aplicada ao E-Commerce e \u00e0s Vendas \u00e0 Dist\u00e2ncia para 2021"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"74014\" class=\"elementor elementor-74014 elementor-73948\" data-elementor-post-type=\"service\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c5c130e elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c5c130e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-611386d0\" data-id=\"611386d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4727d4e0\" data-id=\"4727d4e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8342e50 elementor-widget elementor-widget-text-editor\" data-id=\"8342e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"\/\">ASD GROUP<\/a> &gt; <a href=\"\/pt-pt\/contacto\/\">FISCALIDADE<\/a> &gt; REFORMA DO IVA APLICADA AO E-COMMERCE E \u00c0S VENDAS \u00c0 DIST\u00c2NCIA PARA 2021<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c90e6e elementor-widget elementor-widget-heading\" data-id=\"57c90e6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Reforma do IVA aplicada ao E-Commerce e \u00e0s Vendas \u00e0 Dist\u00e2ncia para 2021<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e130fa5 elementor-widget elementor-widget-button\" data-id=\"4e130fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/pt-pt\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Precisa de ajuda?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-736f4608 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"736f4608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d3a1633 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d3a1633\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36285c00\" data-id=\"36285c00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d88357 elementor-widget elementor-widget-html\" data-id=\"65d88357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9293f1c elementor-widget elementor-widget-html\" data-id=\"9293f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-134c4bf0 elementor-widget elementor-widget-image\" data-id=\"134c4bf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg\" title=\"shutterstock_393401239\" alt=\"shutterstock_393401239\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c670285 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c670285\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-403e2c78\" data-id=\"403e2c78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f7e842 elementor-widget elementor-widget-text-editor\" data-id=\"70f7e842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partir de 1 de julho de 2021, as regras para o <a href=\"https:\/\/www.asd-int.com\/pt-pt\/nossos-servicos\/fiscal\/vendas-a-distancia-online_e-commerce\/vendas-a-distancia-limiares-iva\/\">IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia<\/a> e mais geralmente ao E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. <strong>Adotado pelo Conselho Europeu <\/strong>em dezembro de 2017, o <strong>modelo do IVA sobre o E-commerce<\/strong> tem um triplo objetivo:<\/p>\n<ul>\n<li><strong>Simplificar as formalidades em mat\u00e9ria de IVA <\/strong>que pesam sobre as empresas;<\/li>\n<li>Melhor combater as fraudes;<\/li>\n<li><strong>Garantir uma concorr\u00eancia justa <\/strong>entre as empresas europeias e n\u00e3o europeias.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6480763b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6480763b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d498430\" data-id=\"1d498430\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e93f56 elementor-widget elementor-widget-html\" data-id=\"56e93f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd1fb87 elementor-widget elementor-widget-heading\" data-id=\"4fd1fb87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A quem se destina esta reforma do IVA aplicada \u00e0s vendas \u00e0 dist\u00e2ncia e ao E-commerce?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a53db78 elementor-widget elementor-widget-text-editor\" data-id=\"a53db78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A todas as empresas da <strong>UE e fora da UE <\/strong>que vendem mercadorias e servi\u00e7os <em>on-line <\/em>a particulares europeus abrangidos pela reforma, independentemente do canal de venda:<\/p>\n<ul>\n<li><strong>Sites WEB exclusivos;<\/strong><\/li>\n<li><strong>Market-Places<\/strong> (Amazon, Ebay, AliExpress, Fnac, Darty, CDiscount, etc\u2026) ;<\/li>\n<li><strong>Redes Sociais<\/strong> (Facebook, Instagram, Snapchat, Twitter, etc\u2026).<\/li>\n<\/ul>\n<p>Os agentes do <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Drop_shipping\"><strong>Dropshipping<\/strong><\/a>, que at\u00e9 ent\u00e3o estavam pouco abrangidos, ser\u00e3o de um modo geral particularmente afetados por esta reforma.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74ed2d39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74ed2d39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b56732c\" data-id=\"b56732c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7152900c elementor-widget elementor-widget-html\" data-id=\"7152900c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29f0c842 elementor-widget elementor-widget-html\" data-id=\"29f0c842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66036d80 elementor-widget elementor-widget-heading\" data-id=\"66036d80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais os impactos desta reforma das regras do IVA no E-commerce B2C?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-133fdf74 elementor-widget elementor-widget-text-editor\" data-id=\"133fdf74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"Corps\" style=\"text-align: justify; text-justify: inter-ideograph;\"><strong>A reforma prev\u00ea a introdu\u00e7\u00e3o de 3 regimes particulares <u>facultativos <\/u><\/strong><strong>(OSS-UE, OSS-HUE e iOSS) que permitir\u00e3o \u00e0s empresas centralizar todas as formalidades declarativas num s\u00f3 pa\u00eds da UE, atrav\u00e9s de um novo n\u00famero de IVA espec\u00edfico para cada OSS.<\/strong><\/p>\n<p><em>Aten\u00e7\u00e3o: as condi\u00e7\u00f5es de acesso aos OSS s\u00e3o estritamente enquadradas e pr\u00f3prias a cada regime. Em muitos casos,\u00a0 uma declara\u00e7\u00e3o de IVA cl\u00e1ssica n\u00e3o ser\u00e1 poss\u00edvel. Por conseguinte, uma empesa poder\u00e1 ter de entregar mais do que uma declara\u00e7\u00e3o de IVA num pa\u00eds, e isto atrav\u00e9s de v\u00e1rios n\u00fameros de IVA para um mesmo pa\u00eds.<\/em><\/p>\n<p class=\"Corps\" style=\"text-align: justify; text-justify: inter-ideograph;\">Al\u00e9m disso, com a aboli\u00e7\u00e3o da isen\u00e7\u00e3o da declara\u00e7\u00e3o aduaneira na importa\u00e7\u00e3o para a UE de remessas de valor inferior a 22 euros, <strong>os operadores de Dropshipping devem desde j\u00e1, rever os seus padr\u00f5es de abastecimento fora da UE.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b471b38 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1b471b38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/zh-hans\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTE OS NOSSOS ESPECIALISTAS PARA UMA AUDITORIA DO IVA ECOMMERCE\/VAD B2C 2021<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f08dbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f08dbe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20b9645\" data-id=\"20b9645\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-135a743 elementor-widget elementor-widget-html\" data-id=\"135a743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdcbf7f elementor-widget elementor-widget-heading\" data-id=\"cdcbf7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conv\u00e9m estar prevenido antes da entada em vigor da reforma do IVA Vendas \u00e0 Dist\u00e2ncia\/E-Commerce<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24fa4ff elementor-widget elementor-widget-text-editor\" data-id=\"24fa4ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As novas regras entrar\u00e3o em vigor a partir de 1 de julho de 2021 em todos os Estados Membros da EU.<\/p>\n<p><strong>Faltam apenas alguns meses para que os vendedores determinem onde e como ir\u00e3o declarar cada tipo de venda.<\/strong><\/p>\n<p>Na verdade, \u00e9 preciso que a partir de agora se distingam as vendas em fun\u00e7\u00e3o de:<\/p>\n<ul>\n<li>do valor das mercadorias;<\/li>\n<li>da proveni\u00eancia ( da UE ou fora da EU);<\/li>\n<li>do canal de venda utilizado( Websites, MArket Places, Redes Sociais\u2026);<\/li>\n<li>da utiliza\u00e7\u00e3o ou n\u00e3o de uma linha de stock;<\/li>\n<li>e da pessoa encarregue do transporte.<\/li>\n<\/ul>\n<p>Gra\u00e7as ao seu servi\u00e7o exclusivo \u201cAUDITORIA DO IVA E-COMMERCE 2021\u201d <strong>a ASD Group ajuda-o a determinar quais as suas obriga\u00e7\u00f5es em mat\u00e9ria de IVA a partir de 1 de julho de 2021<\/strong>.<\/p>\n<p>Para al\u00e9m disso, para poder beneficiar dos regimes particulares a partir de 1 de julho de 2021, \u00e9 necess\u00e1rio que se obtenham previamente os n\u00fameros de IVA espec\u00edficos dos OSS.<\/p>\n<p><strong>A ASD Group encarrega-se por si de todas as etapas para obter os n\u00fameros espec\u00edficos dos OSS.<\/strong><\/p>\n<p>Como tal, ser\u00e1 igualmente necess\u00e1rio adaptar tamb\u00e9m as suas ferramentas inform\u00e1ticas, para que possam atender aos novos procedimentos para entrega de declara\u00e7\u00f5es via OSS.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e61ab21 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e61ab21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/zh-hans\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ANTICIPE AS MUDAN\u00c7AS COM A ASD GROUP<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc6e7a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc6e7a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68da72f\" data-id=\"68da72f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e4a7c7 elementor-widget elementor-widget-html\" data-id=\"8e4a7c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c532bd elementor-widget elementor-widget-html\" data-id=\"0c532bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2da60a elementor-widget elementor-widget-heading\" data-id=\"d2da60a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O desalfandegamento de mercadorias a importar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c7892 elementor-widget elementor-widget-text-editor\" data-id=\"49c7892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"Corps\" style=\"text-align: justify; text-justify: inter-ideograph;\">A partir de 1 de julho de 2021, <strong>todas as mercadorias SEM EXCE\u00c7\u00c3O dever\u00e3o a partir desse momento fazer acompanhar-se de uma declara\u00e7\u00e3o da alf\u00e2ndega <\/strong>aquando da importa\u00e7\u00e3o na Uni\u00e3o Europeia<\/p>\n<p><em><strong>Os bens de valor inferior a 150 euros poder\u00e3o, no entanto, beneficiar de isen\u00e7\u00e3o do IVA sobre as importa\u00e7\u00f5es, <\/strong><\/em><em>sob condi\u00e7\u00e3o de que as vendas sejam declaradas via iOSS e que o n\u00famero de IVA iOSS do vendedor esteja mencionado na declara\u00e7\u00e3o da importa\u00e7\u00e3o.<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e54ecaf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e54ecaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.asd-int.com\/zh-hans\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRECISA DE AJUDA? CONTACTE OS NOSSOS ESPECIALISTAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b192921 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b192921\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddb7457\" data-id=\"ddb7457\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6737621 elementor-widget elementor-widget-html\" data-id=\"6737621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e25fc4b elementor-widget elementor-widget-heading\" data-id=\"e25fc4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O que pode a ASD fazer antes da entrada em vigor desta reforma do IVA em 2021?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ddb2bb elementor-widget elementor-widget-text-editor\" data-id=\"5ddb2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Acompanh\u00e1-lo durante toda a mudan\u00e7a para as novas regras\u00a0:<\/p>\n<ul>\n<li>Ao fornecer-lhe <strong>informa\u00e7\u00f5es fi\u00e1veis, atualizadas e em primeira m\u00e3o<\/strong>, gra\u00e7as \u00e0 an\u00e1lise aprofundada desta <strong>nova regulamenta\u00e7\u00e3o do Imposto sobre o Valor Acrescentado<\/strong> pelos nossos fiscalistas.<\/li>\n<li>Ao definir quais ser\u00e3o as novas obriga\u00e7\u00f5es em mat\u00e9ria de IVA a contar desde o dia 1 de julho de 2021, gra\u00e7as ao nosso servi\u00e7o especializado <strong>\u201cAUDITORIA TVA E-COMMERCE 2021\u201d.<\/strong><\/li>\n<li>Ao encarregar-se por si de todas as <strong>etapas necess\u00e1rias para utiliza\u00e7\u00e3o das OSS.<\/strong><\/li>\n<li>Ao proporcionar-lhe <strong>ferramentas inform\u00e1ticas<\/strong> para facilitar a gest\u00e3o das suas opera\u00e7\u00f5es.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-769a18e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"769a18e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-729e77b9\" data-id=\"729e77b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75ce3291 elementor-widget elementor-widget-html\" data-id=\"75ce3291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a04f97a elementor-widget elementor-widget-html\" data-id=\"4a04f97a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pre-fil-bas\">\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c427d5c elementor-widget elementor-widget-heading\" data-id=\"c427d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Entre em contato com nossos especialistas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-376de378 elementor-widget elementor-widget-heading\" data-id=\"376de378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Gostaria de saber mais sobre nossas ofertas?<br \/>Entre em contato conosco e nossos especialistas responder\u00e3o o mais breve poss\u00edvel.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe0fdc7 elementor-widget elementor-widget-shortcode\" data-id=\"7fe0fdc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><link rel='stylesheet' id='formidable-css' href='https:\/\/www.asd-int.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=4291231' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_center_submit frm_style_asd\" id=\"frm_form_18_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contact-form3\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Mini contact<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"18\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_18\" id=\"frm_hide_fields_18\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form3\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_18\" name=\"frm_submit_entry_18\" value=\"ea26797d17\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/service\/74014\" \/><div id=\"frm_field_281_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_i41ef\" class=\"frm_primary_label\">Empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_i41ef\" name=\"item_meta[281]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_280_container\" class=\"frm_form_field form-field  frm_top_container frm_half relative frm_other_container\">\r\n    <label for=\"field_85w6d\" class=\"frm_primary_label\">Setor de atividade\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[280]\" id=\"field_85w6d\"  data-placeholder=\"Qual \u00e9 o seu setor de atividade?\"  placeholder=\"Qual \u00e9 o seu setor de atividade?\" data-invmsg=\"Setor de atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Qual \u00e9 o seu setor de atividade?<\/option><option  value=\"Agroalimentaire\">Alimentar<\/option><option  value=\"Bois \/ Papier \/ Carton \/ Imprimerie\">Madeira \/ Papel \/ Cart\u00e3o \/ Impress\u00e3o<\/option><option  value=\"Chimie \/ Parachimie\">Chimie \/ Parachimie<\/option><option  value=\"Editions \/ Communication \/ Multim\u00e9dia\">Edi\u00e7\u00e3o \/ Comunica\u00e7\u00e3o \/ Multim\u00eddia<\/option><option  value=\"Etudes et conseils\">Etudes et conseils<\/option><option  value=\"Informatique \/ T\u00e9l\u00e9coms\">Tecnologias de Informa\u00e7\u00e3o\/Telecomunica\u00e7\u00f5es;<\/option><option  value=\"M\u00e9tallurgie \/ Travail du m\u00e9tal\">Metalurgia<\/option><option  value=\"Service aux entreprises\">Servi\u00e7o de neg\u00f3cios<\/option><option  value=\"Transports \/ Logistique\">Transporte \/ Log\u00edstica<\/option><option  value=\"Banque \/ Assurance\">Banco \/ Seguros<\/option><option  value=\"BTP \/ Mat\u00e9riaux de construction\">Constru\u00e7\u00e3o \/ Materiais de Constru\u00e7\u00e3o<\/option><option  value=\"Commerce \/ N\u00e9goce \/ Distribution\">Com\u00e9rcio \/ Distribui\u00e7\u00e3o<\/option><option  value=\"Electronique \/ Electricit\u00e9\">Eletr\u00f4nica \/ Eletricidade<\/option><option  value=\"Industrie pharmaceutique\">Ind\u00fastria farmac\u00eautica<\/option><option  value=\"Machine et \u00e9quipements \/ Automobile\">M\u00e1quina e Equipamentos \/ Automotivo<\/option><option  value=\"Plastique \/ Caoutchouc\">Pl\u00e1stico \/ Borracha<\/option><option  value=\"Textile \/ Habillement \/ Chaussure\">T\u00eaxtil \/ Vestu\u00e1rio<\/option><option  value=\"Outro setor\" class=\"frm_other_trigger\">Outro setor<\/option>\t<\/select>\n\t<label for=\"field_85w6d-otext\" class=\"frm_screen_reader frm_hidden\">Setor de atividade<\/label><input type=\"text\" id=\"field_85w6d-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][280]\" value=\"\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_246_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy4\" class=\"frm_primary_label\">Apelido\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_qh4icy4\" name=\"item_meta[246]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_247_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_ocfup14\" class=\"frm_primary_label\">Nome\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_ocfup14\" name=\"item_meta[247]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pr\u00e9nom is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_270_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half frm_first\">\r\n    <label for=\"field_zv6jc\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_zv6jc\" name=\"item_meta[270]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"texte est non valide\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_279_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half\">\r\n    <label for=\"field_n5xa2\" class=\"frm_primary_label\">Telefone\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_n5xa2\" name=\"item_meta[279]\" value=\"\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"T\u00e9l\u00e9phone est non valide\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_276_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half relative\">\r\n    <label for=\"field_okuhn\" class=\"frm_primary_label\"> Pa\u00eds de estabelecimento da sua empresa\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[276]\" id=\"field_okuhn\"  data-placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\"  placeholder=\"Onde est\u00e1 estabelecida a sua empresa?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\" Pa\u00eds de estabelecimento da sua empresa is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde est\u00e1 estabelecida a sua empresa?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"Afrique du Sud\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanz\u00e2nia<\/option><option  value=\"TD\">Chade<\/option><option  value=\"Tha\u00eflande\">Tail\u00e2ndia<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinity e Tobago<\/option><option  value=\"Tunisie\">Tun\u00edsia<\/option><option  value=\"Turquie\">Turquia<\/option><option  value=\"Turkm\u00e9nistan\">Turquemenist\u00e3o<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ucr\u00e2nia<\/option><option  value=\"Uruguay\">Uruguai<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">Venezuela<\/option><option  value=\"Vietnam\">Vietn\u00e3<\/option><option  value=\"Y\u00e9men\">I\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_278_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_half relative\">\r\n    <label for=\"field_l1biv\" class=\"frm_primary_label\">Pa\u00eds onde deseja desenvolver atividade\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[278]\" id=\"field_l1biv\"  data-placeholder=\"Onde deseja expandir-se?\"  placeholder=\"Onde deseja expandir-se?\" data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"Pa\u00eds onde deseja desenvolver atividade is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Onde deseja expandir-se?<\/option><option  value=\"AF\">Afghanistan<\/option><option  value=\"ZAF\">Afrique du Sud<\/option><option  value=\"AL\">Albanie<\/option><option  value=\"DZ\">Alg\u00e9rie<\/option><option  value=\"DE\">Allemagne<\/option><option  value=\"AD\">Andorra<\/option><option  value=\"AO\">Angola<\/option><option  value=\"AI\">Anguilla<\/option><option  value=\"AG\">Ant\u00edgua-et-Barbuda<\/option><option  value=\"Arabie Saoudite\">Arabie Saoudite<\/option><option  value=\"AR\">Argentine<\/option><option  value=\"AM\">Arm\u00e9nie<\/option><option  value=\"AW\">Aruba<\/option><option  value=\"AT\">Australie<\/option><option  value=\"AZ\">Azerbaijan<\/option><option  value=\"BS\">Bahamas<\/option><option  value=\"BH\">Bahre\u00efn<\/option><option  value=\"BD\">Bengladesh<\/option><option  value=\"BB\">Barbade (la)<\/option><option  value=\"BY\">Bi\u00e9lorussie<\/option><option  value=\"BE\">Belgique<\/option><option  value=\"BZ\">Belize<\/option><option  value=\"BJ\">Benin<\/option><option  value=\"BM\">Bermude<\/option><option  value=\"BT\">Bhoutan<\/option><option  value=\"BO\">Bolivie<\/option><option  value=\"BA\">Bosnie et Herzegovie<\/option><option  value=\"BW\">Botswana<\/option><option  value=\"BR\">Br\u00e9sil<\/option><option  value=\"BN\">Brunei<\/option><option  value=\"BG\">Bulgarie<\/option><option  value=\"BF\">Burkina Faso<\/option><option  value=\"BI\">Burundi<\/option><option  value=\"KH\">Cambodge<\/option><option  value=\"CM\">Cameroun<\/option><option  value=\"CA\">Canada<\/option><option  value=\"CV\">Cap vert<\/option><option  value=\"CL\">Chile<\/option><option  value=\"CN\">Chine<\/option><option  value=\"Cit\u00e9 du Vatican\">Cit\u00e9 du Vatican<\/option><option  value=\"CO\">Colombie<\/option><option  value=\"Comores\">Comores<\/option><option  value=\"Congo\">Congo<\/option><option  value=\"Cor\u00e9e du sud\">Cor\u00e9e du sud<\/option><option  value=\"Costa Rica\">Costa Rica<\/option><option  value=\"C\u00f4te d&#039;Ivoire\">C\u00f4te d&#039;Ivoire<\/option><option  value=\"HR\">Croatie<\/option><option  value=\"Cuba\">Cuba<\/option><option  value=\"Chypre\">Chypre<\/option><option  value=\"DK\">Danemark<\/option><option  value=\"Djibouti\">Djibouti<\/option><option  value=\"Dominique\">Dominique<\/option><option  value=\"\u00c9quateur\">\u00c9quateur<\/option><option  value=\"\u00c9gypte\">\u00c9gypte<\/option><option  value=\"AE\">\u00c9mirats Arabes Unis<\/option><option  value=\"\u00c9rythr\u00e9e\">\u00c9rythr\u00e9e<\/option><option  value=\"ES\">Espagne<\/option><option  value=\"EE\">Estonie<\/option><option  value=\"US\">Estados Unidos<\/option><option  value=\"\u00c9thiopie\">\u00c9thiopie<\/option><option  value=\"Fidji\">Fidji<\/option><option  value=\"FI\">Finlande<\/option><option  value=\"FR\">France<\/option><option  value=\"Gabon\">Gabon<\/option><option  value=\"Gambie\">Gambie<\/option><option  value=\"G\u00e9orgie\">G\u00e9orgie<\/option><option  value=\"Ghana\">Ghana<\/option><option  value=\"Gibraltar\">Gibraltar<\/option><option  value=\"GR\">Gr\u00e8ce<\/option><option  value=\"Groenland\">Groenland<\/option><option  value=\"Grenade\">Grenade<\/option><option  value=\"Guam\">Guam<\/option><option  value=\"Guatemala\">Guatemala<\/option><option  value=\"Guin\u00e9e\">Guin\u00e9e<\/option><option  value=\"Guin\u00e9e Bissau\">Guin\u00e9e Bissau<\/option><option  value=\"Guin\u00e9e \u00c9quatoriale\">Guin\u00e9e \u00c9quatoriale<\/option><option  value=\"Guyane\">Guyane<\/option><option  value=\"Guyane Fran\u00e7aise\">Guyane Fran\u00e7aise<\/option><option  value=\"Haiti\">Haiti<\/option><option  value=\"Honduras\">Honduras<\/option><option  value=\"HK\">Hong Kong<\/option><option  value=\"HU\">Hongrie<\/option><option  value=\"\u00cele Maurice\">\u00cele Maurice<\/option><option  value=\"Islande\">Islande<\/option><option  value=\"Inde\">Inde<\/option><option  value=\"Indon\u00e9sie\">Indon\u00e9sie<\/option><option  value=\"Iran\">Iran<\/option><option  value=\"Iraq\">Iraq<\/option><option  value=\"IE\">Irlande<\/option><option  value=\"Isra\u00ebl\">Isra\u00ebl<\/option><option  value=\"IT\">Italie<\/option><option  value=\"Jama\u00efque\">Jama\u00efque<\/option><option  value=\"JP\">Japon<\/option><option  value=\"Jordanie\">Jordanie<\/option><option  value=\"Kazakhstan\">Kazakhstan<\/option><option  value=\"Kenya\">Kenya<\/option><option  value=\"Kiribati\">Kiribati<\/option><option  value=\"Koweit\">Koweit<\/option><option  value=\"Kirghizistan\">Kirghizistan<\/option><option  value=\"Laos\">Laos<\/option><option  value=\"LV\">Lettonie<\/option><option  value=\"Liban\">Liban<\/option><option  value=\"Lesotho\">Lesotho<\/option><option  value=\"Lib\u00e9ria\">Lib\u00e9ria<\/option><option  value=\"Libye\">Libye<\/option><option  value=\"LIE\">Liechtenstein<\/option><option  value=\"LT\">Lituanie<\/option><option  value=\"LU\">Luxembourg<\/option><option  value=\"Mac\u00e9doine\">Mac\u00e9doine<\/option><option  value=\"Madagascar\">Madagascar<\/option><option  value=\"Malawi\">Malawi<\/option><option  value=\"Malaisie\">Malaisie<\/option><option  value=\"Maldives\">Maldives<\/option><option  value=\"Mali\">Mali<\/option><option  value=\"MT\">Malte<\/option><option  value=\"Mauritanie\">Mauritanie<\/option><option  value=\"MX\">Mexique<\/option><option  value=\"Micron\u00e9sie\">Micron\u00e9sie<\/option><option  value=\"Moldavie\">Moldavie<\/option><option  value=\"MA\">Monaco<\/option><option  value=\"Mongolie\">Mongolie<\/option><option  value=\"Mont\u00e9n\u00e9gro\">Mont\u00e9n\u00e9gro<\/option><option  value=\"Montserrat\">Montserrat<\/option><option  value=\"Maroc\">Maroc<\/option><option  value=\"Mozambique\">Mozambique<\/option><option  value=\"Myanmar\">Myanmar<\/option><option  value=\"Namibie\">Namibie<\/option><option  value=\"Nauru\">Nauru<\/option><option  value=\"Nepal\">Nepal<\/option><option  value=\"Nouvelle Z\u00e9lande\">Nouvelle Z\u00e9lande<\/option><option  value=\"Nicaragua\">Nicaragua<\/option><option  value=\"Niger\">Niger<\/option><option  value=\"Nigeria\">Nigeria<\/option><option  value=\"NO\">Norv\u00e8ge<\/option><option  value=\"Oman\">Oman<\/option><option  value=\"Ouganda\">Ouganda<\/option><option  value=\"Ouzb\u00e9kistan\">Ouzb\u00e9kistan<\/option><option  value=\"Pakistan\">Pakistan<\/option><option  value=\"Palau\">Palau<\/option><option  value=\"Palestine\">Palestine<\/option><option  value=\"Panama\">Panama<\/option><option  value=\"Papouasie-Nouvelle-Guin\u00e9e\">Papua Nova Guin\u00e9<\/option><option  value=\"Paraguay\">Paraguay<\/option><option  value=\"Pays-bas\">Holanda<\/option><option  value=\"P\u00e9rou\">P\u00e9rou<\/option><option  value=\"Philippines\">Philippines<\/option><option  value=\"PL\">Pologne<\/option><option  value=\"Polyn\u00e9sie Fran\u00e7aise\">Polyn\u00e9sie Fran\u00e7aise<\/option><option  value=\"PT\">Portugal<\/option><option  value=\"Puerto Rico\">Puerto Rico<\/option><option  value=\"Qatar\">Qatar<\/option><option  value=\"CF\">R\u00e9publique centrafricaine<\/option><option  value=\"R\u00e9publique Dominicaine\">R\u00e9publique Dominicaine<\/option><option  value=\"CZ\">R\u00e9publique Tch\u00e8que<\/option><option  value=\"RO\">Roumanie<\/option><option  value=\"GB\">Reino Unido<\/option><option  value=\"RU\">Russie<\/option><option  value=\"Rwanda\">Rwanda<\/option><option  value=\"Salvador (le)\">Salvador (le)<\/option><option  value=\"Sante Lucie\">Sante Lucie<\/option><option  value=\"Samoa\">Samoa<\/option><option  value=\"San Marino\">San Marino<\/option><option  value=\"Sao Tome and Principe\">Sao Tome and Principe<\/option><option  value=\"Senegal\">Senegal<\/option><option  value=\"Serbie et Mont\u00e9n\u00e9gro\">Serbie et Mont\u00e9n\u00e9gro<\/option><option  value=\"Seychelles\">Seychelles<\/option><option  value=\"Sierra Leone\">Sierra Leone<\/option><option  value=\"Singapour\">Singapour<\/option><option  value=\"SK\">Slovaquie<\/option><option  value=\"SI\">Slov\u00e9nie<\/option><option  value=\"Somalie\">Somalie<\/option><option  value=\"Soudan du Sud\">Soudan du Sud<\/option><option  value=\"Sri Lanka\">Sri Lanka<\/option><option  value=\"Soudan\">Soudan<\/option><option  value=\"Surinam\">Surinam<\/option><option  value=\"Swaziland\">Swaziland<\/option><option  value=\"SE\">Su\u00e8de<\/option><option  value=\"CH\">Suisse<\/option><option  value=\"Syrie\">Syrie<\/option><option  value=\"Taiwan\">Taiwan<\/option><option  value=\"Tadjikistan\">Tadjikistan<\/option><option  value=\"Tanzanie\">Tanzanie<\/option><option  value=\"TD\">Tchad<\/option><option  value=\"Tha\u00eflande\">Tha\u00eflande<\/option><option  value=\"Togo\">Togo<\/option><option  value=\"Tonga\">Tonga<\/option><option  value=\"Trinit\u00e9 et Tobago\">Trinit\u00e9 et Tobago<\/option><option  value=\"Tunisie\">Tunisie<\/option><option  value=\"Turquie\">Turquie<\/option><option  value=\"Turkm\u00e9nistan\">Turkm\u00e9nistan<\/option><option  value=\"Tuvalu\">Tuvalu<\/option><option  value=\"Ukraine\">Ukraine<\/option><option  value=\"Uruguay\">Uruguay<\/option><option  value=\"Vanuatu\">Vanuatu<\/option><option  value=\"V\u00e9n\u00e9zu\u00e9la\">V\u00e9n\u00e9zu\u00e9la<\/option><option  value=\"Vietnam\">Vietnam<\/option><option  value=\"Y\u00e9men\">Y\u00e9men<\/option><option  value=\"Zambie\">Z\u00e2mbia<\/option><option  value=\"Zimbabwe\">Zimb\u00e1bue<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_271_container\" class=\"frm_form_field form-field  frm_top_container frm_half frm_first\">\r\n    <label for=\"field_wtev7\" class=\"frm_primary_label\">\u00c1rea de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[271]\" id=\"field_wtev7\"  data-placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\"  placeholder=\"Escolha uma \u00e1rea de servi\u00e7o\" data-invmsg=\"\u00c1rea de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha uma \u00e1rea de servi\u00e7o<\/option><option  value=\"Fiscal\">Fiscal<\/option><option  value=\"Douane\">Quest\u00f5es Aduaneiras<\/option><option  value=\"Social\">Regulamenta\u00e7\u00e3o social<\/option><option  value=\"Strat\u00e9gie d&#039;entreprise\">Estrat\u00e9gia empresarial<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_272_container\" class=\"frm_form_field form-field  frm_top_container frm_half\">\r\n    <label for=\"field_rltwo\" class=\"frm_primary_label\">Tipo de servi\u00e7o\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[272]\" id=\"field_rltwo\"  data-placeholder=\"Escolha um tipo de servi\u00e7o\"  placeholder=\"Escolha um tipo de servi\u00e7o\" data-invmsg=\"Tipo de servi\u00e7o is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Escolha um tipo de servi\u00e7o<\/option><option  value=\"Repr\u00e9sentation fiscale\">representante fiscal<\/option><option  value=\"Mandataire fiscal\">Consultor Fiscal<\/option><option  value=\"Remboursement de TVA\">Reembolso de IVA<\/option><option  value=\"Vente \u00e0 distance \/ e-commerce\">Vendas \u00e0 Dist\u00e2ncia \/ E-commerce<\/option><option  value=\"Formation TVA intracommunautaire\">Forma\u00e7\u00e3o IVA Intracomunit\u00e1rio<\/option><option  value=\"Audit fiscal TVA\">Auditoria Fiscal IVA<\/option><option  value=\"Cr\u00e9ation d&#039;entreprise\">Cria\u00e7\u00e3o de empresa <\/option><option  value=\"Domiciliation\">Domicilia\u00e7\u00e3o<\/option><option  value=\"Droits d&#039;accises\">Imposto especial sobre a venda \u00e0 dist\u00e2ncia de bebidas alco\u00f3licas<\/option><option  value=\"DEB \/ Intrastat\">Instrastat \/ Declara\u00e7\u00e3o de Troca de Bens<\/option><option  value=\"D\u00e9claration europ\u00e9enne de services\">Declara\u00e7\u00e3o Europeia de Servi\u00e7os<\/option><option  value=\"Formation DEB\">Forma\u00e7\u00e3o DEB \/ DES \/ INTRASTAT<\/option><option  value=\"D\u00e9claration taxe TGAP\">Taxa geral sobre as Actividades Poluentes (TGAP) <\/option><option  value=\"Accompagnement op\u00e9rations douani\u00e8res\">Obriga\u00e7\u00f5es Aduaneiras<\/option><option  value=\"Remboursement taxe TICPE (ex TIPP)\">TICPE ( taxa interior de consumo sobre os produtos energ\u00e9ticos\/combust\u00edveis) <\/option><option  value=\"D\u00e9tachement de travailleurs \u00e9trangers\">Destacamento de Trabalhadores<\/option><option  value=\"Repr\u00e9sentation de firme \u00e9trang\u00e8re\">Repr\u00e9sentation de firme \u00e9trang\u00e8re<\/option><option  value=\"Le pr\u00e9l\u00e8vement \u00e0 la source en France pour les entreprises \u00e9trang\u00e8res\">Reten\u00e7\u00e3o na fonte em fran\u00e7a<\/option><option  value=\"Repr\u00e9sentation\/Conformit\u00e9 RGPD\">Repr\u00e9sentation\/Conformit\u00e9 RGPD<\/option><option  value=\"Contr\u00f4les SIVEP\/SPS\">Contr\u00f4les SIVEP\/SPS<\/option><option  value=\"Formulaires W-8 et W-9 aux \u00c9tats-Unis\">Formul\u00e1rios W-8 e W-9 nos Estados Unidos<\/option><option  value=\"&quot;Sales and Use Tax&quot; aux \u00c9tats-Unis\">Imposto sobre Vendas e Uso nos Estados Unidos<\/option><option  value=\"Certification employeur non-r\u00e9sident au Canada\">Certifica\u00e7\u00e3o de empregador n\u00e3o residente no Canad\u00e1<\/option><option  value=\"Dispense de retenue d\u2019imp\u00f4t pour les employeurs non-r\u00e9sidents au Canada\">Isen\u00e7\u00e3o de reten\u00e7\u00e3o de impostos para empregadores n\u00e3o residentes no Canad\u00e1<\/option><option  value=\"Taxes TPS\/TVH\/TVP au Canada\">Taxes TPS\/TVH\/TVP au Canada<\/option><option  value=\"Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne\">Taxe sur les emballages plastiques non r\u00e9utilisables en Espagne<\/option><option  value=\"Autre service\">Outro servi\u00e7o<\/option><option  value=\"Je ne suis pas s\u00fbr (e)\">N\u00e3o tenho a certeza<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_275_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_bz8k1\" class=\"frm_primary_label\">Descreva as suas necessidades\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[275]\" id=\"field_bz8k1\" rows=\"5\"  data-reqmsg=\"Este campo \u00e9 obrigat\u00f3rio\" aria-required=\"true\" data-invmsg=\"D\u00e9crivez votre besoin est non valide\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_476_container\" class=\"frm_form_field  frm_html_container form-field\">Este site \u00e9 protegido pelo Google reCAPTCHA. Aplicam-se a <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"nofollow\" target=\"_blank\">Pol\u00edtica de Privacidade<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" rel=\"nofollow\" target=\"_blank\">Termos de Servi\u00e7o<\/a>.<\/div>\n<div id=\"frm_field_299_container\" class=\"frm_form_field form-field  frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">Newsletter\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_299-0\">\t\t\t<label  for=\"field_e2sgs-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[299][]\" id=\"field_e2sgs-0\" value=\"Je souhaite recevoir les newsletters d\u2019ASD Group.\"  data-invmsg=\"Newsletter is invalid\"   \/> Quero subscrever a newsletter de ASD Group<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_300_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container checkbox vertical_radio\">\r\n    <label  class=\"frm_primary_label\">RGPD\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <div class=\"frm_opt_container\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_300-0\">\t\t\t<label  for=\"field_y30e2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[300][]\" id=\"field_y30e2-0\" value=\"En soumettant ce formulaire, j&#039;accepte que les informations saisies soient exploit\u00e9es dans le cadre de la pr\u00e9sente demande et de la relation professionnelle qui pourrait en d\u00e9couler. Pour conna\u00eetre et exercer vos droits, notamment de retrait de votre consentement \u00e0 l&#039;utilisation des donn\u00e9es collect\u00e9es par ce formulaire, veuillez consulter nos mentions l\u00e9gales en bas de cette page.\"  data-reqmsg=\"RGPD cannot be blank.\" data-invmsg=\"RGPD is invalid\"   aria-required=\"true\"  \/> Ao enviar este formul\u00e1rio, voc\u00ea aceita que as informa\u00e7\u00f5es inseridas sejam usadas no contexto da rela\u00e7\u00e3o comercial que pode resultar. Para conhecer e exercer os seus direitos, inclu\u00edndo a retirada de seu consentimento para o uso dos dadaos coletados por este formul\u00e1rio consulte nossa <a href=\"\/en\/legal-notice\/\">Informa\u00e7\u00e3o legal<\/a><\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_404_container\" class=\"frm_form_field  frm_html_container form-field\"><input name=\"langue\" type=\"hidden\"><\/div>\n<div id=\"frm_field_509_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_koj6t_label\" class=\"frm_primary_label\">reCAPTCHA\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_koj6t\" class=\"frm-g-recaptcha\" data-sitekey=\"6LdlIoAjAAAAAJHXIYymZBi1cv13caAnMROCjida\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n\t\t<input  type=\"hidden\" name=\"item_meta[519]\" id=\"field_8qg9b\" value=\"\"     \/>\n\t\t<div id=\"frm_field_573_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Enviar<\/button>\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_862_container\">\n\t\t\t<label for=\"field_212jy\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_212jy\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[862]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"aruJTbM\/indlcuEVvkIvg159VTL1C2KoOy6p2U\/pNukRf47cWeREW\/Dr8\/hOmUqx\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ASD GROUP &gt; FISCALIDADE &gt; REFORMA DO IVA APLICADA AO E-COMMERCE E \u00c0S VENDAS \u00c0 DIST\u00c2NCIA PARA 2021 Reforma do IVA aplicada ao E-Commerce e&#8230;<\/p>\n","protected":false},"author":36,"featured_media":0,"menu_order":0,"template":"elementor_header_footer","format":"standard","meta":{"_eb_attr":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"pays":[],"activites":[1090],"type_service":[],"class_list":["post-74014","service","type-service","status-publish","format-standard","hentry","activites-fiscal-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reforma do IVA E-Commerce para 2021 | ASD Group<\/title>\n<meta name=\"description\" content=\"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma do IVA E-Commerce para 2021 | ASD Group\" \/>\n<meta property=\"og:description\" content=\"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"ASD\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-26T12:23:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/\",\"name\":\"Reforma do IVA E-Commerce para 2021 | ASD Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_393401239.jpg\",\"datePublished\":\"2020-03-30T08:11:54+00:00\",\"dateModified\":\"2020-11-26T12:23:13+00:00\",\"description\":\"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_393401239.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/shutterstock_393401239.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/reforma-iva-e-commerce-vendas-a-distancia-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"ASD Group\",\"item\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reforma do IVA aplicada ao E-Commerce e \u00e0s Vendas \u00e0 Dist\u00e2ncia para 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"name\":\"ASD\",\"description\":\"Simplifique a sua expans\u00e3o Internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#organization\",\"name\":\"ASD Group\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"contentUrl\":\"https:\\\/\\\/www.asd-int.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo-ASD_noir.png\",\"width\":1054,\"height\":714,\"caption\":\"ASD Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asd-int.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma do IVA E-Commerce para 2021 | ASD Group","description":"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"Reforma do IVA E-Commerce para 2021 | ASD Group","og_description":"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.","og_url":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/","og_site_name":"ASD","article_modified_time":"2020-11-26T12:23:13+00:00","og_image":[{"url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/","url":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/","name":"Reforma do IVA E-Commerce para 2021 | ASD Group","isPartOf":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg","datePublished":"2020-03-30T08:11:54+00:00","dateModified":"2020-11-26T12:23:13+00:00","description":"A partir de 1 de julho de 2021, as regras para o IVA aplicadas \u00e0 venda \u00e0 dist\u00e2ncia e o E-commerce B2C, ir\u00e3o sofrer grandes altera\u00e7\u00f5es. Anticipe as mudan\u00e7as com ASD Group.","breadcrumb":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/#primaryimage","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2019\/06\/shutterstock_393401239.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asd-int.com\/pt-pt\/reforma-iva-e-commerce-vendas-a-distancia-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"ASD Group","item":"https:\/\/www.asd-int.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Reforma do IVA aplicada ao E-Commerce e \u00e0s Vendas \u00e0 Dist\u00e2ncia para 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.asd-int.com\/pt-pt\/#website","url":"https:\/\/www.asd-int.com\/pt-pt\/","name":"ASD","description":"Simplifique a sua expans\u00e3o Internacional","publisher":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asd-int.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.asd-int.com\/pt-pt\/#organization","name":"ASD Group","url":"https:\/\/www.asd-int.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","contentUrl":"https:\/\/www.asd-int.com\/wp-content\/uploads\/2020\/07\/Logo-ASD_noir.png","width":1054,"height":714,"caption":"ASD Group"},"image":{"@id":"https:\/\/www.asd-int.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/74014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/types\/service"}],"author":[{"embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":0,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/service\/74014\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=74014"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/pays?post=74014"},{"taxonomy":"activites","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/activites?post=74014"},{"taxonomy":"type_service","embeddable":true,"href":"https:\/\/www.asd-int.com\/pt-pt\/wp-json\/wp\/v2\/type_service?post=74014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}